{"id":181,"date":"2019-04-22T05:00:40","date_gmt":"2019-04-22T05:00:40","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/2019\/04\/22\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/"},"modified":"2026-02-11T14:53:25","modified_gmt":"2026-02-11T13:53:25","slug":"steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/","title":{"rendered":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation?"},"content":{"rendered":"\n<p>Von <a href=\"https:\/\/www.linkedin.com\/in\/margrit-keller-a6327914\/\" target=\"_blank\" rel=\"noreferrer noopener\">Margrit Keller<\/a><\/p>\n\n\n\n\n\n<p><strong>Welche Bedeutung haben Budgets von Gemeinwesen?<\/strong><\/p>\n\n\n\n<p>Das Budget eines Gemeinwesens wird durch die Verwaltung erstellt, durch die Exekutive verabschiedet und zur Pr\u00fcfung und rechtskr\u00e4ftigen Genehmigung an die Exekutive (Parlament \/ Bev\u00f6lkerung) \u00fcberwiesen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"604\" height=\"363\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Grafik-im-Text.png\" alt=\"\" class=\"wp-image-183\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Grafik-im-Text.png 604w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Grafik-im-Text-300x180.png 300w\" sizes=\"auto, (max-width: 604px) 100vw, 604px\" \/><\/figure>\n<\/div>\n\n\n<p>Das Budget wird nach seiner Genehmigung zu einem rechtskr\u00e4ftigen Ausgabenbeschluss. Die budgetierten Ausgaben d\u00fcrfen von der Verwaltung und Exekutive get\u00e4tigt und die Ertr\u00e4ge generiert werden. Damit haben die Budgetunterlagen Urkundencharakter (Art. 110 StGB Abs. 4). Eine vors\u00e4tzliche und\/oder fahrl\u00e4ssige Falschdarstellung von entscheidrelevanten Fakten erf\u00fcllt somit grunds\u00e4tzlich den Tatbestand der Urkundenf\u00e4lschung (Art. 251 StGB und\/oder Art. 317 StGB). Beim Rechnungsabschluss muss die Exekutive gegen\u00fcber der Finanzkontrolle und dem Parlament Rechenschaft \u00fcber die Abweichungen zum Budget ablegen.<\/p>\n\n\n\n<p><strong>Der Steuerertrag als wichtigste Einnahmeposition im Kantons- und Gemeindebudget<\/strong><\/p>\n\n\n\n<p>Die Steuerertragsbudgetierung ist ein zentrales Element bei der Erstellung des Budgets eines Gemeinwesens. Mit einem Anteil von durchschnittlich \u00fcber 60 Prozent am Gesamtertrag sind die Steuereinnahmen die entscheidende Schl\u00fcsselgr\u00f6sse. &nbsp;Wegen der Unsicherheit der realen konjunkturellen und wirtschaftlichen Entwicklung ergeben sich jedoch erhebliche Unsicherheiten. Gr\u00f6ssere Abweichungen zu den effektiven Steuereinnahmen ziehen in der Regel auch mediale Aufmerksamkeit mit sich. So wirft beispielsweise die <a href=\"https:\/\/tageswoche.ch\/politik\/erneut-verrechnet-wie-die-baselbieter-regierung-ihre-zahlen-beschoenigt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tageswoche vom 15.10.2015<\/a> den verantwortlichen Politikern offen Trickserei, Versagen und Unf\u00e4higkeit vor.<\/p>\n\n\n\n<p><strong>Erstellen von Steuerertragsprognosen \u2013 Ein Blick in die Zukunft<\/strong><\/p>\n\n\n\n<p>Ziel der Steuerertragsprognose ist, dass diese m\u00f6glichst genau mit den im n\u00e4chsten Jahr effektiv erzielten Steuereinnahmen \u00fcbereinstimmt. Die Herausforderung besteht darin, die Ver\u00e4nderungen der wichtigsten Einflussfaktoren auf den Steuerertrag m\u00f6glichst zuverl\u00e4ssig einzusch\u00e4tzen.<\/p>\n\n\n\n<p>Neben der konjunkturellen und wirtschaftlichen Entwicklung beeinflussen insbesondere auch die Entwicklung der Wohnbev\u00f6lkerung (Wachstum, Einkommen) die H\u00f6he der zu erwartenden Steuereinnahmen. Die Steuern der Unternehmen werden auf den Unternehmensgewinnen erhoben. Diese verhalten sich jedoch sehr volatil. Sie sind abh\u00e4ngig vom jeweiligen Gesch\u00e4ftsverlauf, aber auch von unternehmerischen Entscheiden (z.B. Gewinnpolitik, Standortwahl, Steueroptimierungsstrategie, etc.).<\/p>\n\n\n\n<p><strong>Grenzen von Steuerertragsprognosen<\/strong><\/p>\n\n\n\n<p>Auch mit der besten Steuerertragsprognose l\u00e4sst sich nicht mit absoluter Genauigkeit vorhersagen, wie sich die Zukunft effektiv entwickeln wird und inwieweit sich die getroffenen Annahmen erf\u00fcllen.<\/p>\n\n\n\n<p>So k\u00f6nnen unvorhersehbare Ereignisse (z.B. &nbsp;Wegzug\/Tod des Hauptsteuerzahlers, Firmenschliessungen, Steuersitzverlegungen, W\u00e4hrungsschwankungen, politische Ereignisse, usw.) die <a href=\"https:\/\/www.aargauerzeitung.ch\/aargau\/kanton-aargau\/ueber-100-millionen-franken-minus-kanton-aargau-faehrt-rekord-defizit-ein-131045829\" target=\"_blank\" rel=\"noreferrer noopener\">Prognose vollkommen umstossen<\/a>.<\/p>\n\n\n\n<p>Hinzu kommt, dass der im Budget eingestellte Steuerertrag nicht zwingend mit der von den Steuerspezialisten erstellten fachlichen Steuerertragsprognose \u00fcbereinstimmen muss. Es steht der Exekutive, aber auch der Legislative, grunds\u00e4tzlich frei, diese Werte nach eigenem Ermessen zu \u00abkorrigieren\u00bb und einen davon abweichenden Wert zu beschliessen.<\/p>\n\n\n\n<p><strong>Prognosefehler oder strafrechtlich relevante Budget-Manipulation?<\/strong><\/p>\n\n\n\n<p>Grunds\u00e4tzlich beginnt eine strafrechtliche Manipulation des Steuerertrages (Urkundenf\u00e4lschung im Sinne von Art. 251 StGB, bzw. Art. 317 StGB) erst dort, wo die Steuerertragsprognose in den Budgetunterlagen <em>absichtlich <\/em>verf\u00e4lscht wird. Dies mit dem Ziel, sich dadurch einen <em>unrechtm\u00e4ssigen Vorteil<\/em> (z.B. Sicherung der Wiederwahl, Verhinderung von Ausgabenk\u00fcrzungen und Anpassungen des Steuerfusses, usw.) zu verschaffen.<\/p>\n\n\n\n<p>Bei einer unsystematisch und methodisch mangelhaft erstellten Steuerertragsprognose, die nicht dokumentiert und nicht nachvollziehbar ist, l\u00e4sst sich eine absichtliche Falschdarstellung des Steuerertrages in den Budgetunterlagen kaum beweisen.&nbsp; Auf politischer Ebene kann ein \u00f6ffentlich ge\u00e4usserter Verdacht der Manipulation und\/oder Unf\u00e4higkeit gegen einen verantwortlichen Politiker durchaus ausreichen, dass dieser <a href=\"https:\/\/www.handelszeitung.ch\/politik\/finanzvorsteher-monnard-beugt-sich-dem-druck-764357\" target=\"_blank\" rel=\"noreferrer noopener\">\u00abfreiwillig\u00bb zur\u00fccktritt<\/a>.<\/p>\n\n\n\n<p><strong>Massnahmen zur Reduktion der Risiken von Budgetierungsfehlern und Manipulationen<\/strong><\/p>\n\n\n\n<p>Durch die Verwendung eines geeigneten, standardisierten Prognosemodells lassen sich die Risiken methodisch-handwerklicher Fehler bei der Erstellung der Steuerertragsprognose reduzieren und Transparenz schaffen. Die Einf\u00fchrung zus\u00e4tzlicher Qualit\u00e4tssicherungsmassnahmen und eine Erg\u00e4nzung des bestehenden IKS stellen eine fr\u00fchzeitige Entdeckung von Fehlern sicher und erschweren eine absichtliche Falschdarstellung des Steuerertrages im Budget.<\/p>\n\n\n\n<p><strong>Download Template Risikoreduktion<\/strong><\/p>\n\n\n\n<p>Die Massnahmen zur Risikoreduktion liegen als Template f\u00fcr einen einfach umzusetzenden,<em> standardisierten Budgetierungsprozess<\/em> vor. Dieser kann mit geringem Aufwand an die individuellen Bed\u00fcrfnisse eines Gemeinwesens angepasst und zeitnah umgesetzt werden.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><a href=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2019\/04\/Risiken-und-delliktische-Handlungen-im-Budgetierungsprozesss.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Risiken und deliktische Handlungen im Budgetierungsprozess<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/05\/Massnahmenblaetter-zur-Risikoreduktion.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Massnahmenbl\u00e4tter zur Risikoreduktion<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2019\/04\/Standardprozess-mit-Massnahmen-zur-Risikoreduktion.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Standardprozess mit Massnahmen zur Risikoreduktion<\/a><\/li>\n<\/ol>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Margrit Keller<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"544\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/MArgrit-Keller.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/MArgrit-Keller.jpg 407w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/MArgrit-Keller-224x300.jpg 224w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/MArgrit-Keller-390x520.jpg 390w\" sizes=\"auto, (max-width: 407px) 100vw, 407px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/MArgrit-Keller.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/checkpoint\/challengesV2\/AQELajp4q2SkqAAAAYJAFB0CM_dFxiKtPURXMhkG-J-_eW5cTrobqnD6eX80TYdgeRLTBzfAf9ho1aMQDM01lH-rQysnS1vBhw\" target=\"_blank\">Margrit Keller<\/a>, <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/mas\/ifz\/economic-crime-investigation\/\" target=\"_blank\">MAS Economic Crime Investigation<\/a>, EMBA und MAS Controlling, arbeitet seit \u00fcber f\u00fcnfzehn Jahren in leitender Position in unterschiedlichen Funktionen im Finanzbereich der \u00f6ffentlichen Verwaltung. Seit Anfang M\u00e4rz 2019 leitet sie die Finanzabteilung der Stadt Dietikon.\r\n\r\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bei den Jahresrechnungen von Kantonen und Gemeinden interessiert in erster Linie die H\u00f6he der effektiven Steuereinnahmen. Unerwartet hohe Abweichungen zum Budget werfen Fragen nach dem \u00abWarum\u00bb auf: Haben sich die politisch Verantwortlichen versch\u00e4tzt? Waren unvorhersehbare \/ zuf\u00e4llige Ereignisse Schuld? Oder wurde gar \u00abgetrickst\u00bb, um sich so einen Vorteil zu verschaffen? <\/p>\n","protected":false},"author":111,"featured_media":182,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"3533,3527,3503,3467,3249,3407","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[12],"tags":[199,200,201,202,30,203,204,205,206,207],"class_list":["post-181","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaftskriminalistik","tag-budget","tag-budgetierung","tag-budgetmanipulation","tag-gemeinden","tag-iks","tag-risiken","tag-risikoreduktion","tag-steuerertragsbudgetierung","tag-steuerertragsprognose","tag-urkundenfaelschung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"Bei den Jahresrechnungen von Kantonen und Gemeinden interessiert in erster Linie die H\u00f6he der effektiven Steuereinnahmen. Unerwartet hohe Abweichungen zum Budget werfen Fragen nach dem \u00abWarum\u00bb auf: Haben sich die politisch Verantwortlichen versch\u00e4tzt? Waren unvorhersehbare \/ zuf\u00e4llige Ereignisse Schuld? Oder wurde gar \u00abgetrickst\u00bb, um sich so einen Vorteil zu verschaffen?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-22T05:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1688\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webkinder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"webkinder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/\"},\"author\":{\"name\":\"webkinder\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"headline\":\"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation?\",\"datePublished\":\"2019-04-22T05:00:40+00:00\",\"dateModified\":\"2026-02-11T13:53:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/\"},\"wordCount\":642,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/07\\\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg\",\"keywords\":[\"Budget\",\"Budgetierung\",\"Budgetmanipulation\",\"Gemeinden\",\"IKS\",\"Risiken\",\"Risikoreduktion\",\"Steuerertragsbudgetierung\",\"Steuerertragsprognose\",\"Urkundenf\u00e4lschung\"],\"articleSection\":[\"Wirtschaftskriminalistik\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/\",\"name\":\"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/07\\\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg\",\"datePublished\":\"2019-04-22T05:00:40+00:00\",\"dateModified\":\"2026-02-11T13:53:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/07\\\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/07\\\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg\",\"width\":1688,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\",\"name\":\"webkinder\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g\",\"caption\":\"webkinder\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/","og_locale":"de_DE","og_type":"article","og_title":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog","og_description":"Bei den Jahresrechnungen von Kantonen und Gemeinden interessiert in erster Linie die H\u00f6he der effektiven Steuereinnahmen. Unerwartet hohe Abweichungen zum Budget werfen Fragen nach dem \u00abWarum\u00bb auf: Haben sich die politisch Verantwortlichen versch\u00e4tzt? Waren unvorhersehbare \/ zuf\u00e4llige Ereignisse Schuld? Oder wurde gar \u00abgetrickst\u00bb, um sich so einen Vorteil zu verschaffen?","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/","og_site_name":"Economic Crime Blog","article_published_time":"2019-04-22T05:00:40+00:00","article_modified_time":"2026-02-11T13:53:25+00:00","og_image":[{"width":1688,"height":1125,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","type":"image\/jpeg"}],"author":"webkinder","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"webkinder","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/"},"author":{"name":"webkinder","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"headline":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation?","datePublished":"2019-04-22T05:00:40+00:00","dateModified":"2026-02-11T13:53:25+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/"},"wordCount":642,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","keywords":["Budget","Budgetierung","Budgetmanipulation","Gemeinden","IKS","Risiken","Risikoreduktion","Steuerertragsbudgetierung","Steuerertragsprognose","Urkundenf\u00e4lschung"],"articleSection":["Wirtschaftskriminalistik"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/","name":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation? - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","datePublished":"2019-04-22T05:00:40+00:00","dateModified":"2026-02-11T13:53:25+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","width":1688,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/steuerertragsbudgetierung-bei-gemeinwesen-prognoserisiken-oder-budgetmanipulation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Steuerertragsbudgetierung bei Gemeinwesen: Prognoserisiken oder Budgetmanipulation?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542","name":"webkinder","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/597462d46107dd3eedd2b10f3add8a737c67c8148836713dd97585128d19d477?s=96&d=mm&r=g","caption":"webkinder"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/le_sdis_31_-_nos_moyens_-_le_budget_-_article.jpg","author_info":{"display_name":"webkinder","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/webkinder\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/181","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=181"}],"version-history":[{"count":9,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/181\/revisions"}],"predecessor-version":[{"id":6235,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/181\/revisions\/6235"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/182"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=181"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=181"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=181"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}