{"id":2980,"date":"2022-11-21T06:30:00","date_gmt":"2022-11-21T05:30:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/?p=2980"},"modified":"2026-02-11T14:53:30","modified_gmt":"2026-02-11T13:53:30","slug":"bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/","title":{"rendered":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz"},"content":{"rendered":"\n<p>Von&nbsp;<a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3750\" target=\"_blank\" rel=\"noreferrer noopener\">Susanne Grau<\/a>&nbsp;und&nbsp;<a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3607\" target=\"_blank\" rel=\"noreferrer noopener\">Dr. Claudia V. Brunner<\/a><\/p>\n\n\n\n\n\n<p>Am 16. November 2022 konnten die Seminarleiterinnen Susanne Grau und Dr. Claudia V. Brunner einen hochinteressierten Kreis an Teilnehmenden aus der Justiz, Verwaltung und Privatwirtschaft am Institut f\u00fcr Finanzdienstleistungen Zug IFZ der Hochschule Luzern auf dem Campus Zug-Rotkreuz begr\u00fcssen. Gemeinsam mit den Expertinnen und Experten widmeten sie sich den unterschiedlichsten Aspekten der Bilanzf\u00e4lschung.<\/p>\n\n\n\n<p><strong>Wann ist Bilanzf\u00e4lschung strafbar?<\/strong><\/p>\n\n\n\n<p>In ihrem Vortrag \u00abBilanzf\u00e4lschung aus Sicht des Strafrechts\u00bb f\u00fchrte Susanne Grau, Dozentin am Institut f\u00fcr Finanzdienstleistungen Zug IFZ der Hochschule Luzern, die Anwesenden in den Deliktsaufbau der Bilanzf\u00e4lschung beziehungsweise der <a href=\"https:\/\/www.fedlex.admin.ch\/eli\/cc\/54\/757_781_799\/de#art_251\" target=\"_blank\" rel=\"noreferrer noopener\">Falschbeurkundung<\/a> ein. Zun\u00e4chst zeigte sie anhand eines einfachen Schemas auf, wie buchhalterische Verhaltensweisen strafrechtlich beurteilt werden k\u00f6nnen. Anschliessend wurden die vermittelten Grundlagen anhand zweier ausgew\u00e4hlter F\u00e4lle aus der Praxis vertieft. Wie der Fall Erb anschaulich zeigt, k\u00f6nnen Bilanzen, beziehungsweise Jahresabschl\u00fcsse auch nach deren Fertigstellung in betr\u00fcgerischer Absicht manipuliert werden. So sch\u00f6nten die Verantwortlichen die Zahlen nachtr\u00e4glich mit dem Ziel, bestehende Bankkredite zu verl\u00e4ngern oder neue Kredite zu erhalten. Aber nicht nur die Finanzbuchhaltungen, sondern auch die Betriebsbuchhaltungen k\u00f6nnen von Manipulationen oder F\u00e4lschungen betroffen sein. So verringerte PostAuto mit fiktiven Buchungen den Gewinn der abgeltungsberechtigten Sparte \u00abRegionaler Personenverkehr\u00bb mit dem Ziel, ungerechtfertigte Subventionen geltend zu machen. <a href=\"https:\/\/blog.hslu.ch\/economiccrime\/2019\/06\/24\/postauto-und-die-manipulationen-in-der-betriebsbuchhaltung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Dabei ist die Rede von Subventionsbetrug und manipulierten Zahlen<\/a>. Die verwaltungsstrafrechtliche Untersuchung ist allerdings noch nicht abgeschlossen.<\/p>\n\n\n\n<div class=\"swiper__responsive-container \">\n\t<div class=\"swiper__responsive-wrapper\">\n\t\t<div class=\"swiper mainSwiper\">\n\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_111114.jpg\" alt=\"\">\n\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t<div class=\"slide-action slide-action-zoom\" data-id=\"6a57769e70ddd\">\uf188<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_140058-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t<div class=\"slide-action slide-action-zoom\" data-id=\"6a57769e70ddd\">\uf188<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_151703-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t<div class=\"slide-action slide-action-zoom\" data-id=\"6a57769e70ddd\">\uf188<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t<\/div>\n\t\t<div class=\"swiper-pagination\"><\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"zoom-container\" data-id=\"6a57769e70ddd\">\n\t<div class=\"zoom-container-inner\">\n\t\t<div class=\"zoom-responsive-container\">\n\t\t\t<div class=\"zoom-wrapper\">\n\t\t\t\t<div class=\"swiper zoomSwiper\">\n\t\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_111114.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"slide-action zoom-action-close\">\uf189<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_140058-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"slide-action zoom-action-close\">\uf189<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\">\n\t\t\t\t\t\t\t\t<figure class=\"slide-figure\">\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"slide-image\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/20221116_151703-1.jpg\" alt=\"\">\n\t\t\t\t\t\t\t\t\t<figcaption class=\"slide-caption\"><span><\/span><\/figcaption>\n\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t<div class=\"slide-action-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"slide-action zoom-action-close\">\uf189<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"swiper-button-prev\"><\/div>\n\t\t\t\t\t<div class=\"swiper-button-next\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<p><strong>Welche Rolle nimmt die Revisionsstelle ein?<\/strong><\/p>\n\n\n\n<p>Marc Arnet, Mandatsleiter Wirtschaftspr\u00fcfung bei Mattig-Suter und Partner, f\u00fchrte die Teilnehmenden in seinem Referat \u00abBilanzmanipulation aus Sicht der Revisionsstelle\u00bb gekonnt durch verschiedene Fallbeispiele. Dabei durfte der <a href=\"https:\/\/blog.hslu.ch\/economiccrime\/2021\/05\/31\/wirecard-bilanzmanipulation-der-superlative\/\" target=\"_blank\" rel=\"noreferrer noopener\">Fall Wirecard<\/a> nicht fehlen, bei welchem ein Viertel der Bilanzsumme, beziehungsweise 1.9 Milliarden Euro \u00abfrei erfunden\u00bb waren. Aber auch andere bekannte F\u00e4lle wurden diskutiert, wie beispielsweise derjenige der deutschen \u00abFlowtex\u00bb-Gruppe, welche mit nicht existierenden Spezialbohrmaschinen ein fiktives Warenlager aufgebaut und ein Schneeballsystem betrieben hat. Im Anschluss an die Fallbesprechungen ging Marc Arnet auf das Problem der \u00abmehrfachen Erwartungsl\u00fccke\u00bb bei den Revisionsstellen ein. Zun\u00e4chst ist es so, dass die Mehrheit der Schweizer Unternehmen gar nicht \u00fcber eine Revisionsstelle verf\u00fcgt, da nur wenige von ihnen \u00fcberhaupt pr\u00fcfungspflichtig sind. Bei denjenigen, die eine Revisionsstelle haben, werden die Auswirkungen deliktischer Handlungen auf den Abschluss nur gepr\u00fcft, wenn sie der ordentlichen Revision unterliegen. Das betrifft gerade mal 2% aller Schweizer Unternehmen. Der &nbsp;<a href=\"http:\/\/files.designer.hoststar.ch\/hoststar13173\/file\/ser_15.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Schweizer Standard zur Eingeschr\u00e4nkten Revision (SER)<\/a> schliesst das Einholen von Drittgutachten und Best\u00e4tigungen sowie die Begleitung von Inventuren explizit aus.<\/p>\n\n\n\n<p><strong>Wann ist Bilanzmanipulation erlaubt?<\/strong><\/p>\n\n\n\n<p>Nach dem gemeinsamen Mittagessen widmete sich Marco Passardi, Professor f\u00fcr Accounting am Institut f\u00fcr Finanzdienstleistungen Zug IFZ der Hochschule Luzern, dem Thema der erlaubten Bilanzpolitik. Brilliant f\u00fchrte er die Anwesenden anhand von anschaulichen Fallbeispielen durch die Materie. Zun\u00e4chst verwies er auf Fehler, die h\u00e4ufig keinen deliktischen Hintergrund haben d\u00fcrften, wie beispielsweise solche im Bereich der Gliederung. Sobald Fehler aber zu einer klaren Beeintr\u00e4chtigung der Aussagekraft der Jahresrechnung f\u00fchren, m\u00fcssen sie als qualitativ wesentlich bezeichnet werden. Wie mit diesen im Rahmen der ordentlichen Revision umgegangen wird, erl\u00e4uterte er anhand des Schweizer Pr\u00fcfungsstandards 240, welcher sich mit deliktischen Handlungen auseinandersetzt. Nach einigen Erl\u00e4uterungen zum \u00abJournal-Entry-Testing\u00bb, der Analyse zur Feststellung von auff\u00e4lligen Abweichungen, wie beispielsweise Buchungen mit runden Betr\u00e4gen oder zu ungew\u00f6hnlichen Zeitpunkten, leitete Marco Passardi zu einzelnen Beispielen \u00fcber. Dabei entstand unter den Anwesenden eine angeregte Diskussion, wie sich der Wechsel der Abschreibungsmethode auf die Bilanz und Erfolgsrechnung auswirkt und welche Buchungen erlaubt sind und welche nicht.<\/p>\n\n\n\n<p><strong>Wie kommt man Bilanzf\u00e4lschung auf die Spur?<\/strong><\/p>\n\n\n\n<p>Zum Abschluss des Seminartages erkl\u00e4rte Daniel Pf\u00e4ffli, Senior Wissenschaftlicher Mitarbeiter am Departement Informatik der Hochschule Luzern, wie man mit k\u00fcnstlicher Intelligenz Unregelm\u00e4ssigkeiten visualisieren und identifizieren kann. Zun\u00e4chst f\u00fchrte er die Teilnehmenden in den Begriff der k\u00fcnstlichen Intelligenz ein und erl\u00e4uterte anhand eines einfachen Beispiels, was Algorithmen sind. Danach demonstrierte er anhand des Fallbeispiels der Eidgen\u00f6ssische Elektrizit\u00e4tskommission ElCom, wie potenziell auff\u00e4llige Angaben der Netzbetreiber identifiziert werden k\u00f6nnen. Weiter legte er anhand von Demonstrationen und \u00dcbungen mit den Teilnehmenden dar, wie sich in Datens\u00e4tzen sogenannte Anomalien, also Auff\u00e4lligkeiten, erkennen und isolieren lassen. Dieses Vorgehen kann auch bei der Feststellung und Aufdeckung von Bilanzmanipulationen oder -f\u00e4lschungen hilfreich sein. &nbsp;<\/p>\n\n\n\n<p><strong>Bed\u00fcrfnis nach Erweiterung des Fachwissens<\/strong><\/p>\n\n\n\n<p>Die angeregten Diskussionen w\u00e4hrend den Referaten, in den Pausen und w\u00e4hrend dem gemeinsamen Mittagessen zeigten, wie wichtig und anspruchsvoll das Thema Bilanzf\u00e4lschung ist. Im Rahmen des Fachbereichs Wirtschaftskriminalistik k\u00f6nnen Interessierte im <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/economic-crime-investigation\/\" target=\"_blank\" rel=\"noreferrer noopener\">CAS Economic Crime Investigation<\/a> ihr Wissen \u00fcber die Bilanzf\u00e4lschung hinaus vertiefen. Das Weiterbildungsprogramm kann in einem Zeitraum von sieben Jahren mit einem <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/mas\/ifz\/economic-crime-investigation\/\" target=\"_blank\" rel=\"noreferrer noopener\">Master<\/a> vervollst\u00e4ndigt werden. Das Seminar Bilanzf\u00e4lschung wird auch im Jahr 2023 wieder durchgef\u00fchrt.<\/p>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Susanne Grau<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"393\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Download-e1768379752854.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Download-e1768379752854.jpg 337w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Download-e1768379752854-257x300.jpg 257w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Download-e1768379752854.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\t<a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3750\" target=\"_blank\">Susanne Grau<\/a> ist Leiterin des Themenbereichs Wirtschaftskriminalistik, Dozentin und Projektleiterin am <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/ueber-uns\/institute\/ifz\/\" target=\"_blank\">Institut f\u00fcr Finanzdienstleistungen Zug IFZ<\/a> der <a href=\"https:\/\/www.hslu.ch\/de-ch\/\" target=\"_blank\">Hochschule Luzern<\/a> und Inhaberin und Gesch\u00e4ftsf\u00fchrerin der <a href=\"https:\/\/www.susannegrau.ch\/\" target=\"_blank\">SUSANNEGRAU Consulting GmbH<\/a>. Sie amtet als Vizepr\u00e4sidentin von <a href=\"https:\/\/swissaccounting.org\/\" target=\"_blank\">SwissAccounting<\/a> und ist Verwaltungsr\u00e4tin der <a href=\"https:\/\/www.controller-akademie.ch\/\" target=\"_blank\">Controller Akademie AG<\/a> . Zudem ist sie Vorstandsmitglied der Schweizerischen Expertenvereinigung zur Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t <a href=\"https:\/\/www.seeci.ch\/\" target=\"_blank\">SEBWK<\/a>.\r\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Dr. Claudia V. Brunner<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"449\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Claudia-Brunner.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Claudia-Brunner.jpg 337w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Claudia-Brunner-225x300.jpg 225w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/07\/Claudia-Brunner.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tRechtsanw\u00e4ltin <a href=\"https:\/\/jbra.ch\/rechtsanw%C3%A4lte\/claudiavbrunner\" target=\"_blank\">Dr. Claudia V. Brunner<\/a> ist Partnerin bei <a href=\"https:\/\/www.jbra.ch\/\" target=\"_blank\">Jositsch Brunner Rechtsanw\u00e4lte<\/a> und war bis September 2024 verantwortlich f\u00fcr den Themenbereich Wirtschaftskriminalistik sowie Dozentin und Projektleiterin am <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/institute\/ifz\/\" target=\"_blank\">Institut f\u00fcr Finanzdienstleistungen Zug<\/a> der <a href=\"https:\/\/www.hslu.ch\/de-ch\/\" target=\"_blank\">Hochschule Luzern<\/a>. Sie verf\u00fcgt \u00fcber weitreichende Erfahrungen im Bereich Wirtschaftskriminalit\u00e4t, Compliance und Wirtschaftsstrafrecht. Zudem hat sie bei der <a href=\"https:\/\/www.brunnerinvest.ch\/\" target=\"_blank\">BrunnerInvest AG <\/a> ein Mandat als Vizepr\u00e4sidentin des Verwaltungsrats inne und ist Vorstandsmitglied der <a href=\"https:\/\/www.polyreg.ch\/\" target=\"_blank\">SRO PolyReg<\/a>.\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>In der Praxis f\u00fchrt die Unterscheidung zwischen zul\u00e4ssiger Gestaltung und strafbarer F\u00e4lschung von Bilanzen regelm\u00e4ssig zu Abgrenzungsschwierigkeiten und Problemen. Die Teilnehmenden des Seminars \u00abBilanzf\u00e4lschung\u00bb erhielten einen Einblick in die verschiedenen relevanten Aspekte. Wann sind solche Handlungen strafbar und wie kommt man den Verfehlungen auf die Spur?<\/p>\n","protected":false},"author":163,"featured_media":3010,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"258,46,174,374,221,96","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[13],"tags":[271,154,272,155,273,220],"class_list":["post-2980","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financial-crime","tag-bilanzdelikt","tag-bilanzfaelschung","tag-bilanzkosmetik","tag-bilanzmanipulation","tag-bilanzpolitik","tag-falschbeurkundung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"In der Praxis f\u00fchrt die Unterscheidung zwischen zul\u00e4ssiger Gestaltung und strafbarer F\u00e4lschung von Bilanzen regelm\u00e4ssig zu Abgrenzungsschwierigkeiten und Problemen. Die Teilnehmenden des Seminars \u00abBilanzf\u00e4lschung\u00bb erhielten einen Einblick in die verschiedenen relevanten Aspekte. Wann sind solche Handlungen strafbar und wie kommt man den Verfehlungen auf die Spur?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudiabrunner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudiabrunner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/\"},\"author\":{\"name\":\"claudiabrunner\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"headline\":\"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz\",\"datePublished\":\"2022-11-21T05:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/\"},\"wordCount\":809,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/11\\\/Titelbild-mit-SG.jpg\",\"keywords\":[\"Bilanzdelikt\",\"Bilanzf\u00e4lschung\",\"Bilanzkosmetik\",\"Bilanzmanipulation\",\"Bilanzpolitik\",\"Falschbeurkundung\"],\"articleSection\":[\"Financial Crime\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/\",\"name\":\"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/11\\\/Titelbild-mit-SG.jpg\",\"datePublished\":\"2022-11-21T05:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/11\\\/Titelbild-mit-SG.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/11\\\/Titelbild-mit-SG.jpg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\",\"name\":\"claudiabrunner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"caption\":\"claudiabrunner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/","og_locale":"de_DE","og_type":"article","og_title":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog","og_description":"In der Praxis f\u00fchrt die Unterscheidung zwischen zul\u00e4ssiger Gestaltung und strafbarer F\u00e4lschung von Bilanzen regelm\u00e4ssig zu Abgrenzungsschwierigkeiten und Problemen. Die Teilnehmenden des Seminars \u00abBilanzf\u00e4lschung\u00bb erhielten einen Einblick in die verschiedenen relevanten Aspekte. Wann sind solche Handlungen strafbar und wie kommt man den Verfehlungen auf die Spur?","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/","og_site_name":"Economic Crime Blog","article_published_time":"2022-11-21T05:30:00+00:00","article_modified_time":"2026-02-11T13:53:30+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","type":"image\/jpeg"}],"author":"claudiabrunner","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"claudiabrunner","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/"},"author":{"name":"claudiabrunner","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"headline":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz","datePublished":"2022-11-21T05:30:00+00:00","dateModified":"2026-02-11T13:53:30+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/"},"wordCount":809,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","keywords":["Bilanzdelikt","Bilanzf\u00e4lschung","Bilanzkosmetik","Bilanzmanipulation","Bilanzpolitik","Falschbeurkundung"],"articleSection":["Financial Crime"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/","name":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","datePublished":"2022-11-21T05:30:00+00:00","dateModified":"2026-02-11T13:53:30+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/bilanzfaelschung-vom-deliktsaufbau-bis-zur-aufdeckung-mittels-kuenstlicher-intelligenz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Bilanzf\u00e4lschung \u2013 Vom Deliktsaufbau bis zur Aufdeckung mittels k\u00fcnstlicher Intelligenz"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9","name":"claudiabrunner","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","caption":"claudiabrunner"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Titelbild-mit-SG.jpg","author_info":{"display_name":"claudiabrunner","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/claudiabrunner\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/2980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=2980"}],"version-history":[{"count":24,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/2980\/revisions"}],"predecessor-version":[{"id":6364,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/2980\/revisions\/6364"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/3010"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=2980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=2980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=2980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}