{"id":3424,"date":"2023-05-08T06:30:00","date_gmt":"2023-05-08T04:30:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/?p=3424"},"modified":"2026-05-12T13:33:14","modified_gmt":"2026-05-12T11:33:14","slug":"whistleblowing-ein-effizientes-fruehwarnsystem","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/","title":{"rendered":"<strong>Whistleblowing &#8211; ein effizientes Fr\u00fchwarnsystem<\/strong>"},"content":{"rendered":"\n<p>Von <a href=\"https:\/\/www.linkedin.com\/in\/mona-fahmy-a3a5534a\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mona Fahmy<\/a><\/p>\n\n\n\n<p>Ohne sogenannte \u00abWhistleblower\u00bb, also hinweisgebenden Personen, w\u00fcrden Missst\u00e4nde in Unternehmen, Beh\u00f6rden oder Institutionen oft verborgen bleiben. So machte beispielsweise der ehemalige Mitarbeiter des amerikanischen Nachrichtendienstes CIA, Edward Snowden, bekannt, wie die USA weltweit Kommunikationsfl\u00fcsse \u00fcberwachte. Eine andere Whistleblowerin, die ehemalige US-Armeeangeh\u00f6rige Chelsea Manning, brachte Videos von US-Angriffen auf Zivilisten an die \u00d6ffentlichkeit. Einer der bekanntesten Whistleblower in der Schweiz ist Adam Quadroni, der das B\u00fcndner Baukartell enth\u00fcllte.<\/p>\n\n\n\n<p>Obwohl Whistleblower dank ihres Insiderwissens bestenfalls den entscheidenden Hinweis zur Aufdeckung dunkler Machenschaften geben, werden sie oft als Nestbeschmutzer bezeichnet. Sie haben mit Konsequenzen zu rechnen, wenn bekannt wird, dass sie den Missstand gemeldet haben. Mit der EU-Richtlinie 2019\/1937, der sogenannten <a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/DE\/TXT\/PDF\/?uri=CELEX:32019L1937\" target=\"_blank\" rel=\"noreferrer noopener\">EU-Whistleblower-Richtlinie<\/a>, sind hinweisgebende Personen in der EU mittlerweile besser vor Repressalien beziehungsweise Vergeltungsmassnahmen gesch\u00fctzt. Die Richtlinie trat im Dezember 2019 in Kraft. Bis Dezember 2021 mussten die EU-Mitgliedstaaten die Vorgaben in nationales Recht umsetzen. Mehrere EU-Staaten, darunter auch Deutschland, schafften es jedoch nicht, fristgerecht ein Gesetz zu verabschieden. Das vom Deutschen Bundestag im Dezember 2022 verabschiedete Gesetz hat der Bundesrat in seiner <a href=\"https:\/\/www.bundesrat.de\/SharedDocs\/drucksachen\/2023\/0001-0100\/20-23(B).pdf?__blob=publicationFile&amp;v=1\" target=\"_blank\" rel=\"noreferrer noopener\">Sitzung vom 10. Februar 2023<\/a> abgelehnt. Bundesregierung und Bundestag m\u00fcssen nun zun\u00e4chst einen Kompromiss finden. Das Gesetz sch\u00fctzt hinweisgebende Personen insbesondere vor arbeitsrechtlichen Konsequenzen, wie beispielsweise einer K\u00fcndigung.<\/p>\n\n\n\n<p>In der Schweiz ist die EU-Richtlinie nicht direkt anwendbar. Schweizer Unternehmen, die im EU-Raum Gesch\u00e4fte t\u00e4tigen, k\u00f6nnen aber davon betroffen sein. Dies gilt insbesondere dann, wenn sie in der EU Niederlassungen mit 50 oder mehr Mitarbeitenden betreiben. Diese Unternehmen m\u00fcssen k\u00fcnftig \u00fcber eine Whistleblowing-Hotline verf\u00fcgen.<\/p>\n\n\n\n<p><strong>Whistleblowing-Hotline sch\u00fctzt Unternehmen<\/strong><\/p>\n\n\n\n<p>Bei gr\u00f6sseren Unternehmen und Beh\u00f6rden geh\u00f6ren Whistleblowing-Hotlines mittlerweile aus gutem Grund zur sogenannten \u00abBest Practice\u00bb, also zu den bew\u00e4hrten Vorgehensweisen. Hinweisgebende Personen weisen die Gesch\u00e4ftsleitungen fr\u00fchzeitig auf Fehlverhalten oder Straftaten im Betrieb hin und er\u00f6ffnen dadurch die M\u00f6glichkeit, Missst\u00e4nde anzugehen, bevor der Schaden zu gross ist und\/oder rufsch\u00e4digende Informationen an die \u00d6ffentlichkeit gelangen. Damit k\u00f6nnen Reputationsrisiken, finanzielle Sch\u00e4digungen, Verwarnungen von Aufsichtsbeh\u00f6rden und Strafen verhindert werden.<\/p>\n\n\n\n<p>Hinweise \u00fcber Fehlverhalten k\u00f6nnen sowohl intern, mittels eines eigens daf\u00fcr eingerichteten Meldesystems, als auch extern, \u00fcber eine Whistleblowing-Hotline, die Strafverfolgungsbeh\u00f6rden oder die Medien, anonym erfolgen. Der Schritt nach aussen erfolgt meist dann, wenn der Versuch, intern auf Missst\u00e4nde hinzuweisen, gescheitert ist oder wenig Vertrauen in die internen Untersuchungsabl\u00e4ufe besteht. Ein sorgsamer und \u00fcberlegter Umgang mit Whistleblower-Meldungen, nicht zuletzt, um den Gang an die \u00d6ffentlichkeit zu verhindern, liegt demnach im Interesse der Unternehmen.<\/p>\n\n\n\n<p><strong>Herausforderungen beim Umgang mit hinweisgebenden Personen<\/strong><\/p>\n\n\n\n<p>Hinweisgebende Personen k\u00f6nnen von Mobbing betroffen sein. Im schlimmsten Fall droht gar der Jobverlust. Aus diesem Grund ist es entscheidend, ihre Anonymit\u00e4t zu wahren. Ebenso wichtig ist es, Whistleblower bereits vor der Meldung auf die Risiken von Mobbing bis zum Jobverlust aufmerksam zu machen, beispielsweise mit einem Disclaimer auf der Hinweisgeber-Plattform.<\/p>\n\n\n\n<p>Da Nachfragen zur Abkl\u00e4rung des Sachverhalts oft unerl\u00e4sslich sind, sollte die Whistleblowing-Hotline beziehungsweise -Plattform \u00fcber anonyme Kan\u00e4le verf\u00fcgen, mit denen eine Kommunikation mit den hinweisgebenden Personen m\u00f6glich ist. Ausserdem ist darauf zu achten, dass die Plattform unabh\u00e4ngig betrieben wird und diejenigen, welche die Meldungen pr\u00fcfen, sich nicht in einem Interessen- oder Loyalit\u00e4tskonflikt befinden.<\/p>\n\n\n\n<p>Eine weitere Herausforderung stellt die \u00dcberpr\u00fcfung der Meldungen auf ihre Richtigkeit hin dar. Kann diese stimmen? Will die hinweisgebende Person jemanden anschw\u00e4rzen? Handelt sie aus Rache? Es kann vorkommen, dass die Personen nicht ehrenhaft und uneigenn\u00fctzig handeln, sondern pers\u00f6nliche Motive im Vordergrund stehen. Daher ist es wichtig, den Sachverhalt genau zu kl\u00e4ren und die Meldung in den Gesamtkontext zu stellen.<\/p>\n\n\n\n<p>F\u00fcr Personen, die aufgrund von Hinweisen mit Vorw\u00fcrfen konfrontiert, also eines Fehlverhaltens beschuldigt werden, gilt stets die Unschuldsvermutung. Bevor eine Untersuchung nicht die n\u00f6tigen Beweise liefert, sollten die Unternehmen unverh\u00e4ltnism\u00e4ssiges Verhalten gegen\u00fcber den betroffenen Personen vermeiden. Denn letzteres k\u00f6nnte unerw\u00fcnschte Konsequenzen zur Folge haben und \u00fcberdies bei den Betroffenen zu sch\u00e4digenden Verhaltensweisen gegen\u00fcber dem Unternehmen oder anderen Personen f\u00fchren.<\/p>\n\n\n\n<p>B\u00f6rsenkotierte internationale Unternehmen verf\u00fcgen meistens \u00fcber das n\u00f6tige rechtliche und investigative Wissen, um ad\u00e4quat und zielgerichtet mit solchen Meldungen umzugehen. Kleineren und mittleren Unternehmen fehlen hingegen h\u00e4ufig das Fachwissen und die Ressourcen. Deswegen m\u00fcssen sie aber nicht auf eine Whistleblowing-Hotline verzichten. Externe Fachpersonen k\u00f6nnen sie dabei von der Triage der Meldungen, also deren Ersteinsch\u00e4tzung und Einordnung, bis hin zur Untersuchung des Sachverhalts unterst\u00fctzen.<\/p>\n\n\n\n<p><strong>Whistleblowing-Plattformen sind Fr\u00fchwarnsysteme<\/strong><\/p>\n\n\n\n<p>Whistleblowing-Plattformen sind im Hinblick auf die Bek\u00e4mpfung von unethischem Verhalten sowie von strafbaren Handlungen in Unternehmen, Beh\u00f6rden und Institutionen wichtige Fr\u00fchwarnsysteme. Sie helfen den Organisationen, sich vor Reputationssch\u00e4den und finanziellen Verlusten zu sch\u00fctzen. Anders als in der EU ist in der Schweiz der Schutz von Whistleblowern nicht ausreichend geregelt. Dies ist in Bezug auf den Umgang mit hinweisgebenden Personen stets zu beachten. Ebenfalls ist es wichtig, die Kl\u00e4rung des Sachverhalts, den sogenannten Faktencheck, stets sorgf\u00e4ltig vorzunehmen. Die Motivation der hinweisgebenden Person sollte bekannt und die Meldung auf ihre Plausibilit\u00e4t hin \u00fcberpr\u00fcft worden sein. Dadurch l\u00e4sst sich das Risiko vermindern, dass Unschuldige zu Unrecht beschuldigt werden.<\/p>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Mona Fahmy<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"1365\" height=\"1587\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822.jpg 1365w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822-258x300.jpg 258w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822-881x1024.jpg 881w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822-768x893.jpg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822-1321x1536.jpg 1321w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822-600x698.jpg 600w\" sizes=\"auto, (max-width: 1365px) 100vw, 1365px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2022\/11\/Mona_Fahmy_sw_full-e1738923784822.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\t<a href=\"https:\/\/www.linkedin.com\/in\/mona-fahmy-a3a5534a\/\" target=\"_blank\">Mona Fahmy<\/a> ist \u00d6konomin und Absolventin des <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/mas\/ifz\/economic-crime-investigation\/\" target=\"_blank\">MAS Economic Crime Investigation<\/a>. Sie ist Co-Gr\u00fcnderin und Gesch\u00e4ftsf\u00fchrerin der <a href=\"https:\/\/diraya.ch\/about.html\" target=\"_blank\">Diraya Intelligence GmbH<\/a>, Co-Chair der <a href=\"https:\/\/ethics-compliance.ch\/working-groups\/wg-whistleblowing\/\" target=\"_blank\">Working Group Whistleblowing bei Ethics and Compliance Switzerland<\/a> und Vizepr\u00e4sidentin der Schweizerischen Expertenvereinigung \u00abBek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\u00bb <a href=\"https:\/\/seeci.ch\/\" target=\"_blank\">SEBWK<\/a>. \t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Hinweisgebende Personen decken im Idealfall dunkle Machenschaften auf. Doch anders als in der EU m\u00fcssen Unternehmen in der Schweiz noch keine Whistleblowing-Hotline einf\u00fchren. Dabei g\u00e4be es gute Gr\u00fcnde daf\u00fcr.<\/p>\n","protected":false},"author":163,"featured_media":3438,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"149,159,3025,426,76,546","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[58,237,12],"tags":[104,163,642,645,144,184,60,11],"class_list":["post-3424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-forensics-investigation","category-wirtschaftskriminalistik","tag-betrug","tag-compliance","tag-datenbeschaffung","tag-informationsbeschaffung","tag-praevention","tag-reputationsrisiken","tag-whistleblowing","tag-wirtschaftskriminalitaet"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"Hinweisgebende Personen decken im Idealfall dunkle Machenschaften auf. Doch anders als in der EU m\u00fcssen Unternehmen in der Schweiz noch keine Whistleblowing-Hotline einf\u00fchren. Dabei g\u00e4be es gute Gr\u00fcnde daf\u00fcr.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-08T04:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T11:33:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1463\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudiabrunner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudiabrunner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/\"},\"author\":{\"name\":\"claudiabrunner\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"headline\":\"Whistleblowing &#8211; ein effizientes Fr\u00fchwarnsystem\",\"datePublished\":\"2023-05-08T04:30:00+00:00\",\"dateModified\":\"2026-05-12T11:33:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/\"},\"wordCount\":869,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/04\\\/AdobeStock_199127335-1.jpeg\",\"keywords\":[\"Betrug\",\"Compliance\",\"Datenbeschaffung\",\"Informationsbeschaffung\",\"Pr\u00e4vention\",\"Reputationsrisiken\",\"Whistleblowing\",\"Wirtschaftskriminalit\u00e4t\"],\"articleSection\":{\"1\":\"Forensics &amp; Investigation\",\"2\":\"Wirtschaftskriminalistik\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/\",\"name\":\"Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/04\\\/AdobeStock_199127335-1.jpeg\",\"datePublished\":\"2023-05-08T04:30:00+00:00\",\"dateModified\":\"2026-05-12T11:33:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/04\\\/AdobeStock_199127335-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/04\\\/AdobeStock_199127335-1.jpeg\",\"width\":2048,\"height\":1463},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/whistleblowing-ein-effizientes-fruehwarnsystem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Whistleblowing &#8211; ein effizientes Fr\u00fchwarnsystem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\",\"name\":\"claudiabrunner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"caption\":\"claudiabrunner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/","og_locale":"de_DE","og_type":"article","og_title":"Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog","og_description":"Hinweisgebende Personen decken im Idealfall dunkle Machenschaften auf. Doch anders als in der EU m\u00fcssen Unternehmen in der Schweiz noch keine Whistleblowing-Hotline einf\u00fchren. Dabei g\u00e4be es gute Gr\u00fcnde daf\u00fcr.","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/","og_site_name":"Economic Crime Blog","article_published_time":"2023-05-08T04:30:00+00:00","article_modified_time":"2026-05-12T11:33:14+00:00","og_image":[{"width":2048,"height":1463,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","type":"image\/jpeg"}],"author":"claudiabrunner","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"claudiabrunner","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/"},"author":{"name":"claudiabrunner","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"headline":"Whistleblowing &#8211; ein effizientes Fr\u00fchwarnsystem","datePublished":"2023-05-08T04:30:00+00:00","dateModified":"2026-05-12T11:33:14+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/"},"wordCount":869,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","keywords":["Betrug","Compliance","Datenbeschaffung","Informationsbeschaffung","Pr\u00e4vention","Reputationsrisiken","Whistleblowing","Wirtschaftskriminalit\u00e4t"],"articleSection":{"1":"Forensics &amp; Investigation","2":"Wirtschaftskriminalistik"},"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/","name":"Whistleblowing - ein effizientes Fr\u00fchwarnsystem - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","datePublished":"2023-05-08T04:30:00+00:00","dateModified":"2026-05-12T11:33:14+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","width":2048,"height":1463},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/whistleblowing-ein-effizientes-fruehwarnsystem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Whistleblowing &#8211; ein effizientes Fr\u00fchwarnsystem"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9","name":"claudiabrunner","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","caption":"claudiabrunner"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/04\/AdobeStock_199127335-1.jpeg","author_info":{"display_name":"claudiabrunner","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/claudiabrunner\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/3424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=3424"}],"version-history":[{"count":15,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/3424\/revisions"}],"predecessor-version":[{"id":6679,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/3424\/revisions\/6679"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/3438"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=3424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=3424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=3424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}