{"id":4321,"date":"2024-03-04T06:30:00","date_gmt":"2024-03-04T05:30:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/?p=4321"},"modified":"2026-02-11T14:53:32","modified_gmt":"2026-02-11T13:53:32","slug":"nebenwirkungen-der-corona-pandemie","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/","title":{"rendered":"Nebenwirkungen der Corona Pandemie"},"content":{"rendered":"\n<p>Von Tanja Fuchs, Claudia Kunz und Stephanie Schenker<\/p>\n\n\n\n\n\n<p>Die Ermittlungsabteilung Wirtschaftskriminalit\u00e4t der Kantonspolizei Z\u00fcrich ist ein Spezialdienst innerhalb der Kriminalpolizei. Sie befasst sich mit komplexen Verm\u00f6gensdelikten, wie Betrug, Veruntreuung und Konkurs, aber auch mit Korruption, Geldw\u00e4scherei, Bilanzmanipulationen sowie mit digitalen Begehungsformen, wie beispielsweise dem Online Anlagebetrug. Dar\u00fcber hinaus bearbeitet die Abteilung Rechtshilfeersuchen aus aller Welt und betreibt eine professionelle Verm\u00f6gensabsch\u00f6pfung zur Einziehung deliktisch erlangter Gegenst\u00e4nde und Verm\u00f6genswerte.<\/p>\n\n\n\n<p>Die periodische Ver\u00f6ffentlichung von Berichten aus dem Team von Lt. Lic. iur. Tanja Fuchs gibt einen Einblick in die Arbeit der Polizistinnen und Polizisten sowie in die Herausforderungen, denen sie sich in ihrem Berufsalltag gegen\u00fcbersehen. Der Bericht von Claudia Kunz und Stephanie Schenker wurde erstmals im Nachrichtenblatt 7\/2023 (September) der Kantonspolizei Z\u00fcrich ver\u00f6ffentlicht und wird nachfolgend leicht gek\u00fcrzt aber ansonsten unver\u00e4ndert wiedergegeben.<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Potenzielle Deliktsumme von 260 Millionen Franken<\/strong><\/p>\n\n\n\n<p>Insgesamt verzeichnet der Bund \u00fcber 2200 Verdachtsf\u00e4lle, bei denen im Zusammenhang mit Covid-19-Krediten mit einer potenziellen Deliktsumme von \u00fcber 260 Millionen Franken Strafanzeige erstattet wurde. Zus\u00e4tzlich wurden zwischenzeitlich schweizweit 821 Strafanzeigen abgeschlossen, wobei hier eine Deliktsumme in der H\u00f6he von 68 194 881 Franken verzeichnet wird. Die ausgewiesene Deliktsumme entspricht dem Volumen der Kredite zum Zeitpunkt von deren Gew\u00e4hrung, dabei wird nicht ber\u00fccksichtigt, ob effektiv Verluste entstanden sind. Im Verh\u00e4ltnis zum Gesamtvolumen der gew\u00e4hrten Covid-19-Kredite sowie der Covid-19-Kredite-Plus von etwa 16,9 Milliarden Franken machen die bisher bekannten sowie die verdachtsweise missbr\u00e4uchlich erlangten Kredite circa 1,9 Prozent aus. Der Bund war sich bewusst, dass die Lancierung dieses Wirtschaft-Hilfsprogramms ein Missbrauchspotenzial birgt. Der Anteil an bisher bekannten sowie verdachtsweise missbr\u00e4uchlich erlangten Covid-19-Kredite ist minimal. Dennoch steht hinter der vermeintlich vernachl\u00e4ssigbaren Zahl von circa 1,9 Prozent eine Kreditsumme von \u00fcber 300 Millionen Franken.<\/p>\n\n\n\n<p><strong>Kantonspolizei ermittelt in 473 Verdachtsf\u00e4llen<\/strong><\/p>\n\n\n\n<p>Die Kantonspolizei Z\u00fcrich steht in der Verantwortung, gegen jene Kreditbez\u00fcgerinnen und Kreditbez\u00fcger mit Ankn\u00fcpfungspunkt im Kanton Z\u00fcrich repressiv vorzugehen, die dieses einmalige Hilfsinstrumentarium f\u00fcr die Schweizer Wirtschaft von Gier getrieben zu ihrer pers\u00f6nlichen Bereicherung ausnutzten.<\/p>\n\n\n\n<p>Das neuartige Covid-19-Betrugsph\u00e4nomen etablierte sich innerhalb dreier Jahre zum polizeilichen Ermittlungstagesgesch\u00e4ft. Bis Anfang August 2023 verzeichnete die Kantonspolizei Z\u00fcrich 473 Verdachtsf\u00e4lle, bei denen von missbr\u00e4uchlich erlangten Covid- 19-Krediten auszugehen ist. Die Betr\u00fcgerinnen und Betr\u00fcger liessen dabei ihrer Kreativit\u00e4t freien Lauf, was die Deklaration des angeblich erwirtschafteten Umsatzes des Unternehmens im Gesch\u00e4ftsjahr 2018 oder 2019 auf dem Kreditantragsformular anbelangte. Nicht erstaunlich ist, dass allen diesen Personen eine optimistische Grundhaltung eigen war. Die wirtschaftliche Leistungsf\u00e4higkeit ihrer Unternehmen wurde durchwegs \u00fcbersch\u00e4tzt. Manch ein Betr\u00fcger wurde zum Dokumentengrafiker und \u00fcbermittelte der Bank eine erfundene Erfolgsrechnung.<\/p>\n\n\n\n<p>\u00c4usserst willkommen war die Auszahlung des Covid-19-Kredits f\u00fcr einen Mann, der mit einem Teil des Kredits die Servicekosten f\u00fcr ein privates Luxusfahrzeug begleichen konnte. Teilweise verliehen die Betr\u00fcger ihrem Begehren nach einem Covid-19-Kredit Nachdruck, indem sie das Kreditantragsformular sicherheitshalber an verschiedene Bankinstitute versendeten, auf jedem Kreditantragsformular jedoch best\u00e4tigten, dass bei keinem weiteren Bankinstitut um einen Covid-19-Kredit ersucht worden war.<\/p>\n\n\n\n<p>In Zusammenhang mit beanzeigten Konkursdelikten stellte die Kantonspolizei Z\u00fcrich wiederholt fest, dass solche konkursiten Unternehmen Covid-19-Kredite ausbezahlt erhielten. Insbesondere bei erfolgten Konkurseinstellungen mangels Aktiven sind die Strafverfolgungsbeh\u00f6rden in der Pflicht hinzuschauen, ob die erlangten Covid-19-Kredite gem\u00e4ss dem Verwendungszweck verbraucht wurden, beziehungsweise ob das Unternehmen \u00fcberhaupt berechtigt war, diese Covid-19-Kredite zu beantragen.<\/p>\n\n\n\n<p><strong>Missbrauch mit der Kurzarbeitsentsch\u00e4digung<\/strong><\/p>\n\n\n\n<p>Zur Abfederung der coronabedingten Wirtschaftsausf\u00e4llen kamen weitere Hilfspakete des Bundes zum Einsatz, wie beispielsweise bei der Kurzarbeitsentsch\u00e4digung. Dadurch er\u00f6ffnete sich ein weiteres Betrugsfeld f\u00fcr Gierige.<\/p>\n\n\n\n<p>Mit der Kurzarbeitsentsch\u00e4digung (KAE) deckt die Arbeitslosenversicherung den Arbeitgebern \u00fcber einen gewissen Zeitraum einen Teil der Lohnkosten f\u00fcr die von Kurzarbeit betroffenen Arbeitnehmenden. So soll verhindert werden, dass Arbeitspl\u00e4tze infolge kurzfristiger und unvermeidbarer Arbeitsausf\u00e4lle gek\u00fcndigt werden. Im Gegensatz zur Arbeitslosenentsch\u00e4digung werden die Leistungen der KAE an den Arbeitgeber ausgerichtet.<\/p>\n\n\n\n<p>Die Sicherung von Arbeitspl\u00e4tzen im Zusammenhang mit dem Auftreten des Coronavirus hing wesentlich davon ab, ob die Liquidit\u00e4t der Unternehmen gew\u00e4hrleistet werden kann. Hohe pandemiebedingte Nachfrageeinbr\u00fcche und notwendige beh\u00f6rdliche Schutzmassnahmen f\u00fchrten seit M\u00e4rz 2020 gesamtwirtschaftlich zu starken Arbeits- und Einnahmeausf\u00e4llen.<\/p>\n\n\n\n<p>Die KAE ist das wichtigste Instrument der Arbeitslosenversicherung zur wirtschaftlichen Stabilisierung in Krisenzeiten, und so wurde das Instrument der KAE nach Ausbruch der Corona- Pandemie gerne in Anspruch genommen. Im M\u00e4rz 2020 lagen f\u00fcr 1,6 Millionen und im April 2020 f\u00fcr knapp 1,9 Millionen Arbeitnehmende Bewilligungen zum Bezug von KAE vor. Dies entsprach im April 2020 rund 37 Prozent aller Besch\u00e4ftigten. Damit lag die Zahl der Bewilligungen zum Bezug von KAE rund zehnmal h\u00f6her als bei der letzten grossen (Finanz-)Krise im Jahr 2009.<\/p>\n\n\n\n<p>Die notrechtlichen Massnahmen des Bundesrats zur Unterst\u00fctzung der Wirtschaft w\u00e4hrend der Corona-Pandemie enthielten bez\u00fcglich KAE verschiedene Erleichterungen beziehungsweise Ausweitungen: So wurde die Voranmeldefrist aufgehoben und der \u00abSelbstbehalt\u00bb f\u00fcr Unternehmen auf null reduziert (keine Karenztage). Zudem wurden die anspruchsberechtigten Personengruppen vor\u00fcbergehend ausgeweitet sowie das vereinfachte Verfahren bei der Voranmeldung sowie das summarische Verfahren bei der Abrechnung von KAE eingef\u00fchrt.<\/p>\n\n\n\n<p>Doch nicht alle Betriebe, die KAE erhielten, waren dazu auch berechtigt. So wurden die Antr\u00e4ge nicht oder nur vereinzelt durch die Arbeitslosenversicherung kontrolliert. Zwar musste seitens der Arbeitgeber immer noch eine Begr\u00fcndung angegeben werden. Es reichte jedoch, wenn auf dem Antragsformular zum Beispiel stand, dass die Kunden nicht mehr zahlen w\u00fcrden. Einen Beleg daf\u00fcr brauchte es nicht. Auch f\u00fchrten die Erleichterungen etwa dazu, dass pl\u00f6tzlich Ehefrauen, Nachbarn und weitere Kollegen in der Unternehmung eine Arbeitsstelle hatten.<\/p>\n\n\n\n<p>In einem bekannten Fall wurde eine Mehrzahl von Mitarbeitenden erfunden, die angeblich komplett von Kurzarbeit betroffen gewesen sein sollen. Die Mehrheit der Unterschriften dieser erfundenen Mitarbeitenden waren gef\u00e4lscht, und die gesamte Entsch\u00e4digung wurde Monat f\u00fcr Monat durch die Arbeitgeber eingestrichen. Mit dem ertrogenen Geld konnten die Antragssteller sich schliesslich eine teure Luxuskarosse und Luxusuhren kaufen.<\/p>\n\n\n\n<p>Im Kanton Z\u00fcrich wurden im Zeitraum von 2020 bis 2022 rund 90 Berichte und Anzeigen betreffend eines m\u00f6glichen Bezugsmissbrauchs von Leistungen der Sozialversicherung (Betrug) rapportiert. Die Spanne der ungerechtfertigt erlangten KAE betr\u00e4gt gem\u00e4ss den polizeilichen Datenbanken zwischen ein paar tausend bis zu 1,1 Millionen Franken.<\/p>\n\n\n\n<p><strong>\u00dcber 111 Millionen Franken zur\u00fcckgefordert<\/strong><\/p>\n\n\n\n<p>Da die Arbeitslosenversicherung infolge der Pandemie KAE in historischem Ausmass ausbezahlte, war fr\u00fchzeitig klar, dass auch die Missbrauchsbek\u00e4mpfung deutlich verst\u00e4rkt werden muss. So wurden innerhalb k\u00fcrzester Zeit die personellen Ressourcen zur Kontrolle in diesem Bereich und das Budget deutlich aufgestockt. Dadurch konnten unter anderem die Arbeitgeberkontrollen intensiviert und bezogene Leistungen zur\u00fcckgefordert werden.<\/p>\n\n\n\n<p>Gem\u00e4ss neusten Zahlen des Staatssekretariats f\u00fcr Wirtschaft wurden 2216 F\u00e4lle zwischen September 2020 und M\u00e4rz 2023 gepr\u00fcft, die auf verschiedenen Wegen der Arbeitslosenversicherung gemeldet oder durch die Arbeitslosenkassen selbst aufgrund von Auff\u00e4lligkeiten gepr\u00fcft wurden. Gem\u00e4ss den auf der Webseite <a href=\"https:\/\/www.arbeit.swiss\/secoalv\/de\/home.html\" target=\"_blank\" rel=\"noreferrer noopener\">arbeit.swiss.ch<\/a> ver\u00f6ffentlichten Zahlen ergab das Revisionsergebnis des Staatssekretariats, dass aufgrund der Pr\u00fcfungen 15 F\u00e4lle als missbr\u00e4uchlich und 72 als fehlerhaft betrachtet werden. Diese Zahl ist nicht sonderlich hoch, jedoch resultiert daraus, dass bis M\u00e4rz 2023 ein Betrag in der H\u00f6he von 111\u2009507\u2009186.40 Franken zur\u00fcckgefordert wurde. Beachtlich ist dieser Betrag auch insofern, weil noch l\u00e4ngst nicht alle Verdachtsmeldungen gepr\u00fcft wurden.<\/p>\n\n\n\n<p>Mit den strafrechtlich- und zivilrechtlichen Massnahmen wird erhofft, dass bei einer m\u00f6glichen weiteren Pandemie die Missbr\u00e4uche einged\u00e4mmt werden k\u00f6nnen und sich die Betr\u00fcge nicht mehr lohnen. Es wird sich erst in der Zukunft zeigen, in welchem Ausmass bei den Covid-19-Krediten und bei den Bez\u00fcgen von KAE betrogen wurde. Die Kreditr\u00fcckzahlungen sind mehrheitlich noch nicht f\u00e4llig, und die \u00dcberpr\u00fcfungen allf\u00e4llig unrechtm\u00e4ssiger Leistungsbez\u00fcge von KAE werden noch Monate, wenn nicht Jahre in Anspruch nehmen. Demzufolge ist auch klar, dass uns diese Nebenwirkungen der Corona-Pandemie noch l\u00e4nger besch\u00e4ftigen werden.<\/p>\n\n\n\n<p><strong>Fragen zu Fakten und Zahlen wirtschaftlicher Notmassnahmen<\/strong><\/p>\n\n\n\n<p>Seit Beginn der Corona-Pandemie sind drei Jahre vergangen. Ein kurzer Selbsttest hilft, die Erinnerung an die wirtschaftlichen Notmassnahmen etwas aufzufrischen. Es gibt beim Test nichts zu gewinnen. Mehrfachantworten sind m\u00f6glich. S\u00e4mtliche Angaben sind \u00f6ffentlich recherchierbar auf der <a href=\"http:\/\/www.covid19.easygov.swiss\">Internetseite des Bundes<\/a>. Die Daten beziehen sich auf den Informationsstand vom 9. August 2023.<\/p>\n\n\n\n<p>1. Wann beschloss der Bundesrat ein umfassendes Massnahmenpaket zur Abfederung der wirtschaftlichen Folgen der Ausbreitung des Coronavirus?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp; A) 20. M\u00e4rz 2021<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp; B) 20. M\u00e4rz 2020<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp; C) 1. Januar 2020<\/p>\n\n\n\n<p>2. Welche Summe stellte der Bundesrat bis zum 20. M\u00e4rz 2020 zur Abfederung der wirtschaftlichen Folgen der Ausbreitung des Coronavirus bereit?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) 40 Milliarden Franken<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) 80 Milliarden Franken<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) 10 Milliarden Franken<\/p>\n\n\n\n<p>3. Wann trat die Notverordnung zur Gew\u00e4hrung von Krediten mit Solidarb\u00fcrgschaft des Bundes in Kraft?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) 31. M\u00e4rz 2021<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) 31. Juni 2020<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) 26. M\u00e4rz 2020<\/p>\n\n\n\n<p>4. In welchem Umfang konnten betroffene Unternehmen \u00dcberbr\u00fcckungskredite beantragen?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) minimal 10 Prozent vom Jahresumsatz bis maximal 20 Millionen Franken<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) h\u00f6chstens 10 Prozent vom Jahresumsatz bis maximal 20 Millionen Franken<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) h\u00f6chstens 10 Prozent vom Jahresumsatz bis maximal 10 Millionen Franken<\/p>\n\n\n\n<p>5. Zu wie vielen Prozenten wurden \u00dcberbr\u00fcckungskredite bis zu einem Betrag von 500\u2009000 Franken durch den Bund abgesichert?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) zu 50 Prozent<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) zu 0 Prozent<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) zu 100 Prozent<\/p>\n\n\n\n<p>6. Wie wurden \u00dcberbr\u00fcckungskredite bis 500\u2009000 Franken ausbezahlt?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) unb\u00fcrokratisch und rasch<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) nach Durchlaufen einer Kreditw\u00fcrdigkeitspr\u00fcfung durch die Bank<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) nach Einreichen des Kreditantrags<\/p>\n\n\n\n<p>7. Wie viele Kreditvereinbarungen wurden per 2. April 2020 abgeschlossen?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) 76\u2009034 Kreditvereinbarungen<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) 95\u2009047 Kreditvereinbarungen<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) 36\u2009988 Kreditvereinbarungen<\/p>\n\n\n\n<p>8. Wie viele Kreditvereinbarungen mit welchem Kreditvolumen wurden per 9. August 2023 abgeschlossen?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) 136\u2009737 Covid-Kredite bis 500\u2009000 CHF mit insges. 13\u2009916\u2009639\u2009515 CHF<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) 325\u2009889 Covid-Kredite bis 500\u2009000 CHF mit insgesamt 25\u2009915\u2009115\u2009172 CHF<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) 136\u2009737 Covid-Kredite bis 500\u2009000 CHF mit insgesamt 8\u2009915\u2009060\u2009713 CHF<\/p>\n\n\n\n<p>9. Wie viele Covid-19-\u00dcberbr\u00fcckungskredite wurden per 9. August 2023 vollst\u00e4ndig zur\u00fcckbezahlt?<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; A) 49\u2009666 Kredite mit insgesamt 15 629 949 545 CHF<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; B) 7633 Kredite mit insgesamt 629 949 545 CHF<\/p>\n\n\n\n<p><img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" src=\"\">&nbsp;&nbsp;&nbsp;&nbsp; C) 40\u2009452 Kredite mit insgesamt 7\u2009500\u2009156\u2009849 CHF<\/p>\n\n\n\n<p>L\u00f6sungen:<\/p>\n\n\n\n<p>1B, 2A, 3C, 4B, 5C, 6AC, 7A, 8A, 9C<\/p>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Tanja Fuchs<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"1990\" height=\"1592\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1.jpg 1990w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-300x240.jpg 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-1024x819.jpg 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-768x614.jpg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-1536x1229.jpg 1536w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-873x698.jpg 873w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1-600x480.jpg 600w\" sizes=\"auto, (max-width: 1990px) 100vw, 1990px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/08\/Passfoto-Headshot-fja-1.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tOblt. lic. iur. Tanja Fuchs leitet die Ermittlungsabteilung f\u00fcr Wirtschaftskriminalit\u00e4t der Kantonspolizei Z\u00fcrich. \t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Claudia Kunz<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"130\" height=\"148\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/01\/Bild2.jpg\" class=\"attachment-normal size-normal\" alt=\"\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/01\/Bild2.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tClaudia Kunz ist als Sachbearbeiterin bei der Ermittlungsabteilung Wirtschaftskriminalit\u00e4t der Kantonspolizei Z\u00fcrich t\u00e4tig und ermittelt Finanz- und Wirtschaftsdelikte. \t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Stephanie Schenker<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"115\" height=\"137\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/01\/Bild3.jpg\" class=\"attachment-normal size-normal\" alt=\"\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/01\/Bild3.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tStephanie Schenker ist als Sachbearbeiterin bei der Ermittlungsabteilung Wirtschaftskriminalit\u00e4t der Kantonspolizei Z\u00fcrich t\u00e4tig und ermittelt Finanz- und Wirtschaftsdelikte. \t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Mit den Massnahmen des Bundesrats zur Abfederung der wirtschaftlichen Folgen im Zusammenhang mit der Corona-Pandemie haben sich einige Unternehmen mit Betr\u00fcgereien bei den Covid-19-Krediten, wie auch der Deklaration f\u00fcr die Kurzarbeitsentsch\u00e4digung auf Kosten der Allgemeinheit bereichert. Bis August 2023 verzeichnete allein die Kantonspolizei Z\u00fcrich \u00fcber 470 Verdachtsf\u00e4lle.<\/p>\n","protected":false},"author":163,"featured_media":4323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"46,99,578,2797,2906,462","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[19],"tags":[104,954,406,538,867,536,492,873],"class_list":["post-4321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wirtschaftsrecht","tag-betrug","tag-betrugsphaenomen","tag-corona","tag-covid-19-kredit","tag-kantonspolizei-zuerich","tag-kurzarbeitsentschaedigung","tag-missbrauch","tag-straftat"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nebenwirkungen der Corona Pandemie - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nebenwirkungen der Corona Pandemie - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"Mit den Massnahmen des Bundesrats zur Abfederung der wirtschaftlichen Folgen im Zusammenhang mit der Corona-Pandemie haben sich einige Unternehmen mit Betr\u00fcgereien bei den Covid-19-Krediten, wie auch der Deklaration f\u00fcr die Kurzarbeitsentsch\u00e4digung auf Kosten der Allgemeinheit bereichert. Bis August 2023 verzeichnete allein die Kantonspolizei Z\u00fcrich \u00fcber 470 Verdachtsf\u00e4lle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1244\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudiabrunner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudiabrunner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"15\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/\"},\"author\":{\"name\":\"claudiabrunner\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"headline\":\"Nebenwirkungen der Corona Pandemie\",\"datePublished\":\"2024-03-04T05:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/\"},\"wordCount\":1719,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/11\\\/AdobeStock_337956025.jpeg\",\"keywords\":[\"Betrug\",\"Betrugsph\u00e4nomen\",\"Corona\",\"COVID-19-Kredit\",\"Kantonspolizei Z\u00fcrich\",\"Kurzarbeitsentsch\u00e4digung\",\"Missbrauch\",\"Straftat\"],\"articleSection\":[\"Wirtschaftsrecht\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/\",\"name\":\"Nebenwirkungen der Corona Pandemie - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/11\\\/AdobeStock_337956025.jpeg\",\"datePublished\":\"2024-03-04T05:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:32+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/11\\\/AdobeStock_337956025.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/11\\\/AdobeStock_337956025.jpeg\",\"width\":2048,\"height\":1244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nebenwirkungen-der-corona-pandemie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nebenwirkungen der Corona Pandemie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\",\"name\":\"claudiabrunner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"caption\":\"claudiabrunner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nebenwirkungen der Corona Pandemie - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/","og_locale":"de_DE","og_type":"article","og_title":"Nebenwirkungen der Corona Pandemie - Economic Crime Blog","og_description":"Mit den Massnahmen des Bundesrats zur Abfederung der wirtschaftlichen Folgen im Zusammenhang mit der Corona-Pandemie haben sich einige Unternehmen mit Betr\u00fcgereien bei den Covid-19-Krediten, wie auch der Deklaration f\u00fcr die Kurzarbeitsentsch\u00e4digung auf Kosten der Allgemeinheit bereichert. Bis August 2023 verzeichnete allein die Kantonspolizei Z\u00fcrich \u00fcber 470 Verdachtsf\u00e4lle.","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/","og_site_name":"Economic Crime Blog","article_published_time":"2024-03-04T05:30:00+00:00","article_modified_time":"2026-02-11T13:53:32+00:00","og_image":[{"width":2048,"height":1244,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","type":"image\/jpeg"}],"author":"claudiabrunner","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"claudiabrunner","Gesch\u00e4tzte Lesezeit":"15\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/"},"author":{"name":"claudiabrunner","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"headline":"Nebenwirkungen der Corona Pandemie","datePublished":"2024-03-04T05:30:00+00:00","dateModified":"2026-02-11T13:53:32+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/"},"wordCount":1719,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","keywords":["Betrug","Betrugsph\u00e4nomen","Corona","COVID-19-Kredit","Kantonspolizei Z\u00fcrich","Kurzarbeitsentsch\u00e4digung","Missbrauch","Straftat"],"articleSection":["Wirtschaftsrecht"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/","name":"Nebenwirkungen der Corona Pandemie - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","datePublished":"2024-03-04T05:30:00+00:00","dateModified":"2026-02-11T13:53:32+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","width":2048,"height":1244},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nebenwirkungen-der-corona-pandemie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Nebenwirkungen der Corona Pandemie"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9","name":"claudiabrunner","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","caption":"claudiabrunner"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/11\/AdobeStock_337956025.jpeg","author_info":{"display_name":"claudiabrunner","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/claudiabrunner\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=4321"}],"version-history":[{"count":13,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4321\/revisions"}],"predecessor-version":[{"id":6402,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4321\/revisions\/6402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/4323"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=4321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=4321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=4321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}