{"id":4807,"date":"2024-07-01T06:30:00","date_gmt":"2024-07-01T04:30:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/?p=4807"},"modified":"2026-02-11T14:53:33","modified_gmt":"2026-02-11T13:53:33","slug":"nutzung-von-open-source-intelligence-bei-internen-untersuchungen","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/","title":{"rendered":"Nutzung von Open Source Intelligence bei internen Untersuchungen"},"content":{"rendered":"\n<p>Von <a href=\"https:\/\/www.linkedin.com\/in\/lionel-bloch-79896872\" target=\"_blank\" rel=\"noreferrer noopener\">Lionel Bloch<\/a> und <a href=\"https:\/\/www.linkedin.com\/in\/andy-b-4319927\/\" target=\"_blank\" rel=\"noreferrer noopener\">Andy Bichsel<\/a><\/p>\n\n\n\n\n\n<p>Die Urspr\u00fcnge von OSINT lassen sich bis in den Zweiten Weltkrieg zur\u00fcckverfolgen. Um die Propagandaprogramme der Achsenm\u00e4chte zu \u00fcberwachen und zu analysieren, richteten die USA am 26. Februar 1941 den Foreign Broadcast Information Service (FBIS) ein. Diese Open-Source-Nachrichtendienstkomponente der Direktion f\u00fcr Wissenschaft und Technologie der <a href=\"https:\/\/www.cia.gov\/\" target=\"_blank\" rel=\"noreferrer noopener\">Central Intelligence Agency<\/a> \u00fcberwachte, \u00fcbersetzte und verbreitete innerhalb der US-Regierung frei zug\u00e4ngliche Nachrichten und Informationen aus Medienquellen ausserhalb der Vereinigten Staaten. Im November 2005 wurde bekannt gemacht, dass der FBIS zum neu gegr\u00fcndeten Open Source Center werden w\u00fcrde, das mit der Sammlung und Analyse \u00f6ffentlich zug\u00e4nglicher Informationen beauftragt ist.<\/p>\n\n\n\n<p>Die technologische Entwicklung und die breite Verf\u00fcgbarkeit von Online-Datenquellen haben die Sammlung und Analyse von Informationen seit den ersten Eins\u00e4tzen von OSINT revolutioniert. W\u00e4hrend die Suche urspr\u00fcnglich in Printmedien und anderen physischen Informationsquellen erfolgte, liegt der Schwerpunkt heute auf dem digitalen Raum sowie insbesondere auf dem Internet. Dieses bietet einen deutlich schnelleren und umfassenderen Zugang zu einer Vielzahl von Daten. Doch wie lassen sich die relevanten Informationen in der F\u00fclle der frei zug\u00e4nglichen Informationen effizient finden?<\/p>\n\n\n\n<p><strong>Architektur der drei Schichten des Internets<\/strong><\/p>\n\n\n\n<p>Um die Komplexit\u00e4t und die verschiedenen Ebenen der Informationssuche und -nutzung im Internet besser zu verstehen, ist das Drei-Schichten-Modell hinzuzuziehen. Nach diesem ist das Internet in die nachfolgenden drei Schichten zu unterteilen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Das <strong>Surface Web <\/strong>ist derjenige Teil des Internets, der mit Suchmaschinen, wie <a href=\"https:\/\/www.google.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>, <a href=\"https:\/\/www.bing.com\/?cc=ch\" target=\"_blank\" rel=\"noreferrer noopener\">Bing<\/a> oder <a href=\"https:\/\/duckduckgo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">DuckDuckGo<\/a>, gefunden werden kann. Es umfasst alle \u00f6ffentlich zug\u00e4nglichen Informationen, wie auf Webseiten, Nachrichtenportale, soziale Medien mit \u00f6ffentlichen Inhalten oder Online-Shops. Das sichtbare Internet macht etwa 4% der gesamthaft verf\u00fcgbaren Inhalte aus.<br><br><\/li>\n\n\n\n<li>Das <strong>Deep Web<\/strong> ist derjenige Teil des Internets, der von den herk\u00f6mmlichen Suchmaschinen, wie <a href=\"https:\/\/www.google.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>, <a href=\"https:\/\/www.bing.com\/?cc=ch\" target=\"_blank\" rel=\"noreferrer noopener\">Bing<\/a> oder <a href=\"https:\/\/duckduckgo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">DuckDuckGo<\/a>, nicht durchsucht werden kann. Es umfasst diejenigen Webseiten, die hinter Passw\u00f6rtern oder speziellen Zugriffsschranken verborgen sind. So zum Beispiel private Datenbanken, passwortgesch\u00fctzte Webseiten, soziale Medien mit privaten Inhalten, E-Banking oder wissenschaftliche Journale. Nur autorisierte Personen mit den entsprechenden Berechtigungen k\u00f6nnen darauf zugreifen. Es wird verwendet, um pers\u00f6nliche Informationen zu speichern und macht etwa 90% des ganzen Internets aus.<br><br><\/li>\n\n\n\n<li>Das <strong>Dark Web<\/strong> ist ein Teil des Deep Webs, der absichtlich verborgen und nur \u00fcber eine spezielle Software, wie den <a href=\"https:\/\/www.torproject.org\/\" target=\"_blank\" rel=\"noreferrer noopener\">Tor-Browser<\/a>, f\u00fcr die Nutzer zug\u00e4nglich wird. Es bezweckt den Schutz der Privatsph\u00e4re sowie der Meinungsfreiheit in repressiven Regimen und wird oft benutzt, um anonym zu kommunizieren. Dadurch wurde es zunehmend auch f\u00fcr illegale Aktivit\u00e4ten interessant. Es macht etwa 6% des gesamten Internets aus.<br><\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-1024x576.jpeg\" alt=\"\" class=\"wp-image-4808\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-1024x576.jpeg 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-300x169.jpeg 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-768x432.jpeg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-1536x864.jpeg 1536w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-928x522.jpeg 928w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1-600x338.jpeg 600w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-1.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Bild 1: Schichten des Internets (Eisbergmodell)<\/figcaption><\/figure>\n\n\n\n<p><strong>Der OSINT-Zyklus<\/strong><\/p>\n\n\n\n<p>Der OSINT-Zyklus, auch Open Source Intelligence Cycle genannt, beschreibt die systematische Herangehensweise, die von den Mitarbeitenden des Geheimdienstes und den Analysten verwendet wird, um \u00f6ffentlich verf\u00fcgbare Informationen zu sammeln, zu verarbeiten sowie zu analysieren, um diese in der Folge im Sinne eines endg\u00fcltigen Ergebnisses zu pr\u00e4sentieren. Er dient dazu, den Prozess der Informationsgewinnung effizient und strukturiert zu gestalten, um in m\u00f6glichst kurzer Zeit die bestm\u00f6glichen Ergebnisse zu erzielen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2.png\" alt=\"\" class=\"wp-image-4809\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2.png 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2-300x225.png 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2-768x576.png 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2-928x696.png 928w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/06\/Beitrag-Bild-2-600x450.png 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Bild 2: The OSINT Cycle (Erstellt von Dheeraj Yadav)<\/figcaption><\/figure>\n\n\n\n<p>Es bestehen unterschiedliche Ansichten dar\u00fcber, wie der OSINT-Zyklus und seine Phasen genau aussehen sollen. Grunds\u00e4tzlich kann er in die nachfolgenden f\u00fcnf Prozesse aufgeteilt werden:<\/p>\n\n\n\n<ol class=\"wp-block-list\" start=\"1\">\n<li>Die <strong>Vorbereitung<\/strong> ist die erste Phase des OSINT-Zyklus. Bei dieser werden zun\u00e4chst die Bed\u00fcrfnisse und Anforderungen der Recherche festgelegt. So werden in dieser die Ziele sowie die zu erhebenden Daten definiert und \u00fcberdies festgelegt, welche Quellen verwendet und welche Werkzeuge im Sinne einer effizienten Zielerreichung bevorzugt genutzt werden sollen.<br><br><\/li>\n\n\n\n<li>In der <strong>Sammelphase<\/strong> werden Rohdaten aus s\u00e4mtlichen \u00f6ffentlich zug\u00e4nglichen Quellen gesammelt, darunter sozialer Medien, Nachrichtenwebseiten, Blogs, Regierungsaufzeichnungen und weiterer \u00f6ffentlich zug\u00e4ngliche Quellen, die nicht zwangsl\u00e4ufig online sein m\u00fcssen. Um die Daten zu sammeln, kommen sowohl manuelle als auch automatisierte Ans\u00e4tze &#8211; oder eine Kombination aus beiden &#8211; zum Einsatz.<br><br><\/li>\n\n\n\n<li>Die dritte Phase des OSINT-Zyklus ist die <strong>Verarbeitung<\/strong>. Dabei werden die gesammelten Rohdaten auf ihre Zuverl\u00e4ssigkeit und Authentizit\u00e4t \u00fcberpr\u00fcft. Um dies zu gew\u00e4hrleisten und Fehlalarme zu minimieren, kommen mehrere Quellen, Werkzeuge und Techniken zum Einsatz. Nach der Filterung der Daten werden diese in ein leicht les- und nutzbares Format gebracht und f\u00fcr die Verwendung in den weiteren Phasen gespeichert.<br><br><\/li>\n\n\n\n<li>In der <strong>Analysephase<\/strong> untersuchen die Analysten die gesammelten Daten, um bedeutungsvolle Informationen, Einblicke und Muster zu identifizieren. Dabei geht es unter anderem darum, Fehlalarme und falsche Daten herauszufiltern, Trends und h\u00e4ufige Anomalien zu erkennen. Daf\u00fcr kommen Datenvisualisierungs- und andere Automatisierungstools zum Einsatz.<br><br><\/li>\n\n\n\n<li>Die <strong>Verbreitung<\/strong> ist die f\u00fcnfte und letzte Phase des OSINT-Zyklus. Nachdem die Datenaufbereitung abgeschlossen ist, wird der abschliessende Bericht den entsprechenden Personen und Organisationen weitergeleitet, die die Informationen nach Bedarf nutzen. Dabei ist sicherzustellen, dass der Zugang zu den Informationen lediglich dem vereinbarten Personenkreis gew\u00e4hrt wird und dies innert der vereinbarten Frist erfolgt.<br><br><\/li>\n<\/ol>\n\n\n\n<p><strong>Allgemeine OSINT-Techniken<\/strong><\/p>\n\n\n\n<p>F\u00fcr die effiziente Suche nach relevanten Daten ist ein <a href=\"https:\/\/moz.com\/beginners-guide-to-seo\/how-search-engines-operate\" target=\"_blank\" rel=\"noreferrer noopener\">grundlegendes Verst\u00e4ndnis der Funktionsweisen von Suchmaschinen<\/a>, wie <a href=\"https:\/\/www.google.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google<\/a>, <a href=\"https:\/\/www.bing.com\/?cc=ch\" target=\"_blank\" rel=\"noreferrer noopener\">Bing<\/a> oder <a href=\"https:\/\/duckduckgo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">DuckDuckGo<\/a>, erforderlich. Insbesondere kommen die folgenden drei Funktionen zum Einsatz:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Beim <strong>Crawling<\/strong> wird das Internet nach Inhalten durchsucht, indem der Code oder Inhalt jeder gefundenen URL \u00fcberpr\u00fcft wird. Suchmaschinen senden daf\u00fcr ein Team von Robotern, bekannt als \u00abCrawler\u00bb oder \u00abSpiders\u00bb, aus, um neue und aktualisierte Inhalte zu finden. Wird beispielsweise nach einer Nachrichtenseite gesucht, beginnen die Crawler mit der Startseite und folgen anschliessend den dort aufgef\u00fchrten Links zu den weiteren Artikeln, Kategorien und Seiten. Um die Inhalte zu verstehen und zu speichern, analysieren die Crawler den HTML-Code der gefundenen Seiten. Die gesammelten Informationen werden in den Index der Suchmaschine aufgenommen, sodass Benutzer bei einer Suchanfrage stets die relevanten Ergebnisse dieser Nachrichtenseite finden k\u00f6nnen. Regelm\u00e4ssiges Crawling stellt mit anderen Worten sicher, dass die Informationen der Datenbank der Suchmaschine immer aktuell sind.<br><br><\/li>\n\n\n\n<li>Im Rahmen der<strong> Indexierung<\/strong> werden die w\u00e4hrend des Crawling-Prozesses gefundenen Inhalte organisiert und gespeichert. Sobald eine Seite im Index ist, wird sie als potenzielles Ergebnis f\u00fcr allf\u00e4llige Suchanfragen ber\u00fccksichtigt.<br><br><\/li>\n\n\n\n<li>Im sogenannten<strong> Ranking <\/strong>werden die Inhalte, die die Suchanfrage des Nutzers am besten beantworten, bereitgestellt, wobei die Ergebnisse nach Relevanz geordnet werden.<\/li>\n<\/ul>\n\n\n\n<p><strong>Grundlagen zu den Suchoperatoren<\/strong><\/p>\n\n\n\n<p>Suchoperatoren, auch <a href=\"https:\/\/dlf.uzh.ch\/openbooks\/studifitkurs\/chapter\/suchbegriffe-kombinieren-boolsche-operatoren\/\" target=\"_blank\" rel=\"noreferrer noopener\">Boolesche Operatoren<\/a> genannt, sind W\u00f6rter oder Symbole, die dazu verwendet werden, Schl\u00fcsselw\u00f6rter in einer Suche zu kombinieren oder auszuschliessen. Diese Operatoren helfen, die Suche auf die relevantesten Ergebnisse zu fokussieren. Da jede Suchmaschine ihren eigenen spezifischen Syntax f\u00fcr die Boolesche Operatoren hat, werden im Folgenden beispielhaft diejenigen vorgestellt, die bei der am h\u00e4ufigsten verwendeten <a href=\"https:\/\/southern.libguides.com\/google\/boolean\" target=\"_blank\" rel=\"noreferrer noopener\">Suchmaschine von Google funktionieren<\/a>:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Boolescher Operator<\/strong><\/td><td><strong>Beispiel<\/strong><\/td><\/tr><tr><td><strong>AND<\/strong>  <br>Limitiert Ergebnisse<\/td><td>Crime AND Investigation<br>Suche nach Inhalten, die sowohl die Begriffe \u00abCrime\u00bb als auch \u00abInvestigation\u00bb enthalten.<\/td><\/tr><tr><td><strong>OR<\/strong>  <br>Ein Begriff ODER ein anderer<\/td><td>Crime OR Investigation<br>Suche nach Inhalten, die entweder den Begriff \u00abCrime\u00bb ODER \u00abInvestigation\u00bb enthalten.<\/td><\/tr><tr><td><strong>&#8211;<\/strong> <br>Einen Begriff von der Suche ausschliessen<\/td><td>Bundeshaus -Bern<br>Begrenzt die Ergebnisse auf solche, die den Begriff \u00abBundeshaus\u00bb enthalten, aber nicht den Begriff \u00abBern\u00bb. &nbsp;<\/td><\/tr><tr><td><strong>-site:<\/strong>  <br>Schliesst eine Website von der Suche aus.<\/td><td>Bundeshaus -site:admin.ch<br>Begrenzt die Ergebnisse auf solche, die nicht von \u00abadmin.ch\u00bb stammen.<\/td><\/tr><tr><td><strong>~<\/strong>  <br>Synonyme eines Begriffs<\/td><td>~bribe<br>Suche nach dem Begriff \u00abbribe\u00bb und dessen Synonymen.<\/td><\/tr><tr><td><strong>\u00ab \u00bb<\/strong>  <br>Genaue Suche<\/td><td>\u00abInternal Misconduct\u00bb<br>Suche nach der genauen Phrase \u00abInternal Misconduct\u00bb.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Vorbereitungshandlungen f\u00fcr OSINT-Ermittlungen<\/strong><\/p>\n\n\n\n<p>Um eine OSINT-Ermittlung erfolgreich und effizient durchf\u00fchren zu k\u00f6nnen, ist diese sorgf\u00e4ltig vorzubereiten und zu planen. Dabei sind insbesondere die nachfolgenden Vorbereitungshandlungen zu beachten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Vor dem Beginn der Ermittlung<\/strong> ist ein geeignetes Antivirensoftwareprogramm zu installieren und ein Skript-Blocker sowie ein virtuelles privates Netzwerk (VPN) einzurichten.<br><br><\/li>\n\n\n\n<li>Um die <strong>Privatsph\u00e4re<\/strong> zu <strong>sch\u00fctzen<\/strong>, sollten die Verwendung einer virtuellen Maschine in Betracht gezogen werden. Eine virtuelle Maschine ist ein Computersystem, das mit Software auf einem physischen Computer erstellt wird und die Funktionen eines anderen separaten Computers nachahmt.<br><br><\/li>\n\n\n\n<li>Der verwendete <strong>Browser<\/strong> beeinflusst direkt die Ergebnisse. <a href=\"https:\/\/www.mozilla.org\/de\/firefox\/new\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mozilla Firefox<\/a> und <a href=\"https:\/\/www.google.com\/intl\/de_ch\/chrome\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Chrome<\/a> bieten zahlreiche &#171;Add-Ons&#187; und Erweiterungen, die f\u00fcr die Ermittlungen relevant sind. Diese sind vorg\u00e4ngig zu recherchieren.<br><br><\/li>\n\n\n\n<li>Vor der Nutzung der Daten ist abzukl\u00e4ren, aus welchen Quelle diese stammen. Die <strong>rechtlichen Rahmenbedingungen<\/strong> f\u00fcr die Durchf\u00fchrung von Open-Source-Forschung in dem jeweiligen Land oder der Region sind einzuhalten.<br><\/li>\n<\/ul>\n\n\n\n<p><strong>Hinweise zur operativen Sicherheit<\/strong><\/p>\n\n\n\n<p>Die Operational Security, kurz OPSEC, ist bei der Durchf\u00fchrung von OSINT-Ermittlungen stets zu beachten. Es ist von grosser Wichtigkeit, dass die Sicherheit und Vertraulichkeit der eigenen Operationen jederzeit gew\u00e4hrleistet sind. OPSEC stellt demnach sicher, dass zu keinem Zeitpunkt unbeabsichtigte Informationen preisgeben werden, die von gegnerischen Parteien genutzt werden k\u00f6nnten. Insbesondere sind die folgenden Punkte beachtet werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Es sind sichere Online-Passw\u00f6rter zu verwenden und diese sind regelm\u00e4ssig zu \u00e4ndern.<br><br><\/li>\n\n\n\n<li>Das Versenden von pers\u00f6nlichen Informationen per E-Mail oder Textnachrichten ist zu vermeiden.<br><br><\/li>\n\n\n\n<li>Auf die Ver\u00f6ffentlichung von pers\u00f6nlichen Informationen in sozialen Netzwerken ist zu verzichten.<br><br><\/li>\n\n\n\n<li>Es sind stets die aktuellen Firewall- und Antivirensoftwareprogramme zu verwenden.<br><br><\/li>\n\n\n\n<li>Es ist sicherzustellen, dass die Webseiten, auf denen die ermittelten Informationen geteilt werden, sicher sind, also mit \u00abhttps\u00bb beginnen.<br><br><\/li>\n\n\n\n<li>Bei per E-Mail zugestellten Aufforderungen zur Vornahme von finanziellen Transaktionen ist stets direkt die Webseite der entsprechenden Organisation aufzurufen.<br><br><\/li>\n\n\n\n<li>Aus unsicheren Quellen sollten keine Softwareprogramme oder Apps heruntergeladen werden.<br><br><\/li>\n\n\n\n<li>Es ist niemals ein ungesichertes WLAN f\u00fcr die Ermittlungen zu verwenden.<br><\/li>\n<\/ul>\n\n\n\n<p><strong>Strukturierung der Ermittlungen<\/strong><\/p>\n\n\n\n<p>Je nach Umfang der Ermittlung eignet sich einer der nachfolgenden Forschungsans\u00e4tze, um diese zu beginnen:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Ermittlungsbereich<\/strong><\/td><td><strong>Startpunkt<\/strong><\/td><\/tr><tr><td>Suchmaschinen<\/td><td>Die meisten Ermittler beginnen die Untersuchungen mit einer der grossen Suchmaschinen, wie Google oder Bing. W\u00e4hrend dies in vielen L\u00e4ndern der richtige Ansatz ist, sind in einigen Regionen der Welt andere Suchmaschinen leistungsf\u00e4higer, um die Recherche zu beginnen. Jede Suchmaschine hat ihre eigenen Besonderheiten und eine spezielle Syntax f\u00fcr die Verwendung der Booleschen Operatoren. Es ist zu empfehlen, sich vor der Aufnahme der Ermittlungen mit den suchmaschinenspezifischen Suchoperatoren vertraut zu machen. Um die Forschungsergebnisse vergleichen zu k\u00f6nnen, bietet es sich an, mindestens zwei Suchmaschinen zu verwenden.<\/td><\/tr><tr><td>Personensuchmaschinen<\/td><td>Die Personensuchmaschinen, wie zum Beispiel <a href=\"https:\/\/pipl.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pipl<\/a>, <a href=\"https:\/\/www.spokeo.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Spokeo<\/a> oder <a href=\"https:\/\/thatsthem.com\/challenge?r=%2F\" target=\"_blank\" rel=\"noreferrer noopener\">ThatsThem<\/a>, sind darauf spezialisiert, Inhalte \u00fcber eine bestimmte Person zu finden. Sie sind haupts\u00e4chlich auf die Bereitstellung von Informationen \u00fcber Einzelpersonen in den Vereinigten Staaten ausgerichtet. Dennoch lohnt es sich, sie auch f\u00fcr Recherchen ausserhalb Amerikas auszuprobieren.<\/td><\/tr><tr><td>Regierungs- und Gesch\u00e4ftsdatenbanken<\/td><td>Das Auffinden von Unternehmens- und Gesch\u00e4ftsinformationen ist f\u00fcr die meisten internen Untersuchungen zentral. Diese k\u00f6nnen unter anderem aus Unternehmensregister, Land- oder Gerichtsarchiven, Amtsbl\u00e4ttern, beh\u00f6rdliche Einreichungen sowie Luft- und Schiffsregistern zusammengetragen werden. W\u00e4hrend bestimmte offizielle Register in einigen L\u00e4ndern frei zug\u00e4nglich sind, muss in anderen L\u00e4ndern zun\u00e4chst ein Antrag gestellt und ein berechtigtes Interesse nachgewiesen werden. Die Recherche werden am besten mit grundlegenden Nachforschungen dar\u00fcber begonnen, wie auf die relevanten \u00f6ffentlichen Aufzeichnungen im Zielgebiet zugegriffen werden kann.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>F\u00fcr die Vornahme von spezifischeren Ermittlungshandlungen, die im Nachgang zu den soeben dargelegten Grundlagenrecherchen durchzuf\u00fchren sind, hilft die nachfolgende Struktur, den vertieften Forschungsansatz zu optimieren:<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Ermittlungsbereich<\/strong><\/td><td><strong>Art der Information<\/strong><\/td><\/tr><tr><td>Digitale W\u00e4hrungen<\/td><td>Da digitale W\u00e4hrungen, wie Bitcoin, Ethereum oder Monero, zunehmend im Gebrauch sind, kann deren digitale Verfolgung neue Spuren aufdecken, die anschliessend weiterverfolgt werden k\u00f6nnen.<\/td><\/tr><tr><td>Dokumenten<\/td><td>Interessante Quellen sind beispielsweise <a href=\"https:\/\/www.google.com\/intl\/de_ch\/docs\/about\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Docs<\/a>, <a href=\"https:\/\/www.office.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Microsoft Docs<\/a>, <a href=\"https:\/\/aws.amazon.com\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amazon Web Services<\/a> und <a href=\"https:\/\/www.scribd.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Scribd<\/a>.<\/td><\/tr><tr><td>Domain Namen<\/td><td>Nach der Identifizierung einer bestimmten Webseite, kann diese ebenfalls zum Bestandteil von weiteren Ermittlungen werden. So k\u00f6nnen diese Details zu aktuellen und historischen Domain-Registrierungen enthalten und neue Anhaltspunkte f\u00fcr die weitere Untersuchungen liefern.<\/td><\/tr><tr><td>E-Mail-Adressen<\/td><td>Um die im Verlauf der Ermittlungen gefundenen Details zu einem realen Namen zu best\u00e4tigen, ist es immer eine gute Option, mittels Unterst\u00fctzung durch eine Suchmaschine nach allen E-Mail-Adressen zu suchen, die der Zielperson zugeordnet werden k\u00f6nnen. Dar\u00fcber hinaus gibt es zahlreiche Dienste, die Informationen zu E-Mail-Vermutungen, kompromittierten oder geleakten Konten bieten, die die Recherche optimieren k\u00f6nnen.<\/td><\/tr><tr><td>Bilder<\/td><td>S\u00e4mtliche Suchmaschinen verf\u00fcgen \u00fcber eine Bildersuche. Um vergleichbare Bilder zu finden oder das Originalbild r\u00fcckw\u00e4rts zu suchen, k\u00f6nnen umgekehrte Bildsuchen verwendet werden. Diese k\u00f6nnen helfen, die urspr\u00fcnglichen Metadaten, wie die EXIF-Daten zur Seriennummer der Kamera, geografische Koordinaten wie L\u00e4nge- und Breitengrade, unbeschnittene Ansichten des Bildes oder sogar andere mit derselben Kamera aufgenommene Bilder, zu finden. Einige Dienstanbieter bieten KI-gesteuerte Gesichtserkennungsdienste als Open-Source-Tool an, um die Wahrscheinlichkeit zu \u00fcberpr\u00fcfen, dass zwei Gesichter derselben Person geh\u00f6ren.<\/td><\/tr><tr><td>IP-Adressen<\/td><td>Die Recherche nach IP-Adressen f\u00e4llt normalerweise nicht in den unmittelbaren Umfang einer internen Untersuchung, ist aber ein grundlegender Ansatz f\u00fcr Cyberermittlungen. Da diese zu wertvollen Ergebnissen f\u00fchren kann, ist diese dennoch stets im Hinterkopf zu behalten.<\/td><\/tr><tr><td>Online-Karten<\/td><td>Online-Satellitenbilder von Online-Dienstanbietern, wie <a href=\"https:\/\/www.google.com\/intl\/de_ch\/streetview\/\" target=\"_blank\" rel=\"noreferrer noopener\">Google Street View<\/a>, <a href=\"https:\/\/zoom.earth\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zoom Earth<\/a>, <a href=\"https:\/\/maps.bing.com\" target=\"_blank\" rel=\"noreferrer noopener\">Bing Maps<\/a>, sind n\u00fctzlich, um im Rahmen der Ermittlung zus\u00e4tzliche Informationen zu Adressen zu finden.<\/td><\/tr><tr><td>Soziale Netzwerke<\/td><td>Im Laufe der Jahre wurde die Recherchen in den sozialen Netzwerken immer wichtiger. Anfangs konzentrierten sich alle auf die Abkl\u00e4rungen \u00fcber Personen auf Facebook. In der Zwischenzeit haben sich zahlreiche weitere soziale Netzwerke entwickelt, die f\u00fcr die Recherchen hinzugezogen werden k\u00f6nnen. Allerdings empfiehlt es sich, stets mit einer grundlegenden Recherche in den grossen sozialen Netzwerken, wie <a href=\"https:\/\/www.facebook.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Facebook<\/a>, <a href=\"https:\/\/www.instagram.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instagram<\/a>, <a href=\"https:\/\/twitter.com\" target=\"_blank\" rel=\"noreferrer noopener\">Twitter<\/a> oder <a href=\"https:\/\/www.linkedin.com\" target=\"_blank\" rel=\"noreferrer noopener\">LinkedIn<\/a>, zu beginnen. In einem zweiten Schritt sollten die landes- und gemeinschaftsspezifischen Netzwerke betrachtet werden. Dabei ist zu beachten, dass jedes Netzwerk seine eigenen Suchoperatoren hat. Die daraus resultierenden Strategien sind vor der Durchf\u00fchrung der Recherche im Netzwerk in Erfahrung zu bringen.<\/td><\/tr><tr><td>Online-Communities<\/td><td>Inhalte aus Online-Communities, wie <a href=\"https:\/\/www.reddit.com\/?rdt=53442\" target=\"_blank\" rel=\"noreferrer noopener\">Reddit<\/a>, <a href=\"https:\/\/www.pinterest.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Pinterest<\/a>, <a href=\"https:\/\/www.amazon.de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Amazon<\/a>, <a href=\"https:\/\/www.ebay.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">eBay<\/a>, <a href=\"https:\/\/www.ricardo.ch\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ricardo<\/a>, <a href=\"https:\/\/www.tutti.ch\/de\" target=\"_blank\" rel=\"noreferrer noopener\">Tutti<\/a> oder Online-Dating-Webseiten sind vergleichbar mit der Durchf\u00fchrung von Recherchen in sozialen Netzwerken. Wenn die Interessen oder Freizeitbesch\u00e4ftigungen der Zielperson identifiziert werden konnten, ist nach Online-Communities zu suchen, die diese Gewohnheiten ansprechen.<\/td><\/tr><tr><td>Telefonnummern<\/td><td>W\u00e4hrend die Telefonnummer vor zehn Jahren noch ein eindeutiger Identifikator und damit ein klares Ermittlungsziel darstellte, ist es mit der heutigen Technologie, wie Voice-over-IP oder SMS-Online-Diensten, ein Einfaches, tempor\u00e4re Nummern zu generieren. Dennoch kann die gezielte Recherche von&nbsp; Telefonnummern zu neuen Anhaltspunkten und Erkenntnissen f\u00fchren.<\/td><\/tr><tr><td>Benutzernamen<\/td><td>Echte Namen k\u00f6nnen zu einem Benutzernamen f\u00fchren, der wiederum ein Ausgangspunkt f\u00fcr eine weitere Recherche sein kann. Neben Such- und Personensuchmaschinen gibt es Dienste, wie zum Beispiel <a href=\"https:\/\/x-ray.contact\/reverse-name-lookup\/\" target=\"_blank\" rel=\"noreferrer noopener\">X-Ray<\/a>, die auf die Recherche von Benutzernamen spezialisiert sind.<\/td><\/tr><tr><td>Videos<\/td><td>Das Durchsuchen von Videos ist zeitaufw\u00e4ndig, kann aber viele n\u00fctzliche Informationen liefern. Am meisten Videos finden sich auf <a href=\"https:\/\/www.youtube.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">YouTube<\/a>. Das Durchf\u00fchren von Recherchen auf dieser Plattform ist allerdings eine Kunst f\u00fcr sich, weshalb es sich lohnt, sich vorg\u00e4ngig im Detail zu informieren. In den Suchmaschinen k\u00f6nnen ebenfalls Anfragen nach Videos auf YouTube und in den sozialen Medien gestartet werden.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Propriet\u00e4re Quellen<\/strong><\/p>\n\n\n\n<p>Neben offenen Quellen gibt es auch propriet\u00e4re Datenquellen, die in vier Kategorien unterteilt werden k\u00f6nnen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die <strong>Unternehmensdatenbanken<\/strong> enthalten Unternehmensprofile, Registereintr\u00e4ge und weitere potenziell relevante Daten.<br><br><\/li>\n\n\n\n<li><strong>Compliance-Datenbanken<\/strong> identifizieren negative Medienberichte, Sanktionen und Schwarze Listen.<br><br><\/li>\n\n\n\n<li><strong>Pressearchive<\/strong> umfassen digitale Archive globaler Nachrichteninhalte.<br><br><\/li>\n\n\n\n<li>\u00dcber <strong>Drittanbieter-Informationsdienste<\/strong> k\u00f6nnen Kreditausk\u00fcnfte, Solvenz- und Liquidit\u00e4tsinformationen erlangt werden.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>OSINT-Techniken in der internen Untersuchung<\/strong><\/p>\n\n\n\n<p>Die Struktur des Einsatzes von OSINT-Techniken im Rahmen einer internen Untersuchung k\u00f6nnte beispielhaft wie folgt aussehen:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Phase:<\/strong> Zun\u00e4chst sollten grundlegende Recherchen zu den Zielobjekten durchgef\u00fchrt werden, bevor der Fokus auf die pers\u00f6nlichen Identifikatoren und Verm\u00f6genswerte, wie beispielsweise Aliase, Familienmitglieder, Wohnadressen, berufliche Mitgliedschaften oder Eigentumsverh\u00e4ltnisse, allf\u00e4llige negative Medienberichterstattungen, (Unternehmens-)Beteiligungen sowie Managementpositionen, zu legen sind.<br><br><\/li>\n\n\n\n<li><strong>Phase:<\/strong> Umfassendere und internationale Recherchen zum Zielobjekt mit Fokus auf spezifische Forschungsfragen, wie Untersuchungen der (straf-)rechtlichen und finanziellen Situation, bestehende Verbindungen zu politisch exponierten Personen oder kriminellen Organisationen, gesch\u00e4ftliche Interessen, fr\u00fchere Verurteilungen, Pfandrechte sowie (In-)Solvenzen. Aber auch die Netzwerkanalysen sind in dieser Phase vorzunehmen.<br><br><\/li>\n\n\n\n<li><strong>Phase:<\/strong> Tiefergehende Untersuchungen, wie beispielsweise Vor-Ort-Besuche, die Durchsuchung von physischen Dokumenten oder \u00f6ffentlichen Aufzeichnungen, die Analyse von Lieferketten sowie die Recherche nach versteckten Verm\u00f6genswerten, sind dabei erst in einer optionalen dritten Phase vorzunehmen.<\/li>\n<\/ol>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Dokumentation und Berichterstattung<\/strong><\/p>\n\n\n\n<p>Die Dokumentation ist f\u00fcr jede interne Untersuchung von entscheidender Bedeutung. Die Art und Weise der Dokumentation h\u00e4ngt davon ab, welche Methodik f\u00fcr den Nachweis des gew\u00e4hlten Forschungsansatzes verwendet wird und welche Suchstrategie festgelegt wurde. Ebenso ist wichtig zu entscheiden, wie die Ergebnisse pr\u00e4sentiert werden sollen. Die Tiefe des Berichts hat sich danach zu richten, ob die Ergebnisse vor Gericht als Beweismittel dienen sollen oder nicht.<\/p>\n\n\n\n<p>Der abschliessende Bericht sollte insbesondere die wichtigsten Erkenntnisse, die Details zur Analyse und gegebenenfalls einen Anhang zu enthalten. Dabei ist auch hier zu beachten, dass die Erkenntnisse m\u00f6glicherweise als Beweismitteln werden k\u00f6nnen. Die Sammlung der Informationen muss demnach verteidigungsf\u00e4hig sein muss, um einer formellen Pr\u00fcfung standzuhalten.<\/p>\n\n\n\n<p><strong>Optimierung von internen Untersuchungen durch OSINT<\/strong><\/p>\n\n\n\n<p>Durch den Zugang zu \u00f6ffentlich zug\u00e4nglichen Informationen erm\u00f6glicht OSINT eine deutliche Erweiterung der traditionellen Ermittlungsmethoden. Dabei k\u00f6nnen wesentliche Informationen unabh\u00e4ngig von gesch\u00fctzten Quellen gesammelt und wertvolle Einblicke gewonnen werden. Die systematische Sammlung und Analyse verk\u00fcrzt zudem den Untersuchungszeitraum deutlich, was zu einer schnellen Aufkl\u00e4rung der Angelegenheit beitr\u00e4gt. Die anonyme Durchf\u00fchrung sch\u00fctzt die Identit\u00e4t der Ermittler, w\u00e4hrend gleichzeitig Transparenz und Nachvollziehbarkeit gewahrt bleiben und fundierte Entscheidungsprozesse unterst\u00fctzt werden. Insgesamt kann die Integration von OSINT die Durchf\u00fchrung von internen Untersuchungen somit erheblich optimieren.<\/p>\n\n\n\n<p><em>Der n\u00e4chste Beitrag auf dem Blog Economic Crime erscheint&nbsp; am 19. August 2024.<\/em><\/p>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autor: Lionel Bloch<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2.jpg 2048w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-300x200.jpg 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-1024x683.jpg 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-768x512.jpg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-1536x1024.jpg 1536w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-600x400.jpg 600w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2-928x619.jpg 928w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Lionel-Bloch_2.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tAls Gr\u00fcnder und Gesch\u00e4ftsf\u00fchrer der <a href=\"https:\/\/www.forentec.ch\/\" target=\"_blank\">Forentec AG<\/a> ist <a href=\"https:\/\/www.linkedin.com\/in\/lionel-bloch-79896872\" target=\"_blank\">Lionel Bloch<\/a> spezialisiert im Bereich der IT-Forensik, eDiscovery und OSINT. Zuvor sammelte er als eidg. dipl. Informatiker mit Schwerpunkt Applikationsentwicklung Erfahrung bei zwei \u201eBig4\u201c-Unternehmen in der Schweiz. Zudem erweiterte er seine Expertise in Artificial Intelligence (AI) und Quantentechnologien.\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autor: Andy Bichsel<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT.jpg\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT.jpg 2048w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-300x200.jpg 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-1024x683.jpg 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-768x512.jpg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-1536x1024.jpg 1536w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-600x400.jpg 600w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT-928x619.jpg 928w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Andy-Bichsel-Head-OSINT.jpg\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\tAls Head of OSINT bei der <a href=\"https:\/\/www.forentec.ch\/\" target=\"_blank\">Forentec AG<\/a> ist <a href=\"https:\/\/www.linkedin.com\/in\/andy-b-4319927\/\" target=\"_blank\">Andy Bichsel<\/a> f\u00fcr das F\u00fchren von OSINT-Untersuchungen zust\u00e4ndig. Schon als das Thema noch in den Anf\u00e4ngen war, vertiefte er seine Expertise in diesem Bereich. Zus\u00e4tzlich verf\u00fcgt er \u00fcber ausgewiesene Kenntnisse in der IT-Forensik. Sein enormes Fachwissen und seine Erfahrung gibt er in der t\u00e4glichen Arbeit den OSINT-Analysten weiter und tr\u00e4gt damit massgeblich zur Informationsgewinnung bei komplexen OSINT-Ermittlungen bei.\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die Effizienz umfassender Recherchen, wie sie beispielsweise bei internen Untersuchungen durchgef\u00fchrt werden, l\u00e4sst sich durch die gezielte Nutzung von Open Source Intelligence (OSINT) deutlich steigern. Erfolgt der Zugriff auf die \u00f6ffentlich zug\u00e4nglichen Informationen mit den entsprechenden Techniken, stellt das Vorgehen ein leistungsstarkes Werkzeug zur Optimierung von internen Untersuchungsprozessen dar.<\/p>\n","protected":false},"author":163,"featured_media":4813,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"2906,312,630,134,4510,573","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[42,41,13,237,87,12],"tags":[1019,767,157,322,1023,1025,172,1021,606,1022,429,1020,431,1024],"class_list":["post-4807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate-crime","category-cybercrime","category-financial-crime","category-forensics-investigation","category-geldwaescherei","category-wirtschaftskriminalistik","tag-background-checks","tag-due-dilligence","tag-fraud","tag-information","tag-infosec","tag-intelligence","tag-investigation","tag-ma","tag-monitoring","tag-online-evidences","tag-osint","tag-risk-analysis","tag-socmint","tag-webint"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"Die Effizienz umfassender Recherchen, wie sie beispielsweise bei internen Untersuchungen durchgef\u00fchrt werden, l\u00e4sst sich durch die gezielte Nutzung von Open Source Intelligence (OSINT) deutlich steigern. Erfolgt der Zugriff auf die \u00f6ffentlich zug\u00e4nglichen Informationen mit den entsprechenden Techniken, stellt das Vorgehen ein leistungsstarkes Werkzeug zur Optimierung von internen Untersuchungsprozessen dar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-01T04:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1151\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudiabrunner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudiabrunner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"16\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/\"},\"author\":{\"name\":\"claudiabrunner\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"headline\":\"Nutzung von Open Source Intelligence bei internen Untersuchungen\",\"datePublished\":\"2024-07-01T04:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/\"},\"wordCount\":2857,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2024\\\/07\\\/Titelbild.jpeg\",\"keywords\":[\"Background Checks\",\"due dilligence\",\"Fraud\",\"Information\",\"Infosec\",\"Intelligence\",\"Investigation\",\"M&amp;A\",\"monitoring\",\"Online Evidences\",\"OSINT\",\"Risk Analysis\",\"SOCMINT\",\"Webint\"],\"articleSection\":[\"Corporate Crime\",\"Cybercrime\",\"Financial Crime\",\"Forensics &amp; Investigation\",\"Geldw\u00e4scherei\",\"Wirtschaftskriminalistik\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/\",\"name\":\"Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2024\\\/07\\\/Titelbild.jpeg\",\"datePublished\":\"2024-07-01T04:30:00+00:00\",\"dateModified\":\"2026-02-11T13:53:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2024\\\/07\\\/Titelbild.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2024\\\/07\\\/Titelbild.jpeg\",\"width\":2048,\"height\":1151},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nutzung von Open Source Intelligence bei internen Untersuchungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/5103b66874d111e07f466794810051e9\",\"name\":\"claudiabrunner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g\",\"caption\":\"claudiabrunner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/","og_locale":"de_DE","og_type":"article","og_title":"Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog","og_description":"Die Effizienz umfassender Recherchen, wie sie beispielsweise bei internen Untersuchungen durchgef\u00fchrt werden, l\u00e4sst sich durch die gezielte Nutzung von Open Source Intelligence (OSINT) deutlich steigern. Erfolgt der Zugriff auf die \u00f6ffentlich zug\u00e4nglichen Informationen mit den entsprechenden Techniken, stellt das Vorgehen ein leistungsstarkes Werkzeug zur Optimierung von internen Untersuchungsprozessen dar.","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/","og_site_name":"Economic Crime Blog","article_published_time":"2024-07-01T04:30:00+00:00","article_modified_time":"2026-02-11T13:53:33+00:00","og_image":[{"width":2048,"height":1151,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","type":"image\/jpeg"}],"author":"claudiabrunner","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"claudiabrunner","Gesch\u00e4tzte Lesezeit":"16\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/"},"author":{"name":"claudiabrunner","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"headline":"Nutzung von Open Source Intelligence bei internen Untersuchungen","datePublished":"2024-07-01T04:30:00+00:00","dateModified":"2026-02-11T13:53:33+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/"},"wordCount":2857,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","keywords":["Background Checks","due dilligence","Fraud","Information","Infosec","Intelligence","Investigation","M&amp;A","monitoring","Online Evidences","OSINT","Risk Analysis","SOCMINT","Webint"],"articleSection":["Corporate Crime","Cybercrime","Financial Crime","Forensics &amp; Investigation","Geldw\u00e4scherei","Wirtschaftskriminalistik"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/","name":"Nutzung von Open Source Intelligence bei internen Untersuchungen - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","datePublished":"2024-07-01T04:30:00+00:00","dateModified":"2026-02-11T13:53:33+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","width":2048,"height":1151},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/nutzung-von-open-source-intelligence-bei-internen-untersuchungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Nutzung von Open Source Intelligence bei internen Untersuchungen"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/5103b66874d111e07f466794810051e9","name":"claudiabrunner","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/594109a0f5d7cdc62010529bc8b8e55ea9f6615ae98a2d87734d26d4aaeeebcd?s=96&d=mm&r=g","caption":"claudiabrunner"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/07\/Titelbild.jpeg","author_info":{"display_name":"claudiabrunner","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/claudiabrunner\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/163"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=4807"}],"version-history":[{"count":44,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4807\/revisions"}],"predecessor-version":[{"id":6419,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/4807\/revisions\/6419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/4813"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=4807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=4807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=4807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}