{"id":5166,"date":"2024-12-02T06:30:00","date_gmt":"2024-12-02T05:30:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/economiccrime\/?p=5166"},"modified":"2026-03-24T12:36:47","modified_gmt":"2026-03-24T11:36:47","slug":"phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/","title":{"rendered":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme"},"content":{"rendered":"\n<p>Von <a href=\"https:\/\/jillwick.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Jill Wick<\/a><\/p>\n\n\n\n<p><strong><strong><strong><\/strong><\/strong><\/strong><\/p>\n\n\n\n<p>Phishing-Angriffe sind oft deshalb erfolgreich, weil sie das sogenannte \u00abSystem 1\u00bb aktivieren. Demnach f\u00fchrt das schnelle, intuitive Denken zu automatischen und un\u00fcberlegten Reaktionen. Dadurch werden Opfer dazu verleitet, auf Links zu klicken, oder sensible Informationen preiszugeben, ohne Gelegenheit die Nachricht kritisch zu pr\u00fcfen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"575\" height=\"323\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Bild1.png\" alt=\"\" class=\"wp-image-5175\" style=\"width:840px;height:auto\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Bild1.png 575w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Bild1-300x169.png 300w\" sizes=\"auto, (max-width: 575px) 100vw, 575px\" \/><figcaption class=\"wp-element-caption\">Bild: System 1 und 2 nach D. Kahneman. Quelle: Darstellung entnommen von <a href=\"https:\/\/hub.hslu.ch\/business-psychology\/kaufentscheidung-haben-wir-eine-kontrolle-darueber\/\" target=\"_blank\" rel=\"noreferrer noopener\">HSLU.ch<\/a>, 2024<\/figcaption><\/figure>\n\n\n\n<p>Aufbauend auf diesem Mechanismus nutzen Phishing-Angriffe bew\u00e4hrte Prinzipien der <a href=\"https:\/\/www.microsoft.com\/en-us\/security\/blog\/2020\/06\/30\/psychology-social-engineering-soft-side-cybercrime\/\" target=\"_blank\" rel=\"noreferrer noopener\">sozialen Beeinflussung<\/a>. Der Psychologe Robert Cialdini beschreibt dazu die folgenden sechs <a href=\"https:\/\/www.hogrefe.com\/de\/thema\/robert-cialdinis-waffen-der-einflussnahme\" target=\"_blank\" rel=\"noreferrer noopener\">Schl\u00fcsselprinzipien<\/a> der Persuasion resp. \u00dcberredungskunst:<\/p>\n\n\n\n<p><strong>(1) Reziprozit\u00e4t<\/strong><\/p>\n\n\n\n<p>Wir Menschen verhalten uns von Natur aus prosozial und f\u00fchlen uns verpflichtet, einen Gefallen zu erwidern. In einer <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S0747563216301935\" target=\"_blank\" rel=\"noreferrer noopener\">Studie zu Reziprozit\u00e4t<\/a> (2016) gab fast die H\u00e4lfte der Befragten ihr Passwort preis, nachdem sie Schokolade geschenkt bekommen hatten.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"548\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Phishing-mit-Gutschein.png\" alt=\"\" class=\"wp-image-5225\" style=\"width:485px;height:auto\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Phishing-mit-Gutschein.png 500w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Phishing-mit-Gutschein-274x300.png 274w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Bild: Phishing mit einem Gutschein angeblich von Twint, ktipp.ch, 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<p>In einer Phishing-E-Mail kann dieses Verhalten von Betr\u00fcgern ausgenutzt werden, indem ein Geschenk als Vorwand verwendet wird. Beispielsweise enth\u00e4lt eine E-Mail wie auf dem Bild oben einen Gutschein, um das Vertrauen des Empf\u00e4ngers zu gewinnen. Sobald das Angebot angenommen wird, f\u00fchlen sich die Empf\u00e4nger verpflichtet, der Aufforderung nachzukommen.<\/p>\n\n\n\n<p><strong>(2) Konsistenz<\/strong><\/p>\n\n\n\n<p>Wir wollen in unserem Handeln konsistent bleiben. Dieser Mechanismus macht uns anf\u00e4llig f\u00fcr die sogenannte \u00ab<a href=\"https:\/\/dorsch.hogrefe.com\/stichwort\/foot-in-the-door-technik\" target=\"_blank\" rel=\"noreferrer noopener\">Foot-in-the-door-Technik\u00bb.<\/a> Diese Beeinflussungsstrategie beginnt mit einer kleinen Bitte, die mit grosser Sicherheit erf\u00fcllt wird, und steigert sich dann zu immer gr\u00f6sseren Bitten. Wir als Gefragte wollen unserem Selbstbild als hilfsbereite Person treu bleiben und erf\u00fcllen weiterhin die an uns gestellten Forderungen.<\/p>\n\n\n\n<p>Bei Phishing-Angriffen l\u00e4sst sich das Prinzip der Konsistenz gut an sogenannten <a href=\"https:\/\/www.cybercrimepolice.ch\/de\/fall\/vorsicht-bei-telefonanrufen-mit-bandansagen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Robocalls &#8211; automatisierten Telefonansagen<\/a> &#8211; beobachten. Sobald dieser ersten Aufforderung nachgekommen wird, steigt die Wahrscheinlichkeit, dass auch die weiteren Anweisungen, wie das Anklicken eines Links oder die Eingabe von Login-Daten, befolgt werden, um konsistent zu bleiben.<\/p>\n\n\n\n<p><strong>(3) Soziale Bew\u00e4hrtheit<\/strong><\/p>\n\n\n\n<p>Menschen orientieren sich am Verhalten anderer, insbesondere in unsicheren Situationen. Eine solche Situation kann zum Beispiel der Kauf einer Waschmaschine sein. Es ist wahrscheinlicher, dass ein gleichwertiges Produkt online bestellt wird, das viele gute Rezensionen hat, als wenn diese fehlen.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"509\" height=\"655\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Federer-Werbung-1.png\" alt=\"\" class=\"wp-image-5227\" style=\"width:425px;height:auto\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Federer-Werbung-1.png 509w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/Federer-Werbung-1-233x300.png 233w\" sizes=\"auto, (max-width: 509px) 100vw, 509px\" \/><figcaption class=\"wp-element-caption\">Bild: Werbung angeblich mit Roger Federer, der Kryptoinvestments t\u00e4tigt, Quelle: <a href=\"https:\/\/www.cybercrimepolice.ch\/de\/fall\/online-anlagebetrueger-missbrauchen-prominente\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cybercrimepolice.ch<\/a>, 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Cyberkriminelle nutzen h\u00e4ufig Formulierungen in <a href=\"https:\/\/www.watson.ch\/schweiz\/digital\/795363901-deepfakes-mit-srf-moderatoren-betrugsmaschen-werden-perfider\" target=\"_blank\" rel=\"noreferrer noopener\">betr\u00fcgerischer Werbung<\/a>, die suggerieren, dass bereits viele Menschen, wie Roger Federer im Bild oben, von einem bestimmten Krypto-Angebot profitiert haben. Dies kann auch in Form von Phishing-E-Mails geschehen, in denen anhand gef\u00e4lschter Statistiken dargestellt wird, wie viele Personen bereits ein Passwort-Update durchgef\u00fchrt haben. Dadurch sollen die Empf\u00e4nger motiviert werden, dem vermeintlichen Vorbild zu folgen.<\/p>\n\n\n\n<p><strong>(4) Sympathie<\/strong><\/p>\n\n\n\n<p>Wir sind eher bereit einer Bitte nachzukommen, wenn sie von einer Person kommt, die wir sympathisch finden. Ein Beispiel hierf\u00fcr ist der sogenannte \u00abHalo-Effekt\u00bb, bei dem positive Eigenschaften wie Attraktivit\u00e4t oder Freundlichkeit dazu f\u00fchren, dass wir die gesamte Person als vertrauensw\u00fcrdiger und kompetenter einsch\u00e4tzen, was unsere Bereitschaft zur Zustimmung erh\u00f6ht.<br><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1312\" height=\"1312\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands.jpg\" alt=\"\" class=\"wp-image-5228\" style=\"width:557px;height:auto\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands.jpg 1312w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-300x300.jpg 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-1024x1024.jpg 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-150x150.jpg 150w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-768x768.jpg 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-600x600.jpg 600w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/meistgephishte-brands-698x698.jpg 698w\" sizes=\"auto, (max-width: 1312px) 100vw, 1312px\" \/><figcaption class=\"wp-element-caption\">Bild: Meistgephishte Brands 2024, Quelle: <a href=\"https:\/\/www.statista.com\/chart\/22528\/most-impersonated-brands-in-phishing-attacks\/\" target=\"_blank\" rel=\"noreferrer noopener\">statista.com<\/a>, 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Aus diesem Grund werden f\u00fcr Phishing-E-Mails oder Scams bevorzugt bekannte Personen und Marken imitiert. Diesen Effekt kann man in der Abbildung der meist gephishten Marken 2024 oben sehen, kennt jemand eine dieser Marken nicht? Bekannte Marken wie Microsoft, Google oder die Schweizerische Post und Swisscom wecken Vertrauen und ein Klick auf einen gef\u00e4lschten Link ist wahrscheinlicher.<\/p>\n\n\n\n<p><strong>(5) Autorit\u00e4t<\/strong><\/p>\n\n\n\n<p>Wir neigen dazu, Anweisungen von Quellen zu befolgen, die als autorit\u00e4r wahrgenommen werden. Ein bekanntes Beispiel f\u00fcr die Wirkung von Autorit\u00e4t ist das sogenannte \u00abMilgram-Experiment\u00bb, bei dem Versuchspersonen auf Anweisung eines vermeintlichen Experten anderen Personen Elektroschocks zuf\u00fcgten. Das Experiment zeigte, wie sehr Menschen bereit sind, Anweisungen von Autorit\u00e4tspersonen zu befolgen, selbst wenn diese Anweisungen ethisch fragw\u00fcrdig sind.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"531\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/image-3.png\" alt=\"\" class=\"wp-image-5180\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/image-3.png 372w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/image-3-210x300.png 210w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><figcaption class=\"wp-element-caption\">Bild: Angebliches Bussgeld als Nachricht von der Polizei, ktipp, 2024<\/figcaption><\/figure>\n<\/div>\n\n\n<p>In Phishing-E-Mails tritt dieser Effekt h\u00e4ufig in Form von <a href=\"https:\/\/www.skppsc.ch\/de\/der-ceo-fraud-in-vier-schritten-erklaert\/\" target=\"_blank\" rel=\"noreferrer noopener\">CEO-Fraud<\/a> auf. Kriminelle geben sich aber auch oft als offizielle Beh\u00f6rden oder die Polizei wie auf dem eingef\u00fcgten Screenshot einer betr\u00fcgerischen iMessage oben aus, um zu Zahlungen aufzufordern. Wird zus\u00e4tzlich Zeitdruck erzeugt, handeln die Empf\u00e4nger oft \u00fcberst\u00fcrzt und f\u00fchren ungewollte Aktionen wie das Anklicken von Links oder das Durchf\u00fchren von \u00dcberweisungen aus.<\/p>\n\n\n\n<p><strong>(6) Knappheit<\/strong><\/p>\n\n\n\n<p>Wir sch\u00e4tzen Dinge als wertvoller ein, wenn sie selten oder begrenzt verf\u00fcgbar sind. Dieser Effekt l\u00e4sst sich h\u00e4ufig bei Urlaubsbuchungsportalen beobachten. Dort wird zum Teil k\u00fcnstlich Knappheit erzeugt, um den Kunden zum schnelleren Handeln zu bewegen (z.B. <a href=\"https:\/\/jillwick.com\/2024\/10\/08\/deceptive-patterns-manipulation-by-design\/\" target=\"_blank\" rel=\"noreferrer noopener\">Booking.com, \u201enur noch 7 Zimmer<\/a>\u201c).<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1257\" height=\"307\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email.png\" alt=\"\" class=\"wp-image-5229\" style=\"width:839px;height:auto\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email.png 1257w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email-300x73.png 300w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email-1024x250.png 1024w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email-768x188.png 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email-928x227.png 928w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/11\/email-600x147.png 600w\" sizes=\"auto, (max-width: 1257px) 100vw, 1257px\" \/><figcaption class=\"wp-element-caption\">Bild: Phishing-E-Mail mit Zeitdruck, Zahlung sei schon 2 Tage \u00fcberf\u00e4llig, Quelle: ktipp, 2024<\/figcaption><\/figure>\n\n\n\n<p>In einer Phishing-E-Mail wird diese Taktik in Verbindung mit Zeitdruck eingesetzt. Der Druck wird dadurch erzeugt, dass nur noch ein Tag f\u00fcr die R\u00fcckerstattung eines hohen Betrages zur Verf\u00fcgung steht und ein Link schnell angeklickt werden muss. Die k\u00fcnstlich erzeugte Dringlichkeit verleitet das Opfer dazu, sofort zu handeln, ohne die Nachricht gr\u00fcndlich zu pr\u00fcfen.<\/p>\n\n\n\n<p><strong>Pr\u00e4ventionsstrategie f\u00fcr das Awarenessprogramm<\/strong> Phishing-Angriffe sind erfolgreich, weil sie auf bew\u00e4hrte psychologische Prinzipien setzen und die schnelle, intuitive Reaktion der Opfer ausnutzen. Die Sensibilisierung f\u00fcr solche Taktiken ist ebenso wichtig wie das Erkennen der beschriebenen Techniken. Zusammen mit anderen Sensibilisierungsmassnahmen kann dies kritisches Denken f\u00f6rdern und eine starke Sicherheitskultur im Unternehmen schaffen. Eine bewusst gef\u00f6rderte Sicherheitskultur sorgt daf\u00fcr, dass sich alle aktiv beteiligen und ein starkes gemeinsames Sicherheitsnetz entsteht.<\/p>\n\n\n\t\t<div class=\"detail__member\">\n\t\t<h1 class=\"detail__member--title\">Autorin: Jill Wick<\/h1>\n\t\t<figure class=\"detail__member--img\">\n\t\t\t\t\t\t<!-- <img loading=\"lazy\" decoding=\"async\" width=\"1180\" height=\"1578\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue.png\" class=\"attachment-normal size-normal\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue.png 1180w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-224x300.png 224w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-766x1024.png 766w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-768x1027.png 768w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-1149x1536.png 1149w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-522x698.png 522w, https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue-600x802.png 600w\" sizes=\"auto, (max-width: 1180px) 100vw, 1180px\" \/> -->\n\t\t\t<img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2024\/12\/JW-blue.png\" alt=\"\">\n\t\t<\/figure>\n\t\t<div class=\"detail__member--content\">\n\t\t\t<div class=\"detail__member--content--description\">\n\t\t\t\t<a href=\"https:\/\/jillwick.com\/\" target=\"_blank\">Jill Wick<\/a> ist Schweizer Wirtschaftspsychologin mit \u00fcber zehn Jahren Erfahrung in der Bek\u00e4mpfung von Finanzbetrug im Kreditkartenbereich. Sie hat einen Bachelor in Wirtschaftspsychologie und das <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/economic-crime-investigation\/\" target=\"_blank\">DAS Economic Crime Investigation<\/a> an der Hochschule Luzern absolviert. Derzeit studiert sie berufsbegleitend im Masterprogramm Wirtschaftspsychologie. Sie teilt ihr <a href=\"https:\/\/jillwick.com\/\" target=\"_blank\">Wissen<\/a> \u00fcber Cyberkriminalit\u00e4t, Technologie und deren Einfluss auf den Menschen.\r\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Phishing und Social Engineering geh\u00f6ren zu den gr\u00f6ssten Cyber-Bedrohungen und bilden das Einfallstor f\u00fcr jegliche Cyber-Attacken. Awareness-Schulungen und interaktive Lerninhalte spielen hier eine zentrale Rolle. Ein tiefes Verst\u00e4ndnis der Taktiken von Cyberkriminellen ist entscheidend, um effektive Programme zu entwickeln und Schutz zu bieten. Inwiefern liefern die psychologischen Tricks der Betr\u00fcger einen Ansatz f\u00fcr pr\u00e4ventive Sicherheitsmassnahmen?<\/p>\n","protected":false},"author":230,"featured_media":3609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"407,162,4997,527,141,211","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[58,41],"tags":[1065,43,1067,1066,1071,1063,410,1068,1062,1064,10,1069,1070],"class_list":["post-5166","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-cybercrime","tag-awareness-programme","tag-betrugspraevention","tag-cialdinis-prinzipien","tag-cyberkriminelle","tag-kritisches-denken","tag-persuasion","tag-phishing","tag-psychologische-manipulation","tag-security-awareness","tag-sicherheitskultur","tag-social-engineering","tag-system-1-und-system-2","tag-unternehmenssicherheit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog\" \/>\n<meta property=\"og:description\" content=\"Phishing und Social Engineering geh\u00f6ren zu den gr\u00f6ssten Cyber-Bedrohungen und bilden das Einfallstor f\u00fcr jegliche Cyber-Attacken. Awareness-Schulungen und interaktive Lerninhalte spielen hier eine zentrale Rolle. Ein tiefes Verst\u00e4ndnis der Taktiken von Cyberkriminellen ist entscheidend, um effektive Programme zu entwickeln und Schutz zu bieten. Inwiefern liefern die psychologischen Tricks der Betr\u00fcger einen Ansatz f\u00fcr pr\u00e4ventive Sicherheitsmassnahmen?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T05:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T11:36:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"noelleantoniasmilla\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"noelleantoniasmilla\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/\"},\"author\":{\"name\":\"noelleantoniasmilla\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/3633ec00025224cdc913c180f64915d2\"},\"headline\":\"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme\",\"datePublished\":\"2024-12-02T05:30:00+00:00\",\"dateModified\":\"2026-03-24T11:36:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/\"},\"wordCount\":892,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/03\\\/AdobeStock_576901499-1.jpeg\",\"keywords\":[\"Awareness-Programme\",\"Betrugspr\u00e4vention\",\"Cialdinis Prinzipien\",\"Cyberkriminelle\",\"Kritisches Denken\",\"Persuasion\",\"Phishing\",\"Psychologische Manipulation\",\"Security Awareness\",\"Sicherheitskultur\",\"Social Engineering\",\"System 1 und System 2\",\"Unternehmenssicherheit\"],\"articleSection\":{\"1\":\"Cybercrime\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/\",\"name\":\"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/03\\\/AdobeStock_576901499-1.jpeg\",\"datePublished\":\"2024-12-02T05:30:00+00:00\",\"dateModified\":\"2026-03-24T11:36:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/3633ec00025224cdc913c180f64915d2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/03\\\/AdobeStock_576901499-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/03\\\/AdobeStock_576901499-1.jpeg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#\\\/schema\\\/person\\\/3633ec00025224cdc913c180f64915d2\",\"name\":\"noelleantoniasmilla\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g\",\"caption\":\"noelleantoniasmilla\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/","og_locale":"de_DE","og_type":"article","og_title":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog","og_description":"Phishing und Social Engineering geh\u00f6ren zu den gr\u00f6ssten Cyber-Bedrohungen und bilden das Einfallstor f\u00fcr jegliche Cyber-Attacken. Awareness-Schulungen und interaktive Lerninhalte spielen hier eine zentrale Rolle. Ein tiefes Verst\u00e4ndnis der Taktiken von Cyberkriminellen ist entscheidend, um effektive Programme zu entwickeln und Schutz zu bieten. Inwiefern liefern die psychologischen Tricks der Betr\u00fcger einen Ansatz f\u00fcr pr\u00e4ventive Sicherheitsmassnahmen?","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/","og_site_name":"Economic Crime Blog","article_published_time":"2024-12-02T05:30:00+00:00","article_modified_time":"2026-03-24T11:36:47+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","type":"image\/jpeg"}],"author":"noelleantoniasmilla","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"noelleantoniasmilla","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/"},"author":{"name":"noelleantoniasmilla","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/3633ec00025224cdc913c180f64915d2"},"headline":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme","datePublished":"2024-12-02T05:30:00+00:00","dateModified":"2026-03-24T11:36:47+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/"},"wordCount":892,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","keywords":["Awareness-Programme","Betrugspr\u00e4vention","Cialdinis Prinzipien","Cyberkriminelle","Kritisches Denken","Persuasion","Phishing","Psychologische Manipulation","Security Awareness","Sicherheitskultur","Social Engineering","System 1 und System 2","Unternehmenssicherheit"],"articleSection":{"1":"Cybercrime"},"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/","name":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","datePublished":"2024-12-02T05:30:00+00:00","dateModified":"2026-03-24T11:36:47+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/3633ec00025224cdc913c180f64915d2"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#primaryimage","url":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/phishing-erkennen-und-abwehren-psychologische-einblicke-fuer-effektivere-awareness-programme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Phishing erkennen und abwehren: Psychologische Einblicke f\u00fcr effektivere Awareness-Programme"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#\/schema\/person\/3633ec00025224cdc913c180f64915d2","name":"noelleantoniasmilla","image":{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/secure.gravatar.com\/avatar\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/85444b191d03a7f5fad71a7a129a5b6d1158d83015fac86bbe6fe99f175b82b3?s=96&d=mm&r=g","caption":"noelleantoniasmilla"}}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/economiccrime\/wp-content\/uploads\/sites\/11\/2023\/03\/AdobeStock_576901499-1.jpeg","author_info":{"display_name":"noelleantoniasmilla","author_link":"https:\/\/hub.hslu.ch\/economiccrime\/author\/noelleantoniasmilla\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/5166","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/users\/230"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/comments?post=5166"}],"version-history":[{"count":16,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/5166\/revisions"}],"predecessor-version":[{"id":6432,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts\/5166\/revisions\/6432"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media\/3609"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/media?parent=5166"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/categories?post=5166"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags?post=5166"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}