{"id":319,"count":2,"description":"","link":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/","name":"Expertise","slug":"expertise","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Expertise Archives - Economic Crime Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Expertise Archives - Economic Crime Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/\" \/>\n<meta property=\"og:site_name\" content=\"Economic Crime Blog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/tag\\\/expertise\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/tag\\\/expertise\\\/\",\"name\":\"Expertise Archives - Economic Crime Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/tag\\\/expertise\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/tag\\\/expertise\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Expertise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/\",\"name\":\"Economic Crime Blog\",\"description\":\"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/economiccrime\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Expertise Archives - Economic Crime Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/","og_locale":"de_DE","og_type":"article","og_title":"Expertise Archives - Economic Crime Blog","og_url":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/","og_site_name":"Economic Crime Blog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/","url":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/","name":"Expertise Archives - Economic Crime Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/#breadcrumb"},"inLanguage":"de-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/economiccrime\/tag\/expertise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/economiccrime\/"},{"@type":"ListItem","position":2,"name":"Expertise"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/economiccrime\/#website","url":"https:\/\/hub.hslu.ch\/economiccrime\/","name":"Economic Crime Blog","description":"Bek\u00e4mpfung der Wirtschaftskriminalit\u00e4t","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/economiccrime\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags\/319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/economiccrime\/wp-json\/wp\/v2\/posts?tags=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}