{"id":8892,"date":"2023-02-24T09:58:09","date_gmt":"2023-02-24T08:58:09","guid":{"rendered":"https:\/\/hub.hslu.ch\/financialmanagement\/?p=8892"},"modified":"2026-02-11T14:53:50","modified_gmt":"2026-02-11T13:53:50","slug":"podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/","title":{"rendered":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators"},"content":{"rendered":"\n<p><strong>Herzlich Willkommen zum Podcast \u00abIFZ Talking Finance\u00bb!<\/strong><\/p>\n\n\n\n\n\n<p><strong>IoT-based Finance? Embedded Finance? Asset-as-a-Service Modelle?<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Um was handelt es sich bei diesen Modellen? <\/li>\n\n\n\n<li>Welche potenziellen Vorteile bieten diese Modelle den Unternehmen?<\/li>\n\n\n\n<li>Welche Ausgestaltungsm\u00f6glichkeiten gibt es?<\/li>\n\n\n\n<li>Was ist das Intermedi\u00e4rmodell und welche Rolle spielen SPVs?<\/li>\n\n\n\n<li>Welche Rolle spielen Daten?<\/li>\n\n\n\n<li>Wo kommen diese Modelle konkret in der Praxis zur Anwendung und wie kann man sie implementieren?<\/li>\n<\/ul>\n\n\n\n\t<iframe style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/episode\/15ckP9c7nN0Y20vJTSF7sI??utm_source=generator&#038;theme=0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\" loading=\"lazy\" width=\"100%\" height=\"152\" frameborder=\"0\"><\/iframe>\n\n\n\n<p>Der Podcast \u00abIFZ Talking Finance\u00bb wurde von Thomas Birrer und Timo Heroth vom IFZ der Hochschule Luzern ins Leben gerufen, um einen Einblick in aktuelle Finanzthemen zu geben. Dabei liegt der Hauptfokus auf lokalen und internationalen Themen mit Bezug zur Schweizer Finanzwirtschaft. Wir besch\u00e4ftigen uns unter anderem mit der Disruption durch die Digitalisierung des Finanzbereichs und den Chancen und Herausforderungen f\u00fcr Schweizer Firmen.<\/p>\n\n\n\n<p>In jeder Folge haben wir einen Experten\/eine Expertin zu Gast, um uns einen Einblick in ein jeweiliges Spezialgebiet zu geben und Sie als Zuh\u00f6rer\/in an der Expertise teilhaben zu lassen. Gleichzeitig wollen wir auch die Motivation und Passion der G\u00e4ste f\u00fcr das jeweilige Thema in Erfahrung bringen.<\/p>\n\n\n\n<p>#AssetasaService #Blockchain #IoT #Finance #FinanzmarktSchweiz #HSLU #CorporateFinance<\/p>\n\n\n\n<p>Wir w\u00fcnschen allen viel Spass beim Zuh\u00f6ren!<\/p>\n\n\n\n<p><br>Thomas Birrer und Timo Heroth<\/p>\n\n\n\n<p>Die bisherigen Folgen des Podcasts finden Sie u.a. auf <a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\" target=\"_blank\" rel=\"noreferrer noopener\">Stitcher<\/a> und <a href=\"https:\/\/open.spotify.com\/show\/6ZR7N9WFFEsa2yqw5xrJk0\" target=\"_blank\" rel=\"noreferrer noopener\">Spotify<\/a>:<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-mit-roger-disch-von-ey-69990718\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 1: IFZ Talking Finance mit Roger Disch von EY zur Digitalisierung des Corporate Treasury Managements<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-mit-peter-schnurer-von-daura-74220613\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 2: IFZ Talking Finance mit Peter Schn\u00fcrer von daura zur digitalen Eigenkapitalfinanzierung mit Tokens<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-mit-stefan-feller-von-loanboox-77067872\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 3: IFZ Talking Finance mit Stefan Feller von Loanboox zum Thema Green Bonds \u2013 Trend oder Hype?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-mit-frank-wendt-und-benedikt-schuppli-77880979\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 4: IFZ Talking Finance mit Frank Wendt und Benedikt Schuppli von FQX \u2013 Was sind Electronic Negotiable Instruments?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-with-frank-wendt-and-benedikt-schuppli-77917968\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 5: IFZ Talking Finance mit Frank Wendt und Benedikt Schuppli von FQX \u2013 What ere Electronic Negotiable Instruments?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.stitcher.com\/show\/ifz-talking-finance\/episode\/ifz-talking-finance-mit-dr-olivier-schucht-von-fff-83135969\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 6: IFZ Talking Finance mit Dr. Olivier Schucht, CFO von FFF \u2013 Wie wurde die Buyout-Finanzierung von FFF mit Private Debt strukturiert?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/1kYMBaYOmOuo3plS8yItuk?go=1&amp;utm_source=embed_v3&amp;t=0\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 7: IFZ Talking Finance mit Martin Meyer von Amag Leasing AG \u2013 Wie und zu welchen Konditionen k\u00f6nnen in der Schweiz ABS-Transaktionen platziert werden?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/2mY3gbk2SlbVv8sFbeWcxz?go=1&amp;utm_source=embed_v3&amp;t=0&amp;nd=1\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 8: IFZ Talking Finance mit Stephan Lohnert von Capco &#8211; Was ist ein TMS? Wann ist ein TMS sinnvoll? Was sind die zentralen Kosten-Nutzen-\u00dcberlegungen?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/7yEI3VPrPbHDLwAfh9c9Ky\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 9: IFZ Talking Finance mit Robert Eigenheer von EUROFIMA. Wie integriert man einen ESG Ansatz? Welcher konkreten Informationen bedarf es in der Kommunikation mit \u00abESG Investoren\u00bb? Wie steht es um die Vergleichbarkeit von ESG Ratings?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/4yoG271Xtb1S6jbQSB8E9j\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 10: IFZ Talking Finance mit R\u00fcdiger Petrikowski, CFO ad-interim der Achiko Ltd.. Was macht Achiko und weshalb ist das Unternehmen in der Schweiz kotiert? Welche Finanzierungstransaktionen hat Achiko k\u00fcrzlich durchgef\u00fchrt? Warum wurden diese Finanzierungsarten inklusive Wandelanleihen gew\u00e4hlt und was sind die Vor- und Nachteile?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/5RAvbg9WwGqAh3Cly3dY5i\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 11: IFZ Talking Finance with Dr. Roland Mees, Director of Sustainable Finance at ING, What kind of role do sustainability-linked loans play in the debt market? How is sustainability rated and measured? How does the future of ESG-related loans look like?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/47kO03bv6xbfl8m29huy7X\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 12: IFZ Talking Finance mit Dr. Edith Leitner und Michael Kappeler von Schwabe, Ley &amp; Greiner. Was sind die Gestaltungskriterien konzerninterner Finanzierungsstrukturen aus einer Praxisperspektive? Welche Anreize gibt es f\u00fcr unterschiedliche Formen der Unternehmensfinanzierung? Welche Treiber und Gestaltungskriterien m\u00fcssen Unternehmen bei der Wahl des passenden Finanzierungsinstruments beachten?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/7wqxnwlQMSqU4ozGrmr2YE\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 13: IFZ Talking Finance mit Rolf Weilenmann von der Helvetischen Bank. Wie sieht die Bondstory aus? Was sind kleinere Anleihen? Was sind deren Vor- und Nachteile? Wer sind m\u00f6gliche Emittenten? Und wie gestaltet eine Bank die Preis- und Risikofaktoren von kleineren Anleihen?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/03LIOAp1txM7rf6CQetaW4\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 14: IFZ Talking Finance mit Fabian Egger, Fabian Egger, Head of Finance der Emmi AG. Welchen Einfluss haben erh\u00f6hte Nachhaltigkeitsanforderungen auf Unternehmen und die finanzielle Steuerung? Wie geht Emmi mit den Herausforderungen im Bereich der ESG Analyse und Kommunikation um? Welche Einfl\u00fcsse ergeben sich f\u00fcr die Finanzabteilung und die Finanzierungst\u00e4tigkeiten?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/04mx5QYNg8NfMzUEtkwtbg\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 15: IFZ Talking Finance mit Thomas St\u00e4ubli von der Rieter Management AG, Wie geht Rieter mit der Herausforderung W\u00e4hrungsrisikomanagement um? Wie geht Rieter mit Fremdw\u00e4hrungsrisiken um? Weshalb werden Cashflows aus Projekten anders behandelt als nicht-projektbezogene Cashflows? Inwiefern reagiert Rieter auf kurzfristige W\u00e4hrungsschwankungen?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/5dPgEOj6lMdb7KbWScEZXj\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 16: IFZ Talking Finance mit Daniel Cugni von Coprocess SA, Wie funktioniert das Intercompany-Netting und was sind die Vorteile? Was sind die Unterschiede zwischen der Netting-L\u00f6sung von Coprocess und einem Treasury-Management-System (TMS)? Wie werden digitale Innovationen die Welt des Treasury Managements weiter beeinflussen?&nbsp;<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/show\/6ZR7N9WFFEsa2yqw5xrJk0\" target=\"_blank\" rel=\"noreferrer noopener\">Folge 17: IFZ Talking Finance mit Andres Heusser der AIL Structured Finance Ltd., Welche Instrumente gibt es zur Exportfinanzierung? Wie ist es m\u00f6glich das Liefer- und Finanzierungsangebot zu verkn\u00fcpfen? Wie lassen sich dabei das Cashflow Profil und Working Capital optimieren und Risiken minimieren?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/0EQmwsdgIyfgYdewpmdLki\">Folge 18: IFZ Talking Finance mit Stefan Bosshard der SIX Digital Exchange (SDX), Was ist ein digitaler Bond? Welche Rolle spielen digitale W\u00e4hrungen und die Distributed Ledger Technologie (DLT) bei der Lancierung solcher Bonds? Welche Vorteile gibt es? Wie aufwendig war die Implementierung und Lancierung des ersten digitalen Bonds in der Schweiz und wie hat der Markt die Platzierung aufgenommen? Wie steht es um die Nachhaltigkeit eines solchen Bonds?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/2J0DZnjArtwnccx49hABBy\">Folge 19: IFZ Talking Finance mit Dr. Patrick Mollet von Great Place To Work, Wie positioniert sich eine Firma am besten bei der Gestaltung der Unternehmenskultur? Was ist das Arbeitgeberversprechen, die sogenannte Employee Value Proposition (EVP), gegen\u00fcber den Mitarbeiter\/innen? Welche Branchen sind bez\u00fcglich der Gestaltung der EVP besonders hervorzuheben? Wie steht die Unternehmenskultur in Bezug zu nachhaltigen Unternehmenszielen? Wie erreiche ich als guter Arbeitgeber die j\u00fcngere Generation?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/07suf6qznd07bFdf9P6S7B\">Folge 20: IFZ Talking Finance mit Micha\u00ebl Jaquet von DebtPilot, Wie reagieren Unternehmen auf h\u00f6here Zinskosten? Welche Steuerungsm\u00f6glichkeiten haben Unternehmen im Zinsrisikomanagement? Welche zentralen KPIs spielen dabei eine Rolle? Wie hilft hierbei eine Software wie jene von DebtPilot gerade im Bereich der Risikoanalyse, Finanzplanung und des Reportings? Wie f\u00fchlt sich der Journey vom bew\u00e4hrten Job in einem namhaften Schweizer Unternehmen zum Founder eines Start-ups an?<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/open.spotify.com\/episode\/1Ba9quRGATUFQEQeRJgGSG\">Folge 21: IFZ Talking Finance mit Thomas Friesleben von StoneX. Wer sind die entscheidenden Intermedi\u00e4re im Zahlungsverkehr? Warum ist die neue ISO 20022 eine der gr\u00f6ssten Ver\u00e4nderungen im Zahlungsverkehr der letzten Jahre? Was hat dies f\u00fcr Auswirkungen auf Schweizer Unternehmen? Was f\u00fcr Auswirkungen hat dies auf die Zukunft des Zahlungsverkehrs?<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n\n\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p>Link zu IFZ Angeboten im Finance-Bereich:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/mas\/ifz\/corporate-finance\/\">MAS Corporate Finance<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/funding-and-treasury\/\">CAS Funding &amp; Treasury<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/corporate-finance\/\">CAS Corporate Finance<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/swiss-certified-treasurer\/\">CAS Swiss Certified Treasurer (SCT\u00ae)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/financial-management\/\">CAS Financial Management<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ifz\/turnaround-management\/?gclid=CjwKCAiAq8f-BRBtEiwAGr3DgYwM3IQvRQqLdMUSki57sBqTJCddS7K7HAi1NHRVUXTORpbaYu1DRBoCnUwQAvD_BwE&amp;gclsrc=aw.ds\">CAS Turnaround Management<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/\">\u00dcbersicht IFZ Weiterbildungsangebote<\/a><\/li>\n<\/ul>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.<\/p>\n","protected":false},"author":236,"featured_media":6554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"8401,8367,8162,7826,7751,7673","_relevanssi_noindex_reason":"","ngg_post_thumbnail":0,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[587776,10225],"tags":[588039,46516,67433,3797,587995,28,588040],"class_list":["post-8892","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-finanzen","category-risikomanagement","tag-assetasaservice","tag-blockchain","tag-corporate-finance","tag-finance","tag-finanzmarkt-schweiz","tag-hslu","tag-iot"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog<\/title>\n<meta name=\"description\" content=\"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog\" \/>\n<meta property=\"og:description\" content=\"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/\" \/>\n<meta property=\"og:site_name\" content=\"Financial Management Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-24T08:58:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1404\" \/>\n\t<meta property=\"og:image:height\" content=\"672\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"melanielisafuerch\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"melanielisafuerch\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/\"},\"author\":{\"name\":\"melanielisafuerch\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/#\\\/schema\\\/person\\\/37830b930c7191bcaf93c2a45521ee16\"},\"headline\":\"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators\",\"datePublished\":\"2023-02-24T08:58:09+00:00\",\"dateModified\":\"2026-02-11T13:53:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/\"},\"wordCount\":1073,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/wp-content\\\/blogs.dir\\\/488\\\/files\\\/sites\\\/16\\\/2020\\\/07\\\/200206_HeaderBild_Birrer_Heroth.jpg\",\"keywords\":[\"AssetasaService\",\"Blockchain\",\"Corporate Finance\",\"Finance\",\"Finanzmarkt Schweiz\",\"HSLU\",\"IoT\"],\"articleSection\":[\"Finanzen\",\"Risikomanagement\"],\"inLanguage\":\"de-CH\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/\",\"name\":\"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/wp-content\\\/blogs.dir\\\/488\\\/files\\\/sites\\\/16\\\/2020\\\/07\\\/200206_HeaderBild_Birrer_Heroth.jpg\",\"datePublished\":\"2023-02-24T08:58:09+00:00\",\"dateModified\":\"2026-02-11T13:53:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/#\\\/schema\\\/person\\\/37830b930c7191bcaf93c2a45521ee16\"},\"description\":\"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/wp-content\\\/blogs.dir\\\/488\\\/files\\\/sites\\\/16\\\/2020\\\/07\\\/200206_HeaderBild_Birrer_Heroth.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/wp-content\\\/blogs.dir\\\/488\\\/files\\\/sites\\\/16\\\/2020\\\/07\\\/200206_HeaderBild_Birrer_Heroth.jpg\",\"width\":1404,\"height\":672,\"caption\":\"Podcast-Coverbild\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/2023\\\/02\\\/24\\\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/\",\"name\":\"Financial Management Blog\",\"description\":\"Controlling, Accounting, Risk &amp; Corporate Finance am Institut f\u00fcr Finanzdienstleistungen Zug IFZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/financialmanagement\\\/#\\\/schema\\\/person\\\/37830b930c7191bcaf93c2a45521ee16\",\"name\":\"melanielisafuerch\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog","description":"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/","og_locale":"de_DE","og_type":"article","og_title":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog","og_description":"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.","og_url":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/","og_site_name":"Financial Management Blog","article_published_time":"2023-02-24T08:58:09+00:00","article_modified_time":"2026-02-11T13:53:50+00:00","og_image":[{"width":1404,"height":672,"url":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","type":"image\/jpeg"}],"author":"melanielisafuerch","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"melanielisafuerch","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/"},"author":{"name":"melanielisafuerch","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/#\/schema\/person\/37830b930c7191bcaf93c2a45521ee16"},"headline":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators","datePublished":"2023-02-24T08:58:09+00:00","dateModified":"2026-02-11T13:53:50+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/"},"wordCount":1073,"image":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","keywords":["AssetasaService","Blockchain","Corporate Finance","Finance","Finanzmarkt Schweiz","HSLU","IoT"],"articleSection":["Finanzen","Risikomanagement"],"inLanguage":"de-CH"},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/","url":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/","name":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators - Financial Management Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","datePublished":"2023-02-24T08:58:09+00:00","dateModified":"2026-02-11T13:53:50+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/#\/schema\/person\/37830b930c7191bcaf93c2a45521ee16"},"description":"In der 22. Folge sprechen wir mit Dr. Lars R\u00fcsberg von Innovating Innovators. Diese zugegebenermassen recht lange Folge behandelt viele verschiedene Aspekte von Pay-Per-Use-Modellen. Unter anderem beantworten wir die Frage nach den potenziellen Vorteilen sowie den m\u00f6glichen Ausgestaltungsarten. Neben den verschiedenen Risiken und Auswirkungen auf die Ertr\u00e4ge \u2013 weg vom einmaligen Verkauf hin zu wiederkehrenden Einnahmen \u2013 sprechen wir auch \u00fcber die zentrale Rolle von Daten.","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#primaryimage","url":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","contentUrl":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","width":1404,"height":672,"caption":"Podcast-Coverbild"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/2023\/02\/24\/podcast-ifz-talking-finance-mit-dr-lars-ruesberg-von-innovating-innovators\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/financialmanagement\/"},{"@type":"ListItem","position":2,"name":"Podcast: IFZ Talking Finance mit Dr. Lars R\u00fcsberg von Innovating Innovators"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/#website","url":"https:\/\/hub.hslu.ch\/financialmanagement\/","name":"Financial Management Blog","description":"Controlling, Accounting, Risk &amp; Corporate Finance am Institut f\u00fcr Finanzdienstleistungen Zug IFZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/financialmanagement\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/financialmanagement\/#\/schema\/person\/37830b930c7191bcaf93c2a45521ee16","name":"melanielisafuerch"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-content\/blogs.dir\/488\/files\/sites\/16\/2020\/07\/200206_HeaderBild_Birrer_Heroth.jpg","author_info":{"display_name":"melanielisafuerch","author_link":"https:\/\/hub.hslu.ch\/financialmanagement\/author\/melanielisafuerch\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/posts\/8892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/users\/236"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/comments?post=8892"}],"version-history":[{"count":11,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/posts\/8892\/revisions"}],"predecessor-version":[{"id":12143,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/posts\/8892\/revisions\/12143"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/media\/6554"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/media?parent=8892"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/categories?post=8892"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/financialmanagement\/wp-json\/wp\/v2\/tags?post=8892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}