{"id":854975,"count":1249,"description":"IFZ in den Medien","link":"https:\/\/hub.hslu.ch\/ifz\/category\/ifz-in-den-medien\/","name":"IFZ in den Medien","slug":"ifz-in-den-medien","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IFZ in den Medien Archives - IFZ Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/2019\\\/02\\\/12\\\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/2019\\\/02\\\/12\\\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\\\/\",\"name\":\"IFZ in den Medien Archives - IFZ Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/2019\\\/02\\\/12\\\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/2019\\\/02\\\/12\\\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/2019\\\/02\\\/12\\\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IFZ in den Medien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/\",\"name\":\"IFZ Blog\",\"description\":\"News aus dem Institut f\u00fcr Finanzdienstleistungen Zug IFZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/ifz\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IFZ in den Medien Archives - IFZ Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/","url":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/","name":"IFZ in den Medien Archives - IFZ Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ifz\/#website"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/#breadcrumb"},"inLanguage":"de-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/ifz\/2019\/02\/12\/prof-dr-yvonne-seiler-zimmermann-was-taugen-pk-ratings-fuer-die-wahl-der-vorsorgeeinrichtung\/"},{"@type":"ListItem","position":2,"name":"IFZ in den Medien"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/ifz\/#website","url":"https:\/\/hub.hslu.ch\/ifz\/","name":"IFZ Blog","description":"News aus dem Institut f\u00fcr Finanzdienstleistungen Zug IFZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/ifz\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/ifz\/wp-json\/wp\/v2\/categories\/854975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/ifz\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hub.hslu.ch\/ifz\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/ifz\/wp-json\/wp\/v2\/posts?categories=854975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}