{"id":21489,"date":"2023-12-19T08:48:22","date_gmt":"2023-12-19T07:48:22","guid":{"rendered":"https:\/\/hub.hslu.ch\/ikm\/?p=21489"},"modified":"2026-02-11T14:53:10","modified_gmt":"2026-02-11T13:53:10","slug":"srf-hautnah-ein-blick-hinter-die-kulissen","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/","title":{"rendered":"SRF hautnah: Ein Blick hinter die Kulissen"},"content":{"rendered":"\n<p class=\"is-style-lead\"><em>An einem malerisch verschneiten Donnerstagmorgen, dem 30.11.2023, bot sich einer Gruppe von Studierenden der HSLU eine besondere Gelegenheit: Das SRF-Studio in Leutschenbach zu erkunden. <\/em><\/p>\n\n\n\n<p>F\u00fcr die n\u00e4chsten zwei Stunden stand der Gruppe ein spannendes Programm bevor. Nach einem herzlichen Empfang und einer warmen Tasse Kaffee machte sich die Gruppe, gef\u00fchrt von der SRF-Aufnahmeleiterin Carla Da Re, auf den Weg in die SRF-Fernsehstudios. Die Sets, welche den meisten aus der Gruppe bisher nur aus ihren liebsten TV-Formaten bekannt waren, sorgten bei vielen f\u00fcr grosses Staunen. Als n\u00e4chstes stand ein Einblick in ein Radiostudio von SRF auf dem Programm. Einen Radiomoderator bei einer Sendung nicht nur zu h\u00f6ren, sondern dabei auch zu sehen, war sehr eindr\u00fccklich und inspirierte den ein oder anderen Studierenden. Abschliessend lernten die Anwesenden noch den \u00abTageschau\u00bb-Moderator Michael Rauchenstein kennen. Seine Aufgabe war es, die teilweise sehr kritischen Fragen der Studierenden zu beantworten.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcber Sydney nach Timbuktu<\/h2>\n\n\n\n<p>Ein erstes Highlight, ganz zu Beginn der F\u00fchrung, bestand aus der Besichtigung der \u00abArena\u00bb-Kulisse. Hier lernte die Gruppe verschiedene Methoden kennen, um Kulissen gr\u00f6sser aussehen zu lassen. Indem SRF-Programmverantwortliche Ecken in TV-Studios so weit wie m\u00f6glich vermeiden, versuchen sie die R\u00e4umlichkeit um ein Vielfaches weitl\u00e4ufiger darzustellen. Weitere Tricks beziehen sich auf zentrale Faktoren wie der Beleuchtung oder der Kameraperspektive.<\/p>\n\n\n\n<p>Perspektive ist ein gutes Stichwort f\u00fcr den n\u00e4chsten interessanten Posten, den die Lerngruppe besuchte. Im \u00abSportpanorama\u00bb-Studio erkl\u00e4rte Carla Da Re, dass es im Raum verschiedene Positionen gibt, auf denen sich die Moderatoren und Moderatorinnen systematisch bewegen. Es ist Schritt f\u00fcr Schritt vorgegeben, dass die Moderation auf \u00abSydney\u00bb die G\u00e4ste begr\u00fcsst und auf \u00abTimbuktu\u00bb anschliessend die Sendung in der Mitte des Studios er\u00f6ffnet. Die Namensgebung orientiert sich, mit der Ausnahme von \u00abTimbuktu\u00bb, an den St\u00e4dtenamen von Austragungsorten der olympischen Spiele. \u00abTimbuktu\u00bb heisst so, weil Timbuktu geografisch genau auf dem \u00c4quator liegt, welcher das Zentrum der Erde symbolisiert, parallel zum Zentrum des \u00abSportpanorama\u00bb-Studios. <\/p>\n\n\n\n<p>Das Thema Sport steht auch bei einem weiteren Highlight der Besichtigung im Mittelpunkt. Im Studio 1 wird aktuell die Kulisse f\u00fcr die \u00abSwiss Sport Awards\u00bb aufgebaut. Ein Prozess, den wohl jeder aus der Gruppe aufwandtechnisch untersch\u00e4tzt hat. Es gilt eine B\u00fchne zu erschaffen, richtige Beleuchtung spezifisch f\u00fcr die Sendung zu installieren und vieles mehr. Der Anblick erinnerte an eine Baustelle, da die Gruppe ohne Helme den Aufbau der Kulisse nur aus sicherer Entfernung betrachten konnte.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"702\" height=\"936\" src=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-702x936.jpeg\" alt=\"\" class=\"wp-image-21493\" srcset=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-702x936.jpeg 702w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-225x300.jpeg 225w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-768x1024.jpeg 768w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-1152x1536.jpeg 1152w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-390x520.jpeg 390w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-524x698.jpeg 524w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio-600x800.jpeg 600w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Studio.jpeg 1536w\" sizes=\"auto, (max-width: 702px) 100vw, 702px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Sehen, was bisher nur zu h\u00f6ren war<\/h2>\n\n\n\n<p>Mathias Schenk empfing die interessierte Gruppe anschliessend herzlich im Radiostudio von SRF 3. Nachdem sich der Song \u00abSomeone You Loved\u00bb von Lewis Capaldi dem Ende zuneigte, zeigte Mathias den Studierenden seine F\u00e4higkeiten als Radiomoderator. Auf dem Programm stand die interessante Diskussion, ob sich junge Erwachsene in Zukunft ein Eigenheim w\u00fcnschen und weshalb. Das Thema wird nicht von Mathias Schenk vorgegeben, sondern von der Redaktion. Solche Diskussionen leben gr\u00f6sstenteils von H\u00f6rer-Beitr\u00e4gen, welche vom Moderator aussortiert und eingespielt werden. Ein Studierender stellte die Frage, was der Moderator machen w\u00fcrde, wenn es keine R\u00fcckmeldungen der H\u00f6rer*innen g\u00e4be. Mathias Schenk sagte dazu, dass er dann oft seine eigene Meinung preisgeben k\u00f6nne, um Diskussionen anzuheizen. Der Beruf als Radiomoderator*in setzt dementsprechend eine Portion Schlagfertigkeit und Kreativit\u00e4t voraus.<\/p>\n\n\n\n<p>F\u00fcr einen herzhaften Lacher sorgte der mehr oder weniger gelungene \u00dcbergang zwischen zwei Songs, welcher der Moderator durch den spannenden Austausch mit der Gruppe in letzter Sekunde gerade noch so authentisch wie m\u00f6glich platzieren konnte.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00abHaben Sie manchmal Albtr\u00e4ume aufgrund Ihrer Arbeit?\u00bb<\/h2>\n\n\n\n<p>Jeder kennt die \u00abTageschau\u00bb und jeder kennt die bekannten Gesichter, welche die Sendung jeden Tag voller Stolz moderieren. Der Job als \u00abTageschau\u00bb-Redaktor und -Moderator ist jedoch herausfordernder, als sich die Mehrheit der Gruppe vorgestellt hatte. Die Gruppe erhielt nun die Chance, dem seit einem Jahr aktivem News Anchor der \u00abTageschau\u00bb-Hauptausgabe, Michael Rauchenstein, spannende Fragen zur Sendung und zu seinem Beruf zu stellen.<\/p>\n\n\n\n<p>Da Michael Rauchenstein ebenfalls Planer der SRF-Auslandsredaktion ist, ging es bei der ersten Frage um den Einsatz der Auslandskorrespondenten in Krisengebieten wie zurzeit Israel. Die angesprochenen Themen hinterliessen bei der Gruppe einen bleibenden Eindruck, da die beiden Korrespondenten t\u00e4glich bis zu vier Mal Zuflucht in einem unterirdischen Bunker suchen m\u00fcssen. Sie setzen dementsprechend ihr Leben aufs Spiel, um authentische Berichterstattungen vor Ort durchzuf\u00fchren. SRF biete den mutigen Reportern psychische Hilfeleistung, falls die Arbeit ihnen zu viel wird, und sie k\u00f6nnen sich bei Bedarf auch mal eine Woche in ihre Hotelzimmer ausserhalb des Krisengebietes zur\u00fcckziehen.<\/p>\n\n\n\n<p>Eine weitere Frage im Bezug zur Kriegsberichterstattung behandelte Schlafprobleme nach Recherchen.&nbsp; Michael Rauchenstein antwortete sehr differenziert. Er sagte, dass er hier und da schon von den schrecklichen Bildern der Recherche tr\u00e4ume, die Bilder aber beim Verlassen des Studios versuche auszublenden. Es geh\u00f6re zu seinem Job und er sei sich seiner Verantwortung der heiklen Recherchen bewusst.<\/p>\n\n\n\n<p>Da das letzte Thema jeder \u00abTageschau\u00bb-Ausgabe das Publikum mit positiveren Neuigkeiten in den Abend leiten soll, soll auch dieser Blogbeitrag mit einem sch\u00f6nen Fazit enden. Die Exkursion bildete f\u00fcr <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=2576\" target=\"_blank\" rel=\"noreferrer noopener\">Constanze Jecker<\/a> als Dozentin sowie f\u00fcr die anwesenden Studierenden einen interessanten Morgen, voller spannender Eindr\u00fccke am SRF-Hauptsitz. Die Gruppe konnte vieles im Bezug auf Medienproduktion lernen, traf auf starke, inspirierende Pers\u00f6nlichkeiten und durfte sich in die Rolle der Moderatoren und Moderatorinnen versetzen, wie es ein Studierender vor dem Greenscreen tat.<\/p>\n\n\n\n<p>Die Autorenschaft bedankt sich an der Stelle, auch im Namen der Exkursionsgruppe, bei Constanze Jecker  vom IKM f\u00fcr die Organisation und Begleitung des gelungenen Ausflugs zum Herzen des SRF.<\/p>\n\n\n\n<div style=\"background-color:#f2f2f2;color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb-profile-columns\"><div class=\"gb-profile-column gb-profile-avatar-wrap\"><div class=\"gb-profile-image-wrap\"><figure class=\"gb-profile-image-square\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" class=\"gb-profile-avatar wp-image-21491\" src=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Noah-Andenmatten.jpg\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Noah-Andenmatten.jpg 200w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Noah-Andenmatten-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><\/div><\/div><div class=\"gb-profile-column gb-profile-content-wrap\"><h2 class=\"gb-profile-name\" style=\"color:#32373c\">Noah Andenmatten<\/h2><p class=\"gb-profile-title\" style=\"color:#32373c\">Student Bachelor of Science in Business Administration mit Major Kommunikationsmanagement und Minor Marketing<\/p><div class=\"gb-profile-text\"><\/div><ul class=\"gb-social-links\"><\/ul><\/div><\/div>\n\n\n\n<div style=\"background-color:#f2f2f2;color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb-profile-columns\"><div class=\"gb-profile-column gb-profile-avatar-wrap\"><div class=\"gb-profile-image-wrap\"><figure class=\"gb-profile-image-square\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" class=\"gb-profile-avatar wp-image-21490\" src=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Fabian-Zwicky.jpg\" alt=\"\" srcset=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Fabian-Zwicky.jpg 200w, https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Fabian-Zwicky-150x150.jpg 150w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/figure><\/div><\/div><div class=\"gb-profile-column gb-profile-content-wrap\"><h2 class=\"gb-profile-name\" style=\"color:#32373c\">Fabian Zwicky<\/h2><p class=\"gb-profile-title\" style=\"color:#32373c\">Student Bachelor of Science in Business Administration mit Major Marketing und Minor Kommunikationsmanagement<\/p><div class=\"gb-profile-text\"><\/div><ul class=\"gb-social-links\"><\/ul><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Die neugierigen Studierenden des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement erhielten spannende Einblicke in die Sendestudios, die Arbeit und die Prozesse des gr\u00f6ssten Medienhauses der Schweiz.<\/p>\n","protected":false},"author":247,"featured_media":21492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"10807,10583,10773,11376,9924,20289","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[86671,4165],"tags":[86591,86644,85641],"class_list":["post-21489","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-marketing-und-kommunikationsmanagement","category-studium","tag-bachelor","tag-kommunikationsmanagement","tag-studium"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog<\/title>\n<meta name=\"description\" content=\"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog\" \/>\n<meta property=\"og:description\" content=\"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/\" \/>\n<meta property=\"og:site_name\" content=\"IKM-Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-19T07:48:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"sandramendez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"sandramendez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/\"},\"author\":{\"name\":\"sandramendez\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/#\\\/schema\\\/person\\\/f499a20cf3ea24019b09ec0b7a32f6f3\"},\"headline\":\"SRF hautnah: Ein Blick hinter die Kulissen\",\"datePublished\":\"2023-12-19T07:48:22+00:00\",\"dateModified\":\"2026-02-11T13:53:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/\"},\"wordCount\":969,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/wp-content\\\/blogs.dir\\\/489\\\/files\\\/sites\\\/8\\\/Gruppenbild.jpeg\",\"keywords\":[\"Bachelor\",\"Kommunikationsmanagement\",\"Studium\"],\"articleSection\":[\"Marketing- und Kommunikationsmanagement\",\"Studium\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/\",\"name\":\"SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/wp-content\\\/blogs.dir\\\/489\\\/files\\\/sites\\\/8\\\/Gruppenbild.jpeg\",\"datePublished\":\"2023-12-19T07:48:22+00:00\",\"dateModified\":\"2026-02-11T13:53:10+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/#\\\/schema\\\/person\\\/f499a20cf3ea24019b09ec0b7a32f6f3\"},\"description\":\"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/wp-content\\\/blogs.dir\\\/489\\\/files\\\/sites\\\/8\\\/Gruppenbild.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/wp-content\\\/blogs.dir\\\/489\\\/files\\\/sites\\\/8\\\/Gruppenbild.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/2023\\\/12\\\/19\\\/srf-hautnah-ein-blick-hinter-die-kulissen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SRF hautnah: Ein Blick hinter die Kulissen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/\",\"name\":\"IKM-Blog\",\"description\":\"Kommunikation und Marketing an der Hochschule Luzern \u2013 Wirtschaft\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ikm\\\/#\\\/schema\\\/person\\\/f499a20cf3ea24019b09ec0b7a32f6f3\",\"name\":\"sandramendez\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog","description":"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/","og_locale":"de_DE","og_type":"article","og_title":"SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog","og_description":"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF","og_url":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/","og_site_name":"IKM-Blog","article_published_time":"2023-12-19T07:48:22+00:00","article_modified_time":"2026-02-11T13:53:10+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","type":"image\/jpeg"}],"author":"sandramendez","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"sandramendez","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/"},"author":{"name":"sandramendez","@id":"https:\/\/hub.hslu.ch\/ikm\/#\/schema\/person\/f499a20cf3ea24019b09ec0b7a32f6f3"},"headline":"SRF hautnah: Ein Blick hinter die Kulissen","datePublished":"2023-12-19T07:48:22+00:00","dateModified":"2026-02-11T13:53:10+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/"},"wordCount":969,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","keywords":["Bachelor","Kommunikationsmanagement","Studium"],"articleSection":["Marketing- und Kommunikationsmanagement","Studium"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/","url":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/","name":"SRF hautnah: Ein Blick hinter die Kulissen - IKM-Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ikm\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","datePublished":"2023-12-19T07:48:22+00:00","dateModified":"2026-02-11T13:53:10+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/ikm\/#\/schema\/person\/f499a20cf3ea24019b09ec0b7a32f6f3"},"description":"Studierende des Studienganges Business Administration mit dem Major oder Minor in Kommunikationsmanagement zu Besuch bei SRF","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#primaryimage","url":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/ikm\/2023\/12\/19\/srf-hautnah-ein-blick-hinter-die-kulissen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/ikm\/"},{"@type":"ListItem","position":2,"name":"SRF hautnah: Ein Blick hinter die Kulissen"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/ikm\/#website","url":"https:\/\/hub.hslu.ch\/ikm\/","name":"IKM-Blog","description":"Kommunikation und Marketing an der Hochschule Luzern \u2013 Wirtschaft","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/ikm\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/ikm\/#\/schema\/person\/f499a20cf3ea24019b09ec0b7a32f6f3","name":"sandramendez"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/ikm\/wp-content\/blogs.dir\/489\/files\/sites\/8\/Gruppenbild.jpeg","author_info":{"display_name":"sandramendez","author_link":"https:\/\/hub.hslu.ch\/ikm\/author\/sandramendez\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/posts\/21489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/users\/247"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/comments?post=21489"}],"version-history":[{"count":12,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/posts\/21489\/revisions"}],"predecessor-version":[{"id":24590,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/posts\/21489\/revisions\/24590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/media\/21492"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/media?parent=21489"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/categories?post=21489"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ikm\/wp-json\/wp\/v2\/tags?post=21489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}