{"id":1073,"date":"2013-04-14T05:57:33","date_gmt":"2013-04-14T03:57:33","guid":{"rendered":"https:\/\/hub.hslu.ch\/immobilienblog\/?p=1073"},"modified":"2013-04-12T10:28:33","modified_gmt":"2013-04-12T08:28:33","slug":"zuruck-ins-buro-das-ende-des-home-office","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/","title":{"rendered":"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office?"},"content":{"rendered":"<p><b>Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen<\/b>, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete Telearbeit von zu Hause abschaffte. Prompt hat sie damit nicht nur bei den eigenen Mitarbeitern, sondern auch in den globalen Medien einen Sturm der Entr\u00fcstung ausgel\u00f6st.<\/p>\n<p>In einer Branche, die sich an Mobile-Working, Home-Office und flexible, selbstbestimmte Arbeitszeiten gew\u00f6hnt hat kommt dieser Schritt einem Sakrileg gleich. Was sind die Hintergr\u00fcnde? L\u00e4utet Marissa Meyer damit eine Trendwende ein, in einer Zeit, in der mehr und mehr Unternehmen in die andere Richtung gehen?<\/p>\n<p><b><a href=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-1077\" alt=\"computer_notebook_woman_baby_mother_child\" src=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child-300x156.jpg\" width=\"300\" height=\"156\" \/><\/a><\/b><\/p>\n<p><b>Heimarbeit scheint auf den ersten Blick eine klassische win-win-Situation zu kreieren<\/b>: Mitarbeiter k\u00f6nnen wohnen wo sie wollen, ihre Arbeitszeiten mit dem Privatleben abstimmen, sich den Arbeitsweg sparen und ungest\u00f6rt von unn\u00f6tigen Sitzungen und schwatzhaften Arbeitskollegen arbeiten. Mit der modernen Technologie sind die notwendigen Informationen jederzeit \u00fcberall griffbereit. Arbeitgeber k\u00f6nnen auf ein viel gr\u00f6sseres Arbeitskr\u00e4ftereservoir zur\u00fcckgreifen, sparen teure Arbeitspl\u00e4tze und erhalten motiviertere und produktivere Mitarbeiter. Tele-Working hat in den USA zwischen 2005 und 2011 um rund 75% zugenommen. Auch in Europa und der Schweiz ist der Trend steigend.<\/p>\n<p>Entgegen der Annahme, dass Mitarbeiter, die unbeaufsichtigt zu Hause arbeiten die Zeit vertr\u00f6deln und auf der faulen Haut liegen k\u00f6nnten, zeigen verschiedene Studien, dass sie im Gegenteil um 10-15% produktiver sind als Mitarbeiter im B\u00fcro. Auch die Arbeitszufriedenheit scheint tendenziell h\u00f6her zu sein.<\/p>\n<p><b>Wieso diese Kehrtwende bei Yahoo?<\/b> Der einstige Suchmaschinen-Star k\u00e4mpft seit l\u00e4ngerem mit Problemen und verliert massiv Besucher und Werbeeinnahmen an Google und Facebook. Marissa Meyer wurde geholt, um das Steuer herumzureissen.<\/p>\n<p>Die Harvard Business Review zeigt \u00fcberzeugend auf, dass Unternehmen oder Projekte innovativer, schneller und erfolgreicher ablaufen, wenn die Mitarbeiter m\u00f6glichst viel Zeit m\u00f6glichst Nahe beieinander verbringen. Und das Firmen eine wesentlich st\u00e4rkere Kultur und Verbundenheit entwickeln, wenn die Mitarbeiter zusammen sind. Die Verbundenheit der Mitarbeiter sowohl mit der Firma als auch den Arbeitskollegen ist schwer aufrechtzuerhalten ohne regelm\u00e4ssige pers\u00f6nliche Kontakte. Interessanterweise tun gerade die sehr erfolgreichen Firmen wie Facebook, Google und Apple alles, damit sich die Mitarbeiter am Arbeitsplatz wohl f\u00fchlen und m\u00f6glichst viel Zeit dort verbringen. Google\u2019s CFO Patrick Pichette antwortet auf die Frage, wie viele Google-Mitarbeiter von zu Hause arbeiten mit \u201e<a href=\"http:\/\/www.smh.com.au\/it-pro\/business-it\/do-as-we-say-not-as-we-do-googlers-dont-telecommute-20130219-2eo8w.html\" target=\"_blank\">So wenige wie m\u00f6glich! <\/a>Gemeinsame Mittagessen und Pausen, gemeinsames Probleme und Ideen w\u00e4lzen, zusammen m\u00f6gliche L\u00f6sungen diskutieren hat etwas magisches. \u00a0Bei Google glauben wir, dass diese Momente wichtig sind f\u00fcr die Entwicklung unserer Firma und unserer Projekte, f\u00fcr das pers\u00f6nliche Weiterkommen der Mitarbeiter und f\u00fcr die Entwicklung einer starken Gemeinschaft.<\/p>\n<p>Vor dem Hintergrund der Krisensituation, in der es darum geht, die Truppen hinter sich zu scharen und das Steuer eines sinkenden Schiffes herumzureissen, kann die Massnahme von Yahoo also durchaus Sinn machen.<\/p>\n<p><b>F\u00fcr Mitarbeiter sind die Firma und die Arbeitskollegen eine wichtige Gemeinschaft<\/b> und ein wichtiger Hafen, in dem sie sich geborgen und wohl f\u00fchlen wollen. Die Territorialk\u00e4mpfe, die sich bei der Einf\u00fchrung flexibler B\u00fcrokonzepte h\u00e4ufig ergeben, sind ein Ausdruck davon, wie stark der Arbeitsplatz auch ein St\u00fcck Heimat und Identit\u00e4t bedeutet. Nachdem die Microsoft Mitarbeiter w\u00e4hrend dem Umbau des Schweizerischen Headquarters drei Monate von zu Hause aus arbeiten mussten, sollen sich beim Bezug der neuer\u00f6ffneten R\u00e4ume r\u00fchrende Szenen abgespielt haben nachdem die Mitarbeiter ihre Gemeinschaft und ihre Arbeitsfamilie wieder hatten.<\/p>\n<p><b>Arbeiten aus dem Home-Office stellt h\u00f6here Anforderungen an die F\u00fchrungskultur.<\/b> Auf der sachlichen Ebene setzt es voraus, dass mit klaren Zielvereinbarungen gearbeitet und die Leistung nicht einfach aufgrund von Pr\u00e4senzzeiten beurteilt wird, was in vielen Unternehmen leider immer noch ungen\u00fcgend umgesetzt ist. Auf der emotionalen Ebene bedingt es, dass eine starke, positive Kultur entwickelt wird, die die Mitarbeiter einbindet und Verbundenheit, klare Visionen und Vertrauen schafft. Gerade bei den stark intrinsisch motivierten Leistungstr\u00e4gern wirkt zu viel Regulierung eher kontraproduktiv.<\/p>\n<p>Wie in vielem ist es also\u00a0 nicht eine Frage des entweder-oder, sondern eine des Masses und der konkreten Anwendung. Soll Heimarbeit gelingen, ist das Management gefordert, eine klare, starke Kultur und Vision zu entwickeln.<\/p>\n<p>(Dieser Artikel erschien am 14.4.2013 als Kolumne in der Zentralschweiz am Sonntag)<\/p>\n<p><strong>Vertiefende Links:<\/strong><\/p>\n<ul>\n<li><a href=\"http:\/\/www.teleworkresearchnetwork.com\/whitepapers\" target=\"_blank\">Telenetwork Research Network<\/a><\/li>\n<li><a href=\"http:\/\/blogs.hbr.org\/cs\/2012\/12\/physical_teams_in_an_increasin.html\" target=\"_blank\">Harward Business Review: In praise of Face Time<\/a><\/li>\n<li><a href=\"http:\/\/homeofficeday.files.wordpress.com\/2011\/05\/ratgeber_zwischen-produktivitc3a4t-und-lebensqualitc3a4t_herausforderungen-und-chancen-von-flexiblen-arbeitsplatzmodellen.pdf\">Ratgeber: Zwischen Produktivit\u00e4t und Lebensqualit\u00e4t: Herausforderungen und Chancen<\/a><\/li>\n<li><a href=\"http:\/\/www.stanford.edu\/~nbloom\/WFH.pdf\" target=\"_blank\">Does working from home work?<\/a> Studie Standford University.<\/li>\n<li><a href=\"http:\/\/www.bc.edu\/content\/dam\/files\/centers\/cwf\/research\/publications\/pdf\/BCCWF_Telecommuting_Paper.pdf\" target=\"_blank\">Bringing Work home: Advantages and Challenges of Telecommuting<\/a><\/li>\n<li><a href=\"http:\/\/www.citrix.com\/news\/announcements\/jun-2012\/workplace-survey-reveals-surprises-about-traditional-office-life-working-from-home.html\" target=\"_blank\">Studie zum Verhalten von Home-Office-Workers von Citrix\/Wakefield<\/a><\/li>\n<li><a href=\"http:\/\/www.businessnewsdaily.com\/3522-working-from-home-means-longer-hours.html\" target=\"_blank\">Working from Home means longer hours<\/a><\/li>\n<li><a href=\"http:\/\/www.bls.gov\/opub\/mlr\/2012\/06\/art3full.pdf\" target=\"_blank\">The hard truth about telecommuting<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete Telearbeit von zu Hause abschaffte. Prompt hat sie damit nicht nur bei den eigenen Mitarbeitern, sondern auch in den globalen Medien einen Sturm der Entr\u00fcstung ausgel\u00f6st. In einer Branche, die sich an<\/p>\n","protected":false},"author":966,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[64351,4002],"class_list":["post-1073","post","type-post","status-publish","format-standard","hentry","category-alte-beitraege","tag-corporate-real-estate","tag-trends"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilienblog Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2013-04-14T03:57:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child-300x156.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office?\",\"datePublished\":\"2013-04-14T03:57:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/\"},\"wordCount\":772,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/04\\\/computer_notebook_woman_baby_mother_child-300x156.jpg\",\"keywords\":[\"Corporate Real Estate\",\"Trends\"],\"articleSection\":[\"Archiv\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/\",\"name\":\"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/04\\\/computer_notebook_woman_baby_mother_child-300x156.jpg\",\"datePublished\":\"2013-04-14T03:57:33+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete\",\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/04\\\/14\\\/zuruck-ins-buro-das-ende-des-home-office\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/04\\\/computer_notebook_woman_baby_mother_child.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/04\\\/computer_notebook_woman_baby_mother_child.jpg\",\"width\":650,\"height\":340},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/\",\"name\":\"Immobilienblog Hochschule Luzern\",\"description\":\"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern","description":"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/","og_locale":"de_DE","og_type":"article","og_title":"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern","og_description":"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete","og_url":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/","og_site_name":"Immobilienblog Hochschule Luzern","article_published_time":"2013-04-14T03:57:33+00:00","og_image":[{"url":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child-300x156.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/"},"author":{"name":"","@id":""},"headline":"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office?","datePublished":"2013-04-14T03:57:33+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/"},"wordCount":772,"commentCount":2,"image":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child-300x156.jpg","keywords":["Corporate Real Estate","Trends"],"articleSection":["Archiv"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/","url":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/","name":"Zur\u00fcck ins B\u00fcro! Das Ende des Home-Office? - Immobilienblog Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child-300x156.jpg","datePublished":"2013-04-14T03:57:33+00:00","author":{"@id":""},"description":"Anfang Jahr sorgte die neue Yahoo-Chefin Marissa Mayer weltweit f\u00fcr Aufsehen, indem sie die Mitarbeiter zur\u00fcck ins B\u00fcro beorderte und die weit verbreitete","inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/04\/14\/zuruck-ins-buro-das-ende-des-home-office\/#primaryimage","url":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child.jpg","contentUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/04\/computer_notebook_woman_baby_mother_child.jpg","width":650,"height":340},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website","url":"https:\/\/hub.hslu.ch\/immobilienblog\/","name":"Immobilienblog Hochschule Luzern","description":"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/immobilienblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":""}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"","author_link":"https:\/\/hub.hslu.ch\/immobilienblog\/author\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/users\/966"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":8,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"predecessor-version":[{"id":1081,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1073\/revisions\/1081"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}