{"id":1123,"date":"2013-05-26T05:00:11","date_gmt":"2013-05-26T03:00:11","guid":{"rendered":"https:\/\/hub.hslu.ch\/immobilienblog\/?p=1123"},"modified":"2013-05-25T14:32:12","modified_gmt":"2013-05-25T12:32:12","slug":"die-welt-ist-keine-scheibe","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/","title":{"rendered":"Die Welt ist keine Scheibe!"},"content":{"rendered":"<p><b>\u201eThe world is flat\u201c<\/b> war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den M\u00f6glichkeiten des Datenaustausches und Teleconferencings, dem Fall der Berliner Mauer, den sich ausbreitenden Freihandelsabkommen und den laufend besseren Verkehrsverbindungen die Geographie in Zukunft irrelevant sei. Weil jeder Punkt der Erde mit jedem anderen virtuell verbunden, Information jederzeit \u00fcberall verf\u00fcgbar und auch der G\u00fctertransport immer schneller und g\u00fcnstiger sei, k\u00e4me es nicht mehr darauf an, wo Personen oder Firmen stationiert seien, da sie jederzeit und \u00fcberall am globalen Austausch- und Arbeitsprozess teilnehmen k\u00f6nnten. Die Welt w\u00fcrde damit \u201eflach\u201c, alle Standorte h\u00e4tten gleiche Chancen im globalen Wettbewerb.<\/p>\n<p><b><a href=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-1124\" alt=\"worldisFlat_jacket1\" src=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg\" width=\"155\" height=\"241\" \/><\/a><\/b><\/p>\n<p><b>Wie viele Programmierer kennen Sie<\/b>, die ins Val M\u00fcstair gezogen sind, sich von der Natur inspirieren lassen und gleichzeitig, mit der ganzen Welt vernetzt, bahnbrechende Software schreiben? Wie viele Werber lassen sich in der Provence von der Muse k\u00fcssen und liefern ihren Kunden in Paris umwerfende Kampagnen ab?<\/p>\n<p><b>Interessanterweise ist das Gegenteil eingetroffen.<\/b> Die regionalen Unterschiede in der Welt haben sich eher verst\u00e4rkt. Sowohl in Bezug auf die Wirtschaftsleistung als auch auf die Innovationskraft sind erstaunlich wenige Regionen global tats\u00e4chlich relevant . 85% aller Patente entfallen auf nur 5 L\u00e4nder. Nicht etwa, dass Inder und Chinesen nicht innovativ w\u00e4ren: rund 30% der Silicon-Valley Startups werden von ihnen gegr\u00fcndet, aber eben: nicht bei sich zu Hause, sondern im kreativen, gut vernetzten \u00d6kosystem an der amerikanischen Westk\u00fcste, wo sie in einem innovativen Umfeld Zugang zu interessanten Leuten spannenden Ideen und ausreichend Kapital haben.<\/p>\n<p><b>Trotz aller technischer M\u00f6glichkeiten<\/b> ist eine Konzentration von gut ausgebildeten, kreativen, talentierten einsatzbereiten Leuten (der sogenannten \u201eCreative Class\u201c) wichtig f\u00fcr Innovation und wirtschaftlichen Erfolg. Ideen, Produkte, Gesch\u00e4fte entstehen dort, wo diese Personen in ausreichender Menge und Dichte vorhanden sind und intensiv miteinander interagieren k\u00f6nnen. Eine relativ geringe Anzahl von f\u00fchrenden Stadtregionen wie London \u2013 New York \u2013 San Francisco &#8211; Paris \u2013 Singapur \u2013 Seoul &#8211; Hong Kong und weitere sind eng miteinander vernetzt und dominieren die Weltwirtschaft. Solche Zentren sind nicht nur deshalb wichtig, weil die Leute gerne mit ihresgleichen interagieren, sondern auch wegen den grossen Produktivit\u00e4tsvorteilen, die sich durch diese Clusterbildung ergeben.<\/p>\n<p><b>Firmen wie Google<\/b>, Microsoft und Walt Disney haben wichtige Ableger in Z\u00fcrich, weil sie dort gen\u00fcgen globale High Performers finden und die richtigen Voraussetzungen, um weitere anzuziehen: hervorragende Universit\u00e4ten, hohe Lebensqualit\u00e4t, Offenheit f\u00fcr fremde Kulturen, einen urbanen, mond\u00e4nen \u201eGroove\u201c, verbunden mit hohem Freizeitwert und globaler Anbindung, dazu ein Umfeld, das es ihnen einfach macht, ihr Gesch\u00e4ft zu f\u00fchren. Und je mehr solche Personen und Firmen sich hier wohl f\u00fchlen, desto mehr Neue kommen dazu!<\/p>\n<p><b>Andererseits findet ein Grossteil<\/b> der wirtschaftlichen und sozialen Aktivit\u00e4ten nach wie vor lokal und regional statt. Eltweit sind rund 80% aller Telefonanrufe immer noch Lokalgespr\u00e4che. Mehr und mehr gibt es zwei Ebenen in Gesellschaft und Wirtschaft: die lokale und die globale. Der Unterschied von einem polyglotten \u00a0Z\u00fcrcher zu einem Entlebucher ist gr\u00f6sser als derjenige zu einem Londoner, die Chance, gesch\u00e4ftlich oder privat nach Singapur zu fliegen gr\u00f6sser als die, ins Val Mustair zu fahren.<\/p>\n<p><b>Eine grosse Herausforderung<\/b> f\u00fcr die Zukunft sowohl global als auch in der Schweiz wird es sein, diese beiden Ebenen zu harmonisieren. Die eine kann ohne die andere nicht existieren. Die global wettbewerbsf\u00e4higen Orte zu st\u00e4rken, ohne die lokale Wirtschaft zu schw\u00e4chen. F\u00fcr die internationalen kreativen High Performers attraktiv zu sein ohne die Wurzeln der eigenen Kultur zu besch\u00e4digen.<\/p>\n<p><b>Die Diskussionen \u00fcber \u201eStadtlandschaft Schweiz\u201c<\/b> oder \u201eD\u00f6rfli-Land\u201c zielen ins Leere. Richtig sind lokal angepasste L\u00f6sungen: In den St\u00e4dten durch quantitative und qualitative Verdichtung urbanen, kreativen Geist zu verst\u00e4rken, auf dem Land Freir\u00e4ume, Natur und Erholungszonen zu erhalten. Und daf\u00fcr zu sorgen, dass wir die Rahmenbedingung f\u00fcr global t\u00e4tige Firmen und High Performers weiter st\u00e4rken, statt, wie mit einigen anstehenden Initiativen, mutwillig zu besch\u00e4digen. Davon profitieren letztlich auch der Schreiner in Sempach und der B\u00e4cker in Rotkreuz.<\/p>\n<p>(Dieser Beitrag erschien am 26.5.2013 als Kolumne in der &#171;Zentralschweiz am Sonntag&#187;)<\/p>\n<p>Vertiefende Informationen:<\/p>\n<ul>\n<li><span style=\"line-height: 13px\">Richard Florida: <a href=\"http:\/\/www.creativeclass.com\" target=\"_blank\">Creative Class<\/a><\/span><\/li>\n<li>Arthur D. Little: <a href=\"http:\/\/www.adlittle.ch\/uploads\/tx_extthoughtleadership\/ADL_Headquarters_on_the_Move.pdf\" target=\"_blank\">Headquarters on the Move.<\/a><\/li>\n<li>Greater Zurich Area Insight:\u00a0<a href=\"http:\/\/www.greaterzuricharea.ch\/default.asp?mde=dld&amp;fnm=content\/01\/downloads\/gza_insight022008de.pdf\" target=\"_blank\">Wieso zieht Disney nach Z\u00fcrich?<\/a><\/li>\n<li>Avenir Suisse: <a href=\"http:\/\/www.avenir-suisse.ch\/25447\/die-schweiz-als-stadtlandschaft\/\" target=\"_blank\">Die Schweiz als Stadtlandschaft<\/a><\/li>\n<\/ul>\n<p><strong>Das\u00a0<\/strong><strong>k\u00f6nnte Sie ebenfalls interessieren:<br \/>\n<\/strong>Entdecken Sie die\u00a0<a href=\"http:\/\/immobilien.hslu.ch\/\" target=\"_blank\">Wel<\/a><a href=\"http:\/\/immobilien.hslu.ch\/\" target=\"_blank\">t des Immobilienmanagements<\/a>\u00a0und erfahren Sie alles Wissenswerte rund um den\u00a0<a href=\"http:\/\/www.weiterbildung.hslu.ch\/wirtschaft\/finanzdienstleistungen\/kurs.asp?kid=1679&amp;m=10\" target=\"_blank\">MAS Immobilienmanagement<\/a>\u00a0und andere Angebote zum Thema\u00a0<a title=\"Interview\" href=\"http:\/\/www.youtube.com\/watch?feature=player_embedded&amp;v=w1-6QWCWklM\" target=\"_blank\">Immobilien<\/a>. Gerne beantworten Ihnen\u00a0<a href=\"http:\/\/www.hslu.ch\/wirtschaft\/w-outside-navigation\/ifz\/w-ifz-ueber-uns\/w-ifz-person.htm?id_person=1011614&amp;id_teilschule=25650&amp;row=0\" target=\"_blank\">Prof. Dr. Markus Schmidiger<\/a>\u00a0oder\u00a0<a href=\"http:\/\/www.hslu.ch\/wirtschaft\/w-outside-navigation\/ifz\/w-ifz-ueber-uns\/w-ifz-person.htm?id_person=1124916&amp;id_teilschule=25650&amp;row=0\" target=\"_blank\">Prof. Dr. John Davidson\u00a0<\/a>vom\u00a0<a href=\"http:\/\/www.hslu.ch\/ifz\" target=\"_blank\">IFZ\u00a0<\/a>Ihre Fragen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den M\u00f6glichkeiten des Datenaustausches und Teleconferencings, dem Fall der Berliner Mauer, den sich ausbreitenden Freihandelsabkommen und den laufend besseren Verkehrsverbindungen die Geographie in Zukunft irrelevant sei. Weil jeder Punkt der Erde mit jedem<\/p>\n","protected":false},"author":966,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[1],"tags":[12594,7117,7084],"class_list":["post-1123","post","type-post","status-publish","format-standard","hentry","category-alte-beitraege","tag-immobilienmarkt","tag-raumplanung","tag-real-estate-investment"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilienblog Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2013-05-26T03:00:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Die Welt ist keine Scheibe!\",\"datePublished\":\"2013-05-26T03:00:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/\"},\"wordCount\":769,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/05\\\/worldisFlat_jacket1.jpg\",\"keywords\":[\"Immobilienmarkt\",\"Raumplanung\",\"Real Estate Investment\"],\"articleSection\":[\"Archiv\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/\",\"name\":\"Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/05\\\/worldisFlat_jacket1.jpg\",\"datePublished\":\"2013-05-26T03:00:11+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den\",\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/2013\\\/05\\\/26\\\/die-welt-ist-keine-scheibe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/05\\\/worldisFlat_jacket1.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/wp-content\\\/blogs.dir\\\/443\\\/files\\\/sites\\\/9\\\/2013\\\/05\\\/worldisFlat_jacket1.jpg\",\"width\":155,\"height\":241},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/\",\"name\":\"Immobilienblog Hochschule Luzern\",\"description\":\"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern","description":"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/","og_locale":"de_DE","og_type":"article","og_title":"Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern","og_description":"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den","og_url":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/","og_site_name":"Immobilienblog Hochschule Luzern","article_published_time":"2013-05-26T03:00:11+00:00","og_image":[{"url":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/"},"author":{"name":"","@id":""},"headline":"Die Welt ist keine Scheibe!","datePublished":"2013-05-26T03:00:11+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/"},"wordCount":769,"commentCount":1,"image":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg","keywords":["Immobilienmarkt","Raumplanung","Real Estate Investment"],"articleSection":["Archiv"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/","url":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/","name":"Die Welt ist keine Scheibe! - Immobilienblog Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg","datePublished":"2013-05-26T03:00:11+00:00","author":{"@id":""},"description":"\u201eThe world is flat\u201c war 2005 der Titel eines aufsehenerregenden Buches von Thomas Friedman. Er proklamierte, dass mit der Etablierung des Internets, den","inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/2013\/05\/26\/die-welt-ist-keine-scheibe\/#primaryimage","url":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg","contentUrl":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-content\/blogs.dir\/443\/files\/sites\/9\/2013\/05\/worldisFlat_jacket1.jpg","width":155,"height":241},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website","url":"https:\/\/hub.hslu.ch\/immobilienblog\/","name":"Immobilienblog Hochschule Luzern","description":"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/immobilienblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":""}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"","author_link":"https:\/\/hub.hslu.ch\/immobilienblog\/author\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/users\/966"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/comments?post=1123"}],"version-history":[{"count":4,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1123\/revisions"}],"predecessor-version":[{"id":1126,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts\/1123\/revisions\/1126"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/media?parent=1123"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/categories?post=1123"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/tags?post=1123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}