{"id":121105,"count":3,"description":"","link":"https:\/\/hub.hslu.ch\/immobilienblog\/tag\/digitalisierungsbarometer\/","name":"Digitalisierungsbarometer","slug":"digitalisierungsbarometer","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/immobilienblog\/tag\/digitalisierungsbarometer\/\" \/>\n<meta property=\"og:site_name\" content=\"Immobilienblog Hochschule Luzern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/tag\\\/digitalisierungsbarometer\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/tag\\\/digitalisierungsbarometer\\\/\",\"name\":\"Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/\",\"name\":\"Immobilienblog Hochschule Luzern\",\"description\":\"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/immobilienblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern","og_url":"https:\/\/hub.hslu.ch\/immobilienblog\/tag\/digitalisierungsbarometer\/","og_site_name":"Immobilienblog Hochschule Luzern","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/tag\/digitalisierungsbarometer\/","url":"https:\/\/hub.hslu.ch\/immobilienblog\/tag\/digitalisierungsbarometer\/","name":"Digitalisierungsbarometer Archive - Immobilienblog Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website"},"inLanguage":"de-CH"},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/immobilienblog\/#website","url":"https:\/\/hub.hslu.ch\/immobilienblog\/","name":"Immobilienblog Hochschule Luzern","description":"Immobilienmanagement am Institut f\u00fcr Finanzdienstleistungen Zug - IFZ","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/immobilienblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/tags\/121105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/immobilienblog\/wp-json\/wp\/v2\/posts?tags=121105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}