{"id":18242,"date":"2022-11-25T09:04:00","date_gmt":"2022-11-25T08:04:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/informatik\/?p=18242"},"modified":"2026-02-10T10:25:24","modified_gmt":"2026-02-10T09:25:24","slug":"tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/","title":{"rendered":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\"><\/h3>\n\n\n\n<p><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3964\" target=\"_blank\" rel=\"noreferrer noopener\">Bj\u00f6rn N\u00e4f<\/a>, Sie sagen, neue Technologien forderten Software-Entwickelnde enorm heraus \u2013 bis hin zur \u00dcberforderung. Was tun?<\/strong><\/p>\n\n\n\n<p>Der Beruf war schon immer begleitet von (r)evolution\u00e4ren Ver\u00e4nderungen. Neu ist die Kraft der aktuellen Technologiewende: Tech-Trends wie Blockchain, K\u00fcnstliche Intelligenz, Internet of Everything oder Quantum- und Edge-Computing ver\u00e4ndern in der Summe viele Arbeitsbereiche von Entwicklerinnen und Entwicklern. Das erfordert neue F\u00e4higkeiten und Prozesse. Bew\u00e4hrte Arbeitsweisen werden dadurch radikal verdr\u00e4ngt. So ist es je nach Gebiet n\u00f6tig, sich beruflich neu auszurichten. Dadurch m\u00fcssen wir uns stetig weiterbilden, beispielsweise autodidaktisch mittels Online-Tutorials oder mithilfe einer Weiterbildung.<\/p>\n\n\n\n<p><strong>Programmiererinnen und Programmierer mussten immer schon neue Sprachen und Tools lernen. Was ist heute so herausfordernd?<\/strong><\/p>\n\n\n\n<p>Zum einen hat sich die Evolution beschleunigt: Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Der Fachkr\u00e4ftemangel ist tr\u00fcgerisch. Langj\u00e4hrig t\u00e4tige Software-Entwickelnde haben nicht per se eine gr\u00f6ssere Auswahl an vakanten Stellen, weil die Profile zunehmend spezifischer werden.<\/p>\n<\/blockquote>\n\n\n\n<p>Zum anderen befindet sich das Berufsfeld im Wandel. Wo es fr\u00fcher noch gen\u00fcgte, etwas zu \u00abk\u00f6nnen\u00bb, also etwa eine bestimmte Programmiersprache zu beherrschen, m\u00fcssen Entwicklerinnen und Entwickler heutzutage gleichzeitig immer mehr \u00abkennen\u00bb, und zwar nicht nur oberfl\u00e4chlich, sondern fundiert. Sie m\u00fcssen wissen, welche Ans\u00e4tze und Technologien gerade gehypt werden. Und (mit-)entscheiden k\u00f6nnen, wann es Zeit ist, auf eine andere Technologie zu wechseln.<\/p>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-accordion gb-block-accordion\"><details><summary class=\"gb-accordion-title\"><strong>So hat sich die Software-Entwicklung in den letzten zehn bis 20 Jahren ver\u00e4ndert.<\/strong> <\/summary><div class=\"gb-accordion-text\">\n<p>Wir beobachten Ver\u00e4nderungen auf drei Ebenen: bei den Technologien, bei den Prozessen und Organisationsformen sowie beim Markt.<\/p>\n\n\n\n<p><strong>Technologie: <\/strong>Die Software-Entwicklung war schon immer gleichzeitig Treiberin und Nutzniesserin von Neuerungen wie Programmiersprachen, Frameworks oder Tools. In den letzten zehn Jahren beobachten wir aber eine beschleunigte Evolution: Technologien und Anwendungen werden immer kurzlebiger und m\u00fcssen stetig angepasst werden.<\/p>\n\n\n\n<p><strong>Prozessmodelle:<\/strong> Agile Prozessmodelle haben die Vorgehensweisen bei der Software-Entwicklung revolutioniert. In den letzten Jahren haben sie auch die Organisationsstruktur von Unternehmen ver\u00e4ndert. Selbst Grosskonzerne sind heute \u00abagil\u00bb organisiert und funktionieren \u2013 zumindest auf dem Papier \u2013 nach den Grundprinzipien der Software-Entwicklung. Die Software-Entwicklung hat den agilen Wandel am st\u00e4rksten durchlebt. Prozesse und Strukturen in Softwarefirmen funktionieren heute meist diametral anders als noch vor zwanzig Jahren. Dementsprechend brauchen sowohl Entwickelnde als auch F\u00fchrungspersonen andere Hard und Soft Skills als fr\u00fcher.<\/p>\n\n\n\n<p><strong>Markt: <\/strong>Auf der Anbieterseite schiessen Firmen mit Softwarekontext regelrecht aus dem Boden: Ob Sie Auto oder Zug fahren, eine Kaffeemaschine bedienen, Eink\u00e4ufe bezahlen oder im Spital liegen \u2013 \u00fcberall sind Computerprogramme im Einsatz, die irgendwer entwickeln, betreiben und warten muss. Dadurch entstehen immer neue Stellenprofile und diese Jobs m\u00fcssen besetzt werden. Der oft zitierte Fachkr\u00e4ftemangel ist allerdings tr\u00fcgerisch, denn langj\u00e4hrig t\u00e4tige Software-Entwickelnde haben nicht per se eine gr\u00f6ssere Auswahl an vakanten Stellen, weil die Profile zunehmend spezifischer werden.<\/p>\n<\/div><\/details><\/div>\n\n\n\n<p><strong>Wo sehen Sie die Software-Entwicklung in zehn Jahren?<\/strong><\/p>\n\n\n\n<p>Die aktuellen Trends werden sich nicht nur fortsetzen, sondern verst\u00e4rken. Allen voran hat die K\u00fcnstliche Intelligenz die technologische Revolution schon l\u00e4ngst eingel\u00e4utet. Software, die sich selbstst\u00e4ndig weiterentwickelt und andere Software erstellt, ist kein dystopisches M\u00e4rchen mehr.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Blockchain, K\u00fcnstliche Intelligenz, Internet of Everything oder Quantum- und Edge-Computing ver\u00e4ndern viele Arbeitsbereiche. Das erfordert neue F\u00e4higkeiten und Prozesse.<\/p>\n<\/blockquote>\n\n\n\n<p>Grosse Player wie Google, Amazon, Microsoft und andere (vielleicht neue) werden ihre Marktf\u00fchrung weiter ausbauen. Sie werden mitbestimmen, welche Tech-Trends sich durchsetzen. Diese werden vielleicht noch disruptiver sein als heute. Softwareprofis werden viel mehr Kontextwissen brauchen, um Zusammenh\u00e4nge zu verstehen und unterschiedliche Konzepte und Services zielf\u00fchrend einsetzen zu k\u00f6nnen.<\/p>\n\n\n\n<p><strong>Welchen Einfluss hat die Internationalisierung der Berufswelt?<\/strong><\/p>\n\n\n\n<p>Der ausl\u00e4ndische Druck war und ist hoch. Programmierende in Litauen oder Indien arbeiten oft schneller als Entwickelnde aus der Schweiz. Insbesondere scheinen andere L\u00e4nder neue Tech-Trends deutlich schneller zu adaptieren \u2013 die Schweiz gibt sich eher abwartend als wegweisend. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Software, die sich selbstst\u00e4ndig weiterentwickelt und andere Software erstellt, ist kein dystopisches M\u00e4rchen mehr.<\/p>\n<\/blockquote>\n\n\n\n<p>Durch die technologischen Entwicklungen wird die internationale Konkurrenz gr\u00f6sser. Umso wichtiger ist es f\u00fcr Schweizer Softwareentwickelnde und -firmen, den technologischen Fortschritt proaktiv mitzugestalten, anstatt nur darauf zu reagieren. Zum Beispiel indem sie aktiv teilnehmen an internationalen Tech-Konferenzen, Communities oder Forschungsprojekten.<\/p>\n\n\n\n<p><strong>Was ist der Lohn f\u00fcr all die M\u00fche? Welche Chancen er\u00f6ffnen dir disruptiven Technologien in der Software-Entwicklung?<\/strong><\/p>\n\n\n\n<p>Wenn es uns gelingt, die neuen Technologien wertsteigernd zu nutzen, werden alle profitieren. Softwareentwicklerinnen und -entwickler werden weniger m\u00fcssige Routinearbeiten machen m\u00fcssen. Das schafft Raum f\u00fcr interessantere Aufgaben.<\/p>\n\n\n\n<p><em>Frage in die Runde: Welche Erfahrungen machen Sie in der Software-Entwicklung? <em>Wir freuen uns \u00fcber Kommentare.<\/em><\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Von Yasmin Billeter<br>Ver\u00f6ffentlicht: 25.11.2022<\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<figure id=\"attachment_12199\" aria-describedby=\"caption-attachment-12199\" style=\"width: 225px\" class=\"wp-caption alignright\"><a href=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjo\u0308rn-Na\u0308f-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12199\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjo\u0308rn-Na\u0308f-1-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjo\u0308rn-Na\u0308f-1-225x300.jpg 225w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjo\u0308rn-Na\u0308f-1.jpg 337w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-12199\" class=\"wp-caption-text\">Bj\u00f6rn N\u00e4f<\/figcaption><\/figure>\n<p><strong>Unser Experte f\u00fcr <\/strong><strong>Software-Entwicklung: <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3964\" target=\"_blank\" rel=\"noopener\">Bj\u00f6rn N\u00e4f<\/a> ist Senior wissenschaftlicher Mitarbeiter und Senior Wissenschaftlicher Mitarbeiter und Programmleiter an der Hochschule Luzern \u2013 Informatik. Er unterrichtet unter anderem in den Bereichen <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/smart-steps\/information-security-and-privacy\/\" target=\"_blank\" rel=\"noopener\">Cyber Security<\/a> und <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/technologies-and-methods\/cas-modern-software-engineering-development\/\" target=\"_blank\" rel=\"noopener\">Software Engineering &amp; Development.<\/a><\/p>\n<p><strong>Weiterkommen via Weiterbildung<\/strong>: Nachhaltig erfolgreich als Software Engineer.<\/p>\n<p><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/technologies-and-methods\/cas-modern-software-engineering-development\/\" target=\"_blank\" rel=\"noopener\"><strong>Im CAS Modern Software Engineering &amp; Development<\/strong><\/a><\/p>\n<p>Erfahren Sie, wie Sie die Trends in den Bereichen Cloud-Computing, Hyper Scaling, Multi-Platform Development, IoE \/ IoT und Blockchain gewinnbringend nutzen k\u00f6nnen.<\/p>\n<p><strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/digital-transformation\/cas-digital-architect\/\" target=\"_blank\" rel=\"noopener\">CAS Digital Architect<\/a><\/strong><\/p>\n<p>Diese Weiterbildung bietet einen fundierten Einstieg in die Arbeit von IT-Architektinnen und -Architekten. Sie lernen datengetriebenen L\u00f6sungen zu gestalten. Das praxisnahe Wissen und die Methoden k\u00f6nnen direkt innerhalb von digitalen Transformationsprojekten umgesetzt werden.<\/p>\n<p><strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/technologies-and-methods\/software-architectures\/\" target=\"_blank\" rel=\"noopener\">CAS Software Architecture<\/a><\/strong><\/p>\n<p>Was zeichnet eine moderne Architektur aus?<br \/>\nWie passen Agilit\u00e4t und Software-Architektur zusammen? Wie kann Software-Architektur m\u00f6glichst einfache und genaue Systeme unterst\u00fctzen? Mit diesen Fragen sind Sie sie in diesem Kurs richtig.<\/p>\n<p><strong>Besuchen Sie unsere (<\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/agenda\/veranstaltungen\/\" target=\"_blank\" rel=\"noopener\"><strong>Online-)Info-Veranstaltungen<\/strong><\/a><strong>!<\/strong><\/p>\n<p><strong>Welche Weiterbildung passt zu mir?<\/strong>\u00a0Der\u00a0<a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/weiterbildung\/weiterbildungs-konfigurator#\/\" target=\"_blank\" rel=\"noopener\">Weiterbildungs-Generator<\/a>\u00a0verschafft Ihnen den Durchblick.<\/p>\n<p><strong>Informatik-Blog abonnieren:<\/strong> In diesem Blog erfahren Sie mehr \u00fcber Trends aus der Welt der Informatik. Wir bieten Einsichten in unser Departement und Portr\u00e4ts von IT-Vordenkerinnen, Vision\u00e4ren und spannenden Menschen: Jetzt <a href=\"https:\/\/hub.hslu.ch\/informatik\/#newsletter\" target=\"_blank\" rel=\"noopener\">abonnieren.<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser  wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke.<\/p>\n","protected":false},"author":4,"featured_media":18246,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"2565,15449,13591,574,10558,2988","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[392493,134],"tags":[653433,653541],"class_list":["post-18242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-software-engineering","category-weiterbildung","tag-lebenslanges-lernen","tag-software-engineering"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatik an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-25T08:04:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T09:25:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yasmin Billeter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weitertanzen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmin Billeter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/\"},\"author\":{\"name\":\"Yasmin Billeter\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"headline\":\"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb\",\"datePublished\":\"2022-11-25T08:04:00+00:00\",\"dateModified\":\"2026-02-10T09:25:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/\"},\"wordCount\":784,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg\",\"keywords\":[\"Lebenslanges Lernen\",\"Software Engineering\"],\"articleSection\":[\"Software Engineering\",\"Weiterbildung\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/\",\"name\":\"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg\",\"datePublished\":\"2022-11-25T08:04:00+00:00\",\"dateModified\":\"2026-02-10T09:25:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"description\":\"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg\",\"width\":2048,\"height\":1365,\"caption\":\"Die Software-Entwicklung ist im Laufe der Jahre immer komplexer geworden. Stetige technologische Wandel und neue Werkzeuge fordern Entwickelnde heraus. (Bild: Yanalya auf Freepik)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\",\"name\":\"Informatik an der Hochschule Luzern\",\"description\":\"Der offizielle Blog der Hochschule Luzern \u2013 Informatik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\",\"name\":\"Yasmin Billeter\",\"description\":\"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yasmin-billeter\\\/\",\"https:\\\/\\\/x.com\\\/weitertanzen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern","description":"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/","og_locale":"de_DE","og_type":"article","og_title":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern","og_description":"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %","og_url":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/","og_site_name":"Informatik an der Hochschule Luzern","article_published_time":"2022-11-25T08:04:00+00:00","article_modified_time":"2026-02-10T09:25:24+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","type":"image\/jpeg"}],"author":"Yasmin Billeter","twitter_card":"summary_large_image","twitter_creator":"@weitertanzen","twitter_misc":{"Geschrieben von":"Yasmin Billeter","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/"},"author":{"name":"Yasmin Billeter","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"headline":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb","datePublished":"2022-11-25T08:04:00+00:00","dateModified":"2026-02-10T09:25:24+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/"},"wordCount":784,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","keywords":["Lebenslanges Lernen","Software Engineering"],"articleSection":["Software Engineering","Weiterbildung"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/","url":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/","name":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb - Informatik an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","datePublished":"2022-11-25T08:04:00+00:00","dateModified":"2026-02-10T09:25:24+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"description":"Immer mehr Software-Entwickelnde und -Firmen sind \u00fcberfordert, sagt unser wissenschaftliche Mitarbeiter Bj\u00f6rn N\u00e4f. Sie m\u00fcssen sich stets mit aktuellen Tech-Trends auseinandersetzen und Neues dazulernen. Wer nicht am Ball ist, bleibt eher fr\u00fcher als sp\u00e4ter auf der Strecke. %","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#primaryimage","url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","contentUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","width":2048,"height":1365,"caption":"Die Software-Entwicklung ist im Laufe der Jahre immer komplexer geworden. Stetige technologische Wandel und neue Werkzeuge fordern Entwickelnde heraus. (Bild: Yanalya auf Freepik)"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/informatik\/tech-trends-in-der-software-entwicklung-viele-sind-uberfordert-architecture-engineering-development\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/informatik\/"},{"@type":"ListItem","position":2,"name":"Tech-Trends in der Software-Entwicklung: \u00abViele sind \u00fcberfordert\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/informatik\/#website","url":"https:\/\/hub.hslu.ch\/informatik\/","name":"Informatik an der Hochschule Luzern","description":"Der offizielle Blog der Hochschule Luzern \u2013 Informatik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/informatik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f","name":"Yasmin Billeter","description":"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.","sameAs":["https:\/\/www.linkedin.com\/in\/yasmin-billeter\/","https:\/\/x.com\/weitertanzen"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/young-serious-employee-focused-on-computer-work-in-multiracial-office.jpg","author_info":{"display_name":"Yasmin Billeter","author_link":"https:\/\/hub.hslu.ch\/informatik\/author\/yasminbilleter\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/18242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/comments?post=18242"}],"version-history":[{"count":35,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/18242\/revisions"}],"predecessor-version":[{"id":26613,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/18242\/revisions\/26613"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media\/18246"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media?parent=18242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/categories?post=18242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/tags?post=18242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}