{"id":28482,"date":"2026-09-02T07:55:00","date_gmt":"2026-09-02T05:55:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/informatik\/?p=28482"},"modified":"2026-09-02T08:20:12","modified_gmt":"2026-09-02T06:20:12","slug":"robotik-menschen-und-roboter-werden-enger-zusammenarbeiten","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/","title":{"rendered":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em><a href=\"https:\/\/hub.hslu.ch\/informatik\/tag\/prognosen-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zukunftsserie \u00ab10 Jahre voraus\u00bb<\/a>: Teil 8<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Industrieroboter arbeiten bereits seit Jahrzehnten in Fabriken. Meist folgen sie fest programmierten Abl\u00e4ufen und bleiben in klar abgegrenzten Bereichen. KI sowie humanoide und mobile Roboter ver\u00e4ndern dieses Szenario grundlegend: Sie erfassen ihre Umgebung besser, passen sich neuen Situationen an und arbeiten enger mit Menschen zusammen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Robotik-Experte Bj\u00f6rn Jensen sieht darin eine der wichtigsten Entwicklungen der kommenden Jahre. Der Leiter des AI Robotics Lab der Hochschule Luzern \u2013 Informatik forscht daran, wie solche Systeme sicher und zuverl\u00e4ssig funktionieren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Interview spricht er \u00fcber Roboter in Spit\u00e4lern und Betrieben, die Zusammenarbeit von Mensch und Maschine \u2013 und dar\u00fcber, wo wir technischen M\u00f6glichkeiten Grenzen setzen sollten.<\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Mehr \u00fcber die HSLU-Serie \u00ab10 Jahre voraus\u00bb<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Im September 2026 feiert die HSLU \u2013 Informatik ihr <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/agenda\/veranstaltungen\/10-jahre-informatik\/\" target=\"_blank\" rel=\"noreferrer noopener\">10-Jahre-Jubil\u00e4um<\/a>. Aus diesem Anlass blicken unsere Expertinnen und Experten in einer <a href=\"https:\/\/hub.hslu.ch\/informatik\/tag\/prognosen-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">mehrteiligen Serie<\/a> zehn Jahre voraus. Was ver\u00e4ndert sich gerade, das viele noch untersch\u00e4tzen? Welche Technologien k\u00f6nnten unseren Alltag in zehn Jahren pr\u00e4gen? Und welches heute noch k\u00fchne Szenario k\u00f6nnte Realit\u00e4t werden? Im Fokus stehen folgende Fachgebiete:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/sicherheit-von-anfang-an-secure-by-design-wird-zur-neuen-norm\/\" target=\"_blank\" rel=\"noreferrer noopener\">Cyber Security<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/mehr-als-ein-werkzeug-kuenstliche-intelligenz-wird-zur-persoenlichen-begleiterin\/\" target=\"_blank\" rel=\"noreferrer noopener\">K\u00fcnstliche Intelligenz<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/immersive-technologien-raumliches-computing-und-ki-wachsen-zusammen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immersive&nbsp;Realities<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/iot-und-edge-bis-ins-all-vernetzte-systeme-lernen-dazu\/\" target=\"_blank\" rel=\"noreferrer noopener\">Internet of Things (IoT)<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/informatikausbildung-ki-erweitert-den-gestaltungsraum\/\" target=\"_blank\" rel=\"noreferrer noopener\">Zukunft der Lehre und Informatikausbildung<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/wahlmoeglichkeiten-behalten-wie-die-schweiz-digital-selbstbestimmt-bleibt\/\" target=\"_blank\" rel=\"noreferrer noopener\">Datensouver\u00e4nit\u00e4t<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/blockchain-der-zukunft-vertrauen-in-digitale-dienste-staerken\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blockchain<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/\" target=\"_blank\" rel=\"noreferrer noopener\">Robotik<\/a><\/li>\n<\/ul>\n<\/details>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb-profile-columns\" style=\"background-color:#f2f2f2;color:#32373c\"><div class=\"gb-profile-column gb-profile-avatar-wrap\"><div class=\"gb-profile-image-wrap\"><figure class=\"gb-profile-image-square\"><img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"449\" class=\"gb-profile-avatar wp-image-28485\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjoern-Jensen.jpg\" alt=\"Portr\u00e4t von B\u00f6rn Jensen\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjoern-Jensen.jpg 337w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Bjoern-Jensen-225x300.jpg 225w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/figure><\/div><\/div><div class=\"gb-profile-column gb-profile-content-wrap\"><h2 class=\"gb-profile-name\" style=\"color:#32373c\">Prof. Dr. <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3528\" target=\"_blank\" rel=\"noreferrer noopener\">Bj\u00f6rn Jensen<\/a><\/h2><p class=\"gb-profile-title\" style=\"color:#32373c\"><\/p><div class=\"gb-profile-text\">Leitet das <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/labs\/ai-robotics\/\" target=\"_blank\" rel=\"noreferrer noopener\">AI Robotics Lab<\/a> der Hochschule Luzern \u2013 Informatik (HSLU) und lehrt Robotik. Er studierte Elektrotechnik mit Schwerpunkt Automation und Bildverarbeitung sowie Wirtschaftsingenieurwesen an der Technischen Universit\u00e4t Darmstadt. Anschliessend forschte er an der \u00c9cole polytechnique f\u00e9d\u00e9rale de Lausanne (EPFL) und promovierte dort zur Zusammenarbeit zwischen Menschen und Robotern.<\/div><ul class=\"gb-social-links\"><\/ul><\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Herr Jensen, welche Entwicklung in Ihrem Fachgebiet sollten wir heute ernst nehmen?<\/strong> <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir untersch\u00e4tzen das Potenzial und die M\u00f6glichkeiten, die sich aus der Verbindung von KI und Robotik ergeben. Bei \u00abEmbodied AI\u00bb verbindet sich KI mit einem physischen System, etwa einem Roboter. Software, Hardware, KI und Robotik wachsen dadurch noch enger zusammen. Maschinen k\u00f6nnen autonomer handeln, komplexere Aufgaben bew\u00e4ltigen und enger mit Menschen zusammenarbeiten.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Embodied AI: Wie KI mit einem K\u00f6rper wahrnimmt und handelt<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">\u00abEmbodied AI\u00bb bezeichnet k\u00fcnstliche Intelligenz, die mit einem physischen System verbunden ist, etwa mit einem Roboter. Sie nimmt ihre Umgebung \u00fcber Kameras, Sensoren oder Mikrofone wahr. Dabei erfasst sie auch <a href=\"https:\/\/hub.hslu.ch\/informatik\/immersive-technologien-raumliches-computing-und-ki-wachsen-zusammen\/\" target=\"_blank\" rel=\"noreferrer noopener\">r\u00e4umliche Zusammenh\u00e4nge<\/a>: Wo befinden sich Menschen und Gegenst\u00e4nde? Wie sind sie zueinander angeordnet? Danach verarbeitet das System diese Informationen und leitet daraus Handlungen ab. Ein Roboter kann so Gegenst\u00e4nde erkennen, sich im Raum bewegen oder auf Ver\u00e4nderungen reagieren. Solche Systeme m\u00fcssen mit unvollst\u00e4ndigen Daten, unerwarteten Situationen und physikalischen Grenzen umgehen. Das macht ihre Entwicklung anspruchsvoll.<\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\">Wir bewegen uns weg von starren, vorprogrammierten Industrierobotern. An ihre Stelle treten anpassungsf\u00e4hige Systeme. Sie sollen sich auch in un\u00fcbersichtlichen menschlichen Umgebungen zurechtfinden und mit Menschen und ihrer Umgebung umgehen k\u00f6nnen.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Roboter werden ihre Umgebung besser erfassen und ihr Verhalten an die Situation anpassen.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Grosse multimodale Modelle verarbeiten verschiedene Arten von Informationen, etwa Sprache, Bilder und Sensordaten. Dadurch sollen Roboter r\u00e4umliche Zusammenh\u00e4nge und menschliche Absichten besser erfassen. Statt nur festgelegte Abl\u00e4ufe auszuf\u00fchren, k\u00f6nnen sie ihr Verhalten st\u00e4rker an die jeweilige Situation anpassen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Welche Anwendungen k\u00f6nnten Menschen in der Schweiz in den n\u00e4chsten zehn Jahren konkret nutzen?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Besonders wichtig wird die Interaktion zwischen Menschen und Robotern. Schon heute erkennen Systeme unsere Sprache oder Gesten. K\u00fcnftig sollen Roboter auch besser erfassen, was ein Mensch als N\u00e4chstes tun m\u00f6chte. So k\u00f6nnten sie gezielter unterst\u00fctzen und sicherer mit uns zusammenarbeiten. Ein Beispiel aus unserem Lab ist eine \u00abRobotic Scrub Nurse\u00bb: Da erkennt ein Roboter eine Geste und reicht der operierenden Person das gew\u00fcnschte Instrument. Ein solches intuitives Zusammenspiel ist auch in anderen Anwendungen, wie etwa bei Rettungseins\u00e4tzen oder in der industriellen Fertigung, relevant.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Forschung und konkrete Anwendungen verbinden: Das AI Robotics Lab<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Das <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/labs\/ai-robotics\/?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\">AI Robotics Lab<\/a> der Hochschule Luzern \u2013 Informatik verbindet k\u00fcnstliche Intelligenz mit Robotik. Bj\u00f6rn Jensen leitet das Lab. Sein Team erforscht, wie mehrere Roboter navigieren und wie Maschinen ihre Umgebung wahrnehmen. Es entwickelt gemeinsam mit Unternehmen L\u00f6sungen f\u00fcr Produktion und Logistik, mobile und kollaborative Roboter sowie Eins\u00e4tze in anspruchsvollen Umgebungen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch die Lehre geh\u00f6rt zum Lab: Es verantwortet den <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/informatik\/module\/major-ai-robotics\/\" target=\"_blank\" rel=\"noreferrer noopener\">Major AI Robotics im Bachelor Informatik<\/a>. So verbindet das Lab Forschung, Lehre und konkrete Anwendungen.<\/p>\n<\/details>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Welche Aufgaben k\u00f6nnten Roboter konkret in Betrieben und Einrichtungen \u00fcbernehmen?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In Spit\u00e4lern \u00fcbernehmen Roboter bereits einzelne Aufgaben. Sie lagern zum Beispiel Medikamente und verteilen sie. Mobile Roboter d\u00fcrften k\u00fcnftig h\u00e4ufiger Essen, Material, W\u00e4sche oder Abfall durch Geb\u00e4ude transportieren. So entlasten sie Mitarbeitende von langen Laufwegen. Ich hoffe, sie verschaffen ihnen so mehr Zeit f\u00fcr Aufgaben, bei denen es Menschen braucht.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Wir Menschen werden enger mit Robotern zusammenarbeiten.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Auch Hotels und Restaurants d\u00fcrften solche Systeme h\u00e4ufiger einsetzen. Dort \u00fcbernehmen Roboter bereits heute Transporte und zunehmend einfache, wiederkehrende Arbeiten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In der Kreislaufwirtschaft sortieren Roboter bereits Abf\u00e4lle. K\u00fcnftig k\u00f6nnten sie Materialien noch genauer erkennen und wiederverwendbare Teile gezielt weiterverarbeiten. Drohnen \u00fcbernehmen heute schon einzelne Transporte. In den n\u00e4chsten Jahren d\u00fcrften sie h\u00e4ufiger dringende Lieferungen ausf\u00fchren oder schwer zug\u00e4ngliche Orte versorgen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Welche hoffnungsvollen Zukunftsbilder diskutiert Ihre Fach-Community?<\/strong>&nbsp;<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">In der Robotik sprechen wir oft von den drei \u00abD\u00bb: dull, dirty und dangerous \u2013 also von eint\u00f6nigen, schmutzigen oder gef\u00e4hrlichen Arbeiten. Gerade im Gesundheitswesen, in der Landwirtschaft und in der Logistik k\u00f6nnen Roboter solche Aufgaben f\u00fcr Menschen \u00fcbernehmen.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Roboter \u00fcbernehmen gef\u00e4hrliche, monotone oder k\u00f6rperlich belastende Arbeiten.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Beispiel f\u00fcr gef\u00e4hrliche Eins\u00e4tze ist <a href=\"https:\/\/www.youtube.com\/watch?v=tXrsB4og_PU\" target=\"_blank\" rel=\"noreferrer noopener\">EnRicH<\/a>, ein europ\u00e4ischer Robotik-Hackathon f\u00fcr radiologische und nukleare Szenarien. Dort testen Forschungsteams zum Beispiel Roboter in realit\u00e4tsnahen nuklearen Szenarien. Sie suchen Strahlenquellen, erstellen Karten von schwer zug\u00e4nglichen Bereichen oder arbeiten mit radioaktivem Material.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU_Roboterhund_Tunnel_H264-1.mp4\"><\/video><figcaption class=\"wp-element-caption\"><em><strong>Roboter f\u00fcr die drei \u00abD\u00bb: dull, dirty, dangerous.<\/strong> Das HSLU-Video zeigt einen Roboterhund beim Einsatz in einem Tunnel. Solche mobilen Roboter k\u00f6nnen k\u00fcnftig dort helfen, wo Arbeiten eint\u00f6nig, schmutzig oder gef\u00e4hrlich sind \u2013 etwa in schwer zug\u00e4nglichen oder riskanten Umgebungen.<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Roboter \u00fcbernehmen zudem monotone oder k\u00f6rperlich belastende Arbeiten. Ich hoffe, dass Menschen dadurch mehr Zeit f\u00fcr Aufgaben gewinnen, bei denen Kreativit\u00e4t, Erfahrung und Urteilsverm\u00f6gen gefragt sind.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig lernen Menschen und Roboter immer besser, direkt zusammenzuarbeiten. Verbinden wir diese Entwicklung mit \u00abPhysical AI\u00bb, entstehen Arbeitspl\u00e4tze, an denen Roboter Menschen flexibel unterst\u00fctzen, statt nur fest programmierte Abl\u00e4ufe auszuf\u00fchren.<\/p>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Embodied AI, Physical AI, autonome Systeme: Was ist der Unterschied?<\/strong><\/summary>\n<ul class=\"wp-block-list\">\n<li><strong>Embodied AI<\/strong> verbindet KI mit einem physischen K\u00f6rper, etwa einem Roboter. Dieser K\u00f6rper ist Teil davon, wie das System seine Umgebung wahrnimmt, lernt und handelt.<\/li>\n\n\n\n<li><strong>Physical AI<\/strong> bezeichnet KI, die in der physischen Welt handelt und deren Gesetzm\u00e4ssigkeiten ber\u00fccksichtigt \u2013 etwa Bewegung, Kr\u00e4fte oder r\u00e4umliche Beziehungen. Der Begriff \u00fcberschneidet sich mit Embodied AI, setzt aber einen anderen Schwerpunkt.<\/li>\n\n\n\n<li><strong>Autonome Systeme<\/strong> k\u00f6nnen selbstst\u00e4ndig Entscheidungen treffen und handeln, ohne dass jeder einzelne Schritt vorgegeben ist. Dazu nutzen sie unter anderem KI. Beispiele sind autonome Roboter oder selbstfahrende Fahrzeuge.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz gesagt: Autonome Systeme handeln selbstst\u00e4ndig. Embodied AI verbindet KI mit einem K\u00f6rper. Physical AI betont das Handeln in und das Verstehen der physischen Welt.<\/p>\n<\/details>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Vertrauen entsteht nicht von selbst.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Welche kritischen Zukunftsbilder diskutiert die Fachwelt?&nbsp;<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Eine grosse Herausforderung ist die Sicherheit komplexer, lernender Robotersysteme. Klassische Robotersteuerungen beruhen stark auf mathematischen Modellen. Damit l\u00e4sst sich unter bestimmten Voraussetzungen berechnen und \u00fcberpr\u00fcfen, wie sich ein System verh\u00e4lt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei lernenden Systemen wird das schwieriger. Ein Roboter k\u00f6nnte zum Beispiel einen ungeeigneten Bewegungsweg berechnen oder eine Situation falsch einsch\u00e4tzen. Im gemeinsamen Arbeitsraum mit Menschen kann das gef\u00e4hrlich werden. Anders als bei einem gew\u00f6hnlichen Softwarefehler kann das Menschen unmittelbar k\u00f6rperlich gef\u00e4hrden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb brauchen wir neue Ans\u00e4tze, die lernende Systeme mit \u00fcberpr\u00fcfbaren Sicherheitsmechanismen verbinden. Daran forschen wir im Bereich \u00abPhysical AI\u00bb.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Wie reagieren Menschen auf die neuen Roboter-Kollegen?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Manche f\u00fcrchten, dass Roboter ihre Arbeit ersetzen. Andere st\u00f6rt, dass Kameras und Sensoren laufend Daten erfassen. Neue Robotersysteme funktionieren im Betrieb nur, wenn Mitarbeitende ihnen vertrauen k\u00f6nnen. Daf\u00fcr m\u00fcssen sie wissen, was die Roboter leisten und wo ihre Grenzen liegen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vertrauen entsteht nicht von selbst. Unternehmen m\u00fcssen die Mitarbeitenden fr\u00fch einbeziehen und offen informieren. Sie sollten ihnen zeigen, welchen konkreten Nutzen die Systeme im Arbeitsalltag bringen.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Wir m\u00fcssen uns fragen, was wir Robotern \u00fcberlassen wollen.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Was ist das verr\u00fcckteste Szenario, das eintreffen k\u00f6nnte?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mein Regelungstechnik-Professor tr\u00e4umte fr\u00fcher davon, dass eines Tages ein humanoider Roboter morgens in den Garten geht, eine gelbe Rose pfl\u00fcckt und sie seiner Frau \u00fcberreicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sp\u00e4ter haben wir an der EPFL dar\u00fcber philosophiert, ob man einen Roboter \u00fcberhaupt noch einfach abschalten darf, wenn er ein hohes Mass an Autonomie erreicht. Was, wenn er sich selbst und seine Umgebung zunehmend versteht? K\u00f6nnte ein solches System sogar ein Bewusstsein f\u00fcr das eigene Abschalten ausbilden? Vor rund 25 Jahren klang das noch stark nach Science-Fiction. Heute wirken solche Fragen deutlich weniger fern.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Vielleicht wird das sichere Abschalten k\u00fcnftig zu einer festen Anforderung bei der Entwicklung von Robotern.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Wie viel Science-Fiction wird gerade Wirklichkeit?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Viele Technologien, die damals noch weit entfernt schienen, sind heute verf\u00fcgbar oder in greifbare N\u00e4he ger\u00fcckt. Damit geht es nicht mehr nur darum, was technisch machbar ist. Wir m\u00fcssen auch kl\u00e4ren, welche Sicherheitsmechanismen und ethischen Regeln solche Systeme brauchen. Vielleicht wird das sichere Abschalten k\u00fcnftig sogar zu einer festen Anforderung bei der Entwicklung von Robotern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die spannendere Frage ist f\u00fcr mich deshalb nicht nur, was Roboter k\u00fcnftig k\u00f6nnen. Wir m\u00fcssen uns auch fragen, was wir ihnen \u00fcberlassen wollen. Soll selbst eine romantische Geste wie das \u00dcberreichen einer Rose automatisiert werden?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Buch, das mich in diesem Zusammenhang besch\u00e4ftigt, ist Max Tegmarks \u00abLeben 3.0\u00bb. Ich empfehle es immer wieder \u2013 obwohl ich es selbst nicht zu Ende lesen konnte. Einige der beschriebenen Zukunftsszenarien fand ich schlicht zu bedr\u00fcckend.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Tegmarks \u00abLeben 3.0\u00bb: Welche Zukunft wollen wir mit KI?<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">In \u00ab<a href=\"https:\/\/katalog.bibliothek.kit.edu\/bib\/1073175?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noreferrer noopener\">Leben 3.0<\/a>\u00bb verbindet der Physiker Max Tegmark wissenschaftliche Erkenntnisse mit m\u00f6glichen Zukunftsszenarien der KI. Er fragt, was geschieht, wenn k\u00fcnstliche Intelligenz F\u00e4higkeiten erreicht, die jene des Menschen \u00fcbertreffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Buch beschreibt Chancen, aber auch beunruhigende Szenarien \u2013 bis hin zu einer sogenannten Superintelligenz. Im Zentrum steht die Frage, wie Menschen daf\u00fcr sorgen k\u00f6nnen, dass fortgeschrittene KI der Menschheit n\u00fctzt. Mehr dazu in unserem Beitrag \u00ab<a href=\"https:\/\/hub.hslu.ch\/informatik\/sieben-buecher-ueber-ki-die-du-gelesen-haben-musst\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sieben B\u00fccher \u00fcber KI<\/a>, die du gelesen haben musst.\u00bb<\/p>\n<\/details>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn wir \u00fcber das k\u00fcnftige Zusammenleben von Menschen und Robotern sprechen, tauchen schnell Bilder aus Filmen auf. Vielleicht steuern Roboter eines Tages Raumschiffe auf dem Weg zum Mars. Oder sie k\u00e4mpfen gegeneinander wie in \u00abTerminator\u00bb.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nehmen die Roboter k\u00fcnftig an der Besprechung vor Schichtbeginn teil? Geben wir ihnen Namen?<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<h2 class=\"wp-block-heading\"><strong>Was bedeuten aktuelle Fortschritte jenseits von Science-Fiction f\u00fcr die Praxis?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Da interessiert mich vor allem die Produktion. K\u00f6nnen wir Embodied AI nutzen, um mit flexiblen Robotern g\u00fcnstiger und zugleich vielseitiger zu produzieren?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine grosse Chance sehe ich darin, KI und Robotik so zu verbinden, dass Roboter nicht nur repetitive Aufgaben \u00fcbernehmen, sondern auch zu kreativen Werkzeugen werden. Ein Beispiel ist das Projekt \u00abGaud-AI\u00bb von <a href=\"https:\/\/ch.linkedin.com\/in\/anastasiia-dubinkina\" target=\"_blank\" rel=\"noreferrer noopener\">Anastasiia Dubinkina<\/a> und <a href=\"https:\/\/www.linkedin.com\/in\/vojt%C4%9Bch-mare%C4%8Dek-a51390270\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vojt\u011bch Mare\u010dek<\/a> an der HSLU. Dabei setzt ein Roboter Keramiksplitter zu neuen Fliesenelementen zusammen, w\u00e4hrend KI beim Entwurf der Muster hilft. So entstehen Wandverkleidungen f\u00fcr B\u00e4der oder Pools \u2013 und zerbrochene Keramik erh\u00e4lt im Sinn der Kreislaufwirtschaft ein neues Leben.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Roboter k\u00f6nnen nicht nur repetitive Aufgaben \u00fcbernehmen, sondern auch zu kreativen Werkzeugen werden.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-video\"><video height=\"1080\" style=\"aspect-ratio: 1920 \/ 1080;\" width=\"1920\" controls src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/gaud.ai_.mp4\"><\/video><figcaption class=\"wp-element-caption\"><strong><em>Kreislaufdesign mit KI und Robotik:<\/em><\/strong><em>&nbsp;Im HSLU-Projekt \u00abGaud-AI\u00bb werden ausrangierte Keramikst\u00fccke digital erfasst, mit KI zu Mustern angeordnet und von einem Roboterarm platziert. So zeigt das Projekt, wie Abfall im Kreislaufdesign zum Ausgangsmaterial f\u00fcr Neues werden kann.<\/em><\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Solche Beispiele zeigen, wie sich die Rolle von Robotern ver\u00e4ndern kann. Sie f\u00fchren nicht mehr nur vorgegebene Arbeiten aus, sondern werden flexibler in Arbeitsprozesse eingebunden. Und wie sieht dann die kurze Besprechung vor Schichtbeginn aus? Nehmen die Roboter daran teil? Geben wir ihnen Namen? Ich bin gespannt, welche Formen der Zusammenarbeit und Akzeptanz wir in den n\u00e4chsten Jahren entwickeln.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was geschieht, wenn wir Robotern menschliche Eigenschaften zuschreiben?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Das passiert schnell, sobald Roboter mit uns sprechen, auf uns reagieren oder sich menschen\u00e4hnlich bewegen. Menschen beginnen dann, den Systemen Eigenschaften zuzuschreiben, die sie nicht tats\u00e4chlich besitzen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In Japan gibt es Ans\u00e4tze, Roboter st\u00e4rker in soziale Zusammenh\u00e4nge einzubinden. Sie k\u00f6nnen etwa als Kolleginnen und Kollegen gedacht werden oder bestimmte Aufgaben in einem Arbeitsteam \u00fcbernehmen. Das kann den Umgang mit ihnen erleichtern. Gleichzeitig m\u00fcssen wir aufpassen, dass wir daraus nicht auf Gef\u00fchle, <a href=\"https:\/\/hub.hslu.ch\/informatik\/mehr-als-ein-werkzeug-kuenstliche-intelligenz-wird-zur-persoenlichen-begleiterin\/\" target=\"_blank\" rel=\"noreferrer noopener\">Verst\u00e4ndnis<\/a> oder eigene Absichten schliessen.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Eine gute Zusammenarbeit braucht Vertrauen \u2013 aber kein falsches Bild davon, was die Maschine ist.<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">F\u00fcr mich ist deshalb wichtig, dass Menschen wissen, was ein Roboter tats\u00e4chlich kann und wo seine Grenzen liegen. Eine gute Zusammenarbeit braucht Vertrauen \u2013 aber kein falsches Bild davon, was die Maschine ist.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Was sollte<\/strong> <strong>die HSLU in Ihrem Fachbereich konkret anpacken?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">KI ver\u00e4ndert, wie wir <a href=\"https:\/\/hub.hslu.ch\/informatik\/informatikausbildung-ki-erweitert-den-gestaltungsraum\/\" target=\"_blank\" rel=\"noreferrer noopener\">lernen, pr\u00fcfen<\/a> und arbeiten. In der Robotik zeigt sich das besonders deutlich: KI-Modelle m\u00fcssen nicht nur in Simulationen funktionieren, sondern auch auf echter Hardware und in der realen Welt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Daf\u00fcr brauchen wir praxisnahe Testumgebungen. Studierende sollen KI-Modelle auf humanoiden Robotern, Drohnenflotten und Cobots einsetzen. Cobots sind Roboter, die direkt mit Menschen zusammenarbeiten. In der realen Welt treffen diese Systeme auf Hindernisse, wechselndes Licht, Menschen oder andere unerwartete Situationen. Genau daran zeigt sich, ob ein Modell zuverl\u00e4ssig funktioniert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im AI Robotics Lab erforschen wir deshalb, wie KI-gest\u00fctzte Roboter k\u00fcnftig sicher und verl\u00e4sslich arbeiten. Damit unterst\u00fctzen wir Schweizer Unternehmen dabei, neue Robotersysteme zu entwickeln und einzusetzen.<a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/labs\/ai-robotics\/?utm_source=chatgpt.com\"><\/a><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/informatik\/majors-informatik\"><\/a><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/artificial-intelligence-and-machine-learning?utm_source=chatgpt.com\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Welches Szenario halten Sie pers\u00f6nlich f\u00fcr realistisch?<\/strong>&nbsp;<br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Der Einsatz von Robotern wird sich vor allem dort ausweiten, wo er sich f\u00fcr Unternehmen wirtschaftlich lohnt. Cobots arbeiten heute bereits direkt mit Menschen zusammen. Bisher geschah das aber oft in klar begrenzten Einsatzfeldern.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Neue Robotersysteme werden flexibler. Unternehmen k\u00f6nnten sie dadurch leichter f\u00fcr wechselnde Aufgaben einsetzen. Das w\u00e4re besonders f\u00fcr KMU interessant, bei denen sich klassische Industrieroboter h\u00e4ufig nicht rechnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig w\u00e4chst m\u00f6glicherweise die Abh\u00e4ngigkeit von grossen Anbietern cloudbasierter KI-Dienste. Dann stellt sich auch die Frage, wer Daten, KI-Modelle und technische Infrastruktur kontrolliert.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Cloud-KI: Wenn ein Teil der Intelligenz ausserhalb des Roboters l\u00e4uft<\/strong><\/summary>\n<p class=\"wp-block-paragraph\">Ein Roboter muss seine KI nicht vollst\u00e4ndig auf dem Ger\u00e4t ausf\u00fchren. Er kann Daten \u00fcber das Internet an einen Cloud-Dienst senden, der sie verarbeitet. So k\u00f6nnen auch kleinere Unternehmen leistungsf\u00e4hige KI nutzen, ohne selbst grosse Rechenanlagen oder eigene KI-Modelle zu entwickeln.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gleichzeitig entsteht eine Abh\u00e4ngigkeit vom Anbieter: Er stellt Rechenleistung, technische Infrastruktur und m\u00f6glicherweise sogar Modelle bereit. Unternehmen m\u00fcssen deshalb kl\u00e4ren, welche Daten die Cloud verarbeitet, wo sie gespeichert werden und wie leicht sie den Anbieter wechseln k\u00f6nnen.<\/p>\n<\/details>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-group is-style-interview-questions\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<p class=\"wp-block-paragraph\">Die grosse Frage lautet deshalb: Wird Robotik so flexibel und erschwinglich, dass deutlich mehr Unternehmen sie sinnvoll einsetzen k\u00f6nnen?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gibt es ein Missverst\u00e4ndnis \u00fcber Ihr Fachgebiet, das Sie gerne korrigieren m\u00f6chten?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ein h\u00e4ufiges Missverst\u00e4ndnis ist, dass ein Roboter mit KI im Grunde nur ein Chatbot in einem \u00abBlechk\u00f6rper\u00bb sei. Das greift zu kurz. Wenn KI mit robotischer Hardware zusammenkommt, entstehen neue M\u00f6glichkeiten \u2013 aber auch neue Herausforderungen. Ein Roboter muss seine Umgebung r\u00e4umlich erfassen, Bewegungen planen und zuverl\u00e4ssig steuern.<\/p>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ein Roboter mit KI ist nicht einfach ein Chatbot im \u00abBlechk\u00f6rper\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Chatbot kann eine falsche Aussage erzeugen und sie sp\u00e4ter korrigieren. Bei einem Roboter kann ein Fehler unmittelbare Folgen haben. Es kann gef\u00e4hrlich werden, wenn ein humanoider Roboter einen falschen Schritt plant, ein Cobot einen ungeeigneten Bewegungsweg w\u00e4hlt oder ein Greifvorgang misslingt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Deshalb forschen wir am AI Robotics Lab daran, KI-gest\u00fctzte Cobots so zuverl\u00e4ssig zu machen, dass Unternehmen sie sicher in der Produktion einsetzen k\u00f6nnen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Zum Weiterdenken:<\/em><\/strong><em> Diese Zukunftsbilder betreffen uns alle. Welche Chancen und Risiken sollten wir heute diskutieren, damit technologische Entwicklungen verantwortungsvoll gestaltet werden?<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Redaktionelle Verantwortung: <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=4745\" target=\"_blank\" rel=\"noreferrer noopener\">Gabriela Bonin<\/a><br>Illustration Aufmacherbild: <a href=\"https:\/\/weareyork.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Simon Gast<\/a><br>Ver\u00f6ffentlicht am: 2. September 2026<\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong>Aus- und weiterbilden<\/strong>: Die Hochschule Luzern \u2013 Informatik bietet <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/\" target=\"_blank\" rel=\"noreferrer noopener\">Bachelor- und Master-Studieng\u00e4nge<\/a>, anwendungsorientierte <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Forschung<\/a> und Entwicklung sowie <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/\" target=\"_blank\" rel=\"noreferrer noopener\">Weiterbildungsangebote<\/a> der Informatik und Wirtschaftsinformatik auf einem Campus.<\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><strong>Besuche unsere <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/agenda\/veranstaltungen\/#?filters=1621&amp;q=Bachelor\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Online-Info-Veranstaltungen<\/strong><\/a><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph --><strong>Gef\u00e4llt dir unser Blog?<\/strong> Hier erh\u00e4ltst du Tipps und liest \u00fcber Trends aus der Welt der Informatik. Wir bieten Einsichten in unser Departement und Portr\u00e4ts von IT-Vordenkerinnen, Vision\u00e4ren und spannenden Menschen. <a href=\"https:\/\/hub.hslu.ch\/informatik\/#newsletter\" target=\"_blank\" rel=\"noreferrer noopener\">Hier kannst du den Informatik-Blog abonnieren.<\/a><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:paragraph -->Aktuelles aus unserem Departement auf LinkedIn. Jetzt <a href=\"https:\/\/www.linkedin.com\/showcase\/hochschule-luzern-informatik\/?viewAsMember=true\" target=\"_blank\" rel=\"noreferrer noopener\">folgen!<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik.<\/p>\n","protected":false},"author":21,"featured_media":28483,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"22621,6092,2988,24952,19891,16654","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[653304,71255,393019,4678,134],"tags":[653934,653933,653327,103467,653917,653410,653921],"class_list":["post-28482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artificial-intelligence-machine-learning","category-forschung-entwicklung","category-gesellschaft-ethik","category-informatik","category-weiterbildung","tag-autonome-systeme","tag-embodied-ai","tag-ki","tag-kuenstliche-intelligenz","tag-physical-ai","tag-prognosen","tag-prognosen-2026"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatik an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-02T05:55:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T06:20:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2044\" \/>\n\t<meta property=\"og:image:height\" content=\"1131\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gabriela Bonin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriela Bonin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"14\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/\"},\"author\":{\"name\":\"Gabriela Bonin\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/27da2348b7e471b60538f142295c83eb\"},\"headline\":\"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb\",\"datePublished\":\"2026-09-02T05:55:00+00:00\",\"dateModified\":\"2026-09-02T06:20:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/\"},\"wordCount\":2721,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg\",\"keywords\":[\"Autonome Systeme\",\"Embodied AI\",\"KI\",\"K\u00fcnstliche Intelligenz\",\"Physical AI\",\"Prognosen\",\"Prognosen 2026\"],\"articleSection\":[\"Artificial Intelligence\",\"Forschung &amp; Dienstleistung\",\"Gesellschaft &amp; Ethik\",\"Studium\",\"Weiterbildung\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/\",\"name\":\"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg\",\"datePublished\":\"2026-09-02T05:55:00+00:00\",\"dateModified\":\"2026-09-02T06:20:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/27da2348b7e471b60538f142295c83eb\"},\"description\":\"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg\",\"width\":2044,\"height\":1131,\"caption\":\"Roboter-Arme pr\u00e4gen die Industrie. K\u00fcnftig sollen Roboter flexibler reagieren, ihre Umgebung besser erfassen und enger mit Menschen zusammenarbeiten. (Illustration: Simon Gast, KI-unterst\u00fctzt)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\",\"name\":\"Informatik an der Hochschule Luzern\",\"description\":\"Der offizielle Blog der Hochschule Luzern \u2013 Informatik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/27da2348b7e471b60538f142295c83eb\",\"name\":\"Gabriela Bonin\",\"description\":\"Bloggerin, Textcoach, Dozentin. Gabriela Bonin arbeitet als Bloggerin und Textcoach bei der Hochschule Luzern, im Department Informatik. Daneben ist sie als Dozentin an der Journalistenschule MAZ und als Texterin t\u00e4tig.\",\"sameAs\":[\"http:\\\/\\\/www.gbonin.com\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/gabriela-bonin\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern","description":"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/","og_locale":"de_DE","og_type":"article","og_title":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern","og_description":"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.","og_url":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/","og_site_name":"Informatik an der Hochschule Luzern","article_published_time":"2026-09-02T05:55:00+00:00","article_modified_time":"2026-09-02T06:20:12+00:00","og_image":[{"width":2044,"height":1131,"url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg","type":"image\/jpeg"}],"author":"Gabriela Bonin","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Gabriela Bonin","Gesch\u00e4tzte Lesezeit":"14\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/"},"author":{"name":"Gabriela Bonin","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/27da2348b7e471b60538f142295c83eb"},"headline":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb","datePublished":"2026-09-02T05:55:00+00:00","dateModified":"2026-09-02T06:20:12+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/"},"wordCount":2721,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg","keywords":["Autonome Systeme","Embodied AI","KI","K\u00fcnstliche Intelligenz","Physical AI","Prognosen","Prognosen 2026"],"articleSection":["Artificial Intelligence","Forschung &amp; Dienstleistung","Gesellschaft &amp; Ethik","Studium","Weiterbildung"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/","url":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/","name":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb - Informatik an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg","datePublished":"2026-09-02T05:55:00+00:00","dateModified":"2026-09-02T06:20:12+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/27da2348b7e471b60538f142295c83eb"},"description":"In Teil 8 unserer Zukunftsserie sieht Robotik-Experte Bj\u00f6rn Jensen eine Zukunft voraus, in der Roboter ihre Umgebung besser erkennen und enger mit Menschen zusammenarbeiten. Er zeigt, welche Chancen darin liegen und warum solche Systeme zuverl\u00e4ssig arbeiten m\u00fcssen. Die Serie \u00ab10 Jahre voraus\u00bb erscheint zum 10-Jahre-Jubil\u00e4um der Hochschule Luzern \u2013 Informatik. Wie ver\u00e4ndert sich die Robotik in den n\u00e4chsten zehn Jahren? HSLU-Experte Bj\u00f6rn Jensen \u00fcber KI, neue Einsatzgebiete, Chancen und Risiken.","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#primaryimage","url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg","contentUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU.jpg","width":2044,"height":1131,"caption":"Roboter-Arme pr\u00e4gen die Industrie. K\u00fcnftig sollen Roboter flexibler reagieren, ihre Umgebung besser erfassen und enger mit Menschen zusammenarbeiten. (Illustration: Simon Gast, KI-unterst\u00fctzt)"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/informatik\/robotik-menschen-und-roboter-werden-enger-zusammenarbeiten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/informatik\/"},{"@type":"ListItem","position":2,"name":"Robotik: \u00abMenschen und Roboter werden enger zusammenarbeiten\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/informatik\/#website","url":"https:\/\/hub.hslu.ch\/informatik\/","name":"Informatik an der Hochschule Luzern","description":"Der offizielle Blog der Hochschule Luzern \u2013 Informatik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/informatik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/27da2348b7e471b60538f142295c83eb","name":"Gabriela Bonin","description":"Bloggerin, Textcoach, Dozentin. Gabriela Bonin arbeitet als Bloggerin und Textcoach bei der Hochschule Luzern, im Department Informatik. Daneben ist sie als Dozentin an der Journalistenschule MAZ und als Texterin t\u00e4tig.","sameAs":["http:\/\/www.gbonin.com","https:\/\/www.linkedin.com\/in\/gabriela-bonin\/"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU-600x400.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/08-Robotik_zukunftsserie_HSLU_I_NEU-600x600.jpg","author_info":{"display_name":"Gabriela Bonin","author_link":"https:\/\/hub.hslu.ch\/informatik\/author\/gabrielabonin\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/28482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/comments?post=28482"}],"version-history":[{"count":16,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/28482\/revisions"}],"predecessor-version":[{"id":28509,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/28482\/revisions\/28509"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media\/28483"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media?parent=28482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/categories?post=28482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/tags?post=28482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}