{"id":6173,"date":"2019-10-10T11:44:30","date_gmt":"2019-10-10T09:44:30","guid":{"rendered":"https:\/\/hub.hslu.ch\/informatik\/?p=6173"},"modified":"2026-02-18T10:19:07","modified_gmt":"2026-02-18T09:19:07","slug":"du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/","title":{"rendered":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb"},"content":{"rendered":"\n<div class=\"post-meta-custom\">By Yasmin Billeter<\/div>\n\n\n\n<div style=\"height:21px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:23px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Informatik-Blog: Hallo zusammen, wieso habt ihr euch f\u00fcr euer <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/international\/studieren-im-ausland\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\"><strong>Auslandsemester<\/strong><\/a><strong> entschieden?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Kevin Schuler:<\/strong> Ich habe seit der Lehre immer gearbeitet\nund wollte eine Pause. Um etwas komplett anderes zu erleben, bin ich f\u00fcr ein\nSemester nach Hongkong. Die Umgebung dort ist sehr gr\u00fcn und es ist ein guter\nHotspot zum Weiterreisen, Campen und Wandern. <\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ein Auslandsemester in Hongkong\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/G0_ZSum8lVU?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Yann Keiser:<\/strong> Das Silicon Valley spricht f\u00fcr sich. Ich wollte mein Englisch aufbessern und verstehen, wie die Leute dort ticken. Eigentlich h\u00e4tte ich gerne an der <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/wirtschaftsinformatik\/einblick-ins-studium\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">international Project Experience<\/a> teilgenommen. Da ich berufsbegleitend studiere, war dies aber nicht m\u00f6glich und so habe ich es auf diesem Weg gemacht. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Patric Weber: <\/strong>Bei mir war es \u00e4hnlich. Ich bin nach\nLondon, weil die Stadt ein \u00abMelting Pot\u00bb ist und dort Menschen aus\nverschiedenen Nationen zusammenkommen. Ausserdem hat mich das Universit\u00e4tsleben\nder Briten fasziniert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was unterschied den Unterricht an der Gastuniversit\u00e4t von\ndem der Hochschule Luzern \u2013 Informatik?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> An der <a href=\"https:\/\/www.lsbu.ac.uk\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">London Southbank University<\/a> war der Unterrichtsstoff weniger verdichtet als an der Hochschule Luzern und ich habe die 30 Credits (ECTS) mit weniger M\u00fche erreicht. Es wurde viel Eigeninitiative gefordert, was ich gesch\u00e4tzt habe. Dadurch hatte ich mehr Zeit, mich mit dem Stoff auseinanderzusetzen. Ausserdem konnte ich Module belegen, die ich mir hier nicht zugetraut h\u00e4tte \u2013 Machine Learning zum Beispiel. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> An der <a href=\"http:\/\/www.hkbu.edu.hk\/eng\/main\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (opens in a new tab)\">Hongkong Baptist University<\/a> hatten wir keine klassischen Vorlesungen, sondern Unterricht in kleinen Klassen. Es waren praxisnahe F\u00e4cher und gute Lehrpersonen. Das Niveau war tiefer als in der Schweiz und es gab ein riesiges Sportangebot, f\u00fcr welches wir teilweise sogar Credits erhielten. Ich habe versucht Chinesisch zu lernen, dies fiel mir schwer. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Ebenfalls an der <a href=\"http:\/\/www.sjsu.edu\/\">San Jos\u00e9 State University<\/a> war das Niveau\neinfacher. Allein schon die Anwesenheit gab ein paar ECTS-Punkte und 70 Prozent\nder Vornote konnte w\u00e4hrend des Semesters gemacht werden. Wir hatten spannende\nReferenten aus dem Silicon Valley und praxisnahe F\u00e4lle. F\u00fcr eine Lektion im\nInnovationsmanagement durften wir beispielsweise bei Tesla hinter die Kulissen\nblicken. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie habt ihr gewohnt?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler: <\/strong>Hongkong ist teuer; ich habe f\u00fcr 250 Franken\nvergleichsweise g\u00fcnstig in einem Studentenwohnheim-Zimmer mit einem Finnen\nzusammengewohnt. Das Zimmer war sehr einfach eingerichtet, hatte jedoch alles\nwas es braucht.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ich h\u00e4tte auch in ein \u00abinternational House\u00bb gehen k\u00f6nnen, habe mich jedoch bewusst entschieden, die WG mit drei Amerikanern zu teilen.<\/p>\n<cite>Yann Keiser<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> Ich wohnte in einem Haus f\u00fcr internationale\nStudierende in einer 8er-WG. Meine WG-Kolleginnen und -Kollegen waren aus\nDeutschland sowie \u00d6sterreich und wir waren eine super Gruppe, die viel zusammen\nunternommen hat.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Ich h\u00e4tte auch in ein \u00abinternational House\u00bb gehen\nk\u00f6nnen, habe mich jedoch bewusst entschieden, die WG mit drei Amerikanern zu\nteilen.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ein Auslandssemester in San Jos\u00e9 (Silicon Valley)\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/TFFjfJ4smrI?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ist das Studierendenleben im Ausland anders?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> Klar ist das Leben anders, wenn du nur ein\nSemester dort bist. Bei uns im Wohnheim gab es viele Partys. Anders als hier\ntrafen sich die meisten Studierenden nach der Uni im Gym. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> Bei uns im Haus herrschte Alkoholverbot und\nPartys gab es keine. Die Chinesen trinken nicht viel und der Alkohol ist teuer.\nWir, Exchange-Studierenden, hatten einen Chat und haben manchmal zusammen\ngekocht und eine Flasche Wein reingeschmuggelt. Ansonsten gingen wir f\u00fcr Partys\nausw\u00e4rts. Was ich gesch\u00e4tzt habe, war das riesige und g\u00fcnstige Sportangebot. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Bei uns im Wohnheim gab es viele Partys. Anders als hier trafen sich die meisten Studierenden nach der Uni im Gym. <\/p>\n<cite>Patric Weber<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Der gr\u00f6sste Unterschied ist, dass wir hier nur zur Schule gehen, die Studierenden in den USA hingegen auf dem Campus leben. Es besteht eine riesige Infrastruktur mit Verpflegungsm\u00f6glichkeiten, Sport, Einkaufs- und Freizeitangebot. Wir haben auch ein <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/campus\/labs-und-infrastruktur\/hochschulsport\/\">Sportangebot<\/a> \u2013 nur kennt das an der Hochschule Luzern \u2013 Informatik fast niemand.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie war der Kontakt mit den einheimischen Studierenden?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> Der Kontakt fand haupts\u00e4chlich w\u00e4hrend des\nUnterrichts statt. Die chinesischen Studierenden haben einen komplett anderen Rhythmus.\nVor 4 Uhr morgens gehen sie nicht ins Bett, sondern spielen Fussball und andere\nSpiele in den G\u00e4ngen des Wohnheims. Als wir sie darauf hingewiesen haben, waren\nsie zuerst etwas beleidigt, haben dann aber verst\u00e4ndnisvoll reagiert.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> In unserem Londoner Wohnheim waren nur internationale Studierende, in unserer Wohnung waren alle deutschsprechend. \u00abGuided Experience\u00bb nennt sich das. Offenbar gab es immer wieder Probleme, wenn zu unterschiedliche Kulturen zusammenwohnen. Mit Einheimischen hatte ich in der Freizeit selten Kontakt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Ich habe viel Zeit mit zwei meiner\namerikanischen Mitbewohner verbracht. Wir hatten ein geniales Zusammenleben und\nhaben viel unternommen. Dies war extrem wertvoll, denn so konnte ich lokale\nLeute kennenlernen und mit ihnen etwas unternehmen.&nbsp; <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Was habt ihr kulinarisch entdeckt?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> In Hongkong gab es alles, so auch europ\u00e4isches\nEssen. Vom chinesischen Essen war ich wenig begeistert, obwohl ich viel\nprobiert habe: Oktopus am Stiel, H\u00fchnerf\u00fcsse oder Froschschenkel zum Beispiel. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Vom chinesischen Essen war ich wenig begeistert, obwohl ich viel probiert habe: Oktopus am Stiel, H\u00fchnerf\u00fcsse oder Froschschenkel zum Beispiel. <\/p>\n<cite>Kevin Schuler<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber <\/strong>Ich war \u00fcberrascht, was London an\ninternationaler K\u00fcche zu bieten hat. Meine Mitbewohninnen und Mitbewohner waren\nimmer auf der Suche nach dem n\u00e4chsten Instagram-Motiv. So habe ich schon mal\n50-60 Pfund f\u00fcr ein Sushi-H\u00e4ppchen ausgegeben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> In Amerika gibt es alles in allen Gr\u00f6ssen \u2013\nvor allem gross und nicht klein. Ich habe meist zuhause gegessen, wir hatten\neinen riesigen K\u00fchlschrank.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Ein Auslandsemester in London\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/eOWEVg9iYKA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Gab es ein besonders brenzlige Erlebnis?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> W\u00e4hrend meines Aufenthalts hat ein Hurrikan\ngew\u00fctet. Ich war gl\u00fccklicherweise gerade nicht in Hongkong, doch als ich\nzur\u00fcckkam waren Str\u00e4nde, W\u00e4lder und H\u00e4user zerst\u00f6rt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Ich wollte zu einer Party gehen, leider ereignet sich kurz davor eine Schiesserei. Es waren etliche Polizeiautos vor Ort und die Party war dann vorbei. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Und ein besonders sch\u00f6nes?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Weil ich berufsbegleitend studiere, konnte\nich viele Ausfl\u00fcge unternehmen und zum Beispiel \u00fcbers Wochenende der K\u00fcste hoch\nnach San Francisco fahren. Ich w\u00fcrde es jedem empfehlen, nicht nur zu lernen,\nsondern sich auch Zeit zu nehmen, um mit anderen etwas zu erleben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> Ich habe mit meiner WG-Gruppe Roadtrips gemacht und konnte es geniessen, Student zu sein. Da ich vorher immer nebenbei gearbeitet habe, kam ich in London zum ersten Mal in den Genuss nur studieren zu d\u00fcrfen.  Da wusste ich pl\u00f6tzlich, was Erholung heisst.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Habt ihr nach dem Auslandsemester etwas an euren\nGewohnheiten ge\u00e4ndert?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Weber:<\/strong> Ich habe meine Bachelorarbeit verschoben, weil\nich es nicht viel gleichzeitig abschliessen wollte. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Ich gehe offener auf Menschen zu, lebe einfacher und bin toleranter. <\/p>\n<cite>Kevin Schuler<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Keiser:<\/strong> Bei mir ist die Hemmschwelle gesunken Englisch\nzu reden \u2013 auch wenn es immer noch nicht perfekt ist. Ausserdem nehme ich alles\netwas lockerer, wenn ich zum Beispiel im Stau stehe. Das Sch\u00f6nste war, als ich\nzur\u00fcckkam und wieder Leitungswasser trinken konnte.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Schuler:<\/strong> Ich gehe offener auf Menschen zu, lebe\neinfacher und bin toleranter. Wenn du siehst wie andere Menschen leben, wird\ndir bewusst, welchen riesen Luxus wir hier haben. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Danke f\u00fcr das Gespr\u00e4ch!<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f6ffentlicht am 10. Oktober 2029<br><strong>Update vom Februar 2026:<\/strong> Wir haben diesen Blogbeitrag um ein neues Video erg\u00e4nzt. Wie andere Studierende ihr Austauschsemester erlebt haben, erf\u00e4hrst du hier:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Auslandssemester: Nicht alles geplant, umso mehr erlebt\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/WoYTAXkg5RM?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/international\/pinboard\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>M\u00f6glichkeiten f\u00fcr die internationale Vernetzung<\/strong><\/a><\/p>\n<p><!-- \/wp:paragraph --><!-- wp:list --><\/p>\n<ul>\n<li>Aktuelle Konferenzen, Summer und Winter School Angebote f\u00fcr Studierende und Mitarbeitende werden laufend auf der <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/international\/pinboard\/\" target=\"_blank\" rel=\"noopener\">Website vom International Office<\/a> publiziert.<\/li>\n<li>Studierende, die sich f\u00fcr ein ganzes Semester im Ausland interessieren, erhalten mehr Informationen auf der Website <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/international\/studieren-im-ausland\/\" target=\"_blank\" rel=\"noopener\">Studieren an unseren Partnerhochschulen<\/a>.<\/li>\n<\/ul>\n<p><!-- \/wp:list --><!-- wp:paragraph --><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/international-it-management\/\" target=\"_blank\" rel=\"noopener\"><strong>Bachelor in International IT Management <\/strong><\/a><br \/>\nEin Studium mit Fokus auf die interkulturelle und interdisziplin\u00e4re IT-Projekte.<\/p>\n<p><!-- \/wp:paragraph --><\/p>\n<h3><strong>\u00dcber den Informatik-Blog<\/strong><\/h3>\n<p>Hier erhalten Sie Tipps und Neuigkeiten aus der Welt der IT. Wir portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die Hochschule Luzern \u2013 Informatik mitpr\u00e4gt. Abonnieren Sie jetzt unseren Blog und bleiben Sie informiert.<\/p>\n<p>&nbsp;<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. <\/p>\n","protected":false},"author":4,"featured_media":6178,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"20962,20875,20738,20773,20536,20591","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[4678],"tags":[653690,653687,653331,653430,4165],"class_list":["post-6173","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informatik","tag-auslandssemester","tag-austauschsemester","tag-austauschstudium","tag-internationales","tag-studium"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatik an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-10T09:44:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-18T09:19:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1124\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yasmin Billeter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weitertanzen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmin Billeter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/\"},\"author\":{\"name\":\"Yasmin Billeter\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"headline\":\"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb\",\"datePublished\":\"2019-10-10T09:44:30+00:00\",\"dateModified\":\"2026-02-18T09:19:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/\"},\"wordCount\":1257,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Austausch-Studierende.jpg\",\"keywords\":[\"Auslandssemester\",\"Austauschsemester\",\"Austauschstudium\",\"Internationales\",\"Studium &amp; Campus\"],\"articleSection\":[\"Studium\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/\",\"name\":\"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Austausch-Studierende.jpg\",\"datePublished\":\"2019-10-10T09:44:30+00:00\",\"dateModified\":\"2026-02-18T09:19:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"description\":\"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Austausch-Studierende.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Austausch-Studierende.jpg\",\"width\":2048,\"height\":1124,\"caption\":\"Patric Weber, Kevin Schuler und Yann Keiser tauschen sich \u00fcber ihre Austauschsemester aus.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\",\"name\":\"Informatik an der Hochschule Luzern\",\"description\":\"Der offizielle Blog der Hochschule Luzern \u2013 Informatik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\",\"name\":\"Yasmin Billeter\",\"description\":\"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yasmin-billeter\\\/\",\"https:\\\/\\\/x.com\\\/weitertanzen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern","description":"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern","og_description":"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %","og_url":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/","og_site_name":"Informatik an der Hochschule Luzern","article_published_time":"2019-10-10T09:44:30+00:00","article_modified_time":"2026-02-18T09:19:07+00:00","og_image":[{"width":2048,"height":1124,"url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","type":"image\/jpeg"}],"author":"Yasmin Billeter","twitter_card":"summary_large_image","twitter_creator":"@weitertanzen","twitter_misc":{"Geschrieben von":"Yasmin Billeter","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/"},"author":{"name":"Yasmin Billeter","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"headline":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb","datePublished":"2019-10-10T09:44:30+00:00","dateModified":"2026-02-18T09:19:07+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/"},"wordCount":1257,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","keywords":["Auslandssemester","Austauschsemester","Austauschstudium","Internationales","Studium &amp; Campus"],"articleSection":["Studium"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/","url":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/","name":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb - Informatik an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","datePublished":"2019-10-10T09:44:30+00:00","dateModified":"2026-02-18T09:19:07+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"description":"Ob Hongkong, San Jos\u00e9 oder London \u2013 ein Semester im Ausland bereichert das Studierendenleben und h\u00e4lt einige \u00dcberraschungen bereit. Patric Weber, Kevin Schuler und Yann Keiser berichten von ihren Erfahrungen. %","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#primaryimage","url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","contentUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","width":2048,"height":1124,"caption":"Patric Weber, Kevin Schuler und Yann Keiser tauschen sich \u00fcber ihre Austauschsemester aus."},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/informatik\/du-gehst-dort-nicht-nur-zur-schule-du-lebst-auf-dem-campus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/informatik\/"},{"@type":"ListItem","position":2,"name":"\u00abDu gehst dort nicht nur zur Schule \u2013 du lebst auf dem Campus!\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/informatik\/#website","url":"https:\/\/hub.hslu.ch\/informatik\/","name":"Informatik an der Hochschule Luzern","description":"Der offizielle Blog der Hochschule Luzern \u2013 Informatik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/informatik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f","name":"Yasmin Billeter","description":"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.","sameAs":["https:\/\/www.linkedin.com\/in\/yasmin-billeter\/","https:\/\/x.com\/weitertanzen"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Austausch-Studierende.jpg","author_info":{"display_name":"Yasmin Billeter","author_link":"https:\/\/hub.hslu.ch\/informatik\/author\/yasminbilleter\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/6173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/comments?post=6173"}],"version-history":[{"count":47,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/6173\/revisions"}],"predecessor-version":[{"id":27015,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/6173\/revisions\/27015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media\/6178"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media?parent=6173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/categories?post=6173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/tags?post=6173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}