{"id":8936,"date":"2020-08-19T11:39:57","date_gmt":"2020-08-19T09:39:57","guid":{"rendered":"https:\/\/hub.hslu.ch\/informatik\/?p=8936"},"modified":"2026-02-06T15:11:51","modified_gmt":"2026-02-06T14:11:51","slug":"so-wird-kunstliche-intelligenz-unser-leben-beeinflussen","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/","title":{"rendered":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p><strong>Herr Daly, wie sehr hat k\u00fcnstliche Intelligenz (KI) bereits unsere Welt ver\u00e4ndert?<\/strong><\/p>\n\n\n\n<p>Donnacha Daly: Die KI ver\u00e4ndert unsere Welt kontinuierlich. Aber wir Menschen sind unglaublich gut darin, uns anzupassen. Heute verwenden wir viele KI-Systeme, manchmal ohne uns dessen bewusst zu sein. Zum Beispiel, wenn wir einen Text online \u00fcbersetzen lassen oder die Gesichtserkennungsfunktion unseres Smartphones nutzen. K\u00fcnstliche Intelligenz ist in unserem Alltag angekommen und hat die Gesch\u00e4ftswelt ver\u00e4ndert: Vor zehn Jahren waren die Top-Unternehmen in den USA Grossindustrielle wie Exxon oder General Electric. Heute sind es Apple, Amazon und Facebook. Sie alle haben Gesch\u00e4ftsmodelle, die durch KI untermauert werden. KI hilft der Welt auch in vielerlei Hinsicht, mit der Corona-Pandemie fertigzuwerden. Zum Beispiel durch Contact-Tracing-Apps, welche die Infektionsketten nachverfolgen und so die Verbreitung des Virus eind\u00e4mmen.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Machine Learning einfach erkl\u00e4rt\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/LAJHeUAP9l4?start=2&#038;feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><em>Das Video bietet einen Einstieg in die KI-Technologie Machine Learning.<\/em><br><br><strong>Welches sind die neusten Entwicklungen im Bereich KI?<\/strong><\/p>\n\n\n\n<p>K\u00fcnstliche Kreativit\u00e4t und KI-Innovation stehen zunehmend im Mittelpunkt. Diese werden durch sogenannte \u00abGenerative Adversarial Networks\u00bb (GANs) erm\u00f6glicht. GANs bestehen aus zwei neuronalen Netzen, die sich gegenseitig verbessern. (<a href=\"https:\/\/hub.hslu.ch\/informatik\/kann-ein-computer-ein-neues-latte-art-kunstwerk-kreieren\/\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\">Wie das genau funktioniert, wird hier am Beispiel der computergenerierten Latte Art erl\u00e4utert<\/a>). KI kann auch neue Erkentnisse zu Tage bringen. Es besteht eine reelle Chance, dass der Coronavirus-Impfstoff teilweise mit Hilfe einer KI gefunden wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/DSC0307_lowres-Kopie.jpg\" alt=\"\" class=\"wp-image-8981\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/DSC0307_lowres-Kopie.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/DSC0307_lowres-Kopie-300x200.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/DSC0307_lowres-Kopie-768x512.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/DSC0307_lowres-Kopie-928x618.jpg 928w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">\u00abBei der k\u00fcnstlichen Intelligenz geht es auch um Wertsch\u00f6pfung durch Anwendungstechnik und digitale Ideenfindung\u00bb sagt Donnacha Daly. Er ist \u00fcberzeugt: In zehn Jahren werden kreative Menschen die KI-Technologie auf sehr unerwartete Weise nutzen. \n<\/figcaption><\/figure>\n\n\n\n<p><strong>Wird es eine Intelligenz geben, die kl\u00fcger ist als wir?<\/strong><\/p>\n\n\n\n<p>Absolut! Es kann viele Jahrzehnte oder sogar Jahrhunderte dauern, aber es wird kommen. Eine bessere Frage ist, ob eine k\u00fcnstliche allgemeine Intelligenz ein Motiv hat und wie sie mit uns interagiert. Stellen Sie sich eine Intelligenz vor, die der Menschheit relativ weit voraus ist, etwa so, wie wir als Spezies den Ameisen voraus sind. Ameisen sind uns eigentlich egal, ausser wenn sie in unseren H\u00e4usern nisten. Aber im Allgemeinen betreffen menschliche Motive Ameisen nicht. Ebenso k\u00f6nnte eine Superintelligenz mit Motiv uns Menschen nicht einmal als Teil ihres Motivs betrachten. Vorausgesetzt, wir bleiben draussen \u2026<\/p>\n\n\n\n<p><strong>Aber man tritt auf Ameisen \u2013 aus Versehen oder absichtlich &#8230;<\/strong><\/p>\n\n\n\n<p>Das ist richtig, und deshalb m\u00fcssen wir bei der Entwicklung der KI schon jetzt vorsichtig sein. Ich w\u00fcrde niemals f\u00fcr einen Stopp der Forschung im Bereich der k\u00fcnstlichen Intelligenz pl\u00e4dieren sondern bin der Meinung, dass die KI-Forschung und die Erforschung der Grenzen der KI mit voller Geschwindigkeit fortgesetzt werden sollten. Aber die Entwicklung, Kommerzialisierung und Anwendung der KI sollte stark reguliert werden.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Die Idee einer Roboterarmee ist nicht sehr weit hergeholt.<\/p>\n<\/blockquote>\n\n\n\n<p>Wir am Departement Informatik nehmen dies ernst und arbeiten mit der Hochschule Luzern \u2013 Soziale Arbeit und der Hochschule Luzern Desing &amp; Kunst zusammen, um die gesellschaftlichen Auswirkungen der KI und ihre Wechselwirkungen mit Ethik, Philosophie und sogar Kunst zu untersuchen.<\/p>\n\n\n\n<p><strong>Dennoch fragen sich viele, was passiert, <\/strong><strong>wenn KI so intelligent wird, dass sie zur Gefahr wird.<\/strong><\/p>\n\n\n\n<p>Falsch eingesetzt kann KI tats\u00e4chlich zur Gefahr werden: f\u00fcr Menschen, Kulturen und Demokratien. Es besteht ein grosses Risiko, dass KI als Waffe instrumentalisiert wird. Die Idee einer Roboterarmee ist nicht sehr weit hergeholt. Ich glaube auch, dass Drohnen bald ein Problem werden k\u00f6nnten, wenn man Flotten von selbstorganisierenden, intelligenten Drohnen h\u00e4tte. Stephen Hawking und Elon Musk warnen vor dieser Gefahr. Andere wie Demis Hassabis, der CEO von Google DeepMind, sind eher zuversichtlich.<\/p>\n\n\n\n<p><strong>Welche fundamentalen Regeln f\u00fcr KI brauchen wir in Zukunft? <\/strong><a href=\"https:\/\/hub.hslu.ch\/informatik\/kunstliche-intelligenz-gibt-es-nicht-wichtig-ist-digitale-ethik\/\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\"><strong>&nbsp;Ladan Pooyan-Weihs spricht im Interview zum Beispiel dar\u00fcber, wie wichtig digitale Ethik ist, und fordert n\u00f6tige Weichenstellungen. <\/strong><\/a><strong>&nbsp;<\/strong><\/p>\n\n\n\n<p>Ich vergleiche die KI gerne mit der Kernenergie. Sie hat dieses transformative Potenzial, im Guten wie im Schlechten. Mit der Kernenergie k\u00f6nnen wir einen grossen gesellschaftlichen Nutzen erzielen. Zum Beispiel werden in der Schweiz fast 50 Prozent des Stroms durch Kernenergie erzeugt. Auf der anderen Seite haben wir Atomwaffen und leben seit vielen Jahrzehnten mit der Drohkulisse der <a aria-label=\"undefined (opens in a new tab)\" href=\"https:\/\/de.wikipedia.org\/wiki\/Gleichgewicht_des_Schreckens\" target=\"_blank\" rel=\"noreferrer noopener\">wechselseitig zugesicherten Zerst\u00f6rung<\/a>. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Ich vergleiche die KI gerne mit der Kernenergie. Sie hat dieses transformative Potenzial, im Guten wie im Schlechten.<\/p>\n<\/blockquote>\n\n\n\n<p>Wie sind wir als Weltgemeinschaft mit diesen Risiken umgegangen? Durch internationale Vertr\u00e4ge, globale Zusammenarbeit, unabh\u00e4ngige Aufsicht und sehr starke Regulierung. Ich bin der festen \u00dcberzeugung, dass wir bei der KI einen \u00e4hnlichen Ansatz brauchen.<\/p>\n\n\n\n<p><strong>Welche Gesetze zur KI-Regulierung gibt es heute schon?<\/strong><\/p>\n\n\n\n<p>Die Europ\u00e4ische Kommission hat Anfang Jahr ein <a href=\"https:\/\/ec.europa.eu\/jrc\/en\/publication\/robustness-and-explainability-artificial-intelligence\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\">Whitepaper zur Regulierung von KI<\/a> herausgegeben. Darin steht etwa, dass maschinenbeeinflusste Entscheidungen erkl\u00e4rbar sein m\u00fcssen. Dies hat enorme Auswirkungen: Nehmen wir an, Sie haben ein Hautproblem. Sie k\u00f6nnen zum Arzt gehen, k\u00f6nnen aber auch eine App konsultieren. Die App w\u00fcrde ihnen angeben, in welches Cluster ihre Haut statistisch gesehen f\u00e4llt. Gem\u00e4ss den EU-Regulationen w\u00e4re diese Diagnose nicht akzeptabel, da sie nur statistisch erkl\u00e4rbar ist und nicht medizinisch.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>Die erkl\u00e4rbare KI ist eines der wichtigsten und schwierigsten offenen Probleme, die richtig gel\u00f6st werden m\u00fcssen.<\/p>\n<\/blockquote>\n\n\n\n<p>Ich halte es f\u00fcr wichtig, dass wir weltweit eine starke Regulierung haben, wenn es um die Anwendung der k\u00fcnstlichen Intelligenz und ihren Einsatz f\u00fcr Entscheidungen geht, die Menschenleben betreffen.<\/p>\n\n\n\n<p><strong>Sie erachten diese Regel \u00fcber die <\/strong><a href=\"https:\/\/de.wikipedia.org\/wiki\/Explainable_Artificial_Intelligence\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\"><strong>Erkl\u00e4rbarkeit von KI<\/strong><\/a><strong> also als nicht sehr sinnvoll?<\/strong><\/p>\n\n\n\n<p>Im Gegenteil! Ich denke, die erkl\u00e4rbare KI ist eines der wichtigsten und schwierigsten offenen Probleme, die richtig gel\u00f6st werden m\u00fcssen. Jetzt. Erkl\u00e4rbare KI wird der Schl\u00fcssel sein, um die B\u00fcchse der Pandora zu \u00f6ffnen und den Einsatz von KI in sensiblen Anwendungsbereichen wie Recht, Medizin und Sicherheit erheblich zu steigern. Die Regel \u00fcber die Erkl\u00e4rbarkeit wird auch die Regulierung der KI erheblich vereinfachen.<\/p>\n\n\n\n<p><strong>Welche H\u00fcrden hat KI aktuell neben der Erkl\u00e4rbarkeit?<\/strong><\/p>\n\n\n\n<p>K\u00fcnstliche Intelligenz ist schrecklich energiehungrig. Der Kohlendioxid-Fussabdruck ist das schmutzige Geheimnis der KI. Auch brauchen wir derzeit zu viele Daten, um die KI-Algorithmen zu trainieren. Wenn man einem Baby 100 Bilder einer Katze zeigt, weiss es, wenn es drei Jahre alt ist, was eine Katze ist \u2013 jede Katze. Eine KI muss 100&#8217;000 bis 1&#8217;000&#8217;000 Bilder einer Katze sehen, bis sie weiss, was eine Katze ist. Wir brauchen KI, um an Small Data (wenigere, daf\u00fcr pr\u00e4zisere Daten) zu arbeiten, nicht nur an Big Data.<\/p>\n\n\n\n<p><strong>Macht uns KI bald unsere Jobs streitig?<\/strong><\/p>\n\n\n\n<p>K\u00fcnstliche Intelligenz wird eine Menge Aufgaben \u00fcbernehmen, doch die Technologie schafft auch neue Arbeitspl\u00e4tze. Viele Jobs werden sich in der Zeit des technologischen \u00dcbergangs ver\u00e4ndern. Die Angestellten werden neue Wege lernen m\u00fcssen, um in der Gesellschaft produktiv zu sein. Dies wird auch neue Sozialvertr\u00e4ge erfordern, wie zum Beispiel das universelle Grundeinkommen.<\/p>\n\n\n\n<p><strong>Wie lautet Ihre Prognose f\u00fcr die Zukunft der k\u00fcnstlichen Intelligenz?<\/strong><\/p>\n\n\n\n<p>Ich erkl\u00e4re es mit dem Bild des Zentauren \u2013 eines Mischwesens aus Pferd und Mensch der griechischen Mythologie. Garri Kasparow wurde als erster Schachweltmeister von einem Computer geschlagen. Er entwickelte nach seiner Niederlage das Zentauren-Schach: Dabei spielen Mensch und Schachcomputer zusammen in einem Team. Sie k\u00f6nnen besser Schach spielen, als es Menschen oder Computer alleine je schaffen w\u00fcrden. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>F\u00fcr die Zukunft der KI bedeutet dies, dass Menschen und Maschinen am besten im Team arbeiten. Dies ist dann nicht \u00abArtificial Intelligence\u00bb, es ist \u00abAugmented Intelligence\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<p>\u00dcbertragen auf die Zukunft der KI bedeutet dies, dass Menschen und Maschinen am besten im Team arbeiten. Dies ist dann nicht \u00abArtificial Intelligence\u00bb, es ist \u00abAugmented Intelligence\u00bb. Sehr bald werden wir <a href=\"https:\/\/futurism.com\/the-byte\/elon-musk-neuralink-stream-music-brians\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\">eine Ank\u00fcndigung von Neuralink<\/a>, der KI-Gesellschaft von Elon Musk, sehen, die dieses Konzept viel weiter voranbringen wird.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"722\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-1024x722.jpg\" alt=\"\" class=\"wp-image-8946\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-1024x722.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-300x212.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-768x542.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-1536x1083.jpg 1536w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313-928x654.jpg 928w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/A_Tiger_Fighting_a_Centaur_LACMA_65.37.313.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Halb Pferd, halb Mensch: Ein Zentaur ist eine m\u00e4chtige Figur aus der griechischen Mythologie und ein Beispiel daf\u00fcr, wie das optimale Zusammenspiel von Mensch und Maschine aussehen k\u00f6nnte. (Bild: Wikimedia Commons)<\/figcaption><\/figure>\n\n\n\n<p><strong>Der Begriff \u00aberweiterte Intelligenz\u00bb wird<\/strong><a href=\"https:\/\/hub.hslu.ch\/informatik\/kunstliche-intelligenz-gibt-es-nicht-wichtig-ist-digitale-ethik\/\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\"><strong> von Ladan Pooyan-Weihs in unserem Interview<\/strong><\/a><strong> als Alternative f\u00fcr die Bezeichnung \u00abk\u00fcnstliche Intelligenz\u00bb verwendet. Sie sagt der Begriff \u00ab<\/strong><a href=\"https:\/\/de.wikipedia.org\/wiki\/K%C3%BCnstliche_Intelligenz\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>k\u00fcnstliche Intelligenz<\/strong><\/a><strong>\u00bb k\u00f6nne im Alltag zu falschen Erwartungen verleiten und unn\u00f6tige \u00c4ngste sch\u00fcren. Sie verstehen unter \u00abAugmented Intelligence\u00bb etwas anderes\u2026<\/strong><\/p>\n\n\n\n<p>Nicht wirklich, nein, ich stimme mit Ladan Pooyan-Weihs \u00fcberein. Wenn wir heute von KI sprechen, meinen wir im Allgemeinen maschinelles Lernen (ML) und Computational Intelligence und nicht neuromorphes Rechnen (ein Computer nach Vorbild des Gehirns) oder gar anthropomorphe allgemeine Intelligenz (ein Computer mit menschlichen Eigenschaften). Der Grund daf\u00fcr ist, dass ML die derzeit leistungsf\u00e4higste Technologie ist, die wir f\u00fcr die k\u00fcnstliche Intelligenz haben. Und wir setzen sie als Hilfsmittel f\u00fcr die menschliche Intelligenz ein, weil sie derzeit auf einem ausreichend fortgeschrittenen Niveau ist, um unsere Produktivit\u00e4t zu steigern, aber nicht weit genug fortgeschritten, um unseren Einfallsreichtum zu ersetzen. Also, ja, ich stimme Ladan Pooyan-Weihs zu, dass wir heute eine \u00aberweiterte Intelligenz\u00bb haben.<\/p>\n\n\n\n<p><strong>Wof\u00fcr werden Menschen KI k\u00fcnftig einsetzen?<\/strong><\/p>\n\n\n\n<p>Blickt man zehn Jahre zur\u00fcck, w\u00fcrde man in \u00e4hnlicher Weise fragen: Was werden die Menschen mit all dieser Rechenleistung nur machen? H\u00e4tten Sie gesagt: Jemand wird \u00abAngry Birds\u00bb erfinden und das Videospiel wird die Nummer eins unter den Anwendungen werden, h\u00e4tte man Sie f\u00fcr verr\u00fcckt erkl\u00e4rt. Doch das war nicht verr\u00fcckt, das war kreativ! <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>In zehn Jahren werden kreative Menschen die KI-Technologie auf sehr unerwartete Weise nutzen.<\/p>\n<\/blockquote>\n\n\n\n<p>Wenn Sie gleichwohl zehn Jahre in die Zukunft blicken, werden Sie in \u00e4hnlicher Weise erweiterte Intelligenz und eine Menge kreativer Menschen sehen. Diese werden die Technologie auf sehr unerwartete Weise nutzen.<\/p>\n\n\n\n<p><strong>Wo stehen wir in zehn Jahren?<\/strong><\/p>\n\n\n\n<p>Wir werden eine weit verbreitete Akzeptanz der Verbesserung menschlicher koginitiver F\u00e4higkeiten durch direkte Schnittstellen zum Gehirn erleben. Das klingt weit hergeholt, aber Innovationen wie etwa das iPhone (2007 eingef\u00fchrt) und Facebook (2004 lanciert) haben die Welt ebenfalls in sehr kurzer Zeit ver\u00e4ndert.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-vimeo wp-block-embed-vimeo wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HSLU Informatik - Bachelor in Artifical Intelligence and machine learning\" src=\"https:\/\/player.vimeo.com\/video\/387707821?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p><strong>Im Fr\u00fchling 2020 haben die ersten Studierenden des Bachelor-Studiengangs <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/artificial-intelligence-and-machine-learning\/\" target=\"_blank\" aria-label=\"undefined (opens in a new tab)\" rel=\"noreferrer noopener\"><strong>K\u00fcnstliche Intelligenz &amp; Maschinelles Lernen<\/strong><\/a><strong> gestartet. Wie ist es ihnen bisher ergangen?<\/strong><\/p>\n\n\n\n<p>Es tut mir sehr leid f\u00fcr unsere Studierenden, die aufgrund der Corona-Pandemie viele Aspekte des ersten Semesters verpasst haben: neue Freunde treffen und neue Erfahrungen machen. Dennoch haben alle enorme Arbeit geleistet, damit sie zumindest Vorlesungen besuchen und Pr\u00fcfungen ablegen konnten. Ich hoffe, dass wir die n\u00e4chsten Semester wie geplant durchf\u00fchren k\u00f6nnen. Vor allem dann, wenn der Schwerpunkt auf Projektarbeit, Kreativit\u00e4t und Innovation liegt.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>KI ist von hoher strategischer Bedeutung f\u00fcr die Zentralschweiz, f\u00fcr die Volkswirtschaft und f\u00fcr die Wettbewerbsf\u00e4higkeit der Schweiz auf dem internationalen Markt.<\/p>\n<\/blockquote>\n\n\n\n<p>Bei der k\u00fcnstlichen Intelligenz geht es nicht nur um rechnerische Intelligenz, sondern auch um Wertsch\u00f6pfung durch Anwendungstechnik und digitale Ideenfindung. Dies bedeutet, dass wir in Teams arbeiten und physisch interagieren m\u00fcssen.<\/p>\n\n\n\n<p><strong>Was sind Ihre Ziele und Visionen f\u00fcr den Studiengang?<\/strong><\/p>\n\n\n\n<p>Mein Ziel ist es, dass unsere Studierenden mit einem vollen Satz an KI-Werkzeugen in ihre berufliche Laufbahn starten k\u00f6nnen, sei es in der Industrie oder im \u00f6ffentlichen Sektor. KI ist zweifellos von hoher strategischer Bedeutung f\u00fcr die Zentralschweiz, f\u00fcr die Volkswirtschaft und f\u00fcr die Wettbewerbsf\u00e4higkeit der Schweiz auf dem internationalen Markt.<\/p>\n\n\n\n<p><em>Publiziert: 19. August 2020<\/em><\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<figure id=\"attachment_8941\" aria-describedby=\"caption-attachment-8941\" style=\"width: 150px\" class=\"wp-caption alignright\"><a href=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Daly_Donnacha_B.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8941 size-thumbnail\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Daly_Donnacha_B-150x150.jpg\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><figcaption id=\"caption-attachment-8941\" class=\"wp-caption-text\">Donnacha Daly<\/figcaption><\/figure>\n<p><strong>Langj\u00e4hriger KI-Experte: <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=4717\" target=\"_blank\" rel=\"noopener\">Donnacha Daly<\/a> ist Studiengangleiter des <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/artificial-intelligence-and-machine-learning\/\" target=\"_blank\" rel=\"noopener\">Bachelor-Studiums Artficial Intelligence &amp; Machine Learning<\/a> und Mitglied des <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/teams\/team-algorithmic-business\/?sourceurl=\/abiz\" target=\"_blank\" rel=\"noopener\">Algorithmic Business (ABIZ) Research Team<\/a>. Er ist seit 20 Jahren in verschiedenen Bereichen des maschinellen Lernens und der Signalverarbeitung t\u00e4tig. Seit f\u00fcnf Jahren f\u00fchlt sich KI f\u00fcr ihn an wie ein Technologie-Durchbruch, \u00abweil die Rechenleistung, die Algorithmen, die Daten und die Hochgeschwindigkeitskommunikation nun an einem Punkt sind, an dem die Durchbr\u00fcche einfach ph\u00e4nomenal sind\u00bb. In all diesen Bereichen war Daly w\u00e4hrend seiner Karriere aktiv.<\/p>\n<p><strong>Bilden Sie sich weiter:<\/strong> Mit dem <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/weiterbildung\/data-intelligence-and-big-data\/cas-artificial-intelligence\/\" target=\"_blank\" rel=\"noopener\">CAS Artificial Intelligence\/K\u00fcnstliche Intelligenz (AI\/KI)<\/a> KI verstehen, innovativ anwenden und hinter den Hype blicken! Der Kurs bietet einen fundierten Einstieg in die Algorithmen der K\u00fcnstlichen Intelligenz (KI) und vermittelt grundlegendes Wissen zu allen wichtigen Teilgebieten der KI.<\/p>\n<p><strong>Holen Sie sich einen Bachelor<\/strong>: Der zukunftsweisende Studiengang <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/studium\/bachelor\/artificial-intelligence-and-machine-learning\/\" target=\"_blank\" rel=\"noopener\">Artificial Intelligence &amp; Machine Learning<\/a> legt seinen Fokus auf die Schl\u00fcsseltechnologien der K\u00fcnstlichen Intelligenz. Hier holen Sie sich das R\u00fcstzeug f\u00fcr die steigende Nachfrage der Wirtschaft nach Fachkr\u00e4ften in den Bereichen K\u00fcnstliche Intelligenz und Robotik.<\/p>\n<p><strong>\u00dcber den Informatik-Blog:<\/strong> Hier erhalten Sie Tipps und Neuigkeiten aus der Welt der IT. Wir portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die Hochschule Luzern \u2013 Informatik mitpr\u00e4gen. <a href=\"https:\/\/hub.hslu.ch\/informatik\/#newsletter\" target=\"_blank\" rel=\"noopener\">Abonnieren Sie jetzt unseren Blog<\/a> und bleiben Sie informiert.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. <\/p>\n","protected":false},"author":4,"featured_media":8982,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"21475,21313,21379,21433,21291,21247","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[653304,4678],"tags":[653328,653588,653327],"class_list":["post-8936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artificial-intelligence-machine-learning","category-informatik","tag-ai","tag-digitale-ethik","tag-ki"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatik an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-19T09:39:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T14:11:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1620\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yasmin Billeter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weitertanzen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmin Billeter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/\"},\"author\":{\"name\":\"Yasmin Billeter\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"headline\":\"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen\",\"datePublished\":\"2020-08-19T09:39:57+00:00\",\"dateModified\":\"2026-02-06T14:11:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/\"},\"wordCount\":1863,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg\",\"keywords\":[\"AI\",\"digitale Ethik\",\"KI\"],\"articleSection\":[\"Artificial Intelligence\",\"Studium\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/\",\"name\":\"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg\",\"datePublished\":\"2020-08-19T09:39:57+00:00\",\"dateModified\":\"2026-02-06T14:11:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"description\":\"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg\",\"width\":1620,\"height\":1080,\"caption\":\"Donnacha Daly erkl\u00e4rt im Interview, wie das optimale Zusammenspiel von Mensch und Maschine in Zukunft aussehen k\u00f6nnte und welchen Beitrag unsere Studierenden dazu leisten k\u00f6nnen. (Bild: Ingo H\u00f6hn)\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\",\"name\":\"Informatik an der Hochschule Luzern\",\"description\":\"Der offizielle Blog der Hochschule Luzern \u2013 Informatik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\",\"name\":\"Yasmin Billeter\",\"description\":\"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yasmin-billeter\\\/\",\"https:\\\/\\\/x.com\\\/weitertanzen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern","description":"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/","og_locale":"de_DE","og_type":"article","og_title":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern","og_description":"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %","og_url":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/","og_site_name":"Informatik an der Hochschule Luzern","article_published_time":"2020-08-19T09:39:57+00:00","article_modified_time":"2026-02-06T14:11:51+00:00","og_image":[{"width":1620,"height":1080,"url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","type":"image\/jpeg"}],"author":"Yasmin Billeter","twitter_card":"summary_large_image","twitter_creator":"@weitertanzen","twitter_misc":{"Geschrieben von":"Yasmin Billeter","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/"},"author":{"name":"Yasmin Billeter","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"headline":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen","datePublished":"2020-08-19T09:39:57+00:00","dateModified":"2026-02-06T14:11:51+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/"},"wordCount":1863,"commentCount":1,"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","keywords":["AI","digitale Ethik","KI"],"articleSection":["Artificial Intelligence","Studium"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/","url":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/","name":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen - Informatik an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","datePublished":"2020-08-19T09:39:57+00:00","dateModified":"2026-02-06T14:11:51+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"description":"Futuristische Entwicklungen: Ob Roboterarmeen, direkte Gehirnschnittstellen oder digitale Ideenfindung \u2013 Donnacha Daly, der Studiengangleiter des Bachelor-Studiums Artificial Intelligence &amp; Machine Learning, traut KI vieles zu. Darum fordert er eine starke Regulierung. %","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#primaryimage","url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","contentUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","width":1620,"height":1080,"caption":"Donnacha Daly erkl\u00e4rt im Interview, wie das optimale Zusammenspiel von Mensch und Maschine in Zukunft aussehen k\u00f6nnte und welchen Beitrag unsere Studierenden dazu leisten k\u00f6nnen. (Bild: Ingo H\u00f6hn)"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/informatik\/so-wird-kunstliche-intelligenz-unser-leben-beeinflussen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/informatik\/"},{"@type":"ListItem","position":2,"name":"So wird k\u00fcnstliche Intelligenz unser Leben beeinflussen"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/informatik\/#website","url":"https:\/\/hub.hslu.ch\/informatik\/","name":"Informatik an der Hochschule Luzern","description":"Der offizielle Blog der Hochschule Luzern \u2013 Informatik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/informatik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f","name":"Yasmin Billeter","description":"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.","sameAs":["https:\/\/www.linkedin.com\/in\/yasmin-billeter\/","https:\/\/x.com\/weitertanzen"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/HSLU-Informatik-Bachelor-Info-11_19-110\u00a9Ingo-Hoehn-Kopie-e1610375778695.jpg","author_info":{"display_name":"Yasmin Billeter","author_link":"https:\/\/hub.hslu.ch\/informatik\/author\/yasminbilleter\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/8936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/comments?post=8936"}],"version-history":[{"count":73,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/8936\/revisions"}],"predecessor-version":[{"id":26506,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/8936\/revisions\/26506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media\/8982"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media?parent=8936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/categories?post=8936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/tags?post=8936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}