{"id":9269,"date":"2020-09-21T08:00:11","date_gmt":"2020-09-21T06:00:11","guid":{"rendered":"https:\/\/hub.hslu.ch\/informatik\/?p=9269"},"modified":"2026-02-10T14:33:06","modified_gmt":"2026-02-10T13:33:06","slug":"virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/","title":{"rendered":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">By Yasmin Billeter<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Die Luzerner <a href=\"https:\/\/www.kathluzern.ch\/pfarreien-standorte\/peterskapelle\/ueber-uns\/peterskapelle.html\" target=\"_blank\" rel=\"noreferrer noopener\">Peterskapelle<\/a>, die im Jahr 1178 erstmals erw\u00e4hnt wird, gibt es nun auch virtuell: F\u00fcr die <a href=\"https:\/\/www.hslu.ch\/de-ch\/design-kunst\/agenda\/alle-veranstaltungen\/2020\/09\/21\/palacetine\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ausstellung \u00abPalacetine\u00bb<\/a> wurde der Innenraum der Kirche von unserem <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/teams\/immersive-realities\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immersive Realities Research Lab<\/a> nachmodelliert. Besucherinnen und Besucher k\u00f6nnen sich nun mit einer VR-Brille in der Kapelle bewegen und diese komplett neu erleben: mit Gl\u00fchw\u00fcrmchen und Kerzenschein oder im Ambiente einer pal\u00e4stinensischen Stadt. In einer anderen Szene werden Teile der Kapelle abgerissen. Ein Hubschrauber kreist, man h\u00f6rt die Ger\u00e4usche einer Schlacht. Oder sie beobachten, wie die Natur das Innere der Kapelle zur\u00fcckerobert: B\u00e4ume, Gras, Schafe und Ger\u00e4usche eines Waldes, der gerade aufwacht.<\/p>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"9281\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-1024x1024.jpg\" alt=\"\" class=\"wp-image-9281\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-1024x1024.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-300x300.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-150x150.jpg 150w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-768x768.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743-698x698.jpg 698w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092743.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"9278\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-1024x1024.jpg\" alt=\"\" class=\"wp-image-9278\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-1024x1024.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-300x300.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-150x150.jpg 150w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-768x768.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538-698x698.jpg 698w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092538.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" data-id=\"9279\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-1024x1024.jpg\" alt=\"\" class=\"wp-image-9279\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-1024x1024.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-300x300.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-150x150.jpg 150w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-768x768.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645-698x698.jpg 698w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/com.ImmersiveRealities.PeterskapelleVR-20200917-092645.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"618\" data-id=\"9275\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6-1024x618.png\" alt=\"\" class=\"wp-image-9275\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6-1024x618.png 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6-300x181.png 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6-768x463.png 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6-928x560.png 928w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PeterskapellePhotoArrangementScreenshot6.png 1076w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><br><br><br><br><em>Durch das Darstellen der Fotografien und Kunstwerke in den unterschiedlichen Szenen ergeben sich neue Kontexte f\u00fcr die Arbeit.<\/em><\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In der echten wie auch in der virtuellen Kirche sind Fotografien, Videos und Installationen zu sehen, welche im Rahmen des interdisziplin\u00e4ren <a href=\"https:\/\/www.hslu.ch\/de-ch\/design-kunst\/studium\/studienuebergreifende-module\/ida-im-bachelor\/ida-modulangebot-2020\/ida-110\/\" target=\"_blank\" rel=\"noreferrer noopener\">Moduls \u00abIsrael-Pal\u00e4stina<\/a>\u00bb entstanden sind. Dabei setzen sich K\u00fcnstlerinnen und K\u00fcnstler aus der Schweiz und aus Pal\u00e4stina mit der geografisch-politischen Region Israel-Pal\u00e4stina auseinander. \u00abDurch die unterschiedlichen VR-Szenen k\u00f6nnen wir die Stimmung der Fotos aufnehmen und verst\u00e4rken. So ergeben sich neue Kontexte f\u00fcr die Arbeit\u00bb, sagt Richard Wetzel, Co-Leiter des <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/teams\/immersive-realities\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immersive Realities Research Labs<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VR erm\u00f6glicht Ausstellung, welche durch Corona verunm\u00f6glicht wurde<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das <a rel=\"noreferrer noopener\" href=\"https:\/\/www.hslu.ch\/de-ch\/design-kunst\/studium\/studienuebergreifende-module\/ida-im-bachelor\/ida-modulangebot-2020\/ida-110\/\" target=\"_blank\">Modul<\/a> der Hochschule Luzern \u2013 Design &amp; Kunst sah eigentlich eine Studienreise nach Pal\u00e4stina vor. Durch den Corona-Lockdown kam aber alles anders: \u00abStatt nach Betlehem zu reisen, tauschten wir uns via Zoom mit Studierenden und Referenten in Betlehem aus\u00bb, sagt Marco Schmid von der Peterskapelle. <\/p>\n\n\n\n<figure class=\"wp-block-embed aligncenter is-type-video is-provider-vimeo\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"The Question Project Pt. I\" src=\"https:\/\/player.vimeo.com\/video\/425871726?dnt=1&amp;app_id=122963\" width=\"640\" height=\"360\" frameborder=\"0\" allow=\"autoplay; fullscreen; picture-in-picture; clipboard-write\"><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Der Theologe absolviert in Teilzeit den Studiengang Kunst und Vermittlung und hat das Modul initiiert. Da der Austausch nun virtuell stattfand, hatte er die Idee zu einer VR-Ausstellung und zu der Zusammenarbeit mit dem Forschungsteam des Departements Informatik. \u00abMit diesem Projekt m\u00f6chten wir erste Erfahrungen sammeln\u00bb, sagt Schmid. Und es ist Grundlage f\u00fcr m\u00f6gliche weitere gemeinsame Projekte der Hochschule Luzern und der Peterskapelle.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote has-text-align-center is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00abDie Kirche w\u00e4re ja bl\u00f6d, wenn sie die Technik nicht f\u00fcr sich nutzen w\u00fcrde\u00bb<\/p>\n<cite>Marco Schmid, Peterskapelle<\/cite><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Die Forschenden untersuchten gemeinsam mit dem Team der Peterskapelle, welche Rolle Virtual und Augmented Reality f\u00fcr die Institution Kirche in Zukunft spielen k\u00f6nnten. \u00abVR wird vereinzelt bei besonders bekannten Kirchen eingesetzt\u00bb, sagt Richard Wetzel. So k\u00f6nne man etwa die Pariser Kathedrale <a rel=\"noreferrer noopener\" href=\"https:\/\/www.youtube.com\/watch?v=UFZEYeJH3gg\" target=\"_blank\">Notre-Dame<\/a> in VR besuchen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>VR um architektonische Entwicklung zu visualisieren<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch f\u00fcr die Peterskapelle sei es interessant, einen \u00abvirtuellen Zwilling\u00bb zu erstellen. \u00abGerade wenn man architektonische Entwicklungen aufzeigen m\u00f6chte.\u00bb Als eines der \u00e4ltesten Geb\u00e4ude der Stadt Luzern ist die Kapelle historisch wichtig: Hier gab es die erste Siedlung, und am rechten Reuss-Ufer <a rel=\"noreferrer noopener\" href=\"https:\/\/www.luzernerzeitung.ch\/zentralschweiz\/luzern\/als-die-luzerner-kapellbruecke-noch-zur-kapelle-fuehrte-ld.1245854\" target=\"_blank\">reichte die Kapellbr\u00fccke einst bis direkt vor die Peterskapelle<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Virtuelle Inszenierung eines Krippenspiels denkbar<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Christlicher Glaube und neueste Technik \u2013 passt das zusammen? \u00abDie Kirche w\u00e4re ja bl\u00f6d, wenn sie die Technik nicht f\u00fcr sich nutzen w\u00fcrde\u00bb, sagt Marco Schmid von der Peterskapelle. Daraus k\u00f6nnten sich wunderbare Sachen entwickeln: \u00abEine virtuelle Weihnachtskrippe zum Beispiel, die man mit VR-Brille betreten und dann mit den Figuren sprechen k\u00f6nnte.\u00bb Da die Kapelle denkmalgesch\u00fctzt ist, er\u00f6ffnet die Technologie auch neue M\u00f6glichkeiten, den Raum spielerisch zu nutzen. Und auch ein neues Publikum k\u00f6nne angesprochen werden: Technikaffine, aber auch Menschen, die aufgrund von gesundheitlichen Einschr\u00e4nkungen die Peterskapelle nicht aufsuchen k\u00f6nnen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-1024x768.jpg\" alt=\"\" class=\"wp-image-9318\" srcset=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-1024x768.jpg 1024w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-300x225.jpg 300w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-768x576.jpg 768w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-1536x1152.jpg 1536w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820-928x696.jpg 928w, https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/PXL_20200916_164948820.jpg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Die VR-Brillen liegen bereit: Die virtuelle Peterskapelle mit der VR-Brille ist t\u00e4glich von 15.30-18.30 zug\u00e4nglich.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Marco Schmid von der Peterskapelle ist gespannt, wie die Besucherinnen und Besucher reagieren. Aus eigener Erfahrung mit einer studentischen Arbeit im Bereich Augmented Reality weiss er: \u00abDie H\u00fcrde, sich auf neue Technologien einzulassen, ist bei vielen Menschen hoch. Oft bestehen eine gewisse Angst und Distanz, die \u00fcberwunden werden m\u00fcssen, und es braucht Leute, die einem an der Hand nehmen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f6ffentlicht: 21.09.2020<\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong>Virtual Reality in der Peterskapelle: Unsere Forschenden bauen \u00e4lteste Kirche der Stadt Luzern digital nach<\/strong><\/p>\n<p>Die Peterskapelle wird virtuell dank <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3930\" target=\"_blank\" rel=\"noreferrer noopener\">Tobias Kreienb\u00fchl<\/a> und <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=4586\" target=\"_blank\" rel=\"noreferrer noopener\">Naomi Burgess<\/a> von unserem <a href=\"https:\/\/www.hslu.ch\/de-ch\/informatik\/forschung\/teams\/immersive-realities\/\" target=\"_blank\" rel=\"noreferrer noopener\">Immersive Realities Research Lab<\/a>. Kreienb\u00fchl hat die Kirche durch das \u00dcbereinbanderlegen von Pl\u00e4nen und Fotos nachmodelliert. Burgess ist f\u00fcr die verschiedenen Szenen und die virtuelle Ausstellung verantwortlich. Geleitet wurde das Projekt von <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=4075\" target=\"_blank\" rel=\"noopener\">Markus Zank<\/a> und <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=4112\" target=\"_blank\" rel=\"noopener\">Richard Wetzel<\/a>.<\/p>\n<p><a href=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/flyer1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-9276\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/flyer1-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><a href=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/flyer2.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-thumbnail wp-image-9284\" src=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/flyer2-150x150.png\" alt=\"\" width=\"150\" height=\"150\" \/><\/a><\/p>\n<p><strong>Informiert bleiben: <\/strong>Tipps, Trends und Neuigkeiten aus der Welt der Informatik, Portr\u00e4ts von IT-Vordenkerinnen, Vision\u00e4ren und spannenden Menschen: <a href=\"https:\/\/hub.hslu.ch\/informatik\/#newsletter\" target=\"_blank\" rel=\"noopener\">Abonnieren Sie jetzt unseren Blog<\/a> und bleiben Sie informiert.<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb  in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik.  <\/p>\n","protected":false},"author":4,"featured_media":9274,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"26450,26275,26420,26236,26222,25888","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[393030],"tags":[393034],"class_list":["post-9269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immersive-realities","tag-virtual-und-augmented-reality"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern<\/title>\n<meta name=\"description\" content=\"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/\" \/>\n<meta property=\"og:site_name\" content=\"Informatik an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-21T06:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T13:33:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1951\" \/>\n\t<meta property=\"og:image:height\" content=\"1140\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yasmin Billeter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@weitertanzen\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yasmin Billeter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/\"},\"author\":{\"name\":\"Yasmin Billeter\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"headline\":\"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern\",\"datePublished\":\"2020-09-21T06:00:11+00:00\",\"dateModified\":\"2026-02-10T13:33:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/\"},\"wordCount\":664,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Peterkapelle-white.png\",\"keywords\":[\"Virtual und Augmented Reality\"],\"articleSection\":[\"Immersive Realities\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#respond\"]}]},{\"@type\":[\"WebPage\",\"ItemPage\"],\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/\",\"name\":\"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Peterkapelle-white.png\",\"datePublished\":\"2020-09-21T06:00:11+00:00\",\"dateModified\":\"2026-02-10T13:33:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\"},\"description\":\"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Peterkapelle-white.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/wp-content\\\/blogs.dir\\\/632\\\/files\\\/sites\\\/3\\\/Peterkapelle-white.png\",\"width\":1951,\"height\":1140,\"caption\":\"Voller Gl\u00fchw\u00fcrmchen oder als pal\u00e4stinensischer Ort: So haben Sie die Peterskapelle noch nie erlebt.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/\",\"name\":\"Informatik an der Hochschule Luzern\",\"description\":\"Der offizielle Blog der Hochschule Luzern \u2013 Informatik\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/informatik\\\/#\\\/schema\\\/person\\\/812dcf123b47ed2e36ce795218a6564f\",\"name\":\"Yasmin Billeter\",\"description\":\"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yasmin-billeter\\\/\",\"https:\\\/\\\/x.com\\\/weitertanzen\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern","description":"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/","og_locale":"de_DE","og_type":"article","og_title":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern","og_description":"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %","og_url":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/","og_site_name":"Informatik an der Hochschule Luzern","article_published_time":"2020-09-21T06:00:11+00:00","article_modified_time":"2026-02-10T13:33:06+00:00","og_image":[{"width":1951,"height":1140,"url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","type":"image\/png"}],"author":"Yasmin Billeter","twitter_card":"summary_large_image","twitter_creator":"@weitertanzen","twitter_misc":{"Geschrieben von":"Yasmin Billeter","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/"},"author":{"name":"Yasmin Billeter","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"headline":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern","datePublished":"2020-09-21T06:00:11+00:00","dateModified":"2026-02-10T13:33:06+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/"},"wordCount":664,"commentCount":2,"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","keywords":["Virtual und Augmented Reality"],"articleSection":["Immersive Realities"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#respond"]}]},{"@type":["WebPage","ItemPage"],"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/","url":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/","name":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern - Informatik an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","datePublished":"2020-09-21T06:00:11+00:00","dateModified":"2026-02-10T13:33:06+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f"},"description":"VR ausprobieren und eine virtuelle Kapelle erleben: Die Ausstellung \u00abPalacetine\u00bb in der Peterskapelle findet sowohl real als auch virtuell statt. Unser Immersive Realities Research Lab schafft dabei Raum f\u00fcr einen Austausch zwischen Design und Kunst, Kirche und Informatik. %","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#primaryimage","url":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","contentUrl":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","width":1951,"height":1140,"caption":"Voller Gl\u00fchw\u00fcrmchen oder als pal\u00e4stinensischer Ort: So haben Sie die Peterskapelle noch nie erlebt."},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/informatik\/virtual-reality-in-der-aeltesten-kirche-der-stadt-luzern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/informatik\/"},{"@type":"ListItem","position":2,"name":"Virtual Reality \u2013 in der \u00e4ltesten Kirche der Stadt Luzern"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/informatik\/#website","url":"https:\/\/hub.hslu.ch\/informatik\/","name":"Informatik an der Hochschule Luzern","description":"Der offizielle Blog der Hochschule Luzern \u2013 Informatik","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/informatik\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/informatik\/#\/schema\/person\/812dcf123b47ed2e36ce795218a6564f","name":"Yasmin Billeter","description":"Verantwortlich f\u00fcr den Informatik-Blog der Hochschule Luzern. Hier geben wir Tipps &amp; Neuigkeiten aus der Welt der IT, portr\u00e4tieren Menschen und schreiben \u00fcber Technologien, welche die HSLU \u2013 I mitpr\u00e4gen.","sameAs":["https:\/\/www.linkedin.com\/in\/yasmin-billeter\/","https:\/\/x.com\/weitertanzen"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","featured_image_src_square":"https:\/\/hub.hslu.ch\/informatik\/wp-content\/blogs.dir\/632\/files\/sites\/3\/Peterkapelle-white.png","author_info":{"display_name":"Yasmin Billeter","author_link":"https:\/\/hub.hslu.ch\/informatik\/author\/yasminbilleter\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/9269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/comments?post=9269"}],"version-history":[{"count":70,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/9269\/revisions"}],"predecessor-version":[{"id":26718,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/posts\/9269\/revisions\/26718"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media\/9274"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/media?parent=9269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/categories?post=9269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/informatik\/wp-json\/wp\/v2\/tags?post=9269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}