{"id":34,"count":7,"description":"","link":"https:\/\/hub.hslu.ch\/leadership\/tag\/konflikmanagement\/","name":"Konflikmanagement","slug":"konflikmanagement","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Konflikmanagement Archive - Leadership Network Lucerne<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Konflikmanagement Archive - Leadership Network Lucerne\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/leadership\/tag\/konflikmanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"Leadership Network Lucerne\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/tag\\\/konflikmanagement\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/tag\\\/konflikmanagement\\\/\",\"name\":\"Konflikmanagement Archive - Leadership Network Lucerne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/#website\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/\",\"name\":\"Leadership Network Lucerne\",\"description\":\"Sichtwechsel. Leadership ist Haltung. Das lehren wir.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/leadership\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Konflikmanagement Archive - Leadership Network Lucerne","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Konflikmanagement Archive - Leadership Network Lucerne","og_url":"https:\/\/hub.hslu.ch\/leadership\/tag\/konflikmanagement\/","og_site_name":"Leadership Network Lucerne","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/leadership\/tag\/konflikmanagement\/","url":"https:\/\/hub.hslu.ch\/leadership\/tag\/konflikmanagement\/","name":"Konflikmanagement Archive - Leadership Network Lucerne","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/leadership\/#website"},"inLanguage":"de-CH"},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/leadership\/#website","url":"https:\/\/hub.hslu.ch\/leadership\/","name":"Leadership Network Lucerne","description":"Sichtwechsel. Leadership ist Haltung. Das lehren wir.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/leadership\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/leadership\/wp-json\/wp\/v2\/tags\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/leadership\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hub.hslu.ch\/leadership\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/leadership\/wp-json\/wp\/v2\/posts?tags=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}