{"id":6150,"date":"2023-11-22T17:03:03","date_gmt":"2023-11-22T16:03:03","guid":{"rendered":"https:\/\/hub.hslu.ch\/management-and-law\/?p=6150"},"modified":"2026-02-11T14:53:45","modified_gmt":"2026-02-11T13:53:45","slug":"vertraege-schreiben-mit-ki","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/","title":{"rendered":"Vertr\u00e4ge schreiben mit KI?"},"content":{"rendered":"\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p><strong><em>Management &amp; Law-Blog:<\/em><\/strong> <strong><em>Wer schreibt die besseren Vertr\u00e4ge, ChatGPT oder der erfahrene Rechtsanwalt Ueli Gr\u00fcter?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=126\" target=\"_blank\" rel=\"noreferrer noopener\">Ueli Gr\u00fcter<\/a>:<\/em><\/strong> (lacht) &#8211; Ich nat\u00fcrlich! Nein, Spass beiseite. Auch im juristischen Arbeitsfeld gilt meines Erachtens, was vielerorts gilt: Der gezielte und gekonnte Einsatz von KI-Tools kann einem den Arbeitsalltag enorm erleichtern. Schon vor dem Aufkommen von ChatGPT &amp; Co. hat sich kaum jemand &#8211; ob mit oder ohne juristischen Background &#8211; hingesetzt und einen Vertrag auf dem weissen Blatt Papier erstellt. Fr\u00fcher arbeitete man mit Mustervertr\u00e4gen, heute mit KI-Tools. KI-Tools \u00fcbernehmen also (noch) nicht die Arbeit von Rechtsanw\u00e4ltinnen und Rechtsanw\u00e4lten, sondern unterst\u00fctzen diese bei ihrer Arbeit.<\/p>\n\n\n\n<p><strong><em>Management &amp; Law-Blog: Wieso ist gerade das Verfassen von Vertr\u00e4gen ein Paradebeispiel einer juristischen T\u00e4tigkeit, bei der KI-Tools helfen k\u00f6nnen?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Ueli Gr\u00fcter: <\/em><\/strong>Aus meiner Sicht hat dies verschiedene Gr\u00fcnde, unter anderem und ganz grundlegend jenen, dass es schlicht sehr viele Vertr\u00e4ge zu schreiben gibt: Jedes Unternehmen, vom KMU bis zum Grosskonzern, schliesst t\u00e4glich Vertr\u00e4ge ab. In vielen Unternehmen sind es dabei nicht prim\u00e4r Juristinnen oder Juristen, welche die Vertr\u00e4ge verhandeln, entwerfen und verwalten, sondern beispielsweise Fachpersonen mit betriebswirtschaftlichem oder technischem Hintergrund. Sie bringen das f\u00fcr den Kern des Vertrags essenzielle Business-Knowhow mit und wissen ganz genau, welche Punkte vertraglich wie geregelt werden soll. Diesen klaren Inhalt dann in ein ebenso klares und verst\u00e4ndliches Vertragsdokument zu giessen, kann f\u00fcr diese Fachleute aber bisweilen eine Herausforderung sein. Und hier k\u00f6nnen KI-Tools helfen.<\/p>\n\n\n\n<p><em style=\"font-weight: bold\">Management &amp; Law-Blog:<\/em><strong><em> Wie k\u00f6nnen ChatGPT &amp; Co. konkret bei der Vertragsredaktion unterst\u00fctzen?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Ueli Gr\u00fcter: <\/em><\/strong>Bei der Redaktion von Vertr\u00e4gen k\u00f6nnen Chatbots beispielsweise Checklisten f\u00fcr die Vertragserstellung und Mustervertr\u00e4ge generieren. Anders als generische Vertragsvorlagen, mit denen man fr\u00fcher gearbeitet hat, sind die Tools in der Lage, diese bereits mit den entsprechenden Fakten anzureichern und auf einen konkreten Fall masszuschneidern.<\/p>\n\n\n\n<p><em><strong>Management &amp; Law-Blog:<\/strong><\/em><strong><em> Worauf muss man dabei achten?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Ueli Gr\u00fcter: <\/em><\/strong>Bei der Unterst\u00fctzung der Vertragsredaktion sind die Prompts besonders wichtig: Man muss dem Tool m\u00f6glichst genau sagen, was man will und nach M\u00f6glichkeit auch die dem gew\u00fcnschten Vertrag zugrundeliegenden Fakten eingeben. Bei einem Mustervertrag sollte man auch definieren, wie umfangreich das Muster sein soll. Man kann aber auch sp\u00e4ter verlangen, dass das Tool zu einer bestimmten Vertragsklausel eine umfangreichere, evtl. auch st\u00e4rker auf den Fall bezogene Version liefert. So kann der Chatbot, step by step, bei der Redaktion eines Vertrages behilflich sein.<\/p>\n\n\n\n<p><em><strong>Management &amp; Law-Blog:<\/strong><\/em><strong><em> Wo ist Vorsicht geboten?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Ueli Gr\u00fcter: <\/em><\/strong>Auch im juristischen Bereich muss man sich der Funktionsweise der KI-Tools und ihren damit einhergehenden Grenzen bewusst sein. Die Tools sind nicht fehlerfrei und k\u00f6nnen sogar &#171;halluzinieren&#187;, wie man in diesem Kontext sagt, d.h. Antworten schlicht erfinden. Manchmal scheinen die Resultate plausibel, sind aber trotzdem nicht richtig, was das Ganze gef\u00e4hrlich macht. Mit Blick auf das Schreiben von Vertr\u00e4gen heisst das, dass man die Resultate, die ein Tool ausspuckt, nie unbesehen \u00fcbernehmen kann und immer \u00fcberpr\u00fcfen und gegebenenfalls adaptieren muss. Genauso, wie es nicht zielf\u00fchrend, weil ineffizient, ist, f\u00fcr die Vertragserstellung keine KI zu benutzen, w\u00e4re es nicht zielf\u00fchrend, weil fahrl\u00e4ssig, sie un\u00fcberlegt und ohne Hintergrundwissen einzusetzen.<\/p>\n\n\n\n<p><em><strong>Management &amp; Law-Blog:<\/strong><\/em><strong><em> Sie unterrichten unter anderem im CAS Vertragsmanagement der Hochschule Luzern und geben den Weiterbildungsteilnehmenden dort einen Einblick in Legal Tech, d.h. die Digitalisierung der Rechtsbranche und entsprechende Anwendungen, wie Smart Contracts und Tools basierend auf k\u00fcnstlicher Intelligenz wie eben Chatbots. Wenn Sie die aktuellen Entwicklungen im KI-Bereich verfolgen &#8211; was braucht die Vertragsmanagerin bzw. der Vertragsmanager der Zukunft noch f\u00fcr Kompetenzen?<\/em><\/strong><\/p>\n\n\n\n<p> <strong><em>Ueli Gr\u00fcter: <\/em><\/strong>KI-Tools unterst\u00fctzen Vertragsmanagerinnen und Vertragsmanager zuk\u00fcnftig wohl immer mehr bei ihren Aufgaben \u00fcber den gesamten Vertragslebenszyklus hinweg: vom Verfassen und das Analysieren von Vertr\u00e4gen \u00fcber das \u00dcberwachen bis hin zum Verwalten und Archivieren. Gerade wenn es um das Verfassen geht, ist aber nach wie vor grunds\u00e4tzliches Knowhow im Recht, \u00fcber das Wesen und die Funktionsweise von Vertr\u00e4gen, sowie im Handwerk der Vertragssprache und deren Verwendung n\u00f6tig. Denn der Vertragsmanager oder die Vertragsmanagerin von morgen wird vielleicht in weniger ausgepr\u00e4gtem Masse in das Aufsetzen des ersten Vertragsentwurfs in der aktiv-schreibenden Rolle involviert sein, aber er bzw. sie wird ihn kritisch pr\u00fcfen und adaptieren m\u00fcssen. Und hierf\u00fcr braucht es Vertragsmanagement-Kompetenzen. Mit dem Einsatz von KI werden Vertr\u00e4ge und ihr Management je l\u00e4nger desto weniger ein rein juristischer Task sein, sondern interdisziplin\u00e4re Skills verlangen. Das CAS Vertragsmanagement, bei dem ich als Dozent dabei sein darf, deckt neben den rechtlichen Grundlagen zu Vertr\u00e4gen, denen ein Modul gewidmet ist, auch die taktisch-kommunikative Seite von Vertragsstrategie und -verhandeln und die operativ-prozessorientierte Seite von Vertr\u00e4gen ab (Informationen zum CAS Vertragsmanagement in der Box).&nbsp;<\/p>\n\n\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n\n\n\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns gb-layout-columns-2 gb-2-col-wideright gb-has-custom-background-color\" style=\"padding-top:35px;padding-left:15px;background-color:#f1f2f3\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<figure class=\"wp-block-image size-full is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"337\" height=\"449\" src=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/Bild-Ueli.jpg\" alt=\"\" class=\"wp-image-6152\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/Bild-Ueli.jpg 337w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/Bild-Ueli-225x300.jpg 225w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner\">\n<p style=\"font-size:14px\"><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=126\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Ueli Gr\u00fcter<\/strong><\/a><br>Rechtsanwalt, LL.M.<\/p>\n\n\n\n<p style=\"font-size:14px\">Ueli Gr\u00fcter ist als Rechtsanwalt und Dozent an der Hochschule Luzern spezialisiert auf Themen an der Schnittstelle zwischen Digitalisierung und Recht.<br><br>Ab Januar 2024 unterrichtet Ueli Gr\u00fcter in der n\u00e4chsten Durchf\u00fchrung des CAS Vertragsmanagement der Hochschule Luzern \u2013 Wirtschaft.<\/p>\n\n\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-columns gb-layout-service-3 gb-layout-columns-2 gb-2-col-wideright gb-has-custom-background-color has-black-color gb-columns-center alignfull\" style=\"padding-top:5%;padding-right:5%;padding-left:5%;background-color:#e0f3ff\"><div class=\"gb-layout-column-wrap gb-block-layout-column-gap-2 gb-is-responsive-column\" style=\"max-width:1210px\">\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column\"><div class=\"gb-block-layout-column-inner has-pale-cyan-blue-color\">\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img decoding=\"async\" src=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2021\/06\/Bild_Webseite_Handschlag-1024x683.jpg\" alt=\"\" class=\"wp-image-3800\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-column gb-block-layout-column gb-is-vertically-aligned-center\"><div class=\"gb-block-layout-column-inner\">\n<h6 class=\"wp-block-heading\"><strong>CAS Vertragsmanagement<\/strong><br><\/h6>\n\n\n\n\n\n<p class=\"has-small-font-size\">In drei praxisorientierten Modulen vermittelt das CAS Vertragsmanagement fundierte Kenntnisse in den Bereichen Recht und Vertragsgestaltung, Strategie und Verhandeln sowie Tools und Prozesse.<br>Die n\u00e4chste Durchf\u00fchrung der Weiterbildung startet im Januar 2024 und dauert bis Juni 2024.<\/p>\n\n\n\n<h6 class=\"wp-block-heading has-small-font-size\"><strong>Infoveranstaltung (online): 27. November 2023, 18.00 Uhr<\/strong><\/h6>\n\n\n\n<h6 class=\"wp-block-heading has-small-font-size\"><strong>Anmeldeschluss: 4. Dezember 2023<\/strong><\/h6>\n\n\n\n\n\n\n\n<div class=\"wp-block-genesis-blocks-gb-button gb-block-button\"><a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ibr\/cas-vertragsmanagement\/\" target=\"_blank\" rel=\"noopener noreferrer\" class=\"gb-button gb-button-shape-rounded gb-button-size-medium\" style=\"color:#ffffff;background-color:#4abaff\">Weitere Infos<\/a><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n\n\n\n\n\n\n<figure class=\"wp-block-embed is-type-wp-embed is-provider-juristenfutter wp-block-embed-juristenfutter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"wp-embedded-content\" data-secret=\"uQSWJzhf4d\"><a href=\"https:\/\/juristenfutter.ch\/2023\/11\/19\/chatgpt-co-im-juristischen-alltag\/\">ChatGPT &#038;. Co. im juristischen Alltag<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8222;ChatGPT &#038;. Co. im juristischen Alltag&#8220; &#8212; Juristenfutter\" src=\"https:\/\/juristenfutter.ch\/2023\/11\/19\/chatgpt-co-im-juristischen-alltag\/embed\/#?secret=zpWNSprfWh#?secret=uQSWJzhf4d\" data-secret=\"uQSWJzhf4d\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Themen recherchieren, Social Media-Posts schreiben oder Marketing-Konzepte entwickeln &#8211; Derzeit gewinnt man den Eindruck, dass KI-Tools wie ChatGPT &amp; Co. so ziemlich alles k\u00f6nnen. K\u00f6nnen Sie auch Vertr\u00e4ge entwerfen? Ueli Gr\u00fcter, Rechtsanwalt und Dozent im CAS Vertragsmanagement der Hochschule Luzern, hat es ausprobiert und teilt seine Erfahrungen in einem Interview. <\/p>\n","protected":false},"author":62,"featured_media":6169,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"5240,4629,753,5343,1058,4333","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[563231,563223],"tags":[],"class_list":["post-6150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital-law","category-vertragsrecht"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vertr\u00e4ge schreiben mit KI? - Management and Law Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vertr\u00e4ge schreiben mit KI? - Management and Law Blog\" \/>\n<meta property=\"og:description\" content=\"Themen recherchieren, Social Media-Posts schreiben oder Marketing-Konzepte entwickeln - Derzeit gewinnt man den Eindruck, dass KI-Tools wie ChatGPT &amp; Co. so ziemlich alles k\u00f6nnen. K\u00f6nnen Sie auch Vertr\u00e4ge entwerfen? Ueli Gr\u00fcter, Rechtsanwalt und Dozent im CAS Vertragsmanagement der Hochschule Luzern, hat es ausprobiert und teilt seine Erfahrungen in einem Interview.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/\" \/>\n<meta property=\"og:site_name\" content=\"Management and Law Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T16:03:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1505\" \/>\n\t<meta property=\"og:image:height\" content=\"893\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Isabelle Oehri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle Oehri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/\"},\"author\":{\"name\":\"Isabelle Oehri\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\"},\"headline\":\"Vertr\u00e4ge schreiben mit KI?\",\"datePublished\":\"2023-11-22T16:03:03+00:00\",\"dateModified\":\"2026-02-11T13:53:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/\"},\"wordCount\":914,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2023\\\/11\\\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png\",\"articleSection\":[\"Digitalisierung und Digital Law\",\"Vertragsrecht\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/\",\"name\":\"Vertr\u00e4ge schreiben mit KI? - Management and Law Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2023\\\/11\\\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png\",\"datePublished\":\"2023-11-22T16:03:03+00:00\",\"dateModified\":\"2026-02-11T13:53:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2023\\\/11\\\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2023\\\/11\\\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png\",\"width\":1505,\"height\":893,\"caption\":\"Ueli Gr\u00fcter ist regelm\u00e4ssig Interviewpartner zu Themen an der Schnittstelle zwischen Recht und Digitalisierung \u2013 im Bild f\u00fcr 10vor10 von SRF\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2023\\\/11\\\/22\\\/vertraege-schreiben-mit-ki\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vertr\u00e4ge schreiben mit KI?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\",\"name\":\"Management and Law Blog\",\"description\":\"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\",\"name\":\"Isabelle Oehri\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/isabelle-oehri-b81891158\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vertr\u00e4ge schreiben mit KI? - Management and Law Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/","og_locale":"de_DE","og_type":"article","og_title":"Vertr\u00e4ge schreiben mit KI? - Management and Law Blog","og_description":"Themen recherchieren, Social Media-Posts schreiben oder Marketing-Konzepte entwickeln - Derzeit gewinnt man den Eindruck, dass KI-Tools wie ChatGPT &amp; Co. so ziemlich alles k\u00f6nnen. K\u00f6nnen Sie auch Vertr\u00e4ge entwerfen? Ueli Gr\u00fcter, Rechtsanwalt und Dozent im CAS Vertragsmanagement der Hochschule Luzern, hat es ausprobiert und teilt seine Erfahrungen in einem Interview.","og_url":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/","og_site_name":"Management and Law Blog","article_published_time":"2023-11-22T16:03:03+00:00","article_modified_time":"2026-02-11T13:53:45+00:00","og_image":[{"width":1505,"height":893,"url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","type":"image\/png"}],"author":"Isabelle Oehri","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Isabelle Oehri","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/"},"author":{"name":"Isabelle Oehri","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d"},"headline":"Vertr\u00e4ge schreiben mit KI?","datePublished":"2023-11-22T16:03:03+00:00","dateModified":"2026-02-11T13:53:45+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/"},"wordCount":914,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","articleSection":["Digitalisierung und Digital Law","Vertragsrecht"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/","url":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/","name":"Vertr\u00e4ge schreiben mit KI? - Management and Law Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","datePublished":"2023-11-22T16:03:03+00:00","dateModified":"2026-02-11T13:53:45+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#primaryimage","url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","contentUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","width":1505,"height":893,"caption":"Ueli Gr\u00fcter ist regelm\u00e4ssig Interviewpartner zu Themen an der Schnittstelle zwischen Recht und Digitalisierung \u2013 im Bild f\u00fcr 10vor10 von SRF"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2023\/11\/22\/vertraege-schreiben-mit-ki\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/management-and-law\/"},{"@type":"ListItem","position":2,"name":"Vertr\u00e4ge schreiben mit KI?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website","url":"https:\/\/hub.hslu.ch\/management-and-law\/","name":"Management and Law Blog","description":"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/management-and-law\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d","name":"Isabelle Oehri","sameAs":["https:\/\/www.linkedin.com\/in\/isabelle-oehri-b81891158\/"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","featured_image_src_square":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2023\/11\/FireShot-Capture-609-SRF_-Rekordbusse-fuer-Google-tp.srgssr.ch_.png","author_info":{"display_name":"Isabelle Oehri","author_link":"https:\/\/hub.hslu.ch\/management-and-law\/author\/isabelleoehri\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/comments?post=6150"}],"version-history":[{"count":39,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6150\/revisions"}],"predecessor-version":[{"id":7479,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6150\/revisions\/7479"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media\/6169"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media?parent=6150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/categories?post=6150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/tags?post=6150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}