{"id":6520,"date":"2024-08-22T08:17:14","date_gmt":"2024-08-22T06:17:14","guid":{"rendered":"https:\/\/hub.hslu.ch\/management-and-law\/?p=6520"},"modified":"2026-02-11T14:53:46","modified_gmt":"2026-02-11T13:53:46","slug":"unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/","title":{"rendered":"Unbezahlter Urlaub &#8211; Was ist arbeitsrechtlich zu beachten?"},"content":{"rendered":"\n\n\n<p>Johanna, die mittlerweile am Strand sitzt und die Sonne geniesst, entschliesst sich, anhand einer Internetrecherche die wichtigsten Dinge f\u00fcr ihre geplante Weltreise herauszufinden. Sobald sie n\u00e4mlich aus den Ferien zur\u00fcck ist, m\u00f6chte sie mit ihrem Arbeitgeber \u00fcber die M\u00f6glichkeit von unbezahltem Urlaub sprechen. Werfen Sie einen Blick in Johannas Notizbuch, um herauszufinden was dabei arbeitsrechtlich zu beachten ist:<\/p>\n\n\n\n<p style=\"text-decoration:underline\"><strong><em>Ausgangslage<\/em><\/strong><\/p>\n\n\n\n<p><em>Mein Arbeitgeber hat mir gem\u00e4ss <em><a href=\"https:\/\/www.fedlex.admin.ch\/eli\/cc\/27\/317_321_377\/de#art_329_a\">Art. 329a OR<\/a><\/em> wenigstens&nbsp;4 Wochen Ferien pro Jahr zu gew\u00e4hren. W\u00e4hrend dieser Zeit erhalte ich den vollen Lohn.<\/em><\/p>\n\n\n\n<p><em>\u00dcber diesen&nbsp;bezahlten&nbsp;Ferienanspruch hinaus habe ich grunds\u00e4tzlich kein Anrecht auf zus\u00e4tzliche unbezahlte Ferien, es ist jedoch m\u00f6glich diese mit meinem Arbeitgeber zu verhandeln. Normalerweise wird eine solche Auszeit als Belohnung f\u00fcr gute Arbeit gew\u00e4hrt und\/oder um die Arbeitgeberattraktivit\u00e4t zu steigern. Beim unbezahlten Urlaub werde ich f\u00fcr eine bestimmte Zeit von meiner Arbeitspflicht befreit, der Arbeitsvertrag bleibt jedoch bestehen. <\/em><\/p>\n\n\n\n<p style=\"text-decoration:underline\"><strong><em>Allgemeine Bestimmungen<\/em><\/strong><\/p>\n\n\n\n<p><em>W\u00e4hrend dieser Zeit schuldet mir der Arbeitgeber keinen Lohn und der Anspruch auf den 13.&nbsp;Monatslohn wird entsprechend der Dauer meiner Abwesenheit gek\u00fcrzt. <\/em><\/p>\n\n\n\n<p><em>Wichtig ist, dass der Arbeitgeber und ich unsere Abmachungen betreffend der Dauer, der vorhergesehenen K\u00fcrzung des 13. Monatslohns und so weiter schriftlich festhalten.<\/em><\/p>\n\n\n\n<p><em>F\u00fcr jeden Monat der unbezahlten Ferien, kann mein regul\u00e4rer Ferienanspruch um einen Zw\u00f6lftel gek\u00fcrzt werden. <\/em><\/p>\n\n\n\n<p style=\"text-decoration:underline\"><em><strong>K\u00fcndigung w\u00e4hrend Auszeit<\/strong><\/em><\/p>\n\n\n\n<p><em>Da das Arbeitsverh\u00e4ltnis weiter besteht, darf mir mein Arbeitgeber auch die K\u00fcndigung aussprechen. Grunds\u00e4tzlich startet die K\u00fcndigungsfrist jedoch erst dann, wenn ich die Arbeit nach der unbezahlten Auszeit wieder aufnehme. <\/em><\/p>\n\n\n\n<p class=\"is-style-default\" style=\"text-decoration:underline\"><strong><em>Auswirkungen der Auszeit&nbsp;auf meinen Versicherungsschutz:<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>AHV\/IV\/EO<\/em><br><\/strong><em>W\u00e4hrend des unbezahlten Urlaubs sind keine Beitr\u00e4ge geschuldet. Da je nach Dauer der Auszeit eine gr\u00f6ssere L\u00fccke entstehen k\u00f6nnte, ist es sinnvoll, diese auszurechnen und m\u00f6gliche L\u00fccken durch Nachzahlung der Beitr\u00e4ge zu schliessen.<\/em><\/p>\n\n\n\n<p><strong><em>Arbeitslosenversicherung<br><\/em><\/strong><em>W\u00e4hrend des unbezahlten Urlaubs sind keine Beitr\u00e4ge geschuldet.<br>Der Anspruch auf Arbeitslosenentsch\u00e4digung besteht nach dem unbezahlten Urlaub, sofern vor der Auszeit w\u00e4hrend der Rahmenfrist von 2 Jahren mindestens 12 Monate Beitr\u00e4ge entrichtet wurden.<\/em><\/p>\n\n\n\n<p><strong><em>Berufliche Vorsorge und Risikoversicherung<\/em><br><\/strong><em>Der Arbeitgeber muss w\u00e4hrend der Auszeit keine Beitr\u00e4ge bezahlen. <br>30 Tage nach der letzten Lohnzahlung endet der Versicherungsschutz gegen Tod und Invalidit\u00e4t (Risikoversicherung). Ich kann im BVG Reglement nachsehen, ob meine Pensionskasse eine M\u00f6glichkeit bietet, auch w\u00e4hrend einer Auszeit weiterhin Beitr\u00e4ge einzuzahlen. Je nach Pensionskasse ist es m\u00f6glich, die Risikoversicherung gegen Bezahlung weiterzuf\u00fchren (normalerweise bis zu 24 Monate). Auch den Sparprozess kann man teilweise weiterlaufen lassen: in diesem Fall \u00fcbernehmen die Arbeitnehmenden <em>in der Regel<\/em><\/em> <em>die monatlichen Arbeitnehmer- und Arbeitgeberbeitr\u00e4ge.<\/em><\/p>\n\n\n\n<p><strong><em>Familienzulagen<\/em><\/strong><em><strong><br><\/strong>Diese Zulagen werden weiter ausbezahlt, allerdings nur f\u00fcr den laufenden und die darauf folgenden 3&nbsp;Monate.<\/em><\/p>\n\n\n\n<p class=\"is-style-lead\"><em><strong>Unfallversicherung <br><\/strong>Auch hier endet der Versicherungsschutz nach 30 Tagen.<br>Wenn die unbezahlte Auszeit l\u00e4nger als 30 Tage ist, kann ich eine Abredeversicherung beim Unfallversicherer meines Arbeitgebers abschliessen. Diese ist eine Weiterf\u00fchrung der obligatorischen Unfallversicherung und <em>bietet&nbsp;w\u00e4hrend maximal 180 Tagen&nbsp;Schutz f\u00fcr Nichtbetriebsunf\u00e4lle (ein Betriebsunfall ist ausgeschlossen, da ich <em><em>w\u00e4hrend meines unbezahlten Urlaubs<\/em><\/em><\/em><\/em> <em>nicht<em> bei der Arbeit bin).<\/em> Danach m\u00fcsste ich allenfalls bei meiner Krankenkasse eine Unfallversicherung abschliessen (vgl. Grafik).<\/em><\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" data-id=\"177\" src=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2018\/07\/Graphik-unbez-Urlaub-1024x576.png\" alt=\"\" class=\"wp-image-177\" srcset=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2018\/07\/Graphik-unbez-Urlaub-1024x576.png 1024w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2018\/07\/Graphik-unbez-Urlaub-300x169.png 300w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2018\/07\/Graphik-unbez-Urlaub-768x432.png 768w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2018\/07\/Graphik-unbez-Urlaub.png 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong>Quellen und weiterf\u00fchrende Informationen:<\/strong><\/p>\n<ul>\n<li><a href=\"https:\/\/bvk.ch\/de\/vorsorge\/unbezahlter-urlaub\">Unbezahlter Urlaub &#8211; BVK<\/a><\/li>\n<li><a href=\"https:\/\/www.kmu.admin.ch\/kmu\/de\/home\/aktuell\/monatsthema\/2020\/antraege-auf-unbezahlten-urlaub-wie-kann-man-darauf-reagieren.html\">Antr\u00e4ge auf unbezahlten Urlaub &#8211; KMU-Portal SECO<\/a><\/li>\n<li><a href=\"https:\/\/www.vermoegenszentrum.ch\/wissen\/berufliche-vorsorge-im-unbezahlten-urlaub\">Pensionskasse w\u00e4hrend eines unbezahlten Urlaubs &#8211; VZ<\/a><\/li>\n<li><a href=\"https:\/\/www.versicherung-schweiz.ch\/ratgeber\/abredeversicherung\">Abredeversicherung: Was ist es und wer braucht es? &#8211; Versicherung Schweiz<\/a><\/li>\n<li><a href=\"https:\/\/www.suva.ch\/de-ch\/versicherung\/unfallversicherung\/unfallversicherung-uvg\/unfallversicherung-wer-ist-versichert\">Wer ist unfallversichert? &#8211; Suva<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Im letzten Beitrag \u00abEndlich Ferien! &#8211; Und was sagt das Arbeitsrecht?\u00bb hier auf dem Management &amp; Law-Blog wurden die Essentials rund um das Thema Ferien in einem fiktiven Dialog zwischen Johanna und der HR Abteilung ihres Arbeitgebers erl\u00e4utert. Doch was, wenn der regul\u00e4re Ferienanspruch nicht gen\u00fcgt? Dann kommt allenfalls ein unbezahlter Urlaub in Frage. Auch in diesem Kontext stellen sich juristische Fragen. Diese werden im heutigen Blog-Beitrag beantwortet.<\/p>\n","protected":false},"author":191,"featured_media":6558,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"469,6002,1658,1327,1432,1694","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[109763],"tags":[],"class_list":["post-6520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arbeitsrecht"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog<\/title>\n<meta name=\"description\" content=\"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog\" \/>\n<meta property=\"og:description\" content=\"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/\" \/>\n<meta property=\"og:site_name\" content=\"Management and Law Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-22T06:17:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lialuedi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lialuedi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/\"},\"author\":{\"name\":\"lialuedi\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\"},\"headline\":\"Unbezahlter Urlaub &#8211; Was ist arbeitsrechtlich zu beachten?\",\"datePublished\":\"2024-08-22T06:17:14+00:00\",\"dateModified\":\"2026-02-11T13:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/\"},\"wordCount\":549,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/08\\\/AdobeStock_55923645.jpeg\",\"articleSection\":[\"Arbeit und Arbeitsrecht\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/\",\"name\":\"Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/08\\\/AdobeStock_55923645.jpeg\",\"datePublished\":\"2024-08-22T06:17:14+00:00\",\"dateModified\":\"2026-02-11T13:53:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\"},\"description\":\"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/08\\\/AdobeStock_55923645.jpeg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/08\\\/AdobeStock_55923645.jpeg\",\"width\":2048,\"height\":1536},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/08\\\/22\\\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unbezahlter Urlaub &#8211; Was ist arbeitsrechtlich zu beachten?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\",\"name\":\"Management and Law Blog\",\"description\":\"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\",\"name\":\"lialuedi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog","description":"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/","og_locale":"de_DE","og_type":"article","og_title":"Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog","og_description":"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.","og_url":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/","og_site_name":"Management and Law Blog","article_published_time":"2024-08-22T06:17:14+00:00","article_modified_time":"2026-02-11T13:53:46+00:00","og_image":[{"width":2048,"height":1536,"url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","type":"image\/jpeg"}],"author":"lialuedi","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"lialuedi","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/"},"author":{"name":"lialuedi","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c"},"headline":"Unbezahlter Urlaub &#8211; Was ist arbeitsrechtlich zu beachten?","datePublished":"2024-08-22T06:17:14+00:00","dateModified":"2026-02-11T13:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/"},"wordCount":549,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","articleSection":["Arbeit und Arbeitsrecht"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/","url":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/","name":"Unbezahlter Urlaub - Was ist arbeitsrechtlich zu beachten? - Management and Law Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","datePublished":"2024-08-22T06:17:14+00:00","dateModified":"2026-02-11T13:53:46+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c"},"description":"Verl\u00e4ngerung des regul\u00e4ren Ferienanspruchs durch unbezahlten Urlaub: was gilt es arbeitsrechtlich zu beachten? Die Antworten finden Sie hier.","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#primaryimage","url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","contentUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","width":2048,"height":1536},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/08\/22\/unbezahlter-urlaub-was-ist-arbeitsrechtlich-zu-beachten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/management-and-law\/"},{"@type":"ListItem","position":2,"name":"Unbezahlter Urlaub &#8211; Was ist arbeitsrechtlich zu beachten?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website","url":"https:\/\/hub.hslu.ch\/management-and-law\/","name":"Management and Law Blog","description":"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/management-and-law\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c","name":"lialuedi"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","featured_image_src_square":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/08\/AdobeStock_55923645.jpeg","author_info":{"display_name":"lialuedi","author_link":"https:\/\/hub.hslu.ch\/management-and-law\/author\/lialuedi\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/comments?post=6520"}],"version-history":[{"count":25,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6520\/revisions"}],"predecessor-version":[{"id":7490,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6520\/revisions\/7490"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media\/6558"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media?parent=6520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/categories?post=6520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/tags?post=6520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}