{"id":6602,"date":"2024-09-10T13:20:23","date_gmt":"2024-09-10T11:20:23","guid":{"rendered":"https:\/\/hub.hslu.ch\/management-and-law\/?p=6602"},"modified":"2026-02-11T14:53:46","modified_gmt":"2026-02-11T13:53:46","slug":"mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/","title":{"rendered":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt"},"content":{"rendered":"\n<p><strong><strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=5494\"><\/strong><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong>Simulationsveranstaltung Arbeitskonflikt: seien Sie dabei beim Videodreh zum Lernvideo!<\/strong><\/p>\n<p>Datum und Zeit: 30. Oktober 2024, 18:00-20:00 Uhr<\/p>\n<p>Ort: Rotkreuz, Hochschule Luzern &#8211; Wirtschaft, Institut f\u00fcr Finanzdienstleistungen Zug IFZ<\/p>\n<p>Teilnahme: kostenlos<\/p>\n<p>Weitere Informationen und Anmeldung unter <a href=\"https:\/\/skwm.ch\/events\/simulationsveranstaltung-arbeitskonflikt\/\">Simulationsveranstaltung Arbeitskonflikt \u2013 SKWM<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p class=\"is-style-default\"><em><strong>Katharina Windler:<\/strong> <strong>Wie kamt Ihr \u00fcberhaupt auf die Idee, ein Lernvideo f\u00fcr die Mediation zu produzieren? War das ein Geistesblitz oder ein langer Prozess?<\/strong><\/em><\/p>\n\n\n\n<p><em><strong>Susann Bongers:<\/strong> <\/em>Es war eher ein langer Prozess. Vor zwei Jahren haben wir eine Mediationstagung organisiert, bei der zur Sprache kam, dass es keine wirklich geeigneten Lernvideos zur Mediation gibt. Die wenigen, die gut sind, sind veraltet. So ist die Idee entstanden und irgendwann gab es eine Initialz\u00fcndung, wo wir gesagt haben, komm, jetzt machen wir es.<\/p>\n\n\n\n<p><strong><em>Daniel Girsberger:<\/em><\/strong> Genau. Ich bilde seit einigen Jahren Studierende in Mediation aus und habe nolens volens mit einem deutschen Video gearbeitet, das eigentlich auch sehr gut ist, aber eben veraltet, vom Stil her. Von den Studierenden kam h\u00e4ufig die Kritik, dass das existierende Material nicht mehr zeitgem\u00e4ss sei und dass es auch sch\u00f6n w\u00e4re, wenn es etwas g\u00e4be, das zugeschnittener auf die Schweiz w\u00e4re. Susann kam dann mit der Idee, ein neues Video zu erstellen, und ich war sofort dabei.<\/p>\n\n\n\n<p><strong><em>Katharina Windler: Es gibt bereits viele Lehrmaterialien zur Mediation. Was macht Euer Video anders?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Was bei uns sicherlich anders ist, ist, dass wir eine ganze Mediation von A bis Z zeigen, dies aber auch unterteilt in die Phasen \u2013 so ein bisschen nach Lehrbuch. Zwar wissen wir alle, dass es in der Realit\u00e4t dann \u00f6fters anders l\u00e4uft, aber so bietet es den Lernenden doch Orientierung. Zus\u00e4tzlich pr\u00e4sentieren wir auch spezielle Methoden, die in anderen Videos nicht so ausf\u00fchrlich behandelt werden.<\/p>\n\n\n\n<p><em><strong>Daniel Girsberger:<\/strong> <\/em>Und wir arbeiten mit deutschen und schweizerischen Schauspielenden, die nicht nur Erfahrung in der Theaterkunst haben, sondern auch in Mediation. Diese Kombination macht unser Video einzigartig<\/p>\n\n\n\n<p><strong><em>Katharina Windler: Was sind die drei Kernbotschaften des Lernvideos?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Erstens, dass Mediation machbar ist und man keine Angst davor haben muss. Zweitens, dass Methoden flexibel anwendbar sind. Und drittens, dass theoretisches Wissen in der Praxis durchaus anders aussehen kann.<\/p>\n\n\n\n<p><em><strong>Katharina Windler: Mit Gabriela Renggli und Markus Berg konntet Ihr zwei Ausnahmetalente als Protagonisten des Videos gewinnen. Wie kam es dazu und warum habt Ihr gerade diese beiden ausgew\u00e4hlt?<\/strong><\/em><\/p>\n\n\n\n<p><em><strong>Susann Bongers:<\/strong> <\/em>Ich kenne Gabriela Renggli schon lange und sch\u00e4tze die Zusammenarbeit mit ihr sehr. Sie kennt Markus Berg, und wir wollten mit Leuten arbeiten, die sich in diesem Bereich auskennen, und mit denen die Zusammenarbeit angenehm ist.<\/p>\n\n\n\n<p><strong><em>Daniel Girsberger:<\/em><\/strong> Gabriela Renggli ist selbst ausgebildete Mediatorin und Markus Berg hat Expertise im Unternehmenstheater. Dabei werden Theaterszenen f\u00fcr Unternehmen gespielt und die Zuschauenden d\u00fcrfen intervenieren. Das werden wir \u00fcbrigens auch zus\u00e4tzlich zum Video noch machen. Am Tag nach dem Videodreh haben wir am Abend noch eine Veranstaltung, an der eine solches Unternehmenstheater mit demselben Thema durchgef\u00fchrt wird. Und wir haben die Idee, dass wir das auch aufnehmen und in der einen oder anderen Form in das Lernvideo integrieren.<\/p>\n\n\n\n<p><strong><em>Katharina Windler:<\/em><\/strong> <strong><em>Wie flexibel ist das Drehbuch, und was macht Ihr, wenn etwas nicht nach Plan l\u00e4uft?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> F\u00fcr mich war zu Beginn nicht klar, was die beiden Schauspielenden brauchen, um gut in ihren Rollen funktionieren zu k\u00f6nnen. Nun ist das Drehbuch so gestaltet, dass man gewisse Meilensteine hat: Was sind das f\u00fcr Menschen? In welchem Kontext sind sie? Und wo werden wir am Ende der Mediation landen? Wir haben das Ziel definiert, aber dazwischen gibt es sehr viele Freir\u00e4ume und es kommt nat\u00fcrlich auch sehr darauf an, wie die beiden das ausgestalten. Wir hatten eine Probe, in welcher wir festgestellt haben, dass sie den Konflikt noch etwas st\u00e4rker durchleben k\u00f6nnten \u2013 wie das auch real bei Konfliktparteien ist, wenn sie zu uns in die Mediationspraxis kommen. Sie sind oftmals sehr angespannt und gestresst, und das d\u00fcrfen unsere Schauspielenden auch sein. Daran haben wir noch ein bisschen gearbeitet. Also, der Rahmen ist gesetzt, aber wir lassen viel Raum f\u00fcr Flexibilit\u00e4t.<br>Und wenn es mal nicht so l\u00e4uft\u2026 Dani, was machen wir dann?<\/p>\n\n\n\n<p><strong><em>Daniel Girsberger:<\/em><\/strong> Das Sch\u00f6ne ist dann ja, dass man eine Szene noch ein zweites oder drittes Mal drehen kann.<\/p>\n\n\n\n<p><em><strong>Katharina Windler: Wie seht ihr den praktischen Nutzen des Videos f\u00fcr die Lernenden?<\/strong><\/em><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Das Video kann sowohl kapitelweise zur gezielten Vertiefung einer bestimmten Phase in der Mediation genutzt werden als auch als Ganzes, um den gesamten Mediationsprozess besser zu verstehen. Es eignet sich auch hervorragend f\u00fcr Intervisionsgruppen.<\/p>\n\n\n\n<p><em><strong>Daniel Girsberger:<\/strong> <\/em>Ich hoffe, dass es den Studierenden hilft, sich st\u00e4rker mit dem Thema zu identifizieren, besonders da es in einem schweizerischen Kontext entstanden ist. Aber auch, dass die Studierenden das Video n\u00e4her an sich heranlassen, weil es von ihren Dozierenden gemacht wurde.<\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Und ich denke, es ist auch f\u00fcr Unternehmen spannend, die intern Mediator:innen ausbilden. Oder auch wenn HR-Abteilungen sich einmal mit dem Thema auseinandersetzen m\u00f6chten. Dass man ihnen einmal zeigen kann, wie sowas abl\u00e4uft und funktioniert. Weil es sich um einen klassischen Arbeitskonflikt handelt, wie er in vielen Unternehmen vorkommt.<\/p>\n\n\n\n<p><em><strong>Katharina Windler:<\/strong> <\/em><strong><em>Wenn nun jemand das Video sehen m\u00f6chte \u2013 sei es f\u00fcr die Aus- oder Weiterbildung, den Einsatz in einem Unternehmen oder einfach aus Interesse \u2013 wie kann man darauf zugreifen?<\/em><\/strong><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Wir planen, das Video online als Download verf\u00fcgbar zu machen. Details werden noch entschieden.<\/p>\n\n\n\n<p><em><strong>Katharina Windler: Habt Ihr schon Feedback zu Eurem Vorhaben erhalten?<\/strong><\/em><\/p>\n\n\n\n<p><strong><em>Susann Bongers:<\/em><\/strong> Alle warten gespannt auf das Video. Es gibt auch einen gewissen Leistungsdruck, weil es verschiedene Schulen und Stile der Mediation gibt. Es wird auch kritische Stimmen geben, das geh\u00f6rt dazu, aber wir tun unser Bestes.<\/p>\n\n\n\n<p><strong><em>Daniel Girsberger:<\/em><\/strong> Ich bin gespannt, wie es ankommen wird und welche weiteren Projekte daraus entstehen k\u00f6nnten.<\/p>\n\n\n\n<p><strong><em>Katharina Windler: Gibt es denn schon Ideen f\u00fcr weitere Projekte in dieser Richtung?<\/em><\/strong><\/p>\n\n\n\n<p><em><strong>Susann Bongers:<\/strong> <\/em>Wir haben schon dar\u00fcber gesprochen, dass wir analog der bevorstehenden Abendveranstaltung auch interaktive Theater bei Mediationskongressen oder in grossen Firmen anbieten k\u00f6nnten. Es gibt da einige Einsatzm\u00f6glichkeiten.<\/p>\n\n\n\n<p><strong><em>Daniel Girsberger<\/em>:<\/strong> Wenn das Video Erfolg hat, k\u00f6nnten wir auch \u00fcber eine Fortsetzung nachdenken, etwa zu B2B-Mediation, die doch etwas anders ist.<\/p>\n\n\n\n<p><strong><em>Katharina Windler: Herzlichen Dank, liebe Susann, lieber Daniel, f\u00fcr die spannenden Einblicke und Eure Zeit.<\/em><\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"531\" src=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image.png\" alt=\"\" class=\"wp-image-6607\" srcset=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image.png 945w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image-300x169.png 300w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image-768x432.png 768w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image-928x521.png 928w, https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/image-600x337.png 600w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong>Vertiefen Sie Ihre Kenntnisse in Mediation mit einem CAS der Hochschule Luzern:<\/strong><\/p>\n<p>Das\u00a0<a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ibr\/mediation-grundlagen\/\" target=\"_blank\" rel=\"noreferrer noopener\">CAS Mediation\u00a0Grundlagen<\/a>\u00a0bef\u00e4higt zu konstruktiver Konfliktintervention im beruflichen und privaten Umfeld und schafft die Voraussetzung, Mediation als Dienstleistung in verschiedenen Anwendungsfeldern erfolgreich anbieten zu k\u00f6nnen.<\/p>\n<p>Die n\u00e4chsten Info-Veranstaltungen:<\/p>\n<ul class=\"nav\">\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2024\/10\/21\/ibr-online-infoveranstaltung-cas-mediation\">Montag, 21. Oktober 2024, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2024\/12\/05\/ibr-online-info-veranstaltung-cas-med-g\">Donnerstag, 5. Dezember 2024, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2025\/01\/22\/ibr-online-info-veranstaltung-cas-mediation\">Mittwoch, 22. Januar 2025, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2025\/03\/11\/ibr-online-infoveranstaltung-cas-mediation\">Dienstag, 11. M\u00e4rz 2025, Online<\/a><\/li>\n<\/ul>\n<p>Das\u00a0<a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/weiterbildung\/cas\/ibr\/mediation-vertiefung\/\" target=\"_blank\" rel=\"noreferrer noopener\">CAS Mediation Vertiefung<\/a>\u00a0bef\u00e4higt die Teilnehmenden, als Mediator*innen auch in schwierigen Konfliktsituationen selbst\u00e4ndig aktiv zu werden.<\/p>\n<p>Die n\u00e4chsten Info-Veranstaltungen:<\/p>\n<h2 class=\"section-title nospace columns\"><\/h2>\n<ul class=\"nav\">\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2024\/10\/21\/ibr-online-infoveranstaltung-cas-mediation\">Montag, 21. Oktober 2024, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2024\/12\/05\/ibr-online-info-veranstaltung-cas-med-g\">Donnerstag, 5. Dezember 2024, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2025\/01\/22\/ibr-online-info-veranstaltung-cas-mediation\">Mittwoch, 22. Januar 2025, Online<\/a><\/li>\n<li><a class=\"gtm-infoevent\" href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2025\/03\/11\/ibr-online-infoveranstaltung-cas-mediation\">Dienstag, 11. M\u00e4rz 2025, Online<\/a><\/li>\n<\/ul>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Susann Bongers ist Dozentin an der Hochschule Luzern und Gesch\u00e4ftsf\u00fchrerin der bcompanion gmbh. Daniel Girsberger ist Professor an der Universit\u00e4t Luzern, Vorsitzender des Direktoriums des CCR (Center for Conflict Resolution) und Konsulent bei der Anwaltskanzlei Kaufmann R\u00fcedi Rechtsanw\u00e4lte AG. Zusammen haben sie in einem Kooperationsprojekt der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation ein Konzept f\u00fcr ein Lernvideo zur Mediation entwickelt. Im Gespr\u00e4ch mit Katharina Windler erl\u00e4utern sie, wie dieses spannende Projekt entstanden ist, was es besonders macht und wie es in der Praxis eingesetzt wird.<\/p>\n","protected":false},"author":191,"featured_media":6621,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"5800,5462,5159,5046,4420,4159","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[875500],"tags":[],"class_list":["post-6602","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mediation-verhandeln"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog<\/title>\n<meta name=\"description\" content=\"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog\" \/>\n<meta property=\"og:description\" content=\"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/\" \/>\n<meta property=\"og:site_name\" content=\"Management and Law Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-10T11:20:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1748\" \/>\n\t<meta property=\"og:image:height\" content=\"2480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lialuedi\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lialuedi\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/\"},\"author\":{\"name\":\"lialuedi\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\"},\"headline\":\"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt\",\"datePublished\":\"2024-09-10T11:20:23+00:00\",\"dateModified\":\"2026-02-11T13:53:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/\"},\"wordCount\":1045,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/09\\\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg\",\"articleSection\":[\"Mediation &amp; Verhandlungsf\u00fchrung\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/\",\"name\":\"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/09\\\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg\",\"datePublished\":\"2024-09-10T11:20:23+00:00\",\"dateModified\":\"2026-02-11T13:53:46+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\"},\"description\":\"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/09\\\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2024\\\/09\\\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg\",\"width\":1748,\"height\":2480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2024\\\/09\\\/10\\\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\",\"name\":\"Management and Law Blog\",\"description\":\"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/41ddab7a162d805ef20caf86fa50209c\",\"name\":\"lialuedi\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog","description":"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/","og_locale":"de_DE","og_type":"article","og_title":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog","og_description":"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation","og_url":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/","og_site_name":"Management and Law Blog","article_published_time":"2024-09-10T11:20:23+00:00","article_modified_time":"2026-02-11T13:53:46+00:00","og_image":[{"width":1748,"height":2480,"url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","type":"image\/jpeg"}],"author":"lialuedi","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"lialuedi","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/"},"author":{"name":"lialuedi","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c"},"headline":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt","datePublished":"2024-09-10T11:20:23+00:00","dateModified":"2026-02-11T13:53:46+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/"},"wordCount":1045,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","articleSection":["Mediation &amp; Verhandlungsf\u00fchrung"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/","url":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/","name":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt - Management and Law Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","datePublished":"2024-09-10T11:20:23+00:00","dateModified":"2026-02-11T13:53:46+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c"},"description":"Wie geht Mediation? Ein Lernvideo der Hochschule Luzern, der Universit\u00e4t Luzern, der Universit\u00e4t Z\u00fcrich und der Schweizer Kammer f\u00fcr Wirtschaftsmediation","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#primaryimage","url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","contentUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","width":1748,"height":2480},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2024\/09\/10\/mediation-erlebbar-machen-ein-neues-konzept-fuer-ein-lernvideo-im-interview-erklaert\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/management-and-law\/"},{"@type":"ListItem","position":2,"name":"Mediation erlebbar machen: Ein neues Konzept f\u00fcr ein Lernvideo im Interview erkl\u00e4rt"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website","url":"https:\/\/hub.hslu.ch\/management-and-law\/","name":"Management and Law Blog","description":"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/management-and-law\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/41ddab7a162d805ef20caf86fa50209c","name":"lialuedi"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2024\/09\/Layout_Event_Flyer_SKWM_30_10_24_v4.jpg","author_info":{"display_name":"lialuedi","author_link":"https:\/\/hub.hslu.ch\/management-and-law\/author\/lialuedi\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/users\/191"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/comments?post=6602"}],"version-history":[{"count":24,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6602\/revisions"}],"predecessor-version":[{"id":7492,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6602\/revisions\/7492"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media\/6621"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media?parent=6602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/categories?post=6602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/tags?post=6602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}