{"id":6966,"date":"2025-02-13T04:20:00","date_gmt":"2025-02-13T03:20:00","guid":{"rendered":"https:\/\/hub.hslu.ch\/management-and-law\/?p=6966"},"modified":"2026-02-04T11:41:07","modified_gmt":"2026-02-04T10:41:07","slug":"ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/","title":{"rendered":"KI-Regulierung: Schweiz positioniert sich &#8211; oder doch nicht?"},"content":{"rendered":"\n<p>Seit dem fl\u00e4chendeckenden Aufkommen von k\u00fcnstlicher Intelligenz wird allenthalben diskutiert, ob und wie KI zu regulieren ist. W\u00e4hrend etwa der Europarat mit der <a href=\"https:\/\/search.coe.int\/cm#{%22CoEIdentifier%22:[%220900001680afb122%22],%22sort%22:[%22CoEValidationDate%20Descending%22]}\" target=\"_blank\" rel=\"noreferrer noopener\">KI-Konvention<\/a> und die EU mit dem <a href=\"https:\/\/eur-lex.europa.eu\/eli\/reg\/2024\/1689\/oj\/eng\" target=\"_blank\" rel=\"noreferrer noopener\">AI Act<\/a> bereits umfassende Regelwerke erlassen haben, besteht in der Schweiz bisher keine \u00fcbergreifende Gesetzgebung spezifisch zu KI. Im November 2023 hat der Bundesrat in diesem Kontext das Bundesamt f\u00fcr Kommunikation BAKOM des Eidgen\u00f6ssischen Departements f\u00fcr Umwelt, Verkehr, Energie und Kommunikation (UVEK) sowie die Abteilung Europa beim Eidgen\u00f6ssischen Departement des \u00c4usseren (EDA) beauftragt, eine Auslegeordnung zur m\u00f6glichen Regulierung von KI zu erarbeiten. Bereits per Ende 2024 erwartet, wurde diese Auslegeordnung nun am 12. Februar 2025 vorgelegt.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Stossrichtungen der zuk\u00fcnftigen KI-Regulierung in der Schweiz<\/strong><\/h5>\n\n\n\n<p><\/p>\n\n\n\n<p>Basierend auf der Auslegeordnung hat der Bundesrat sogleich mehrere Grundsatzentscheide zur Stossrichtung der zuk\u00fcnftigen Schweizer KI-Regulierung gef\u00e4llt, um die Ziele St\u00e4rkung des Innovationsstandorts Schweiz, Wahrung des Grundrechtsschutzes inklusive der Wirtschaftsfreiheit und St\u00e4rkung des Vertrauens der Bev\u00f6lkerung in KI zu erreichen.<\/p>\n\n\n\n<p><em>Schweiz ratifiziert KI-Konvention des Europarats<\/em><\/p>\n\n\n\n<p> <em>Erstens <\/em>soll die KI-Konvention des Europarats ratifiziert werden. Diese ist nicht unmittelbar anwendbar und enth\u00e4lt keine direkten Verpflichtungen f\u00fcr Unternehmen oder Privatpersonen. Vielmehr richtet sie sich prim\u00e4r an den Staat, der entsprechende Ausf\u00fchrungsbestimmungen zu erlassen hat. <\/p>\n\n\n\n<p><em>Prinzipienbasierte, technologie- und wettbewerbsneutrale, m\u00f6glichst sektorielle Regulierung zur Umsetzung der KI-Konvention<\/em><\/p>\n\n\n\n<p>Entsprechend h\u00e4lt der Bundesrat <em>zweitens <\/em>fest, dass dort, wo aufgrund der Ratifikation der KI-Konvention Gesetzesanpassungen erforderlich sind, diese m\u00f6glichst sektoriell ausfallen sollen. Allgemeine, sektor\u00fcbergreifende Regulierung soll nur in zentralen, grundrechtsrelevanten Bereichen erlassen werden. Als Beispiel wird hier der Datenschutz genannt. In jedem Fall soll die Regulierung prinzipienbasiert und technologieneutral erfolgen, bei Bedarf auch Ausnahmen zulassen und m\u00f6glichst wettbewerbsneutral gestaltet sein. <\/p>\n\n\n\n<p><em>Rechtlich nicht verbindliche Massnahmen flankieren die verbindliche KI-Regulierung<\/em><\/p>\n\n\n\n<p>Flankiert werden soll die Ratifikation der KI-Konvention sowie die n\u00f6tigen, punktuellen Gesetzesanpassungen <em>drittens <\/em>durch rechtlich nicht verbindliche Massnahmen zur Umsetzung der Konvention. Hier werden Selbstdeklarationsvereinbarungen und Branchenl\u00f6sungen erw\u00e4hnt. Aus dem resultierenden Zusammenspiel von rechtlich verbindlichen und unverbindlichen Massnahmen verspricht sich der Bundesrat einen sicheren Rechtsrahmen unter gleichzeitiger Ber\u00fccksichtigung der raschen Entwicklung und des Potenzials von KI.<\/p>\n\n\n\n<p>Zur Umsetzung dieser grunds\u00e4tzlichen Festlegungen soll bis Ende 2026 eine Vernehmlassungsvorlage zur Ratifikation der KI-Konvention vorbereitet werden, in der die notwendigen gesetzlichen Massnahmen, namentlich in den Bereichen Transparenz, Datenschutz, Nichtdiskriminierung und Aufsicht festgelegt werden. Gleichzeitig soll ein Plan f\u00fcr die weiteren, rechtlich nicht verbindlichen Massnahmen erarbeitet werden. W\u00e4hrend bei der Vernehmlassungvorlage das Eidgen\u00f6ssische Justiz- und Polizeidepartement EJPD im Lead ist und durch das UVEK und das EDA unterst\u00fctzt wird, liegt die Federf\u00fchrung f\u00fcr die rechtlich nicht verbindlichen Massnahmen beim UVEK (unterst\u00fctzt durch das EJPD, das EDA und das Eidgen\u00f6ssische Departement f\u00fcr Wirtschaft, Bildung und Forschung WBF).<\/p>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>  Auslegeordnung als Basis f\u00fcr den gew\u00e4hlten Regulierungsansatz<\/strong><\/h5>\n\n\n\n<p><\/p>\n\n\n\n<p>Die vom Bundesrat definierten Ans\u00e4tze und Massnahmen basieren wesentlich auf der bereits erw\u00e4hnten Auslegeordnung zur Regulierung von k\u00fcnstlicher Intelligenz, die das BAKOM und die Abteilung Europa des EDA vorgelegt haben. Entsprechend lohnt sich ein Blick in diese Grundlagen.<\/p>\n\n\n\n<p>Die Auslegeordnung besteht aus einem 38-seitigen Bericht der auf drei Basisanalysen beruht:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.bakom.admin.ch\/dam\/bakom\/de\/dokumente\/KI\/Auslegeordnung%20zur%20Regulierung%20von%20%20k%C3%BCnstlicher%20Intelligenz_def.pdf.download.pdf\/Auslegeordnung.pdf\">Auslegeordnung zur Regulierung von k\u00fcnstlicher Intelligenz &#8211; Bericht an den Bundesrat<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.bakom.admin.ch\/dam\/bakom\/de\/dokumente\/KI\/analyse_juritisch.pdf.download.pdf\/Juristische%20Analyse.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Rechtliche Analyse<\/a> (Bundesamt f\u00fcr Justiz \/ EJPD): Untersuchung der Vorgaben der KI-Konvention und des AI Acts und der Auswirkungen auf die Schweiz und Analyse ausgew\u00e4hlte Aspekte inkl. Regulierungsbedarf unter Schweizer Recht (geistiges Eigentum, ausservertragliche Haftung, allgemeines Vertragsrecht, Arbeitsrecht, Strafrecht)<\/li>\n\n\n\n<li><a href=\"https:\/\/www.bakom.admin.ch\/dam\/bakom\/de\/dokumente\/KI\/ueberblick_regulierungsvorhaben.pdf.download.pdf\/Sektorielle%20Analyse.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Sektorielle Analyse<\/a> (BAKOM): \u00dcberblick zu aktuellen und geplanten sektoriellen Regulierungsaktivit\u00e4ten<\/li>\n\n\n\n<li><a href=\"https:\/\/www.bakom.admin.ch\/dam\/bakom\/de\/dokumente\/KI\/analyse_laender.pdf.download.pdf\/L%C3%A4nderanalyse.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">L\u00e4nderanalyse<\/a> (BAKOM und EDA): Darstellung der regulatorischen Entwicklungen im KI-Kontext in 20 ausgew\u00e4hlten L\u00e4ndern<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Welches sind die wichtigsten Erkenntnisse der Auslegeordnung?<\/strong><\/h5>\n\n\n\n<p><\/p>\n\n\n\n<p><em>Keine einheitlichen Regulierungsans\u00e4tze im internationalen Vergleich<\/em><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>Die L\u00e4nderanalyse zeigt, dass in allen 20 analysierten Staaten ein Handlungsbedarf hinsichtlich der Regulierung von KI anerkannt zu sein scheint, dass aber weltweit verschiedene Regulierungsans\u00e4tze bestehen, wobei kein Regulierungsansatz identifiziert werden k\u00f6nne, der sich klar durchsetze. Die meisten L\u00e4nder verf\u00fcgten im Gegensatz zur Schweiz zumindest \u00fcber eine nationale Strategie oder einen Aktionsplan zu KI. Rechtsverbindliche Instrumente existierten aber abgesehen von der EU bisher nur in wenigen L\u00e4ndern; die meisten Staaten bef\u00e4nden sich diesbez\u00fcglich derzeit in einer mehr oder weniger fortgeschrittenen Reflexions-, Verhandlungs- oder Entwicklungsphase. Hinsichtlich der Ausgestaltung lassen sich gem\u00e4ss der L\u00e4nderanalyse verschiedene Ans\u00e4tze unterscheiden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>\u00dcbergreifend vs. sektoriell:<\/strong> Bei der Frage, ob KI umfassend in einem \u00fcbergreifenden Erlass (z.B. EU, Kanada, Brasilien, S\u00fcdkorea) oder in mehreren sektoriellen Erlassen (z.B. Grossbritannien, Israel) reguliert werden soll, besteht keine einheitliche Tendenz. <\/li>\n\n\n\n<li><strong>Staatlicher vs. privater Adressatenkreis:<\/strong> W\u00e4hrend sich die Regulierung in den meisten Staaten sowohl an den \u00f6ffentlichen wie den privaten Sektor richtet, beschr\u00e4nken sich einige Staaten (z.B. Australien, Japan, Singapur und die USA) f\u00fcr den privaten Sektor auf freiwillige Leitlinien.<\/li>\n\n\n\n<li><strong>Umsetzung durch bestehende vs. neue Beh\u00f6rden: <\/strong>In einigen Staaten werden neue Umsetzungs- und Aufsichtsbeh\u00f6rden geschaffen, w\u00e4hrend in anderen bestehende Beh\u00f6rden mit dem KI-Thema betraut werden. <\/li>\n<\/ul>\n\n\n\n<p><em>Rechtliche Analyse offenbart punktuellen Handlungsbedarf<\/em><\/p>\n\n\n\n<p>Die rechtliche Analyse befasst sich <em>erstens <\/em>mit der KI-Konvention des Europarats und einer m\u00f6glichen Umsetzung in der Schweiz. Die am 17. Mai 2024 unter Schweizer Vorsitz verabschiedete Konvention wurde bereits von der EU, Andorra, Georgien, Island, Israel, Moldau, Norwegen, San Marino, Grossbritannien und den USA unterzeichnet. Sie will sicherstellen, das der Einsatz von KI menschen- und grundrechtskonform und im Einklang mit Demokratie und Rechtsstaatlichkeit erfolgt. Entsprechend richtet sie sich prim\u00e4r an die Staaten und gibt diesen durch die grunds\u00e4tzlichen Prinzipien breiten Umsetzungsspielraum; private Akteure werden nur dort erfasst, wo eine direkte oder indirekte horizontale Wirkung der Grundrechte unter Privaten besteht. Jedenfalls aber identifiziert die rechtliche Analyse bei einer Ratifizierung der KI-Konvention durch die Schweiz Gesetzgebungsbedarf, vornehmlich in den Bereichen Transparenz und Kontrolle, sichere Innovation, Rechtsmittel, Verfahrensgarantien sowie Risiko- und Folgeabsch\u00e4tzung f\u00fcr KI-Systeme und Aufsichtsmechanismen. Insbesondere im Datenschutzbereich ortet die rechtliche Analyse zudem Koordinationsbedarf.<\/p>\n\n\n\n<p><em>Zweitens<\/em> betrachtet die rechtliche Analyse den AI Act der EU und dessen Auswirkungen auf die Schweiz. Es wird festgehalten, dass der AI Act zwar grunds\u00e4tzlich nicht f\u00fcr die Schweiz gelte, aber aufgrund der extraterritorialen Wirkung f\u00fcr Schweizer Akteure trotzdem in vielfacher Hinsicht zentral sei. Sofern die Schweiz ihre Gesetzgebung dem AI Act ann\u00e4hern wollte, so die rechtliche Analyse, w\u00fcrde dies umfangreiche Anpassungen nach sich ziehen. Aber auch ohne eigentlichen gesetzgeberischen Nachvollzug, der laut der Auslegeordnung vielerorts kritisch gesehen w\u00fcrde, hat der AI Act praktische Auswirkungen auf die Schweiz und entsprechend ist insbesondere auch das <a href=\"https:\/\/www.fedlex.admin.ch\/eli\/cc\/2002\/276\/de\" target=\"_blank\" rel=\"noreferrer noopener\">Abkommen zwischen der Schweiz und der EU \u00fcber die gegenseitige Anerkennung von Konformit\u00e4tsbewertungen (sog. MRA)<\/a> relevant. Die Auslegeordnung kommt zum Schluss, dass die aktuellen Konformit\u00e4tsbewertungsverfahren f\u00fcr KI im MRA nicht abgedeckt sind, sodass Schweizer Unternehmen f\u00fcr Produkte mi KI-Bestandteilen ab August 2027 ein zus\u00e4tzliches Verfahren in der EU nach den Vorgaben des AI Acts durchlaufen und weitere Vorgaben erf\u00fcllen m\u00fcssten. Sofern KI-Anwendungen nicht ins MRA integriert werden k\u00f6nnen, resultieren somit Doppelspurigkeiten und enorme Mehraufw\u00e4nde.<\/p>\n\n\n\n<p><em>Drittens <\/em>er\u00f6rtert die rechtliche Analyse ausgew\u00e4hlte Rechtsgebiete mit sektor\u00fcbergreifendem Charakter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Geistiges Eigentum:<\/strong> Im Bereich des geistigen Eigentums, insbesondere des Urheberrechts, anerkennt die rechtliche Analyse zwar, dass gewisse Fragen ungekl\u00e4rt sind (vgl. dazu auch vertieft den Beitrag <a href=\"https:\/\/hub.hslu.ch\/management-and-law\/2023\/04\/05\/chat-gpt-co-was-sagt-das-urheberrecht\/\">&#171;ChatGPT &amp; Co. &#8211; Was sagt das Urheberrecht?&#187;<\/a> hier auf dem Management &amp; Law-Blog), h\u00e4lt jedoch fest, dass aktuell keine Revision geplant ist.<\/li>\n\n\n\n<li><strong>Zivilrecht, insbesondere Haftpflichtrecht: <\/strong>Generell wird dem Zivilrecht aufgrund seiner offenen Generalklauseln in der rechtlichen Analyse attestiert, dass es den Gerichten ein ausreichendes Instrumentarium biete, um einzelfallad\u00e4quate L\u00f6sungen unter Ber\u00fccksichtigung der technischen Fortschritte zu finden. Hinsichtlich haftungsrechtlicher Fragen (insbesondere selbstfahrende Autos und Drohnen) seien vertiefte Analysen unter Ber\u00fccksichtigung der weiteren Entwicklungen (auch in der EU) n\u00f6tig und es wird auf einen generellen Modernisierungsbedarf im Produktehaftpflichtrecht hingewiesen.<\/li>\n\n\n\n<li><strong>Arbeitsrecht:<\/strong> Im arbeitsrechtlichen Kontext wird punktueller gesetzgeberischer Handlungsbedarf etwa bei der Anwendung von KI im Bewerbungsverfahren anerkannt im Bereich Transparenz, Nichtdiskriminierung und Datenschutz. Jedoch wird in der Folge generisch auf die Entwicklung des allgemeinen rechtlichen Rahmens verwiesen.<\/li>\n\n\n\n<li><strong>Strafrecht:<\/strong> Im strafrechtlichen Bereich wird wiederum ein grunds\u00e4tzlich gen\u00fcgender Rahmen f\u00fcr eine technologieneutrale Anwendung gesehen, wobei sich praktische Abgrenzungsfragen (z.B. in Bezug auf die Verantwortlichkeit von KI-Herstellern und -Nutzern) stellen k\u00f6nnten. Auch hier erfolgt wiederum eine etwas allgemeine Relativierung, dass punktuelle Anpassungen (insbesondere auch unter Ber\u00fccksichtigung internationaler Bestrebungen) zu evaluieren seien.<\/li>\n<\/ul>\n\n\n\n<p><em>Kombination von sektor\u00fcbergreifenden und sektorspezifischen Ans\u00e4tzen sowie rechtlich unverbindlichen Massnahmen zielf\u00fchrend<\/em><\/p>\n\n\n\n<p>Gem\u00e4ss der sektoriellen Analyse stellt KI grunds\u00e4tzlich alle Sektoren vor neue Herausforderungen insbesondere punkto Transparenz, Nachvollziehbarkeit, Schutz der Privatsph\u00e4re und Datenschutz, Diskriminierung und Fairness sowie Cybersicherheit. Die Gewichtung der verschiedenen Faktoren sei jedoch sektoriell unterschiedlich. Die sektorielle Analyse kommt insgesamt zum Schluss, dass es sowohl gewisser sektor\u00fcbergreifender Regulierungen als auch sektorspezifischer Ans\u00e4tze bed\u00fcrfe. Zudem befasst sich die sektorielle Analyse auch mit unverbindlichen (vornehmlich internationalen) Standards und Best Practices gerade auf technischer Ebene, welche sich derzeit stark entwickelten. Diese k\u00f6nnten eine wichtige Erg\u00e4nzung und Pr\u00e4zisierung zu Regulierungen bieten.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Hat der Elefant eine Maus geboren?<\/strong><\/h5>\n\n\n\n<p><\/p>\n\n\n\n<p>Nach der Publikation der bundesr\u00e4tlichen Grundsatzentscheide und der zugrundeliegenden Auslegeordnung f\u00fcllte sich gestern mein &#8211; zugegebenermassen von Juristinnen und Juristen deutlich gepr\u00e4gter &#8211; LinkedIn-Feed mit Beitr\u00e4gen rund um das Thema. Gleich mehrere Personen kamen w\u00f6rtlich zum markanten Fazit, &#171;der Elefant habe eine Maus geboren&#187;. Voneinander inspiriert oder einfach ein treffendes Res\u00fcmee? Das Sprichwort d\u00fcrfte dahingehend zutreffen, dass \u00c4ngste vor einem Schweizer AI Act, wie sie in den letzten Monaten bisweilen ge\u00e4ussert wurden, mit der bundesr\u00e4tlichen Strategie zerstreut wurden. Gleichzeitig &#8211; und das w\u00e4re mit Blick auf das Sprichwort ebenfalls passend &#8211; bringen die Entscheidungen und die zugrundeliegende Auslegeordnung, die lange mit Spannung erwartet wurden, inhaltlich wenig grundlegend Neues und vor allen nichts \u00dcberraschendes. Dass beispielsweise die KI-Konvention des Europarats ratifiziert werden soll, erstaunt kaum, wurde sie doch unter Schweizer Vorsitz erarbeitet. <\/p>\n\n\n\n<p>Der nun eingeschlagene Weg passt zum liberalen Ansatz der technologieneutralen und prinzipienbasierten Regulierung der Schweiz. In vielen Bereichen bleiben die Ausf\u00fchrungen &#8211; dem Charakter der Auslegeordnung entsprechend &#8211; noch sehr generisch und programmatisch. Ob der definierte Ansatz zielf\u00fchrend sein wird, h\u00e4ngt mit anderen Worten von der konkreten Umsetzung ab, die es erst noch im Einzelnen zu definieren gilt. Es bleibt also weiterhin spannend.<\/p>\n\n\n\n<p>Kritische Stimmen gab es in meinem LinkedIn-Feed zum Timing &#8211; angesichts des Zeitplans, wonach &#171;erst&#187; bis Ende 2026 eine Vernehmlassungsvorlage f\u00fcr die n\u00f6tigen Gesetzesanpassungen sowie ein Plan f\u00fcr die weiteren, rechtlich nicht verbindlichen Massnahmen erarbeitet werden solle, w\u00fcnschte sich so manch einer &#171;raschere Rechtssicherheit&#187;. Tats\u00e4chlich kommen einem knapp zwei Jahre in einem derart dynamischen Technologiebereich vor wie eine Ewigkeit. Auch kommt man nicht umhin, ein gewisses Spannungsfeld zu orten zwischen diesem Zeitplan und dem erkl\u00e4rten Ziel des Bundesrats, er wolle mit dem Zusammenspiel aus rechtlich verbindlichen und unverbindlichen Massnahmen auch &#171;der <em>raschen <\/em>Entwicklung Rechnung tragen&#187;. <\/p>\n\n\n\n<p>Allerdings gilt es auch festzuhalten, dass weder ein schneller Gesetzgebungsprozess noch der Erlass von Regeln per se ein Garant sind f\u00fcr Rechtssicherheit sind. So bleiben etwa in der EU auch mehr als ein halbes Jahr nach dem Erlass des AI Acts viele Aspekte unklar. Der umsichtige Ansatz, nur dort zu regulieren, wo mit der Anwendung des bestehenden Rechts keine ad\u00e4quaten L\u00f6sungen erzielt werden, ist vor diesem Hintergrund jedenfalls zu begr\u00fcssen. In dieser Hinsicht bringt die nun vorliegende Auslegeordnung in einigen Bereichen eine gewisse, wenn auch nicht \u00fcberall gleichermassen vertiefte und noch lange nicht abschliessende Kl\u00e4rung.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lange wurde mit Spannung darauf gewartet, wie sich die Schweiz punkto Regulierung von k\u00fcnstlicher Intelligenz positioniert: Nun hat der Bundesrat am 12. Februar 2025 basierend auf einer umfassenden Auslegeordnung die Leitplanken zur KI-Regulierung festgelegt. Der vorliegende Blogbeitrag fasst die wichtigsten Punkte zusammen, ordnet die Stossrichtungen und die zugrundeliegenden Analysen ein und beantwortet die Frage, ob die Schweiz damit nun Stellung bezogen hat &#8211; oder doch nicht. <\/p>\n","protected":false},"author":62,"featured_media":6970,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"6798,6739,6640,6719,6662,6602","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[563231,563234],"tags":[],"class_list":["post-6966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-digital-law","category-gesetzgebungsprojekte"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog\" \/>\n<meta property=\"og:description\" content=\"Lange wurde mit Spannung darauf gewartet, wie sich die Schweiz punkto Regulierung von k\u00fcnstlicher Intelligenz positioniert: Nun hat der Bundesrat am 12. Februar 2025 basierend auf einer umfassenden Auslegeordnung die Leitplanken zur KI-Regulierung festgelegt. Der vorliegende Blogbeitrag fasst die wichtigsten Punkte zusammen, ordnet die Stossrichtungen und die zugrundeliegenden Analysen ein und beantwortet die Frage, ob die Schweiz damit nun Stellung bezogen hat - oder doch nicht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/\" \/>\n<meta property=\"og:site_name\" content=\"Management and Law Blog\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-13T03:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-04T10:41:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Isabelle Oehri\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Isabelle Oehri\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/\"},\"author\":{\"name\":\"Isabelle Oehri\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\"},\"headline\":\"KI-Regulierung: Schweiz positioniert sich &#8211; oder doch nicht?\",\"datePublished\":\"2025-02-13T03:20:00+00:00\",\"dateModified\":\"2026-02-04T10:41:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/\"},\"wordCount\":1916,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2025\\\/02\\\/GettyImages-2017676996_hslu.jpg\",\"articleSection\":[\"Digitalisierung und Digital Law\",\"Gesetzgebung und Rechtsprechung\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/\",\"name\":\"KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2025\\\/02\\\/GettyImages-2017676996_hslu.jpg\",\"datePublished\":\"2025-02-13T03:20:00+00:00\",\"dateModified\":\"2026-02-04T10:41:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2025\\\/02\\\/GettyImages-2017676996_hslu.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/wp-content\\\/blogs.dir\\\/901\\\/files\\\/sites\\\/15\\\/2025\\\/02\\\/GettyImages-2017676996_hslu.jpg\",\"width\":2048,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/2025\\\/02\\\/13\\\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KI-Regulierung: Schweiz positioniert sich &#8211; oder doch nicht?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/\",\"name\":\"Management and Law Blog\",\"description\":\"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/management-and-law\\\/#\\\/schema\\\/person\\\/fe571c9fc0254d8d85fc6fbc781b260d\",\"name\":\"Isabelle Oehri\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/isabelle-oehri-b81891158\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/","og_locale":"de_DE","og_type":"article","og_title":"KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog","og_description":"Lange wurde mit Spannung darauf gewartet, wie sich die Schweiz punkto Regulierung von k\u00fcnstlicher Intelligenz positioniert: Nun hat der Bundesrat am 12. Februar 2025 basierend auf einer umfassenden Auslegeordnung die Leitplanken zur KI-Regulierung festgelegt. Der vorliegende Blogbeitrag fasst die wichtigsten Punkte zusammen, ordnet die Stossrichtungen und die zugrundeliegenden Analysen ein und beantwortet die Frage, ob die Schweiz damit nun Stellung bezogen hat - oder doch nicht.","og_url":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/","og_site_name":"Management and Law Blog","article_published_time":"2025-02-13T03:20:00+00:00","article_modified_time":"2026-02-04T10:41:07+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","type":"image\/jpeg"}],"author":"Isabelle Oehri","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Isabelle Oehri","Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/"},"author":{"name":"Isabelle Oehri","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d"},"headline":"KI-Regulierung: Schweiz positioniert sich &#8211; oder doch nicht?","datePublished":"2025-02-13T03:20:00+00:00","dateModified":"2026-02-04T10:41:07+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/"},"wordCount":1916,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","articleSection":["Digitalisierung und Digital Law","Gesetzgebung und Rechtsprechung"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/","url":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/","name":"KI-Regulierung: Schweiz positioniert sich - oder doch nicht? - Management and Law Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","datePublished":"2025-02-13T03:20:00+00:00","dateModified":"2026-02-04T10:41:07+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#primaryimage","url":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","contentUrl":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","width":2048,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/management-and-law\/2025\/02\/13\/ki-regulierung-schweiz-positioniert-sich-oder-doch-nicht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/management-and-law\/"},{"@type":"ListItem","position":2,"name":"KI-Regulierung: Schweiz positioniert sich &#8211; oder doch nicht?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#website","url":"https:\/\/hub.hslu.ch\/management-and-law\/","name":"Management and Law Blog","description":"Institut f\u00fcr Betriebs- und Regional\u00f6konomie IBR","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/management-and-law\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/management-and-law\/#\/schema\/person\/fe571c9fc0254d8d85fc6fbc781b260d","name":"Isabelle Oehri","sameAs":["https:\/\/www.linkedin.com\/in\/isabelle-oehri-b81891158\/"]}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/management-and-law\/wp-content\/blogs.dir\/901\/files\/sites\/15\/2025\/02\/GettyImages-2017676996_hslu.jpg","author_info":{"display_name":"Isabelle Oehri","author_link":"https:\/\/hub.hslu.ch\/management-and-law\/author\/isabelleoehri\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/comments?post=6966"}],"version-history":[{"count":35,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6966\/revisions"}],"predecessor-version":[{"id":7598,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/posts\/6966\/revisions\/7598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media\/6970"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/media?parent=6966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/categories?post=6966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/management-and-law\/wp-json\/wp\/v2\/tags?post=6966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}