{"id":13009,"date":"2020-08-24T07:58:55","date_gmt":"2020-08-24T05:58:55","guid":{"rendered":"https:\/\/hub.hslu.ch\/retailbanking\/?p=13009"},"modified":"2026-02-11T14:52:55","modified_gmt":"2026-02-11T13:52:55","slug":"rueckblick-auf-die-konferenz-innovationen-im-banking","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/","title":{"rendered":"R\u00fcckblick auf die Konferenz Innovationen im Banking"},"content":{"rendered":"\n\n\n<p><strong>Einf\u00fchrung, Prof. Dr. Andreas Dietrich, Hochschule Luzern-Wirtschaft<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Andreas Dietrich begr\u00fcsste die Teilnehmenden zum ersten Mal seit langem wieder zu einer physischen Konferenz, welche organisatorisch stark durch das Corona-Schutzkonzept gepr\u00e4gt war.<\/li><li>Aus Sicht von Andreas Dietrich beginnen die Angebote von FinTechs im Schweizer Finanzmarkt langsam Spuren zu hinterlassen. Ein Beispiel daf\u00fcr sind die Geb\u00fchren f\u00fcr Debit- und Kreditkarten, wo ein gewisser Druck durch Anbieter wie Revolut oder N26 entstanden ist.<\/li><li>Auch im Bereich Open Banking und im Anlegen ist Bewegung in den Schweizer Markt gekommen.<\/li><\/ul>\n\n\n\n<p><strong>Digitale Anlagel\u00f6sungen bei Vontobel und Raiffeisen<br>Christian Gm\u00fcnder, COO Wealth Management, Bank Vontobel<br><\/strong><strong>Felix Wenger, Ehemaliger Leiter Vertrieb &amp; Kanalkonzeption, Raiffeisen Schweiz<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Die Bank Vontobel hat deshalb vor drei Jahren begonnen, die IT-Architektur grundlegend zu \u00fcberarbeiten. Darauf aufbauend soll die Implementation von neuen Produkten und Dienstleistungen, bzw. deren Customer Journey, schnell und flexibel m\u00f6glich sein. Ziel ist es, neue L\u00f6sungen innert sechs Monaten lancieren zu k\u00f6nnen. Die flexible IT-Architektur von Vontobel erlaubt es auch, ziemlich rasch neue Partner anzubinden. Die digitale Verm\u00f6gensverwaltung RIO von Raiffeisen ist ein Beispiel daf\u00fcr.<\/li><li>Zwei Beispiele f\u00fcr neu eingef\u00fchrten L\u00f6sungen sind die Verm\u00f6gensverwaltungs-Apps <a href=\"https:\/\/volt.vontobel.com\/de-ch\" target=\"_blank\" rel=\"noreferrer noopener\">Volt<\/a> von Vontobel (siehe den <a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2019\/08\/12\/revolution-im-private-banking-der-vontobel-robo-advisor-volt-im-test\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blog<\/a> dazu) sowie <a href=\"https:\/\/www.raiffeisen.ch\/sensetal\/de\/privatkunden\/anlegen\/vermoegensverwaltung\/digitale-vermoegensverwaltung.html\" target=\"_blank\" rel=\"noreferrer noopener\">RIO<\/a> von Raiffeisen.<\/li><\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png\"><img loading=\"lazy\" decoding=\"async\" width=\"622\" height=\"293\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png\" alt=\"\" class=\"wp-image-13010\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png 622w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO-300x141.png 300w\" sizes=\"auto, (max-width: 622px) 100vw, 622px\" \/><\/a><figcaption><em>Abbildung 1: Ein erster Blick in den bald lancierten Robo Advisor von Raiffeisen<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\"><li>Christian Gm\u00fcnder k\u00fcndigt zudem an, dass die Bank Vontobel in zwei Wochen ein digitales S\u00e4ule 3a Produkt, basierend auf Volt, lancieren wird.<\/li><li>RIO wird aktuell mit 1&#8217;500 Mitarbeitenden von Raiffeisen getestet und soll im dritten Quartal 2020 live gehen. Die L\u00f6sung scheint \u00e4hnlich zur L\u00f6sung von Volt zu sein. Das Pricing von RIO wird sich aber von demjenigen von Volt unterscheiden. Es richtet sich in erster Linie an Kunden mit einem E-Banking Vertrag.<\/li><li>Felix Wenger stellte die L\u00f6sung vor und zeigte auf, wie eng verzahnt die Wertsch\u00f6pfungsketten von Vontobel und Raiffeisen sind. So stammen zum Beispiel das Front- und Backend sowie die Risk Engine von Vontobel, Raiffeisen \u00fcbernimmt unter anderem das Portfoliomanagement, den Vertrieb, das Marketing sowie den Support.<\/li><\/ul>\n\n\n\n<p><strong>Zielbasiert Investieren: digital zu den Wurzeln zur\u00fcck<br>David Strebel, Mitglied der Gesch\u00e4ftsleitung, Thurgauer Kantonalbank<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Die TKB setzt als erste Schweizer Bank seit nun etwa einem Jahr auf <a href=\"https:\/\/www.tkb.ch\/private\/zielbasiert-investieren\" target=\"_blank\" rel=\"noreferrer noopener\">zielbasiertes Investieren<\/a>. Die Anlagestrategie leitet sich dabei von den gesetzten Sparzielen ab (z.B. in Pension mit 63 Jahren, Hauskauf, etc.; siehe dazu auch meinen <a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2019\/02\/20\/paradigmen-wechsel-im-anlagegeschaeft-die-thurgauer-kantonalbank-setzt-als-erste-schweizer-bank-auf-zielbasiertes-investieren\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blog<\/a>).<\/li><li>Der Ansatz ist aus Sicht der TKB ein Paradigmenwechsel, weg von den traditionellen Ans\u00e4tzen. Ein Merkmal der neuen Anlagestrategie ist beispielsweise, dass das Risiko gegen Ende des Ziels abh\u00e4ngig von der Wahrscheinlichkeit der Zielerreichung m\u00f6glicherweise deutlich reduziert wird, um die Erreichung auch wirklich sicherzustellen.<\/li><li>Erste Erfahrungen zeigen, dass dieses Vorgehen sowohl von Kunden als auch von Mitarbeitenden sehr gut akzeptiert wird. Kundengespr\u00e4che werden nicht mehr als Verkaufsgespr\u00e4che wahrgenommen, sondern man erarbeitet zusammen eine L\u00f6sung f\u00fcr ein Ziel. Der Kundenberater hat in diesem Konzept eine absolut zentrale Rolle.<\/li><\/ul>\n\n\n\n<p><strong>Open Banking \u2013 Eine Frage der Strategie<br>Sven Siat, Head Connectivity, SIX<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sven Siat stellte b.link, die Plattform f\u00fcr standardisierte Schnittstellen von SIX vor (auch dazu auch meinen <a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2020\/05\/18\/open-banking-in-der-schweiz-six-group-lanciert-b-link\/\" target=\"_blank\" rel=\"noreferrer noopener\">Blog<\/a>-Artikel).<\/li><li>Die Relevanz von Open Banking muss in der Schweiz vor allem auf <a href=\"https:\/\/www.six-group.com\/de\/blog\/2020\/open-banking-competencies.html\" target=\"_blank\" rel=\"noreferrer noopener\">strategischer Ebene noch st\u00e4rker verankert<\/a> werden. Bisher hatte der Schweizer Markt aus Sicht von Sven Siat auf das Thema Open Banking noch eine zu technische Sicht.<\/li><li>Neue Business Cases ergeben sich im Bereich von Effizienzsteigerungen, Erweiterungen des Produktangebotes, oder der Monetarisierung von Daten. Zudem sind verschiedene Banken vor allem auch an standardisierten Schnittstellen rund um das Thema \u00abImmobilien\u00bb resp. Hypotheken interessiert.<\/li><li>Auf die Frage, welche Standards sich in der Schweiz durchsetzen werden, sieht Siat verschiedene Standards in verschiedenen Bereichen (z.B. Anlegen, Hypotheken etc.). Er weist zudem darauf hin, dass Standards auch kompatibel gemacht werden k\u00f6nnen und derzeit verschiedene Gespr\u00e4ch am Laufen sind.<\/li><\/ul>\n\n\n\n<p><strong>Wertsch\u00f6pfungskette erweitern: Wie Valiant mit dem Immobilienmaklerdienst AgentSelly Mehrwert f\u00fcr Kunden und Partner schafft<br>Christoph Wille, Leiter Kundenservices und Kan\u00e4le, Valiant Bank<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Valiant ist bereits im 2017 eine Beteiligung an fidesso eingegangen, damals eine L\u00f6sung f\u00fcr Selbstverk\u00e4ufer von Immobilien. fidesso wurde 2018 in Agent Selly umbenannt, im 2019 hat Valiant die Mehrheit an <a href=\"https:\/\/www.agentselly.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Agent Selly<\/a> \u00fcbernommen.<\/li><li>Mit diesem Schritt m\u00f6chte Valiant die Customer Journey im Bereich Immobilien komplett abdecken, bzw. die Wertsch\u00f6pfungskette der Bank erweitern. Dazu geh\u00f6rt unter anderem auch das Anbieten und Suchen von Immobilien, sowie die Besichtigung und Sch\u00e4tzung von Immobilien.<\/li><li>Kundenberater \u00fcbernehmen unter anderem auch Aufgaben wie die Besichtigung von Immobilien. Dies generiert f\u00fcr die Bank nat\u00fcrlich einen sehr wertvollen Lead.<\/li><li>Valiant m\u00f6chte ihr k\u00fcnftiges Vertriebsnetz noch st\u00e4rker als zuvor nutzen, um AgentSelly bei den Kunden bekannt zu machen. Kundenberatende sollen AgentSelly als interessanten Immobilienmakler positionieren. Es wird vermehrte Logo-Pr\u00e4senz und auch AgentSelly-Beratende in den Gesch\u00e4ftsstellen von Valiant geben. Des Weiteren gibt es k\u00fcnftig m\u00f6glicherweise auch eine strategische Erweiterung mit einem Hypothekenvermittlungs-Angebot und der Anbindung eines Versicherungspartners.<\/li><li>Die Zusammenarbeit mit Agent Selly steht auch anderen Banken offen. Die Bank Thalwil hat sich <a href=\"https:\/\/www.bankthalwil.ch\/de\/Privatkunden\/Hypotheken-und-Finanzierungen\/verkauf-und-kauf-von-immobilien\/Kooperation-mit-AgentSelly\" target=\"_blank\" rel=\"noreferrer noopener\">als erste Bank angeschlossen.<\/a><\/li><\/ul>\n\n\n\n<p><strong>Touchpointerlebnisse im Banking &#8211; was Kunden wollen, was Banken anbieten<br>Prof. Dr. Nils Hafner, Hochschule Luzern &#8211; Wirtschaft, Institut f\u00fcr Finanzdienstleistungen Zug IFZ<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Nils Hafner stellte die Resultate der Touchpoint-Studie vor (<a href=\"https:\/\/services.bsi-software.com\/studio\/public\/c\/Oacd7IhCTvWC4aE5Hb8jJgY4iuF5LEQai7pw8_lUjzNw7CU2xlRiSSKBDvokg1p0Qg\" target=\"_blank\" rel=\"noreferrer noopener\">Download<\/a>)<\/li><li>Eine Zusammenfassung der Studie findet sich <a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2020\/06\/22\/kundenmanagement-im-banking-durchgehend-orchestrieren\/\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a>.<\/li><\/ul>\n\n\n\n<p><strong>Sprachassistenten im Kundenkontakt &#8211; wie Swisscard Services clever automatisiert<br><\/strong><strong>Gregorio Uglioni, Head of Transformation Operations Services, Swisscard AECS GmbH<br><\/strong><strong>Stephan Fehlmann, Senior Business Developer bei Spitch<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Gregorio Uglioni zeigte auf, wie Swisscard Spracherkennung einsetzt. Dadurch konnte bei telefonischen Anfragen ein Teil des Prozesses digitalisiert werden. Die Identifikation der Kunden erfolgt \u00fcber die App von Swisscard.<\/li><li>Der Kunde kann nach der Identifikation sein Anliegen verbal schildern anstatt mit den \u00fcblichen Nummern f\u00fcr den Gesch\u00e4ftsfall (\u00abDr\u00fccken Sie 1 f\u00fcr\u2026\u00bb) selber eine Zuteilung vorzunehmen. Dank der Spracherkennung wird das Anliegen in der Regel automatisch dem richtigen Call Center Agent zugewiesen. Dieser sieht zudem bereits einige Sekunden bevor er den Anruf annimmt, um welches Thema es geht \u2013 was von den Mitarbeitenden sehr gesch\u00e4tzt wird.<\/li><li>Die Spracherkennung funktioniert auch in Schweizerdeutsch. Etwa 60% der Anfragen werden in Schweizerdeutsch formuliert.<\/li><li>Aktuell werden 90 Prozent der Kundenanfragen korrekt erkannt. Stephan Fehlmann von der Firma Spitch sieht das Potential bei etwa 95 Prozent.<\/li><li>M\u00f6gliche Erweiterungsschritte gehen in Richtung Automatisierung. So k\u00f6nnen dank der Sprache und abh\u00e4ngig vom Gesch\u00e4ftsfall, gewisse Dialoge von vornherein automatisiert werden.<\/li><\/ul>\n\n\n\n<p><strong>Digitalize your customer journey around cash<br>Sandipan Chakraborty, Founder &amp; CEO, Sonect AG<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Sandipan Chakraborty stellte sein Start-up sonect vor. Das Gesch\u00e4ftsmodell von sonect erlaubt Retail-Gesch\u00e4ften, die Rolle von Bankomaten zu \u00fcbernehmen. Personen, die Geld beziehen m\u00f6chten, k\u00f6nnen dies in angeschlossenen Gesch\u00e4ften mittels Vorzeige eines Strichcodes erledigen. Der Vorteil f\u00fcr Banken ist es, dass sie ihre Kosten f\u00fcr das Bankomaten-Netz reduzieren k\u00f6nnten. Gesch\u00e4fte k\u00f6nnen ihr Cash-Management verbessern und erhalten zus\u00e4tzlich Laufkundschaft.<\/li><li>Das Gesch\u00e4ft ist auf B2B2C ausgerichtet. Eine zuk\u00fcnftige Partner-Bank beispielsweise hat Sonect direkt in der Mobile Banking App integriert.<\/li><li>Das Angebot von sonect geht aber \u00fcber das eigentliche Geld beziehen hinaus. So k\u00f6nnen Kunden auch weitere Angebote gemacht werden (z.B. verg\u00fcnstigtes Getr\u00e4nk bei Bargeldbezug etc.).<\/li><li>Sonect ist im Juli 2017 gestartet mit vier Pilot-Gesch\u00e4ften, wo der Bargeldbezug m\u00f6glich war. Mittlerweile kann in der Schweiz bei 2&#8217;300 Gesch\u00e4ften Bargeld bezogen werden. Die Dichte ist gem\u00e4ss sonect somit bereits h\u00f6her als diejenige aller Bankomaten in der Schweiz.<\/li><li>Unter anderem arbeitet sonect mit Unternehmen wie Volg, Valora (k Kiosk, Press&amp;Books) oder den toppharm Apotheken zuammen.<\/li><li>Demn\u00e4chst expandiert sonect nach Italien in Zusammenarbeit mit einer grossen italienischen Bank. In den n\u00e4chsten Quartalen ist auch die Expansion nach Deutschland, Frankreich und Grossbritannien geplant.<\/li><\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"384\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen-1024x384.png\" alt=\"\" class=\"wp-image-13012\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen-1024x384.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen-300x113.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen-768x288.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/Konferenz-Innovationen.png 1247w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption><em>Abbildung 2: Bilder der Konferenz<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p><em>PS: Bereits kommenden Donnerstag, 27. August 2020, findet am IFZ die Sourcing Konferenz statt. Es sind noch wenige Pl\u00e4tze verf\u00fcgbar. <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2020\/08\/27\/sourcing-konferenz\/\" target=\"_blank\" rel=\"noreferrer noopener\">Weitere Informationen finden Sie hier<\/a><\/em><em>. Ab Donnerstag wird dann auch unsere neue <a href=\"https:\/\/blog.hslu.ch\/sourcing\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sourcing Studie online verf\u00fcgbar<\/a><\/em><em> sein, in der wir aufzeigen, wo die Schweizer Banken in Bezug auf das Sourcing stehen.<\/em><\/p>\n\n\n\n<p><em>PPS: Am 26. November findet die Retail Banking Konferenz 2020 statt. Weiter Informationen <a href=\"https:\/\/www.hslu.ch\/de-ch\/wirtschaft\/agenda\/veranstaltungen\/2020\/11\/26\/retail-banking-konferenz-2020\/\" target=\"_blank\" rel=\"noreferrer noopener\">hier<\/a><\/em><em>.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>An der IFZ-Konferenz \u00abInnovationen im Banking\u00bb wurden zahlreiche Innovationen im Schweizer Bankenmarkt vorgestellt und diskutiert. Unter anderem standen die Themen Anlegen\/Investieren, Open Banking und Touchpoints im Fokus. Nachfolgend ein kurzer R\u00fcckblick auf die Referate.<\/p>\n","protected":false},"author":1270,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[46482,647343,19520,46509,23682,46469,19459,436,4051,723,19461,647337],"tags":[],"class_list":["post-13009","post","type-post","status-publish","format-standard","hentry","category-bank-it","category-bankberatung","category-bankfiliale","category-bankstrategie","category-digitalisierung","category-fintech","category-hypothekargeschaft","category-436","category-studie","category-veranstaltungen","category-vertriebsmanagement","category-wealth-management"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog\" \/>\n<meta property=\"og:description\" content=\"An der IFZ-Konferenz \u00abInnovationen im Banking\u00bb wurden zahlreiche Innovationen im Schweizer Bankenmarkt vorgestellt und diskutiert. Unter anderem standen die Themen Anlegen\/Investieren, Open Banking und Touchpoints im Fokus. Nachfolgend ein kurzer R\u00fcckblick auf die Referate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/\" \/>\n<meta property=\"og:site_name\" content=\"IFZ Retail Banking Blog\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-24T05:58:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:52:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"R\u00fcckblick auf die Konferenz Innovationen im Banking\",\"datePublished\":\"2020-08-24T05:58:55+00:00\",\"dateModified\":\"2026-02-11T13:52:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/\"},\"wordCount\":1363,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/RIO.png\",\"articleSection\":[\"Bank IT\",\"Bankberatung\",\"Bankfiliale\",\"Bankstrategie\",\"Digitalisierung\",\"FinTech\",\"Hypothekargesch\u00e4ft\",\"Kantonalbanken\",\"Studie\",\"Veranstaltungen\",\"Vertriebsmanagement\",\"Wealth Management\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/\",\"name\":\"R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/RIO.png\",\"datePublished\":\"2020-08-24T05:58:55+00:00\",\"dateModified\":\"2026-02-11T13:52:55+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/RIO.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2020\\\/08\\\/RIO.png\",\"width\":622,\"height\":293},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/rueckblick-auf-die-konferenz-innovationen-im-banking\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckblick auf die Konferenz Innovationen im Banking\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\",\"name\":\"IFZ Retail Banking Blog\",\"description\":\"News und Trends aus dem Retail Banking Markt Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/","og_locale":"de_DE","og_type":"article","og_title":"R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog","og_description":"An der IFZ-Konferenz \u00abInnovationen im Banking\u00bb wurden zahlreiche Innovationen im Schweizer Bankenmarkt vorgestellt und diskutiert. Unter anderem standen die Themen Anlegen\/Investieren, Open Banking und Touchpoints im Fokus. Nachfolgend ein kurzer R\u00fcckblick auf die Referate.","og_url":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/","og_site_name":"IFZ Retail Banking Blog","article_published_time":"2020-08-24T05:58:55+00:00","article_modified_time":"2026-02-11T13:52:55+00:00","og_image":[{"url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/"},"author":{"name":"","@id":""},"headline":"R\u00fcckblick auf die Konferenz Innovationen im Banking","datePublished":"2020-08-24T05:58:55+00:00","dateModified":"2026-02-11T13:52:55+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/"},"wordCount":1363,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png","articleSection":["Bank IT","Bankberatung","Bankfiliale","Bankstrategie","Digitalisierung","FinTech","Hypothekargesch\u00e4ft","Kantonalbanken","Studie","Veranstaltungen","Vertriebsmanagement","Wealth Management"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/","url":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/","name":"R\u00fcckblick auf die Konferenz Innovationen im Banking - IFZ Retail Banking Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png","datePublished":"2020-08-24T05:58:55+00:00","dateModified":"2026-02-11T13:52:55+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#primaryimage","url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png","contentUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2020\/08\/RIO.png","width":622,"height":293},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/retailbanking\/rueckblick-auf-die-konferenz-innovationen-im-banking\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hub.hslu.ch\/retailbanking\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckblick auf die Konferenz Innovationen im Banking"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website","url":"https:\/\/hub.hslu.ch\/retailbanking\/","name":"IFZ Retail Banking Blog","description":"News und Trends aus dem Retail Banking Markt Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/retailbanking\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":""}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"","author_link":"https:\/\/hub.hslu.ch\/retailbanking\/author\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/13009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/users\/1270"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/comments?post=13009"}],"version-history":[{"count":8,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/13009\/revisions"}],"predecessor-version":[{"id":21648,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/13009\/revisions\/21648"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/media?parent=13009"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/categories?post=13009"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/tags?post=13009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}