{"id":17637,"date":"2022-09-14T10:35:56","date_gmt":"2022-09-14T08:35:56","guid":{"rendered":"https:\/\/hub.hslu.ch\/retailbanking\/?p=17637"},"modified":"2026-02-02T10:39:57","modified_gmt":"2026-02-02T09:39:57","slug":"krypto-assets-sind-gekommen-um-zu-bleiben","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/","title":{"rendered":"Krypto-Assets sind gekommen, um zu bleiben"},"content":{"rendered":"\n<p><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/download\/crypto-assets-study\/\" target=\"_blank\" rel=\"noreferrer noopener\">Direkt zum Download der Studie<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Neue Produkte kommen auf den Markt<\/strong><\/h2>\n\n\n\n<p>Das Schweizer Anlage\u00f6kosystem f\u00fcr Krypto-Assets-Investments bietet immer mehr Finanzprodukte an. Im Bereich der indirekten Anlagen zeigt sich dies unter anderem an der Anzahl der ETPs, die in der Schweiz und\/oder in Liechtenstein domiziliert sind, gehandelt werden oder zum Verkauf stehen. Nicht nur die Anzahl der Produkte nimmt zu, sondern auch deren Vielfalt (siehe Abbildung 1). Neben der Einf\u00fchrung neuer Produkttypen zeigt sich dies auch in der zunehmenden Breite der zugrunde liegenden Basiswerte. Mit der Entwicklung des \u00d6kosystems sind weitere Innovationen zu erwarten, nicht nur im Bereich der indirekten Anlagen, sondern auch bei den direkten Anlagen, zum Beispiel getrieben durch Entwicklungen im Bereich von Decentralized Finance (DeFi).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"337\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-1024x337.png\" alt=\"\" class=\"wp-image-17648\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-1024x337.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-300x99.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-768x253.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-1536x505.png 1536w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-928x305.png 928w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png 1590w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Abbildung 1: Anzahl der in der Schweiz gehandelten kryptobezogenen indirekten Finanzprodukte nach Produkttyp (linke Grafik) und Basiswert (rechte Grafik) (Quellen: BX Swiss, SIX)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Breites Produkt- und Dienstleistungsangebot, aber nicht f\u00fcr alle Kundensegmente<\/strong> <\/h2>\n\n\n\n<p>Das \u00d6kosystem bietet sowohl direkte als auch indirekte Anlagel\u00f6sungen in Kryptoanlagen sowie Infrastrukturdienste an. In diesem Zusammenhang richtet sich die Mehrheit der befragten Unternehmen<a id=\"_ftnref1\" href=\"#_ftn1\">[1]<\/a> eher an Unternehmen und\/oder institutionelle Kunden als an Retailkunden. Emissions- und Tokenisierungsl\u00f6sungen sowie B\u00f6rsendienstleistungen sind die am h\u00e4ufigsten genannten Angebote. Dienstleistungen im Bereich des \u00abLending\u00bb werden dagegen von vergleichsweise wenigen Unternehmen angeboten (siehe Abbildung 2). Die Auswertung zeigt zudem, dass es im \u00d6kosystem Spezialisten gibt, die nur einzelne Dienstleistungen der gesamten Wertsch\u00f6pfungskette von Krypto-Assets-Investments anbieten, aber auch wenige Generalisten mit einem breiteren Angebot \u00fcber die gesamte Investment-Wertsch\u00f6pfungskette hinweg.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2.png\"><img loading=\"lazy\" decoding=\"async\" width=\"971\" height=\"868\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2.png\" alt=\"\" class=\"wp-image-17649\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2.png 971w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2-300x268.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2-768x687.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb2_2-781x698.png 781w\" sizes=\"auto, (max-width: 971px) 100vw, 971px\" \/><\/a><figcaption class=\"wp-element-caption\">Abbildung 2: Hauptaktivit\u00e4ten der an der Umfrage teilnehmenden Unternehmen<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Die Handelsvolumina an zentralen Kryptob\u00f6rsen sind nach wie vor am gr\u00f6ssten<\/strong> <\/h2>\n\n\n\n<p>Krypto-Assets oder entsprechende Derivate k\u00f6nnen sowohl an traditionellen B\u00f6rsen als auch an zentralen oder dezentralen Kryptob\u00f6rsen gehandelt werden. Das gr\u00f6sste Handelsvolumen wird an zentralen Kryptob\u00f6rsen abgewickelt. Konkret belief sich das aus der Schweiz stammende j\u00e4hrliche Handelsvolumen an zentralen Kryptob\u00f6rsen in der Beobachtungsperiode vom Mai 2021 bis April 2022 auf gesch\u00e4tzte 200 Milliarden Schweizer Franken. Das Handelsvolumen an dezentralen Kryptob\u00f6rsen bel\u00e4uft sich im selben Beobachtungszeitraums auf 5.1 Milliarden Franken und ist damit kleiner als dasjenige an den beiden Schweizer B\u00f6rsen BX Swiss und SIX Swiss Exchange, auf die 6.5 Milliarden Franken entfallen. In Bezug auf die traditionellen B\u00f6rsen ist festzustellen, dass der gr\u00f6sste Anteil des Handelsvolumens auf ETPs entf\u00e4llt. W\u00e4hrend die Anzahl von kryptobezogenen Produkte kontinuierlich steigt, ist das Volumen seit einigen Monaten jedoch r\u00fcckl\u00e4ufig (siehe Abbildung 3). Konkreter: Lag das monatliche Handelsvolumen von kryptobezogenen Finanzprodukten an den beiden B\u00f6rsen BX Swiss und SIX Swiss Exchange im Februar 2021 noch bei 1.2 Milliarden Franken, waren es im April 2022 noch 196 Millionen Franken, also mehr als sechsmal tiefer.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"360\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-1024x360.png\" alt=\"\" class=\"wp-image-17650\" style=\"width:840px;height:295px\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-1024x360.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-300x105.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-768x270.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-1536x540.png 1536w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3-928x326.png 928w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb3_3.png 1562w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Abbildung 3: Handelsvolumen an den Schweizer B\u00f6rsen BX Swiss und SIX (Quellen: Bloomberg, BX Swiss, SIX)<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Hohe Risiken, aber auch potenziell hohe Gewinne<\/strong><\/h2>\n\n\n\n<p>Eine Analyse zeigt, dass selbst einfache Anlagestrategien in Krypto-Assets in der Vergangenheit f\u00fcr Anleger vorteilhaft gewesen sein k\u00f6nnten, indem sie eine h\u00f6here risikobereinigte Performance in einem Portfoliokontext lieferten. Dies ist jedoch mit einem erh\u00f6hten Risiko verbunden, wie Standardrisikomasse wie die Standardabweichung oder der maximale Drawdown eines Portfolios, das Kryptoanlagen enth\u00e4lt, zeigen. Ausserdem kann in Zeiten hoher Volatilit\u00e4t die Renditekorrelation mit traditionellen Anlagen hoch sein, was das Diversifizierungspotenzial von Kryptoanlagen vor\u00fcbergehend verringert.<\/p>\n\n\n\n<p><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/download\/crypto-assets-study\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Hier k\u00f6nnen Sie die Studie herunterladen (nur in englischer Sprache verf\u00fcgbar).<\/strong><\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Im Zeitraum zwischen Mai und Juni 2022 wurden insgesamt 133 Unternehmen im Schweizer und Liechtensteiner \u00d6kosystem f\u00fcr Krypto-Anlagen kontaktiert, wovon 32 an einer standardisierten Umfrage teilgenommen haben.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trotz (oder gerade wegen) hoher Volatilit\u00e4t, tempor\u00e4r steigender Renditekorrelation mit anderen Anlageklassen, Hypes und Crashs ist das schweizerische und liechtensteinische \u00d6kosystem f\u00fcr Kryptoanlagen weiterhin aktiv. Zu diesem Schluss kommt die &#8222;Crypto Assets Study 2022&#8220; der Hochschule Luzern, die zum zweiten Mal eine \u00dcbersicht der verschiedenen Gesch\u00e4ftsmodelle im \u00d6kosystem sowie eine Aufarbeitung der aggregierten Volumina im Kryptomarkt vornimmt. Im Folgenden gehen wir auf ausgew\u00e4hlte Ergebnisse der Studie ein.<\/p>\n","protected":false},"author":168,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"21022,21006,21010,20813,20721,20620","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[252],"tags":[],"class_list":["post-17637","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog<\/title>\n<meta name=\"description\" content=\"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog\" \/>\n<meta property=\"og:description\" content=\"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/\" \/>\n<meta property=\"og:site_name\" content=\"IFZ Retail Banking Blog\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-14T08:35:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-02T09:39:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1590\" \/>\n\t<meta property=\"og:image:height\" content=\"523\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"simonamrein\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"simonamrein\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/\"},\"author\":{\"name\":\"simonamrein\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/0f12032922e7964cc250c39088bac042\"},\"headline\":\"Krypto-Assets sind gekommen, um zu bleiben\",\"datePublished\":\"2022-09-14T08:35:56+00:00\",\"dateModified\":\"2026-02-02T09:39:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/\"},\"wordCount\":592,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/09\\\/Abb1_1-1024x337.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/\",\"name\":\"Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/09\\\/Abb1_1-1024x337.png\",\"datePublished\":\"2022-09-14T08:35:56+00:00\",\"dateModified\":\"2026-02-02T09:39:57+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/0f12032922e7964cc250c39088bac042\"},\"description\":\"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/09\\\/Abb1_1.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/09\\\/Abb1_1.png\",\"width\":1590,\"height\":523},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/krypto-assets-sind-gekommen-um-zu-bleiben\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Krypto-Assets sind gekommen, um zu bleiben\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\",\"name\":\"IFZ Retail Banking Blog\",\"description\":\"News und Trends aus dem Retail Banking Markt Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/0f12032922e7964cc250c39088bac042\",\"name\":\"simonamrein\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g\",\"caption\":\"simonamrein\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog","description":"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/","og_locale":"de_DE","og_type":"article","og_title":"Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog","og_description":"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.","og_url":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/","og_site_name":"IFZ Retail Banking Blog","article_published_time":"2022-09-14T08:35:56+00:00","article_modified_time":"2026-02-02T09:39:57+00:00","og_image":[{"width":1590,"height":523,"url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png","type":"image\/png"}],"author":"simonamrein","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"simonamrein","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/"},"author":{"name":"simonamrein","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/0f12032922e7964cc250c39088bac042"},"headline":"Krypto-Assets sind gekommen, um zu bleiben","datePublished":"2022-09-14T08:35:56+00:00","dateModified":"2026-02-02T09:39:57+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/"},"wordCount":592,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-1024x337.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/","url":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/","name":"Krypto-Assets sind gekommen, um zu bleiben - IFZ Retail Banking Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1-1024x337.png","datePublished":"2022-09-14T08:35:56+00:00","dateModified":"2026-02-02T09:39:57+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/0f12032922e7964cc250c39088bac042"},"description":"Die Crypto Assets Study 2022 der Hochschule Luzern untersucht die Gesch\u00e4ftsmodelle in der Schweiz und Liechtenstein und zeigt Volumina im Kryptomarkt.","breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#primaryimage","url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png","contentUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/09\/Abb1_1.png","width":1590,"height":523},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/retailbanking\/krypto-assets-sind-gekommen-um-zu-bleiben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hub.hslu.ch\/retailbanking\/"},{"@type":"ListItem","position":2,"name":"Krypto-Assets sind gekommen, um zu bleiben"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website","url":"https:\/\/hub.hslu.ch\/retailbanking\/","name":"IFZ Retail Banking Blog","description":"News und Trends aus dem Retail Banking Markt Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/retailbanking\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/0f12032922e7964cc250c39088bac042","name":"simonamrein","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68f93d16812db9d5dd5fa71eb01642d74c8277255afd97bd0e18488321b79789?s=96&d=mm&r=g","caption":"simonamrein"}}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"simonamrein","author_link":"https:\/\/hub.hslu.ch\/retailbanking\/author\/simonamrein\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/users\/168"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/comments?post=17637"}],"version-history":[{"count":16,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17637\/revisions"}],"predecessor-version":[{"id":21193,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17637\/revisions\/21193"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/media?parent=17637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/categories?post=17637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/tags?post=17637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}