{"id":17830,"date":"2023-01-16T08:17:15","date_gmt":"2023-01-16T07:17:15","guid":{"rendered":"https:\/\/hub.hslu.ch\/retailbanking\/?p=17830"},"modified":"2026-02-11T14:52:59","modified_gmt":"2026-02-11T13:52:59","slug":"warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/","title":{"rendered":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist"},"content":{"rendered":"\n\n\n<p class=\"wp-block-paragraph\">Finanzwissen ist gerade f\u00fcr die junge Generation wichtiger denn je. Nur mit einem guten Finanzwissen k\u00f6nnen j\u00fcngere Menschen die f\u00fcr sie pers\u00f6nlich richtigen Entscheidungen zur Verm\u00f6gensbildung und zur immer wichtiger werdenden privaten Altersvorsorge treffen. Gelder auf dem Sparbuch bringen nur geringe Ertr\u00e4ge. Menschen sollten daher auch mit Geldanlagen wie ETFs oder Aktien vertraut sein. Benjamin Franklin, einer der Gr\u00fcnderv\u00e4ter der USA, hatte bereits im 18. Jahrhundert festgehalten, dass \u201eeine Investition in Wissen immer noch die besten Zinsen bringt\u00bb. In Bezug auf Finanzwissen stimmt dies wohl wortw\u00f6rtlich. Wer zum Beispiel Verm\u00f6gen f\u00fcr die Pensionierung aufbauen will, sollte wissen, was Zinseszins-Effekte sind oder was der Effekt der Inflation auf die Ersparnisse sein kann. Und wer anlegt, sollte wissen, was Diversifikation in einem Portfolio-Kontext bedeutet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wie gut ist das Wissen der schweizerischen Bev\u00f6lkerung zu diesen Themen? Wissen junge Menschen heute mehr als \u00e4ltere Personen in der Schweiz?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie misst man das Finanzwissen?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt verschiedene Ans\u00e4tze, wie man Finanzwissen messen kann. Ein breit akzeptierter Ansatz in der Forschung sind drei von Lusardi und Mitchell entwickelte Fragen, welche oftmals zur Erhebung des Finanzwissens eingesetzt werden (die sogenannten \u00abBig Three\u00bb-Fragen). Die Fragen lassen auch eine internationale Vergleichbarkeit von Studien zum Thema Finanzwissen zu. Inhaltlich befassen sich die Fragen mit den oben erw\u00e4hnten Themen Zinseszins-Effekt, der Inflation sowie dem Diversifikationseffekt beim Anlegen (weitere Informationen in der Box).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Rahmen einer Studie, welche das Institut f\u00fcr Finanzdienstleistungen Zug IFZ im Auftrag von PostFinance durchgef\u00fchrt hat, wurde unter anderem das Thema Finanzwissen in der Schweiz erhoben. Die Studie basiert auf einer Befragung von insgesamt 3&#8217;162 in der Schweiz wohnhaften Personen zwischen 18 und 74 Jahren und wurde im April 2022 durchgef\u00fchrt. Die Umfrage ist in Bezug auf Alter, Geschlecht, Bildung sowie die Sprachregion der befragten Personen f\u00fcr die Schweiz repr\u00e4sentativ.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Wie gut steht es um das Finanzwissen in der Schweiz?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abbildung 1 zeigt den Anteil der korrekt beantworteten drei Wissensfragen nach demografischen Merkmalen. Insgesamt beantworteten 55.9 Prozent der befragten Personen alle drei Wissensfragen korrekt. Im Jahr 2011 lag dieser Wert (basierend auf einer ebenfalls repr\u00e4sentativen Befragung) in der Schweiz bei 50.1 Prozent.<a href=\"#_ftn1\" id=\"_ftnref1\">[1]<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Generell scheint das Finanzwissen mit dem Alter zuzunehmen. In der Generation der Babyboomers k\u00f6nnen 64.1 Prozent der Befragten alle drei Antworten korrekt beantworten. Bei der Generation Z sind es lediglich 43.8 Prozent. In vielen anderen L\u00e4ndern ist dieser Zusammenhang etwas anders. Dort nimmt das Finanzwissen mit dem Alter wieder ab.<a href=\"#_ftn2\" id=\"_ftnref2\">[2]<\/a> Bei den M\u00e4nnern ist das Finanzwissen im Schnitt etwas h\u00f6her als bei Frauen. 67.2 Prozent der M\u00e4nner beantworten alle drei Fragen korrekt. Bei den Frauen liegt der Wert bei 44.7 Prozent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine positive Korrelation zeigt sich auch bei der wirtschaftlichen Situation der befragten Personen. Wer mehr verdient und\/oder mehr Verm\u00f6gen hat, kann die drei Wissensfragen eher beantworten. Bei der Bildung gibt es ebenfalls grosse Unterschiede: 72 Prozent der Personen mit einem terti\u00e4ren Bildungsabschluss, k\u00f6nnen alle drei Fragen korrekt beantworten. Bei Personen ohne terti\u00e4ren Bildungsabschluss liegt der Wert bei 46 Prozent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein markanter Unterschied ist auch ersichtlich, wenn Anleger:innen und Nicht-Anleger:innen verglichen werden. 69.9 Prozent der Anleger:innen beantworteten alle drei Fragen korrekt. Bei den Nicht-Anleger:innen konnten nur 41.8 Prozent alle drei Fragen korrekt beantworten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anders gesagt sind finanziell besser gebildete Personen deutlich \u00f6fter an den Finanzm\u00e4rkten investiert als Personen mit tiefe(re)n Finanzkenntnissen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"744\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png\" alt=\"\" class=\"wp-image-17833\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-300x218.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-768x558.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-928x675.png 928w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy.png 1044w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em><a>Abbildung <\/a>1: <a>Finanzwissen in der Schweizer Bev\u00f6lkerung (Anzahl korrekt beantworteter Wissensfragen)<\/a><\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Personen wurden auch befragt, wie sie ihr Finanzwissen subjektiv einsch\u00e4tzen. Tendenziell stimmt die subjektive Wissens-Einsch\u00e4tzung mit den objektiven Resultaten der drei Wissensfragen \u00fcberein. Bei den Personen, die auf die Frage \u00abMir fehlt das generelle Wissen \u00fcber Anlageprodukte\u00bb mit \u00abtrifft zu\u00bb antworten, k\u00f6nnen 37.7 Prozent alle drei Wissensfragen korrekt beantworten. Bei den Personen, welche ihr Finanzwissen gut einsch\u00e4tzen, beantworten 67.7 Prozent alle drei Fragen korrekt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Finanzwissen im internationalen Vergleich<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Im Jahr 2014 f\u00fchrte das Global Financial Literacy Excellence Center in Zusammenarbeit mit S&amp;P\u2019s Ratings Services, Gallup und der Weltbank eine <a href=\"https:\/\/gflec.org\/wp-content\/uploads\/2015\/11\/Finlit_paper_16_F2_singles.pdf\">weltweite Studie<\/a> durch.<a href=\"#_ftn3\" id=\"_ftnref3\">[3]<\/a> Befragt wurden mehr als 150&#8217;000 Personen in 148 L\u00e4ndern. Insgesamt kamen vier Fragen zum Einsatz, wobei drei mit den von uns gestellten Fragen identisch sind. Als \u00abfinancially literate\u00bb gilt gem\u00e4ss der Studie, wer drei von vier Fragen korrekt beantworten kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abbildung 2 zeigt den Protzsatz der Personen, welche drei der vier Fragen korrekt beantwortet hatten. Die Finanzkenntnisse sind vor allem in \u00f6konomisch stark entwickelten L\u00e4ndern hoch. Die h\u00f6chsten Werte erreichen Personen in D\u00e4nemark, Norwegen und Schweden (71% der Personen beantworten drei von vier Fragen korrekt; gleicher Wert f\u00fcr alle drei L\u00e4nder), gefolgt von Kanada (68%), Israel (68%), Grossbritannien (67%), Deutschland und den Niederlanden (beide 66%). In dieser Untersuchung schloss die Schweiz mit 57% ab.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abbildung-2-literacy.png\"><img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"335\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abbildung-2-literacy.png\" alt=\"\" class=\"wp-image-17832\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abbildung-2-literacy.png 605w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abbildung-2-literacy-300x166.png 300w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/><\/a><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Abbildung 2: Finanzwissen in der Welt (Prozentsatz der Personen, welche mindestens drei von vier Wissensfragen korrekt beantwortet haben; Quelle: S&amp;P Global FinLit Survey, 2014)<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Fazit<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ein gutes Finanzwissen in der Bev\u00f6lkerung ist wichtig, damit Personen informierte Entscheidungen zu ihren eigenen Finanzen treffen k\u00f6nnen. In der Schweiz gibt es im Bereich Finanzwissen noch ein grosses Potenzial. Vergleicht man die Schweizer Werte zum Finanzwissen mit internationalen Vergleichs-Studien, so f\u00e4llt die Schweiz im internationalen Vergleich zwar nicht ab, bewegt sich aber im &#8211; aus unserer Sicht unbefriedigenden &#8211; Mittelfeld. Noch immer werden Finanzen hierzulande in den Schulen zu wenig thematisiert, obwohl es viele akademische Studien gibt, welche die vielen Vorteile einer besseren finanziellen Allgemeinbildung herausstreichen. Gerade junge Menschen sollten bessere Finanzkenntnisse haben als dies derzeit der Fall ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Was die internationalen Vergleichswerte h\u00e4ufig nicht zeigen, sind die zum Teil grossen Abweichungen von den Durchschnitten innerhalb der entsprechenden L\u00e4nder. In der Schweiz gibt es beim Finanzwissen zum Beispiel grosse Unterschiede in Bezug auf Alter, das Geschlecht, die Bildung oder die Verm\u00f6genssituation. Auch zeigen Untersuchungen von uns, dass das Finanzwissen ein wichtiger Faktor darstellt, ob Personen anlegen oder nicht. M\u00f6chten Finanzdienstleister mehr Personen \u00fcberzeugen, in Finanzm\u00e4rkte zu investieren, so ist das Thema Aufkl\u00e4rung zu Finanzthemen und somit die Erh\u00f6hung der Financial Literacy ein zentraler Ansatzpunkt.<\/p>\n\n\n\n\n\n<p class=\"wp-block-paragraph\"><em>M\u00f6chten Sie mehr Wissen? Hier finden Sie <a href=\"https:\/\/www.postfinance.ch\/de\/ueber-uns\/medien\/newsroom\/medienmitteilungen\/postfinance-anlegen-report.html\" target=\"_blank\" rel=\"noreferrer noopener\">mehr Infos zur Studie<\/a>.<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"581\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box-1024x581.png\" alt=\"\" class=\"wp-image-17834\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box-1024x581.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box-300x170.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box-768x436.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box-928x527.png 928w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/literacy-box.png 1075w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref1\" id=\"_ftn1\">[1]<\/a> Brown, M. and Graf, R.: \u201cFinancial Literacy and Retirement Planning in Switzerland\u201d. In: Numeracy 6, Iss. 2: Article 6. St. Gallen, 2013<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref2\" id=\"_ftn2\">[2]<\/a> Lusardi, A., &amp; Mitchell, O. (2011). Financial literacy around the world: An overview. Journal of Pension Economics and Finance, 10(4), 497-508.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"#_ftnref3\" id=\"_ftn3\">[3]<\/a> Klapper, L., Lusardi, A. &amp; van Oudheusden, P. (2014). Financial Literacy Around the World.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Financial Literacy, oder finanzielle Bildung, hat eine wichtige Bedeutung in der Gesellschaft. Verschiedene Studien zeigen, dass ein Mangel an Finanzwissen den langfristigen finanziellen Erfolg von Privatpersonen stark beeintr\u00e4chtigen k\u00f6nnen. Verschiedene Forschungsergebnisse zeigen auch auf, dass finanzielles Analphabetentum auch in westlichen L\u00e4ndern weit verbreitet ist. Wie sieht die Situation in der Schweiz aus? Welche Personen haben gute, welche Menschen haben schlechtere Finanzkenntnisse? Und gibt es einen Zusammenhang zwischen den Finanzkenntnissen und dem Anlegen? Der heutige Blog gibt Antworten auf diese Fragen basierend auf einer im Auftrag von PostFinance durchgef\u00fchrten Umfrage bei mehr als 3\u2019100 Schweizer:innen.<\/p>\n","protected":false},"author":165,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"1118,1238,14976,3595,4970,14781","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[647343,1041443,650927],"tags":[],"class_list":["post-17830","post","type-post","status-publish","format-standard","hentry","category-bankberatung","category-digitales-anlegen","category-esg"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog\" \/>\n<meta property=\"og:description\" content=\"Financial Literacy, oder finanzielle Bildung, hat eine wichtige Bedeutung in der Gesellschaft. Verschiedene Studien zeigen, dass ein Mangel an Finanzwissen den langfristigen finanziellen Erfolg von Privatpersonen stark beeintr\u00e4chtigen k\u00f6nnen. Verschiedene Forschungsergebnisse zeigen auch auf, dass finanzielles Analphabetentum auch in westlichen L\u00e4ndern weit verbreitet ist. Wie sieht die Situation in der Schweiz aus? Welche Personen haben gute, welche Menschen haben schlechtere Finanzkenntnisse? Und gibt es einen Zusammenhang zwischen den Finanzkenntnissen und dem Anlegen? Der heutige Blog gibt Antworten auf diese Fragen basierend auf einer im Auftrag von PostFinance durchgef\u00fchrten Umfrage bei mehr als 3\u2019100 Schweizer:innen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/\" \/>\n<meta property=\"og:site_name\" content=\"IFZ Retail Banking Blog\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-16T07:17:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:52:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png\" \/>\n<meta name=\"author\" content=\"andreasdietrich\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"andreasdietrich\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/\"},\"author\":{\"name\":\"andreasdietrich\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/f3ca41731be775323fc03571e19d68a4\"},\"headline\":\"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist\",\"datePublished\":\"2023-01-16T07:17:15+00:00\",\"dateModified\":\"2026-02-11T13:52:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/\"},\"wordCount\":1070,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/11\\\/Abb-1-literacy-1024x744.png\",\"articleSection\":[\"Bankberatung\",\"Digitales Anlegen\",\"ESG\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/\",\"name\":\"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/11\\\/Abb-1-literacy-1024x744.png\",\"datePublished\":\"2023-01-16T07:17:15+00:00\",\"dateModified\":\"2026-02-11T13:52:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/f3ca41731be775323fc03571e19d68a4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/11\\\/Abb-1-literacy.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2022\\\/11\\\/Abb-1-literacy.png\",\"width\":1044,\"height\":759},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\",\"name\":\"IFZ Retail Banking Blog\",\"description\":\"News und Trends aus dem Retail Banking Markt Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#\\\/schema\\\/person\\\/f3ca41731be775323fc03571e19d68a4\",\"name\":\"andreasdietrich\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g\",\"caption\":\"andreasdietrich\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/","og_locale":"de_DE","og_type":"article","og_title":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog","og_description":"Financial Literacy, oder finanzielle Bildung, hat eine wichtige Bedeutung in der Gesellschaft. Verschiedene Studien zeigen, dass ein Mangel an Finanzwissen den langfristigen finanziellen Erfolg von Privatpersonen stark beeintr\u00e4chtigen k\u00f6nnen. Verschiedene Forschungsergebnisse zeigen auch auf, dass finanzielles Analphabetentum auch in westlichen L\u00e4ndern weit verbreitet ist. Wie sieht die Situation in der Schweiz aus? Welche Personen haben gute, welche Menschen haben schlechtere Finanzkenntnisse? Und gibt es einen Zusammenhang zwischen den Finanzkenntnissen und dem Anlegen? Der heutige Blog gibt Antworten auf diese Fragen basierend auf einer im Auftrag von PostFinance durchgef\u00fchrten Umfrage bei mehr als 3\u2019100 Schweizer:innen.","og_url":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/","og_site_name":"IFZ Retail Banking Blog","article_published_time":"2023-01-16T07:17:15+00:00","article_modified_time":"2026-02-11T13:52:59+00:00","og_image":[{"url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png","type":"","width":"","height":""}],"author":"andreasdietrich","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"andreasdietrich","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/"},"author":{"name":"andreasdietrich","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/f3ca41731be775323fc03571e19d68a4"},"headline":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist","datePublished":"2023-01-16T07:17:15+00:00","dateModified":"2026-02-11T13:52:59+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/"},"wordCount":1070,"commentCount":2,"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png","articleSection":["Bankberatung","Digitales Anlegen","ESG"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/","url":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/","name":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist - IFZ Retail Banking Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy-1024x744.png","datePublished":"2023-01-16T07:17:15+00:00","dateModified":"2026-02-11T13:52:59+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/f3ca41731be775323fc03571e19d68a4"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#primaryimage","url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy.png","contentUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2022\/11\/Abb-1-literacy.png","width":1044,"height":759},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/retailbanking\/warum-das-finanzwissen-von-privatpersonen-fuer-banken-relevant-ist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hub.hslu.ch\/retailbanking\/"},{"@type":"ListItem","position":2,"name":"Warum das Finanzwissen von Privatpersonen f\u00fcr Banken relevant ist"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website","url":"https:\/\/hub.hslu.ch\/retailbanking\/","name":"IFZ Retail Banking Blog","description":"News und Trends aus dem Retail Banking Markt Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/retailbanking\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#\/schema\/person\/f3ca41731be775323fc03571e19d68a4","name":"andreasdietrich","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f643c7df11a0d664cc942a8e40e75c6de1d1b8898206fa2c11b192da2f27b408?s=96&d=mm&r=g","caption":"andreasdietrich"}}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"andreasdietrich","author_link":"https:\/\/hub.hslu.ch\/retailbanking\/author\/andreasdietrich\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17830","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/users\/165"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/comments?post=17830"}],"version-history":[{"count":8,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17830\/revisions"}],"predecessor-version":[{"id":21768,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/17830\/revisions\/21768"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/media?parent=17830"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/categories?post=17830"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/tags?post=17830"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}