{"id":3444,"date":"2016-01-11T08:36:23","date_gmt":"2016-01-11T07:36:23","guid":{"rendered":"https:\/\/hub.hslu.ch\/retailbanking\/?p=3444"},"modified":"2022-08-17T16:15:24","modified_gmt":"2022-08-17T14:15:24","slug":"online-kmu-kredit-die-ubs-als-vorreiter","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/","title":{"rendered":"Online KMU-Kredit: Die UBS als Vorreiter"},"content":{"rendered":"\n<p>Im Rahmen der <a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2015\/11\/20\/ifz-retail-banking-studie-2015\/\" target=\"_blank\" rel=\"noreferrer noopener\">Retail Banking-Studie 2015<\/a> wurden die Gesch\u00e4ftsleitungsmitglieder von Schweizer Banken befragt, wie sie verschiedene strategische Optionen im Hinblick auf ihre zuk\u00fcnftige Relevanz beurteilen. Dabei wurde unter anderem auch gefragt, welche Bedeutung Online KMU-Kredite in Zukunft haben werden. Wie die Abbildung 1 aufzeigt, haben die 202 Teilnehmenden diesen Bereich wie folgt eingesch\u00e4tzt:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II.png\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"93\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png\" alt=\"\" class=\"wp-image-3449\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png 1024w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-300x27.png 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-768x70.png 768w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II.png 1452w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption><em>Abbildung 1: Strategische Relevanz von Online KMU-Krediten<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Insgesamt sind vier Prozent der Bankenvertreter der Meinung, dass das Thema Online KMU-Kredite f\u00fcr sie zuk\u00fcnftig eine sehr hohe Relevanz hat. 17 Prozent messen diesem Themengebiet eine hohe Relevanz zu, w\u00e4hrend 36 Prozent der befragten Bank-Vertreter der Meinung sind, dass dieses Thema in Zukunft nur eine mittelhohe Relevanz haben wird. 43 Prozent sehen im Bereich der Online KMU-Kredite nur eine tiefe oder gar keine Relevanz. Zusammengefasst kann man also \u2013 aus meiner Sicht etwas \u00fcberraschend \u2013 festhalten, dass dieses Thema derzeit bei den Banken noch wenig im Fokus steht. Dies im Gegensatz zum Thema Online-Hypothek, welche aus Bankensicht eine sehr grosse Bedeutung erlangen wird.<br>Eine Bank, die dem Online KMU-Kredit ein grosses Potenzial beimisst, ist die UBS. Deshalb m\u00f6chte ich nachfolgend den Ansatz der Bank und die bisherige Entwicklung aufzeigen.<\/p>\n\n\n\n<p><strong>Der UBS-Ansatz<\/strong><\/p>\n\n\n\n<p>Mit dem Angebot eines Online-Kredites f\u00fcr KMU verfolgt die UBS insbesondere die Ziele, sich einerseits besser bei den Schweizer KMU zu positionieren (\u201eKMU Bank\u201c) und andererseits die \u201eClient Convenience\u201c zu erh\u00f6hen, indem man auf einfache Art und Weise schnell (d.h. in 10-15 Minuten) einen Kreditantrag online einreichen kann. Die Online-Kredite fokussieren sich insbesondere auf den eher kleinvolumigen Blanko-Kreditbereich (zwischen CHF 20\u2018000 und 300\u2018000) und dem (derzeit noch eher unbedeutenden) Firmenleasing. Blankokredite sind online einfacher zu vollziehen, da der Einbezug von Sicherheiten teuer und nur schwierig standardisierbar ist und somit die Abwicklungs-Geschwindigkeit darunter leidet.<\/p>\n\n\n\n<p>Kreditantr\u00e4ge k\u00f6nnen online entweder \u00fcber ubs.com (Abbildung 2) oder \u00fcber das E-Banking (Abbildung 3) eingegeben werden. Die \u201eUser journey\u201c ist identisch und die Daten fliessen in die gleichen Kreditsysteme. Der Kunde geniesst aber Vorteile, wenn der Antrag auf dem E-Banking ausgef\u00fcllt wird: Beispielsweise kann der Antrag f\u00fcr sp\u00e4tere Bearbeitung gespeichert werden, einige Kreditnehmer-Angaben sind schon bekannt, und man erh\u00e4lt auf dem E-Banking gleich online ein indikatives Finanzierungsangebot.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/Online-KMU-UBS.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"752\" height=\"659\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/Online-KMU-UBS.jpg\" alt=\"\" class=\"wp-image-3450\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/Online-KMU-UBS.jpg 752w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/Online-KMU-UBS-300x263.jpg 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/Online-KMU-UBS-110x96.jpg 110w\" sizes=\"auto, (max-width: 752px) 100vw, 752px\" \/><\/a><figcaption><em>Abbildung 2: Printscreen KMU Online-Kredit und -Leasing, Webpage UBS<\/em><\/figcaption><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><a href=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/UBS-KMU-Online-Kreditantrag.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"630\" height=\"519\" src=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/UBS-KMU-Online-Kreditantrag.jpg\" alt=\"\" class=\"wp-image-3452\" srcset=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/UBS-KMU-Online-Kreditantrag.jpg 630w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/UBS-KMU-Online-Kreditantrag-300x247.jpg 300w, https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/UBS-KMU-Online-Kreditantrag-168x137.jpg 168w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><figcaption><em>Abbildung 3: Printscreens KMU Online Kredit &#8211; Antrag \u00fcber eBanking<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n<p>Der Antrag bei diesen eher kleinvolumigen Krediten ist einfacher gehalten als bei Krediten mit einem hohen Volumen. Der Kunde muss hierf\u00fcr einige Angaben machen und seine Jahresabschl\u00fcsse online hochladen. Teilweise werden danach \u2013 auch abh\u00e4ngig davon, ob ein (potenzieller) Kunde den Antrag \u00fcber das eBanking oder die Webpage einreicht \u2013 durch Mitarbeitende des Service-Centers noch manuelle Plausibilit\u00e4ts-Checks durchgef\u00fchrt. Ansonsten wird die Kreditf\u00e4higkeitspr\u00fcfung vollkommen automatisiert durchgef\u00fchrt. Zur Kreditf\u00e4higkeitseinsch\u00e4tzung werden aus den verschiedenen Angaben insgesamt sechs Finanzzahlen berechnet. Aus Sicht UBS ist es wichtig, dass das Risiko durch diese Online-Kredite im Portfolio nicht erh\u00f6ht wird. Nicht zuletzt daher nimmt man die Kredit<em>w\u00fcrdigkeits<\/em>pr\u00fcfung am Schluss noch immer pers\u00f6nlich vor. Die UBS m\u00f6chte den Kunden also pers\u00f6nlich sehen, um zu entscheiden, ob ein Kunde nicht nur kreditf\u00e4hig, sondern auch <em>kreditw\u00fcrdig<\/em> ist.<br>Der Prozess ist grunds\u00e4tzlich identisch, ob man als KMU in die Filiale geht oder den Antrag online einreicht. Ebenso ist das Pricing genau gleich. Kunden, welche aus Sicht der UBS den kosteng\u00fcnstigeren Weg \u00fcber den Online-Kreditantrag w\u00e4hlen, werden hierf\u00fcr also Pricing-technisch nicht \u201ebelohnt\u201c.<br>Das Ziel der Bank ist es insbesondere, ihre Prozesse zu optimieren, dadurch die Effizienz zu erh\u00f6hen und die Client Convenience zu verbessern. Entsprechend hat die UBS sehr viel Zeit und Geld investiert, dass der ganze Antrag vollst\u00e4ndig im System integriert ist.<\/p>\n\n\n\n<p><strong>Bisherige Erfahrungen<\/strong><\/p>\n\n\n\n<p>Gem\u00e4ss Aussage von Gerald Leb, Head Business Management der Corporate und Institutional Clients Division, sei der Start bisher \u201egut\u201c gewesen. Durch das neue Angebot sei das Volumen gestiegen. Ein Drittel der Kunden sind Neukunden, welche f\u00fcr dieses Angebot sogar die Hauptbankbeziehung wechseln (Voraussetzung f\u00fcr den Abschluss eines solchen Kredites ist es, dass die UBS die Hauptbank ist, \u00fcber welche auch der Zahlungsverkehr abgewickelt wird). Die anderen zwei Drittel Kunden, welche online einen Kredit beantragt haben, waren zwar schon zuvor UBS-Kunden mit Hauptbankbeziehung, hatten aber noch keinen KMU-Kredit bei der Bank. Aus einer Channel-Sicht betr\u00e4gt der Anteil der externen\/Self-Service Kan\u00e4le (UBS.com, e-banking) ca. 55%; die restlichen 45% kommen via Client Advisor (der dann die Eingabe bzw. die Beantragung \u00fcbernimmt). Die durchschnittlich beantragten Kreditvolumina betragen ca. CHF 100&#8217;000.<\/p>\n\n\n\n<p><strong>Fazit und Einsch\u00e4tzung<\/strong><\/p>\n\n\n\n<p>In der Schweiz ist die UBS meines Wissens die erste Bank, welche ein solches Angebot im Markt lancierte. Im Ausland gibt es hier aber schon verschiedene bedeutende Unternehmen, wie zum Beispiel die Rabobank, welche sogar Online-Kredite f\u00fcr KMU bis zu einer Million EUR vergibt. Grunds\u00e4tzlich bewegt sich die UBS derzeit noch in einer Nische \u2013 einer Nische allerdings, die aus Bankensicht wichtig ist und in den n\u00e4chsten Jahren stark wachsen k\u00f6nnte. Derzeit fokussiert sich die UBS noch auf einfache, kleine KMU. Es ist aber nicht auszuschliessen, dass man sp\u00e4ter auch einmal den Schritt hin zu eher mittelgrossen Kunden macht. Solche Antr\u00e4ge w\u00e4ren dann aber nochmals deutlich komplexer, was entsprechend einen Einfluss auf die Standardisierung der Prozesse hat. Auch aus einer UBS-Gesamtbankperspektive ist dieses Digitalisierungs-Projekt nur ein Element der gesamten Digitalisierungsstrategie f\u00fcr KMU. Weitere Projekte sind beispielsweise die Zusammenarbeiten mit bexio (<a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2015\/06\/16\/digitalisierung-nun-auch-im-firmenkundengeschaeft-die-plaene-der-ubs\/\" target=\"_blank\" rel=\"noreferrer noopener\">fr\u00fcher easySYS, siehe Blog<\/a>) oder mit SumUp (<a href=\"https:\/\/hub.hslu.ch\/retailbanking\/2014\/10\/27\/mobiles-bezahlen-fuer-kmu-ein-zwischenfazit-der-ubs-fuer-sumup-und-das-neue-angebot-der-sixgroup-mcashier\/\" target=\"_blank\" rel=\"noreferrer noopener\">auch dar\u00fcber habe ich schon berichtet<\/a>). Insgesamt beurteile ich diesen Schritt sehr positiv \u2013 es ist aus Skalengr\u00fcnden nachvollziehbar, dass man nach den beiden Segmenten Retail Banking und Private Banking nun auch das Firmenkundengesch\u00e4ft verst\u00e4rkt digitalisiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Thema Online KMU-Kredit hat derzeit f\u00fcr die meisten Banken keine allzu grosse Bedeutung. Seit Mai 2015 bietet aber die UBS ein solches Angebot an. Ich m\u00f6chte nachfolgend die Grund\u00fcberlegungen vorstellen und kurz aufzeigen, wie der Start verlaufen ist.<\/p>\n","protected":false},"author":1270,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"20937,21075,21006,21010,20963,20980","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[252],"tags":[],"class_list":["post-3444","post","type-post","status-publish","format-standard","hentry","category-allgemein"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog\" \/>\n<meta property=\"og:description\" content=\"Das Thema Online KMU-Kredit hat derzeit f\u00fcr die meisten Banken keine allzu grosse Bedeutung. Seit Mai 2015 bietet aber die UBS ein solches Angebot an. Ich m\u00f6chte nachfolgend die Grund\u00fcberlegungen vorstellen und kurz aufzeigen, wie der Start verlaufen ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/\" \/>\n<meta property=\"og:site_name\" content=\"IFZ Retail Banking Blog\" \/>\n<meta property=\"article:published_time\" content=\"2016-01-11T07:36:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T14:15:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Online KMU-Kredit: Die UBS als Vorreiter\",\"datePublished\":\"2016-01-11T07:36:23+00:00\",\"dateModified\":\"2022-08-17T14:15:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/\"},\"wordCount\":942,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/12\\\/online-kmu-kredit-II-1024x93.png\",\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/\",\"name\":\"Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/12\\\/online-kmu-kredit-II-1024x93.png\",\"datePublished\":\"2016-01-11T07:36:23+00:00\",\"dateModified\":\"2022-08-17T14:15:24+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/12\\\/online-kmu-kredit-II.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2015\\\/12\\\/online-kmu-kredit-II.png\",\"width\":1452,\"height\":132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/online-kmu-kredit-die-ubs-als-vorreiter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online KMU-Kredit: Die UBS als Vorreiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/\",\"name\":\"IFZ Retail Banking Blog\",\"description\":\"News und Trends aus dem Retail Banking Markt Schweiz\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/retailbanking\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/","og_locale":"de_DE","og_type":"article","og_title":"Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog","og_description":"Das Thema Online KMU-Kredit hat derzeit f\u00fcr die meisten Banken keine allzu grosse Bedeutung. Seit Mai 2015 bietet aber die UBS ein solches Angebot an. Ich m\u00f6chte nachfolgend die Grund\u00fcberlegungen vorstellen und kurz aufzeigen, wie der Start verlaufen ist.","og_url":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/","og_site_name":"IFZ Retail Banking Blog","article_published_time":"2016-01-11T07:36:23+00:00","article_modified_time":"2022-08-17T14:15:24+00:00","og_image":[{"url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/"},"author":{"name":"","@id":""},"headline":"Online KMU-Kredit: Die UBS als Vorreiter","datePublished":"2016-01-11T07:36:23+00:00","dateModified":"2022-08-17T14:15:24+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/"},"wordCount":942,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png","inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/","url":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/","name":"Online KMU-Kredit: Die UBS als Vorreiter - IFZ Retail Banking Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II-1024x93.png","datePublished":"2016-01-11T07:36:23+00:00","dateModified":"2022-08-17T14:15:24+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#primaryimage","url":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II.png","contentUrl":"https:\/\/hub.hslu.ch\/retailbanking\/wp-content\/uploads\/sites\/7\/2015\/12\/online-kmu-kredit-II.png","width":1452,"height":132},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/retailbanking\/online-kmu-kredit-die-ubs-als-vorreiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/hub.hslu.ch\/retailbanking\/"},{"@type":"ListItem","position":2,"name":"Online KMU-Kredit: Die UBS als Vorreiter"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/retailbanking\/#website","url":"https:\/\/hub.hslu.ch\/retailbanking\/","name":"IFZ Retail Banking Blog","description":"News und Trends aus dem Retail Banking Markt Schweiz","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/retailbanking\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":""}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"","author_link":"https:\/\/hub.hslu.ch\/retailbanking\/author\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/3444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/users\/1270"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/comments?post=3444"}],"version-history":[{"count":7,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/3444\/revisions"}],"predecessor-version":[{"id":16676,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/posts\/3444\/revisions\/16676"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/media?parent=3444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/categories?post=3444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/retailbanking\/wp-json\/wp\/v2\/tags?post=3444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}