{"id":1537,"date":"2021-02-12T17:25:41","date_gmt":"2021-02-12T16:25:41","guid":{"rendered":"https:\/\/hslu-soziale-arbeit.test\/?p=1537"},"modified":"2026-02-11T14:53:58","modified_gmt":"2026-02-11T13:53:58","slug":"kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/","title":{"rendered":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken?"},"content":{"rendered":"\n<p> Einen Beitrag leistet auch&nbsp;<a href=\"https:\/\/blog.hslu.ch\/soziokultur\/2021\/02\/03\/gleichstellung-von-menschen-mit-beeintraechtigungen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Islam Alijaj mit seinem Interview<\/a>&nbsp;\u00fcber die Gleichstellung von Menschen mit Beeintr\u00e4chtigung. Eins vorneweg: Es ist ein sehr eindr\u00fcckliches Interview. Islam Alijaj, der aufgrund angeborener Beeintr\u00e4chtigungen aus eigenen Erfahrungen erz\u00e4hlt, fordert eine nachhaltige Behindertenpolitik. Er ist der Ansicht, dass \u00abauf zivilgesellschaftlicher sowie parteipolitischer Seite ein fundamentaler Strukturwandel stattfinden muss, damit der Traum von Gleichstellung wahr werden kann\u00bb.&nbsp;<a href=\"https:\/\/islamalijaj.ch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Islam Alijaj<\/a>&nbsp;ist eine beeindruckende Pers\u00f6nlichkeit, mit einer guten Portion Optimismus und Realismus. Im Interview spricht er zentrale Punkte der Sozialen Arbeit an. Wer dieses Interview geh\u00f6rt hat, wird geneigt sein, sich der Meinung anzuschliessen, dass es grunds\u00e4tzlich ein Umdenken in der Sozialen Arbeit ben\u00f6tigt. Es braucht mehr Partizipation und Empowerment in der individuellen Aus\u00fcbung des Berufes, wie aber auch in den Strukturen der Institutionen selbst. Die Soziale Arbeit sollte vermehrt die betroffenen Menschen miteinbeziehen. Es ist fundamental, dass ihre Anliegen von Anfang an mit einbezogen werden, da so die Soziale Arbeit viel effektiver wirken kann. Islam Alijaj bem\u00e4ngelt, dass in der Sozialen Arbeit aktuell eine systematische Bevormundung stattfindet. Die Kritik, dass die Betroffenen selber zu wenig miteinbezogen und unterst\u00fctzt werden, ist mehr als bloss bedenkenswert. Aber wo liegt die Grenze zwischen Bevormundung und F\u00fcrsorge? Ist das eine pers\u00f6nliche Ansichtssache oder ein institutionelles Paradigma der Sozialen Arbeit? Es ist mitunter ein schmaler Grad, auf dem jeder einzelne von uns Sozialarbeitenden geht mit dem eigenen Rucksack an Erfahrungen, Werten und Visionen.<\/p>\n\n\n\n<p>Die Schweiz braucht mehr engagierte Menschen wie Islam Alijaj, damit die Diskriminierung von Menschen mit Beeintr\u00e4chtigung aufh\u00f6rt und die Gleichstellung nicht mehr nur ein Traum ist, sondern Tatsache wird.<\/p>\n\n\n\n<hr class=\"wp-block-separator\" \/>\n\n\n\n<p>Dieser Artikel wurde am 12. Februar 2021 von Nicole Berlinger verfasst und auf dem Soziokulturblog ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abSoziale Bewegungen \u2013 welchen Auftrag hat die Soziale Arbeit?\u00bb das Thema der diesj\u00e4hrigen internationalen Studienwoche (1. bis 5. Februar 2021) war breit gef\u00e4chert.<\/p>\n","protected":false},"author":111,"featured_media":2336,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[96,214,132],"class_list":["post-1537","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soziokultur","tag-bachelor-in-sozialer-arbeit","tag-internationale-studienwoche","tag-soziale-arbeit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"\u00abSoziale Bewegungen \u2013 welchen Auftrag hat die Soziale Arbeit?\u00bb das Thema der diesj\u00e4hrigen internationalen Studienwoche (1. bis 5. Februar 2021) war breit gef\u00e4chert.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-12T16:25:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:53:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webkinder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"webkinder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/\"},\"author\":{\"name\":\"webkinder\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"headline\":\"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken?\",\"datePublished\":\"2021-02-12T16:25:41+00:00\",\"dateModified\":\"2026-02-11T13:53:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/\"},\"wordCount\":306,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/02\\\/Islam_Alijaj_702x336.jpg\",\"keywords\":[\"Bachelor in Sozialer Arbeit\",\"Internationale Studienwoche\",\"Soziale Arbeit\"],\"articleSection\":[\"Soziokultur\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/\",\"name\":\"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/02\\\/Islam_Alijaj_702x336.jpg\",\"datePublished\":\"2021-02-12T16:25:41+00:00\",\"dateModified\":\"2026-02-11T13:53:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/02\\\/Islam_Alijaj_702x336.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2021\\\/02\\\/Islam_Alijaj_702x336.jpg\",\"width\":702,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\",\"name\":\"Soziale Arbeit an der Hochschule Luzern\",\"description\":\"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\",\"name\":\"webkinder\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/","og_locale":"de_DE","og_type":"article","og_title":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern","og_description":"\u00abSoziale Bewegungen \u2013 welchen Auftrag hat die Soziale Arbeit?\u00bb das Thema der diesj\u00e4hrigen internationalen Studienwoche (1. bis 5. Februar 2021) war breit gef\u00e4chert.","og_url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/","og_site_name":"Soziale Arbeit an der Hochschule Luzern","article_published_time":"2021-02-12T16:25:41+00:00","article_modified_time":"2026-02-11T13:53:58+00:00","og_image":[{"width":702,"height":335,"url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","type":"image\/jpeg"}],"author":"webkinder","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"webkinder","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/"},"author":{"name":"webkinder","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"headline":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken?","datePublished":"2021-02-12T16:25:41+00:00","dateModified":"2026-02-11T13:53:58+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/"},"wordCount":306,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","keywords":["Bachelor in Sozialer Arbeit","Internationale Studienwoche","Soziale Arbeit"],"articleSection":["Soziokultur"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/","name":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken? &#8211; Soziale Arbeit an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","datePublished":"2021-02-12T16:25:41+00:00","dateModified":"2026-02-11T13:53:58+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#primaryimage","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","contentUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","width":702,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/kritische-gedanken-zur-sozialen-arbeit-von-islam-alijaj-braucht-es-ein-umdenken\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/soziale-arbeit\/"},{"@type":"ListItem","position":2,"name":"Kritische Gedanken zur Sozialen Arbeit von Islam Alijaj \u2013 Braucht es ein Umdenken?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/","name":"Soziale Arbeit an der Hochschule Luzern","description":"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542","name":"webkinder"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2021\/02\/Islam_Alijaj_702x336.jpg","author_info":{"display_name":"webkinder","author_link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/author\/webkinder\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/comments?post=1537"}],"version-history":[{"count":3,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1537\/revisions"}],"predecessor-version":[{"id":12814,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1537\/revisions\/12814"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media\/2336"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media?parent=1537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/categories?post=1537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags?post=1537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}