{"id":1939,"date":"2022-03-07T11:38:18","date_gmt":"2022-03-07T10:38:18","guid":{"rendered":"https:\/\/hslu-soziale-arbeit.test\/?p=1885"},"modified":"2026-01-21T15:42:58","modified_gmt":"2026-01-21T14:42:58","slug":"denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/","title":{"rendered":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien"},"content":{"rendered":"\n<p>\u00abRealutopien\u00bb zeichnen eine sch\u00f6ne zuk\u00fcnftige Welt in unserer Vorstellung, allerdings sollten Realutopien innerhalb einiger Jahre durch entsprechende Rahmenbedingungen im Gegensatz zu Utopien auch erreicht werden. Wenn wir uns vorstellen k\u00f6nnen, wie eine zuk\u00fcnftige Welt aussehen soll, dann k\u00f6nnen wir auch konkret darauf hinarbeiten.<\/p>\n\n\n\n<p>Nebst vielen Spielsequenzen im Modul wurden im Prozess der filmischen Erarbeitung konsequent interaktive Methoden verwendet, d.h. Vor- und Nachbereitung wurden als Teil der filmischen Betrachtung verstanden und die einzelnen Elemente in einem intensiven gemeinsamen Prozess sp\u00e4ter zusammengeschnitten.<\/p>\n\n\n\n<p>Im Film werden vier Projekte vorgestellt: Dock 8, Hof Narr, Madnesst und das realutopische Potential von Zwischennutzungen.<\/p>\n\n\n\n<p>Hier eine Kurzbeschreibung der Projekte:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Dock 8<\/strong><\/h3>\n\n\n\n<p>Auf dem Areal der ehemaligen Kehrichtverbrennungsanlage in Bern realisieren sechs gemeinn\u00fctzige Bautr\u00e4ger die nachhaltige Siedlung Holliger mit verschiedenen Wohnnutzungen sowie Fl\u00e4chen f\u00fcr Gewerbe- und Quartiernutzung. Im Zentrum der Siedlung steht der Holligerhof 8, hier wird das DOCK8&nbsp;im Februar 2022 er\u00f6ffnet. Ein Raum dient als Gastronomie-Betrieb mit etwa 60-80 Pl\u00e4tzen und enth\u00e4lt den Loungebereich f\u00fcr soziokulturelle Nutzung. Durch mobile Elemente wird dieser Raum maximal flexibel gestaltet und kann sowohl gesamthaft mit B\u00fchne f\u00fcr Veranstaltungen als auch abgetrennt als Lounge genutzt werden<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Hof Narr<\/strong><\/h3>\n\n\n\n<p>Gem\u00e4ss dem T\u00e4tigkeitsbericht der Hofn\u00e4rr*innen ist das Sch\u00f6nste an ihrem Wirken nicht die Zahlen, sondern die vielen positiven Feedbacks und dass sich immer mehr B\u00e4uerinnen und Bauern melden, weil sie auch neue landwirtschaftliche Wege ohne Tiernutzung gehen wollen. Hof Narr organisiert Hofunterricht f\u00fcr Schulklassen, spannende Hof\u00adf\u00fchrungen f\u00fcr Gross und Klein, kulinarrische Feste, Konzerte, Vortr\u00e4ge, Filme und viele weitere Anl\u00e4sse, meist verbunden mit leckerem bio-veganem Essen. Die Hofn\u00e4rr*innen k\u00f6nnen \u00fcber 170 Tierpers\u00f6nlichkeiten auf drei H\u00f6fen einen Lebensplatz bieten und jede Woche helfen, neue Lebenspl\u00e4tze f\u00fcr weitere Tiere zu finden.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Madnesst<\/strong><\/h3>\n\n\n\n<p>MADNESST ist ein Netzwerk von Mental-Health-Aktivist*innen. Es realisiert Formate, welche zur Enttabuisierung und Entstigmatisierung psychischer Krisenerfahrungen beitragen soll. Madnesst geht individuell und im Kollektiv mit seinen Geschichten an eine breite \u00d6ffentlichkeit. Erkenntnisse und kreative Zeugnisse der bedeutungsvollen Lebenserfahrung von Betroffenen werden verwendet, um einer Diskriminierung von Betroffenen entgegenzuwirken. MADNESST, das \u00abverr\u00fcckte Nest\u00bb, steht f\u00fcr einen&nbsp;Safe Space, in welchem sich ein neuer Aktivismus entdecken, entfalten und manifestieren kann.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Zwischennutzungen<\/strong><\/h3>\n\n\n\n<p>Die St\u00e4rke der Zwischennutzung liegt in ihrem symbiotischen&nbsp;Charakter f\u00fcr Nutzer, Eigent\u00fcmer und Stadtentwickler. Zwischennutzungen stellen f\u00fcr die Zwischennutzer als Akteure eine Strategie zur Verwirklichung ihrer Ideen dar, w\u00e4hrend sie f\u00fcr den Eigent\u00fcmer eine M\u00f6glichkeit zur befristeten Beseitigung von Leerstand&nbsp;und Vermeidung von Sch\u00e4den durch Vandalismus bedeuten kann. Durch die Anwesenheit eines Nutzers werden einerseits die R\u00e4ume im Sinne des Eigent\u00fcmers teilweise bewirtschaftet sowie eine Beaufsichtigung&nbsp;der baulichen Anlagen erreicht, um sie vor Zerst\u00f6rung zu sch\u00fctzen. Der Begriff der&nbsp;Zwischennutzung&nbsp;bezeichnet eine zeitlich befristete Nutzung baulicher Anlagen, die eine h\u00e4ufig nicht rein \u00f6konomisch&nbsp;orientierte \u00dcbergangsnutzung f\u00fcr zurzeit nicht genutzte R\u00e4ume oder Fl\u00e4chen zu nicht markt\u00fcblichen Konditionen darstellt.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p>Wir laden Sie\/Euch ein, in unsere filmische Besch\u00e4ftigung mit diesen vier realutopischen Projekten einzutauchen.<\/p>\n\n\n\n<p>17. M\u00e4rz 2022, 19.00 Uhr, Kleintheater Luzern, <a href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/06\/FLYER-DENKEN-WIR-DIE-WELT-WIE-SIE-UNS-GEFAeLLT.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">FLYER<\/a><\/p>\n\n\n\n<p>Anmeldung unter <a href=\"http:\/\/www.kleintheater.ch\">www.kleintheater.ch<\/a><\/p>\n\n\n\n<p>Viel Spass!<\/p>\n\n\n\n<p>Heinz Gubler und Reto St\u00e4heli<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p>Dieser Artikel wurde am 7. M\u00e4rz 2022 auf dem Soziokulturblog ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Rahmen des Moduls \u00abKreativwerkstatt\u00bb (Modul 320) an der Hochschule Luzern \u2013 Soziale Arbeit haben sich Studierende aus den Studienrichtungen Sozialarbeit, Sozialp\u00e4dagogik und Soziokulturelle Animation mit dem Thema \u00abSpiel und Realutopien\u00bb filmisch auseinandergesetzt.<\/p>\n","protected":false},"author":111,"featured_media":2231,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"12135,12076,12063,11979,12011,11879","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[96,132],"class_list":["post-1939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soziokultur","tag-bachelor-in-sozialer-arbeit","tag-soziale-arbeit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Im Rahmen des Moduls \u00abKreativwerkstatt\u00bb (Modul 320) an der Hochschule Luzern \u2013 Soziale Arbeit haben sich Studierende aus den Studienrichtungen Sozialarbeit, Sozialp\u00e4dagogik und Soziokulturelle Animation mit dem Thema \u00abSpiel und Realutopien\u00bb filmisch auseinandergesetzt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-07T10:38:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-21T14:42:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"webkinder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"webkinder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/\"},\"author\":{\"name\":\"webkinder\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"headline\":\"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien\",\"datePublished\":\"2022-03-07T10:38:18+00:00\",\"dateModified\":\"2026-01-21T14:42:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/\"},\"wordCount\":570,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/03\\\/Soziokultur_Blog_702x336.gif\",\"keywords\":[\"Bachelor in Sozialer Arbeit\",\"Soziale Arbeit\"],\"articleSection\":[\"Soziokultur\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/\",\"name\":\"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/03\\\/Soziokultur_Blog_702x336.gif\",\"datePublished\":\"2022-03-07T10:38:18+00:00\",\"dateModified\":\"2026-01-21T14:42:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/03\\\/Soziokultur_Blog_702x336.gif\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/03\\\/Soziokultur_Blog_702x336.gif\",\"width\":702,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\",\"name\":\"Soziale Arbeit an der Hochschule Luzern\",\"description\":\"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\",\"name\":\"webkinder\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern","og_description":"Im Rahmen des Moduls \u00abKreativwerkstatt\u00bb (Modul 320) an der Hochschule Luzern \u2013 Soziale Arbeit haben sich Studierende aus den Studienrichtungen Sozialarbeit, Sozialp\u00e4dagogik und Soziokulturelle Animation mit dem Thema \u00abSpiel und Realutopien\u00bb filmisch auseinandergesetzt.","og_url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/","og_site_name":"Soziale Arbeit an der Hochschule Luzern","article_published_time":"2022-03-07T10:38:18+00:00","article_modified_time":"2026-01-21T14:42:58+00:00","og_image":[{"width":702,"height":336,"url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","type":"image\/gif"}],"author":"webkinder","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"webkinder","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/"},"author":{"name":"webkinder","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"headline":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien","datePublished":"2022-03-07T10:38:18+00:00","dateModified":"2026-01-21T14:42:58+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/"},"wordCount":570,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","keywords":["Bachelor in Sozialer Arbeit","Soziale Arbeit"],"articleSection":["Soziokultur"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/","name":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien &#8211; Soziale Arbeit an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","datePublished":"2022-03-07T10:38:18+00:00","dateModified":"2026-01-21T14:42:58+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#primaryimage","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","contentUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","width":702,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/denken-wir-die-welt-wie-sie-uns-gefaellt-spiel-und-realutopien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/soziale-arbeit\/"},{"@type":"ListItem","position":2,"name":"\u00abDenken wir die Welt, wie sie uns gef\u00e4llt\u00bb Spiel und Realutopien"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/","name":"Soziale Arbeit an der Hochschule Luzern","description":"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542","name":"webkinder"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","featured_image_src_square":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/03\/Soziokultur_Blog_702x336.gif","author_info":{"display_name":"webkinder","author_link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/author\/webkinder\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/comments?post=1939"}],"version-history":[{"count":10,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1939\/revisions"}],"predecessor-version":[{"id":12513,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1939\/revisions\/12513"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media\/2231"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media?parent=1939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/categories?post=1939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags?post=1939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}