{"id":1988,"date":"2022-05-25T17:44:00","date_gmt":"2022-05-25T17:44:00","guid":{"rendered":"https:\/\/hslu-soziale-arbeit.test\/?p=1988"},"modified":"2026-03-23T15:58:14","modified_gmt":"2026-03-23T14:58:14","slug":"das-subkutane-grauen-des-zweiten-weltkrieges","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/","title":{"rendered":"Das subkutane Grauen des Zweiten Weltkrieges"},"content":{"rendered":"\n<p>Als erwachsene Frau hat Barbara Bonhage, Dozentin an der Hochschule Luzern, Briefe ihrer Grossmutter v\u00e4terlicherseits gefunden. In der Schweiz aufgewachsen, hat Barbara Bonhage lebhafte Erinnerungen an ihren Grossvater und die Frau, welche er nach dem Tod der Briefeschreiberin geheiratet hatte. Bonhages Grossmutter ist schon 1945 an Tuberkulose verstorben. Bonhage erinnert sich an weitere Familienmitglieder und das Haus der Grosseltern in Deutschland, wo sie in den Schulferien regelm\u00e4ssig zu Besuch war. Die Gespr\u00e4che drehten sich um Schulerfolge und Ausbildungen, Gartenpflege und Kochrezepte. Nie ging es um den Krieg. Nie kam zur Sprache, was Barbara Bonhage in den Briefen ihrer Grossmutter, die mehrheitlich an deren Schwester und die gemeinsame Mutter gerichtet waren, las: dass die Grossmutter eine gl\u00fchende Nationalsozialistin der ersten Stunde war. Ebenso ihr Ehemann, der Grossvater aus Barbara Bonhages Kindheit, der nach dem Krieg schnell wieder Fuss gefasst hatte in der Mitte der Gesellschaft.<\/p>\n\n\n\n<p>Das \u00abgnadenlose Irren\u00bb wie Barbara Bonhage es bezeichnet, hat viel mit der Suche nach einem modernen, erf\u00fcllten Leben als Frau zu tun. Es ist diese Perspektive als Frau in einer Atmosph\u00e4re des Aufschwungs, der Modernisierung, die das Buch \u00abGnadenlos geirrt. Das Leben meiner Grossmutter 1907-1945\u00bb aus meiner Sicht besonders lesenswert macht. Das Grauen ist subkutan omnipr\u00e4sent, obwohl an der Oberfl\u00e4che kaum ein Wort von Krieg und Vernichtung handelt. Einzig der Grossvater spottet ausdr\u00fccklich \u00fcber die \u00abN\u00f6nnchen\u00bb, welche als Pflegerinnen von Kriegsverletzten den Hitler-Gruss verweigern. Und die Epilepsie eines ihrer S\u00f6hne versteckt die Grossmutter vor den Beh\u00f6rden \u2013 zu einer Hinterfragung des Systems der Elimination von \u00abminderwertigem Leben\u00bb f\u00fchrt die Krankheit des eigenen Kindes in keiner Weise.<\/p>\n\n\n\n<p>Wie in Viola Roggenkamps Roman \u00ab<a href=\"https:\/\/www.perlentaucher.de\/buch\/viola-roggenkamp\/familienleben.html\" target=\"_blank\" rel=\"noreferrer noopener\">Familienleben<\/a>\u00bb sind es die kleinen Details, welche den Irrsinn und die Gewalt des Nationalsozialismus hervortreten lassen. Der rote Nagellack, den sich die j\u00fcdische Mutter in Roggenkamps Familienroman mit Aceton entfernt, um ja den Buchpr\u00fcfer nicht zu provozieren und das Bild einer uneitlen deutschen Frau abzugeben. Begeistert kolportierte Vorschl\u00e4ge, das Weihnachtsfest von seinem christlich-konservativen Touch zu entschlacken und moderne Alternativen vorzuschlagen, die sich mehr an germanischen Traditionen wie dem Feiern der Wintersonnenwende orientieren bei Bonhage. Der gleichsam nachsichtige Spott \u00fcber Nachbarinnen und Nachbarn, welche keine Hakenkreuzfahne ans Fenster h\u00e4ngen m\u00f6gen. Dann die Indifferenz gegen\u00fcber der Zerst\u00f6rung des lokalen j\u00fcdischen Miederwarengesch\u00e4fts \u2013 die W\u00e4sche liegt nach der Reichskristallnacht verstreut auf der Strasse. Als n\u00e4chstes ein verwackeltes Bild eines grossen Hauses im Osten, davor eine Frauenfigur mit Baby. Es ist das Haus im Osten, welches Bonhages Grossmutter mit ihrer Familie annektiert, das Schicksalder urspr\u00fcnglichen Bewohnerin<em> auf dem Foto <\/em>ist unbekannt. Nicht ein Wort dar\u00fcber, dass dieses Haus von einer Familie erbaut und bewohnt wurde, die eine Familie war wie die ihre. Nur die Befriedigung, dank den eigenen Verdiensten im Krieg nun standesgem\u00e4ss residieren zu k\u00f6nnen.<\/p>\n\n\n\n<p>Es ist bekannt, dass viele physisch \u00dcberlebende des Holocaust keine Worte f\u00fcr das Erlebte fanden, oft bis zu ihrem Tod nicht. \u00ab<a href=\"https:\/\/literaturkritik.de\/public\/rezension.php?rez_id=20286&amp;ausgabe=201502\" target=\"_blank\" rel=\"noreferrer noopener\">Nach Auschwitz ein Gedicht zu schreiben, ist barbarisch<\/a>\u00bb schrieb <a href=\"https:\/\/de.wikipedia.org\/wiki\/Theodor_W._Adorno\" target=\"_blank\" rel=\"noreferrer noopener\">Theodor W. Adorno<\/a> in seinem Aufsatz \u00abKulturkritik und Gesellschaft\u00bb, der im Jahr 1949 geschrieben und 1951 erstmals ver\u00f6ffentlicht wurde. Schweigen kann auch eine Erz\u00e4hlung sein. Dass auch auf der anderen Seite geschwiegen wurde, aber aus anderen Gr\u00fcnden, das wird durch B\u00fccher wie jenem von Barbara Bonhage erst langsam klar. Dieses Schweigen hat viel zu lange gedauert. Mit ihrem Buch hat Barbara Bonhage das Totschweigen gebrochen. Es ist h\u00f6chste Zeit daf\u00fcr. In diesen Jahren sterben die letzten Zeitzeug:innen des Holocaust, aber auch jene, die den Nationalsozialismus gelebt und getragen haben als aktive Nationalsozialist:innen. Barbara Bonhage legt Zeugnis ab \u00fcber ihr Erbe, tr\u00e4gt es weiter. Es geht nicht um Erkl\u00e4ren, nicht um Verstehen, schon gar nicht um Rechtfertigung oder Entschuldigung. Es geht darum, diese Stimmen zu h\u00f6ren, die gefehlt haben nach dem Krieg, in der Kindheit und Jugend von Barbara Bonhage und allen anderen ihrer Generation. Es geht um das Zeugnis, das Bekenntnis aller Nachgekommenen: nie mehr Antisemitismus. Niemals mehr gnadenlos irren. Gesichert ist dies in keiner Weise.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p>Und hier noch eine aktuelle Auseinandersetzung mit der politischen Situation. Ein Beitrag von Gabi Hangartner, ehemalige Dozentin am Institut f\u00fcr Soziokulturelle Entwicklung.<\/p>\n\n\n\n<p><strong>Kunst in der Werkstatt <\/strong>vom 20. bis 22. Mai 2022<\/p>\n\n\n\n<p>Die Ausstellung findet jedes Jahr in den R\u00e4umen der Schreinerei L\u00fctzelschwab an der <strong>Hauptstrasse 1 in M\u00f6hlin<\/strong> statt.<\/p>\n\n\n\n<p>Mehr Info im <a href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/06\/Flyer-Ausstellung-Moehlin-2022.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Flyer.<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Karte-24.2.2022-768x461-1.jpg\" alt=\"\" class=\"wp-image-2181\" srcset=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Karte-24.2.2022-768x461-1.jpg 768w, https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Karte-24.2.2022-768x461-1-300x180.jpg 300w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><figcaption class=\"wp-element-caption\"><em>Das Plakat \u00abNie wieder Krieg\u00bb (1924) von K\u00e4the Kollwitz und ihre k\u00fcnstlerische Auseinandersetzung mit Kriegen waren f\u00fcr mich Trost und Inspiration.<\/em><br><em>So versuchte ich, durch das Zeichnen mit den Menschen im Krieg in der Ukraine mitzuf\u00fchlen und still ihr Leid wahrzunehmen. Ich fand einen Weg, die \u00e4ussere und innere Bilderflut w\u00e4hrend der Arbeit \u00abanzuhalten\u00bb und einen Raum zu schaffen.&nbsp;<\/em><a href=\"https:\/\/vimeo.com\/705868112\" target=\"_blank\" rel=\"noreferrer noopener\">Video<\/a><\/figcaption><\/figure>\n<\/div>\n\n\n<hr class=\"wp-block-separator has-css-opacity\" \/>\n\n\n\n<p>Dieser Artikel wurde am 19. Mai 2022 von Simone&nbsp;Gretler&nbsp;Heusser verfasst und auf dem Soziokulturblog ver\u00f6ffentlicht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Feinde zu konstruieren, geh\u00f6rt zur Gesellschaft wie das Schmieden von Allianzen. Wenn \u00abdie Anderen\u00bb vernichtet werden sollen, herrscht Krieg. Jeder Krieg ist grausam. Dies alles m\u00fcssen wir angesichts des Angriffs auf die Ukraine aktuell wieder erfahren. Eine erschreckende Parallele zur Herrschaft des Nationalsozialismus stellt dabei die von Russland betriebene \u00abEntmenschlichung des Gegners\u00bb dar. Der Zweite Weltkrieg steht bis heute als Schrecken ohne Vergleich in der Geschichte der Menschheit. Im Holocaust verfolgte und vernichtete das nationalsozialistische Regime die j\u00fcdische Bev\u00f6lkerung, systematisch und kalt. Dazu geh\u00f6ren die Vernichtungslager, die Deportationen, die Berufsverbote: das Entfernen eines Teils der Gesellschaft aus der eigenen Mitte.<\/p>\n","protected":false},"author":111,"featured_media":2186,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"8885,8856,8667,8766,8730,8738","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[20],"tags":[],"class_list":["post-1988","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-soziokultur"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Feinde zu konstruieren, geh\u00f6rt zur Gesellschaft wie das Schmieden von Allianzen. Wenn \u00abdie Anderen\u00bb vernichtet werden sollen, herrscht Krieg. Jeder Krieg ist grausam. Dies alles m\u00fcssen wir angesichts des Angriffs auf die Ukraine aktuell wieder erfahren. Eine erschreckende Parallele zur Herrschaft des Nationalsozialismus stellt dabei die von Russland betriebene \u00abEntmenschlichung des Gegners\u00bb dar. Der Zweite Weltkrieg steht bis heute als Schrecken ohne Vergleich in der Geschichte der Menschheit. Im Holocaust verfolgte und vernichtete das nationalsozialistische Regime die j\u00fcdische Bev\u00f6lkerung, systematisch und kalt. Dazu geh\u00f6ren die Vernichtungslager, die Deportationen, die Berufsverbote: das Entfernen eines Teils der Gesellschaft aus der eigenen Mitte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T17:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T14:58:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"702\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"webkinder\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"webkinder\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/\"},\"author\":{\"name\":\"webkinder\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"headline\":\"Das subkutane Grauen des Zweiten Weltkrieges\",\"datePublished\":\"2022-05-25T17:44:00+00:00\",\"dateModified\":\"2026-03-23T14:58:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/\"},\"wordCount\":821,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/05\\\/Gnadenlos_geirrt_702x336-1.gif\",\"articleSection\":[\"Soziokultur\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/\",\"name\":\"Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/05\\\/Gnadenlos_geirrt_702x336-1.gif\",\"datePublished\":\"2022-05-25T17:44:00+00:00\",\"dateModified\":\"2026-03-23T14:58:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/05\\\/Gnadenlos_geirrt_702x336-1.gif\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2022\\\/05\\\/Gnadenlos_geirrt_702x336-1.gif\",\"width\":702,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-subkutane-grauen-des-zweiten-weltkrieges\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das subkutane Grauen des Zweiten Weltkrieges\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\",\"name\":\"Soziale Arbeit an der Hochschule Luzern\",\"description\":\"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/2fbc41f8eff3a89d0755cce0ed9a2542\",\"name\":\"webkinder\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/","og_locale":"de_DE","og_type":"article","og_title":"Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern","og_description":"Feinde zu konstruieren, geh\u00f6rt zur Gesellschaft wie das Schmieden von Allianzen. Wenn \u00abdie Anderen\u00bb vernichtet werden sollen, herrscht Krieg. Jeder Krieg ist grausam. Dies alles m\u00fcssen wir angesichts des Angriffs auf die Ukraine aktuell wieder erfahren. Eine erschreckende Parallele zur Herrschaft des Nationalsozialismus stellt dabei die von Russland betriebene \u00abEntmenschlichung des Gegners\u00bb dar. Der Zweite Weltkrieg steht bis heute als Schrecken ohne Vergleich in der Geschichte der Menschheit. Im Holocaust verfolgte und vernichtete das nationalsozialistische Regime die j\u00fcdische Bev\u00f6lkerung, systematisch und kalt. Dazu geh\u00f6ren die Vernichtungslager, die Deportationen, die Berufsverbote: das Entfernen eines Teils der Gesellschaft aus der eigenen Mitte.","og_url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/","og_site_name":"Soziale Arbeit an der Hochschule Luzern","article_published_time":"2022-05-25T17:44:00+00:00","article_modified_time":"2026-03-23T14:58:14+00:00","og_image":[{"width":702,"height":336,"url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","type":"image\/gif"}],"author":"webkinder","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"webkinder","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/"},"author":{"name":"webkinder","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"headline":"Das subkutane Grauen des Zweiten Weltkrieges","datePublished":"2022-05-25T17:44:00+00:00","dateModified":"2026-03-23T14:58:14+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/"},"wordCount":821,"commentCount":5,"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","articleSection":["Soziokultur"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/","name":"Das subkutane Grauen des Zweiten Weltkrieges &#8211; Soziale Arbeit an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","datePublished":"2022-05-25T17:44:00+00:00","dateModified":"2026-03-23T14:58:14+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#primaryimage","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","contentUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","width":702,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-subkutane-grauen-des-zweiten-weltkrieges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/soziale-arbeit\/"},{"@type":"ListItem","position":2,"name":"Das subkutane Grauen des Zweiten Weltkrieges"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/","name":"Soziale Arbeit an der Hochschule Luzern","description":"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/2fbc41f8eff3a89d0755cce0ed9a2542","name":"webkinder"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","featured_image_src_square":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2022\/05\/Gnadenlos_geirrt_702x336-1.gif","author_info":{"display_name":"webkinder","author_link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/author\/webkinder\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1988","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/users\/111"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/comments?post=1988"}],"version-history":[{"count":13,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1988\/revisions"}],"predecessor-version":[{"id":13356,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/1988\/revisions\/13356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media\/2186"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media?parent=1988"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/categories?post=1988"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags?post=1988"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}