{"id":7640,"date":"2023-10-23T14:09:57","date_gmt":"2023-10-23T12:09:57","guid":{"rendered":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?p=7640"},"modified":"2026-02-11T14:54:07","modified_gmt":"2026-02-11T13:54:07","slug":"das-programm-ist-eine-echte-horizonterweiterung","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/","title":{"rendered":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb"},"content":{"rendered":"\n\n\n<p><strong>1. Warum hast du dich f\u00fcr das CAS Gemeinde- und Stadtentwicklung entschieden?<\/strong><\/p>\n\n\n\n<p>Ich finde besonders den interdisziplin\u00e4ren Aspekt spannend. In dem CAS kommen Fachleute aus ganz unterschiedlichen Bereichen und Berufen zusammen. Mit dabei waren Vertreterinnen der sozialen Arbeit, \u00d6konomen, Politikwissenschaftlerinnen, Architekten, Raumplanerinnen und weitere Fachpersonen. Sie alle bringen ganz andere Herangehensweisen und Ansichten mit. Dar\u00fcber hinaus werden in dem CAS auch \u00fcbergeordnete Themen wie die Entwicklungen im Wohnbereich, die Klimaver\u00e4nderung oder der demographische Wandel thematisiert. Dies erm\u00f6glichte es mir, meinen Wissens- und Erfahrungsrucksack weiter zu f\u00fcllen.<\/p>\n\n\n\n<p><strong>2. Du arbeitest als Projektleiter Stadtplanung in der Stadt Zug: Was sind aktuell die grossen Herausforderungen und Entwicklungen in diesem Bereich?<\/strong><\/p>\n\n\n\n<p>Zug ist sehr dynamisch: Es wird fleissig gebaut, investiert und saniert. Zudem ist die Stadt recht klein und engmaschig, man kennt sich und ist gut vernetzt. Der Austausch mit der Bev\u00f6lkerung ist deshalb sehr wichtig. In meinem Berufsalltag habe ich auch viel mit Grundeigent\u00fcmerinnen und Investoren zu tun. Der Umgang mit den verschiedenen Akteuren ist zwar herausfordernd, aber auch spannend.<\/p>\n\n\n\n<p><strong>3. Inwiefern kommt dir das Wissen aus dem CAS-Programm in deinem Berufsalltag zugute?<\/strong><\/p>\n\n\n\n<p>Der CAS ist sehr breit ausgerichtet und enth\u00e4lt diverse Themen, die mir bei meiner Arbeit definitiv zugutekommen. So behandelten wir unter anderem auch Themen rund um die Gestaltung von partizipativen Prozessen. Diese spielen in meinem Job eine relevante Rolle. Ein Beispiel: Wenn ein kommunaler Richtplan angepasst wird, sind immer viele verschiedene Akteure involviert. Diese muss man miteinbeziehen, ihnen ein positives Gef\u00fchl vermitteln und kompromissf\u00e4hige L\u00f6sungen finden k\u00f6nnen.<\/p>\n\n\n\n<p><strong>4. Wie gelang es dir, deinen beruflichen Alltag und die anspruchsvolle Weiterbildung unter einen Hut zu bringen?<\/strong><\/p>\n\n\n\n<p>Es ist zwar streng, aber durchaus machbar. Bei mir teilt es sich in etwa so auf: 80 Prozent Arbeit, 20 Prozent Studium. Die 20 Prozent sind dabei alleine f\u00fcr den Unterricht vorgesehen. Weitere Studienleistungen kommen in der Freizeit hinzu. Den Ausgleich finde ich im Morgensport. Abends entspanne ich in der Gesellschaft meiner Freundin oder Freunden oder bei einem Eishockeyspiel der Rapperswil-Jona Lakers.<\/p>\n\n\n\n<p><strong>5. Wem w\u00fcrdest du die Teilnahme an diesem CAS empfehlen?<\/strong><\/p>\n\n\n\n<p>Ich w\u00fcrde es definitiv allen Raumplanerinnen und Raumplanern empfehlen. Aber auch allen anderen Berufsgruppen, die auf irgendeine Art und Weise mit unserer gebauten Umgebung sowie den Menschen, die darin Leben, zu tun haben. Auf pers\u00f6nlicher Ebene war dieses CAS eine echte Horizonterweiterung. Das Netzwerk, das man sich im Verlaufe einer solchen Weiterbildung aufbauen kann, ist aus meiner Sicht einer der gr\u00f6ssten Mehrwerte. Man tauscht sich aus, gibt sich gegenseitig Tipps \u2013&nbsp;und es ist gut m\u00f6glich, dass man sich auch im sp\u00e4teren Berufsleben wieder einmal trifft.<\/p>\n\n\n\n<p>Von:&nbsp;<a href=\"https:\/\/www.schriber-kommunikation.ch\/agentur\/\">Ismail Osman<\/a><br>Ver\u00f6ffentlicht: 23. Oktober 2023<\/p>\n\n\n\n<div style=\"background-color:#f2f2f2;color:#32373c\" class=\"wp-block-genesis-blocks-gb-profile-box square gb-has-avatar gb-font-size-18 gb-block-profile gb-profile-columns\"><div class=\"gb-profile-column gb-profile-avatar-wrap\"><div class=\"gb-profile-image-wrap\"><figure class=\"gb-profile-image-square\"><img loading=\"lazy\" decoding=\"async\" width=\"174\" height=\"183\" class=\"gb-profile-avatar wp-image-7648\" src=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel.jpg\" alt=\"Silas Trachsel\" \/><\/figure><\/div><\/div><div class=\"gb-profile-column gb-profile-content-wrap\"><h2 class=\"gb-profile-name\" style=\"color:#32373c\">Silas Trachsel<\/h2><p class=\"gb-profile-title\" style=\"color:#32373c\">Silas Trachsel (30) hat an der Ostschweizer Fachhochschule Rapperswil-Jona ein Bachelor-Studium Stadt-, Verkehrs- und Raumplanung (SVR) absolviert. Heute ist er im Baudepartement der Stadt Zug als Projektleiter Stadtplanung t\u00e4tig. Aktuell besch\u00e4ftigt er sich beruflich mit der Ortsplanungsrevision und verschiedenen Arealentwicklungen innerhalb der Stadt Zug. Dabei hat er bemerkt, dass er sich im Bereich methodischen Kompetenzen weiterentwickeln m\u00f6chte. Er entschied in der Folge, sich f\u00fcr den Masterstudiengang Gemeinde-, Stadt- und Regionalentwicklung anzumelden. Im Rahmen dieses Studienganges hat er auch das CAS Gemeinde- und Stadtentwicklung im Wandel absolviert.<\/p><div class=\"gb-profile-text\"><\/div><ul class=\"gb-social-links\"><\/ul><\/div><\/div>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/soziale-arbeit\/weiterbildung\/studienprogramm\/cas\/gemeinde-und-stadtentwicklung-im-wandel\/?gclid=CjwKCAjwvfmoBhAwEiwAG2tqzLbmUCuBAuG6UH_LzypmgCmXMYzGftzBBPPW_BO7yRhQW20WPX6SrhoCtr0QAvD_BwE&amp;gclsrc=aw.ds\">Jetzt anmelden: CAS- Gemeinde- und Stadtentwicklung im Wandel<\/a><\/strong><\/p>\n<p>Das CAS-Programm Gemeinde- und Stadtentwicklung im Wandel legt den Fokus auf die kommunalen Handlungsebenen. Themen wie Innenentwicklung, Verdichtung oder Umnutzung, werden ebenso aufgegriffen, wie der Umgang mit Diversity. Erlernt werden zudem die Grundlagen und Methoden von partizipativen und kooperativen Prozessen in der Stadt-, Quartier- und Gemeindeentwicklung.<\/p>\n<p><strong>Anmeldung:<\/strong>\u00a0<a href=\"https:\/\/www.hslu.ch\/de-ch\/soziale-arbeit\/weiterbildung\/studienprogramm\/cas\/gemeinde-und-stadtentwicklung-im-wandel\/?gclid=CjwKCAjwvfmoBhAwEiwAG2tqzLbmUCuBAuG6UH_LzypmgCmXMYzGftzBBPPW_BO7yRhQW20WPX6SrhoCtr0QAvD_BwE&amp;gclsrc=aw.ds\">Hier anmelden<\/a><\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Raumplaner Silas Trachsel will neue Facetten seines Berufs erkunden. Im CAS Gemeinde- und Stadtentwicklung im Wandel fand er spannende Aspekte, die ihn im Berufsalltag zunehmend besch\u00e4ftigen. Zudem konnte er sich ein wertvolles Netzwerk aufbauen.\u00a0<\/p>\n","protected":false},"author":152,"featured_media":7649,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"562,1918,3793,1253,466,1312","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[14,8],"tags":[251,250,30,68],"class_list":["post-7640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gemeinde-stadt-regionalentwicklung","category-weiterbildung","tag-5-fragen-an","tag-cas","tag-gemeinde-stadt-regionalentwicklung","tag-raumplanung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Raumplaner Silas Trachsel will neue Facetten seines Berufs erkunden. Im CAS Gemeinde- und Stadtentwicklung im Wandel fand er spannende Aspekte, die ihn im Berufsalltag zunehmend besch\u00e4ftigen. Zudem konnte er sich ein wertvolles Netzwerk aufbauen.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-23T12:09:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:54:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1614\" \/>\n\t<meta property=\"og:image:height\" content=\"1007\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Roger Ettlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Roger Ettlin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/\"},\"author\":{\"name\":\"Roger Ettlin\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/0d13e861725ae87916921d6d018489e4\"},\"headline\":\"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb\",\"datePublished\":\"2023-10-23T12:09:57+00:00\",\"dateModified\":\"2026-02-11T13:54:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/\"},\"wordCount\":538,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/10\\\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg\",\"keywords\":[\"5 Fragen an\",\"CAS\",\"Gemeinde- Stadt- Regionalentwicklung\",\"Raumplanung\"],\"articleSection\":[\"Gemeinde-, Stadt- und Regionalentwicklung\",\"Weiterbildung\"],\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/\",\"name\":\"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/10\\\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg\",\"datePublished\":\"2023-10-23T12:09:57+00:00\",\"dateModified\":\"2026-02-11T13:54:07+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/0d13e861725ae87916921d6d018489e4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/10\\\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/wp-content\\\/uploads\\\/sites\\\/23\\\/2023\\\/10\\\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg\",\"width\":1614,\"height\":1007},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/das-programm-ist-eine-echte-horizonterweiterung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\",\"name\":\"Soziale Arbeit an der Hochschule Luzern\",\"description\":\"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#\\\/schema\\\/person\\\/0d13e861725ae87916921d6d018489e4\",\"name\":\"Roger Ettlin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/","og_locale":"de_DE","og_type":"article","og_title":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern","og_description":"Raumplaner Silas Trachsel will neue Facetten seines Berufs erkunden. Im CAS Gemeinde- und Stadtentwicklung im Wandel fand er spannende Aspekte, die ihn im Berufsalltag zunehmend besch\u00e4ftigen. Zudem konnte er sich ein wertvolles Netzwerk aufbauen.\u00a0","og_url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/","og_site_name":"Soziale Arbeit an der Hochschule Luzern","article_published_time":"2023-10-23T12:09:57+00:00","article_modified_time":"2026-02-11T13:54:07+00:00","og_image":[{"width":1614,"height":1007,"url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","type":"image\/jpeg"}],"author":"Roger Ettlin","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"Roger Ettlin","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/"},"author":{"name":"Roger Ettlin","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/0d13e861725ae87916921d6d018489e4"},"headline":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb","datePublished":"2023-10-23T12:09:57+00:00","dateModified":"2026-02-11T13:54:07+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/"},"wordCount":538,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","keywords":["5 Fragen an","CAS","Gemeinde- Stadt- Regionalentwicklung","Raumplanung"],"articleSection":["Gemeinde-, Stadt- und Regionalentwicklung","Weiterbildung"],"inLanguage":"de-CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/","name":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb &#8211; Soziale Arbeit an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","datePublished":"2023-10-23T12:09:57+00:00","dateModified":"2026-02-11T13:54:07+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/0d13e861725ae87916921d6d018489e4"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#primaryimage","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","contentUrl":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","width":1614,"height":1007},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/das-programm-ist-eine-echte-horizonterweiterung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/soziale-arbeit\/"},{"@type":"ListItem","position":2,"name":"\u00abDas Programm ist eine echte Horizonterweiterung\u00bb"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/","name":"Soziale Arbeit an der Hochschule Luzern","description":"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#\/schema\/person\/0d13e861725ae87916921d6d018489e4","name":"Roger Ettlin"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-content\/uploads\/sites\/23\/2023\/10\/Silas-Trachsel-an-der-HSLU-Soziale-Arbeit.jpg","author_info":{"display_name":"Roger Ettlin","author_link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/author\/rogerettlin\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/7640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/users\/152"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/comments?post=7640"}],"version-history":[{"count":28,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/7640\/revisions"}],"predecessor-version":[{"id":13011,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts\/7640\/revisions\/13011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media\/7649"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/media?parent=7640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/categories?post=7640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags?post=7640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}