{"id":115,"count":13,"description":"","link":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/","name":"Wohnen","slug":"wohnen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Soziale Arbeit an der Hochschule Luzern\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/tag\\\/wohnen\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/tag\\\/wohnen\\\/\",\"name\":\"Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/tag\\\/wohnen\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/tag\\\/wohnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wohnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/\",\"name\":\"Soziale Arbeit an der Hochschule Luzern\",\"description\":\"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/soziale-arbeit\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/","og_locale":"de_DE","og_type":"article","og_title":"Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern","og_url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/","og_site_name":"Soziale Arbeit an der Hochschule Luzern","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/","name":"Wohnen Archives &#8211; Soziale Arbeit an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/#breadcrumb"},"inLanguage":"de-CH"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/tag\/wohnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/soziale-arbeit\/"},{"@type":"ListItem","position":2,"name":"Wohnen"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/soziale-arbeit\/#website","url":"https:\/\/hub.hslu.ch\/soziale-arbeit\/","name":"Soziale Arbeit an der Hochschule Luzern","description":"Der Blog der Hochschule Luzern \u2013 Soziale Arbeit","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/soziale-arbeit\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags\/115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/soziale-arbeit\/wp-json\/wp\/v2\/posts?tags=115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}