{"id":1701,"date":"2024-01-03T18:14:37","date_gmt":"2024-01-03T17:14:37","guid":{"rendered":"https:\/\/hub.hslu.ch\/sustainable\/?p=1701"},"modified":"2026-02-11T14:54:13","modified_gmt":"2026-02-11T13:54:13","slug":"nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/","title":{"rendered":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren?"},"content":{"rendered":"\n<p><strong> <a href=\"#Wachstumsmotor-Fussnote\"><strong>[1]<\/strong><\/a><\/strong><\/p>\n\n\n\n<p><strong>Autoren: <\/strong><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3275\">Manfred St\u00fcttgen<\/a>, <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=3548\">Brian Mattmann<\/a><\/p>\n\n\n\n<p class=\"has-text-align-left\">In unserem <a href=\"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-als-publikumsmagnet-bei-der-allokation-von-neugeld\/\">letzten Blog-Beitrag<\/a> haben wir gezeigt, dass nachhaltige Fonds \u2013 obschon mit einem Angebot von 2&#8217;155 Fonds insgesamt noch immer ein Nischenmarkt \u2013 den Neugeldzufluss in Schweizer Publikumsfonds beinahe vollst\u00e4ndig dominieren. Einzelne Produktsegmente innerhalb des nachhaltigen Fondsuniversums k\u00f6nnen besonders von diesem Wachstum profitieren, andere weniger. Wer sind bei nachhaltigen Fonds die Wachstumsmotoren und wo besteht aktuell noch Potenzial? Der vorliegende Artikel fokussiert sich auf die Wachstumslokomotive im Segment nachhaltiger Fonds: passive Nachhaltigkeitsfonds. In einem n\u00e4chsten Blog fokussieren wir dann auf das Fondssegment, welches weniger vom Wachstum profitieren konnte: thematische Nachhaltigkeitsfonds.<\/p>\n\n\n\n<p><strong>Passive Nachhaltigkeitsfonds: Ein Blick auf das Wachstumssegment<\/strong><\/p>\n\n\n\n<p>Fonds k\u00f6nnen von ihrem Manager grunds\u00e4tzlich aktiv oder passiv verwaltet werden. Bei einer aktiven Verwaltung beobachtet der Manager das Marktgeschehen und selektiert selbst\u00e4ndig \u00abdie besten\u00bb Unternehmen. Bei passiven Fonds entscheidet der Fondsverwalter nicht autonom, in welche Anlagen er investiert, sondern er repliziert m\u00f6glichst getreu einen Index. Passiv gemanagte Anlagen werden daher oft \u2013 und pr\u00e4ziser \u2013 auch als indexorientierte Anlagen bezeichnet.<br>In unseren Studien haben wir verschiedentlich aufgezeigt, dass passiv verwaltete Nachhaltigkeitsfonds seit mehreren Jahren ein erstaunliches Wachstumssegment innerhalb des nachhaltigen Fondssegments darstellen (Abbildung 1): Im Jahr 2020 betrug das verwaltete Verm\u00f6gen dieses Fondssegments erst CHF 50 Mrd. (linke Grafik). In den darauffolgenden Jahren hat sich das Angebot an passiven Nachhaltigkeitsfonds stark erweitert, das in diesen Fonds investierte Verm\u00f6gen ist kr\u00e4ftig angestiegen. Heute verwalten passive Nachhaltigkeitsfonds CHF 279 Mrd. an Kapital, das sind beachtliche CHF 229 Mrd. mehr als noch im Jahr 2020.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"437\" src=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image.png\" alt=\"\" class=\"wp-image-1703\" srcset=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image.png 945w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-300x139.png 300w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-768x355.png 768w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-928x429.png 928w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-600x277.png 600w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Abbildung 1<\/strong>: Die Entwicklung der Verm\u00f6gen nachhaltiger Passivfonds (jeweils per 30. Juni) <a href=\"#Wachstumsmotor-Fussnote\"><strong>[2]<\/strong><\/a><\/p>\n\n\n\n<p>Die unterschiedlichen Wachstumsraten im nachhaltigen Fondssegment zugunsten passiver Nachhaltigkeitsfonds \u00fcber die letzten zw\u00f6lf Monate wird in Abbildung 2 deutlich: Obwohl nur ein F\u00fcnftel der nachhaltigen Fonds passiv verwaltet wird (linker Balken), vereinen diese Produkte mehr als die H\u00e4lfte der gesamten Neugeldzufl\u00fcsse auf sich, die insgesamt in nachhaltige Fonds geflossen sind (rechter Balken). Konkret haben die 426 passiven Nachhaltigkeitsfonds \u2013 Indexfonds und passive ETFs \u2013 in der Zw\u00f6lfmonats-Periode von Mitte 2022 bis Mitte 2023 insgesamt CHF 42 Mrd. an Neugeld angezogen, also mehr als die H\u00e4lfte der Nettomittelzufl\u00fcsse aller nachhaltigen Publikumsfonds mit Schweizer Vertriebszulassung.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"406\" height=\"505\" src=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-1.png\" alt=\"\" class=\"wp-image-1704\" srcset=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-1.png 406w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-1-241x300.png 241w\" sizes=\"auto, (max-width: 406px) 100vw, 406px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Abbildung 2<\/strong>: Gesamtmarkt aller aktiv und passiv verwalteten Nachhaltigkeitsfonds per Mitte 2023 (links, in Anzahl Fonds) sowie Nettomittelzufl\u00fcsse in die beiden nachhaltigen Fondssegmente von Mitte 2022 bis Mitte 2023 (rechts, in Mrd. CHF) <a href=\"#Wachstumsmotor-Fussnote\"><strong>[3]<\/strong><\/a><\/p>\n\n\n\n<p>In Abbildung 3 wird zudem die Nettomittelzuflussrate verwendet, um das Wachstum der passiven Anlagen noch besser zu verstehen. Die Zuflussrate wird getrennt f\u00fcr das nachhaltige und das konventionelle Fondssegment ausgewiesen und zus\u00e4tzlich in aktiv (mittlere Balken) und passiv verwaltete Fonds (rechte Balken) aufgeschl\u00fcsselt. Hier wird ersichtlich, dass passiv verwaltete Nachhaltigkeitsfonds in der zw\u00f6lfmonatigen Beobachtungsperiode mit Nettomittelzuflussraten von 14.7 Prozent weiterhin \u00fcberdurchschnittlich stark gewachsen sind. Auch aktiv verwaltete Nachhaltigkeitsfonds erzielten mit einer 4.7-prozentigen Zuflussrate ein beachtliches Wachstum. Im Vergleich zu den Wachstumsraten der nachhaltigen Passivprodukte f\u00e4llt das Wachstum der aktiven Nachhaltigkeitsfonds allerdings deutlich geringer aus. Interessant ist f\u00fcr beide Segmente der Vergleich mit den Wachstumsraten im konventionellen Fondssegment: aktiv verwaltete konventionelle Fonds verzeichneten Nettomittelabfl\u00fcsse in Umfang von 0.7 Prozent, w\u00e4hrend passiv gemanagte konventionelle Fonds demgegen\u00fcber 2.4 Prozent Neugeld anziehen konnten.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"490\" src=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2.png\" alt=\"\" class=\"wp-image-1705\" srcset=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2.png 945w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2-300x156.png 300w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2-768x398.png 768w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2-928x481.png 928w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-2-600x311.png 600w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Abbildung 3<\/strong>: Die Nettomittelzuflussraten auf dem Schweizer Fondsmarkt separiert in das nachhaltige und konventionelle Fondssegment sowie unterteilt in aktiv und passiv verwaltete Fonds (Berechnung: total Nettomittelzufl\u00fcsse von Mitte 2022 bis Mitte 2023 bezogen auf die Verm\u00f6gensbasis der Fonds per Mitte 2023) <a href=\"#Wachstumsmotor-Fussnote\"><strong>[4]<\/strong><\/a><\/p>\n\n\n\n<p>Die Zahlen zeigen zweierlei: Erstens konnten im konventionellen Fondsuniversum nur die Passivfonds Neugeld generieren, konventionelle Aktivfonds hingegen verzeichneten kumuliert Nettomittelabfl\u00fcsse. Zweitens ziehen im Nachhaltigkeitssegment sowohl aktiv als auch passiv gemanagte Fonds Neugeld an, wobei nachhaltige Passivfonds weiterhin ein deutlich st\u00e4rkerer Wachstumstreiber sind. Dank dieses Wachstums befindet sich das Segment passiver Nachhaltigkeitsfonds an einer interessanten Wegscheide (Abbildung 4): Heute werden 25 Prozent der Verm\u00f6gen nachhaltiger Fonds passiv verwaltet. Dies entspricht genau dem Anteil, der auch im konventionellen Fondssegment passiv verwaltet wird.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"371\" src=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-3.png\" alt=\"\" class=\"wp-image-1706\" srcset=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-3.png 576w, https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/image-3-300x193.png 300w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/div>\n\n\n<p><strong>Abbildung 4<\/strong>: Der Anteil passiv verwalteter Verm\u00f6gen im nachhaltigen und konventionellen Fondssegment (in Mrd. CHF, per 30. Juni 2023) <a href=\"#Wachstumsmotor-Fussnote\"><strong>[5]<\/strong><\/a><\/p>\n\n\n\n<p>Diese Angleichung der Marktanteile von passiv verwalteten Verm\u00f6gen hat sich in den letzten Jahren abgezeichnet: So hatte das nachhaltige Passivsegment \u00fcberdurchschnittlich stark vom Wachstum nachhaltiger Anlagen profitiert, wodurch sich der Verm\u00f6gensanteil passiver Investments bei nachhaltigen Anlagen stetig erweitert hat (rechte Grafik in Abbildung 1). In den kommenden Jahren wird interessant sein zu beobachten sein, ob die hohen Wachstumsraten bei passiven Nachhaltigkeitsfonds weiter anhalten und ob ihr Anteil sogar gr\u00f6sser wird als jener im Segment der konventionellen Fonds. Sollte dieser Fall eintreten, k\u00f6nnte dies ein Indiz sein daf\u00fcr, dass sich die Vorteile von Passivprodukten bei nachhaltigen Investments besonders gut entfalten. <strong><a href=\"#Wachstumsmotor-Fussnote\"><strong>[6]<\/strong><\/a><\/strong><\/p>\n\n\n\n<p><strong>Fazit<\/strong><\/p>\n\n\n\n<p>Nachhaltige Fonds wachsen stark, insbesondere im Vergleich zum konventionellen Fondssegment. Von diesem Wachstum profitieren speziell passive Nachhaltigkeitsfonds, in welche Investoren einen \u00fcberproportionalen Teil des Neugelds allozieren. Ein differenzierteres Bild ergibt sich bei nachhaltigen Themenfonds, die wir in einem n\u00e4chsten Blogbeitrag in den Blick nehmen werden.<\/p>\n\n\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\" \/>\n\n\n\n<p id=\"Wachstumsmotor-Fussnote\">[1] Der Blog-Artikel st\u00fctzt sich auf die \u00abIFZ Sustainable Investments Studie 2023: Nachhaltige Fonds und soziale Verantwortung\u00bb, verf\u00fcgbar unter <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable<\/a>. Die Studie wurde dankend unterst\u00fctzt von: Goldman Sachs Asset Management, Robeco, Z\u00fcrcher Kantonalbank, DWS, Graub\u00fcndner Kantonalbank, Natixis Investment Managers, UBS, Vanguard, abrdn, AllianceBernstein, Amundi Asset Management, Candriam, Generali, INOKS Capital, iShares by BlackRock, Lombard Odier Investment Managers, Morningstar, OLZ, PGIM Investments, Schroders, Inrate, Thurgauer Kantonalbank und Investment Navigator.<\/p>\n\n\n\n<p>[2] Vgl. St\u00fcttgen\/Mattmann (2023). IFZ Sustainable Investments Studie 2023: Nachhaltige Fonds und soziale Verantwortung, S. 23. Zug: IFZ Eigenverlag. Verf\u00fcgbar unter: <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable\/<\/a><\/p>\n\n\n\n<p>[3] Vgl. St\u00fcttgen\/Mattmann (2023). IFZ Sustainable Investments Studie 2023: Nachhaltige Fonds und soziale Verantwortung, S. 24. Zug: IFZ Eigenverlag. Verf\u00fcgbar unter: <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable\/<\/a><\/p>\n\n\n\n<p>[4] Vgl. St\u00fcttgen\/Mattmann (2023). IFZ Sustainable Investments Studie 2023: Nachhaltige Fonds und soziale Verantwortung, S. 24. Zug: IFZ Eigenverlag. Verf\u00fcgbar unter: <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable\/<\/a><\/p>\n\n\n\n<p>[5] Vgl. St\u00fcttgen\/Mattmann (2023). IFZ Sustainable Investments Studie 2023: Nachhaltige Fonds und soziale Verantwortung, S. 22. Zug: IFZ Eigenverlag. Verf\u00fcgbar unter: <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable\/<\/a><\/p>\n\n\n\n<p>[6] Zu Gr\u00fcnden f\u00fcr das \u00fcberdurchschnittlich starke Wachstum passiver Nachhaltigkeitsfonds siehe St\u00fcttgen\/Mattmann (2021). IFZ Sustainable Investments Studie 2021: Nachhaltige Fonds und Klimarisiken, S. 35\u201336. Zug: IFZ Eigenverlag. Verf\u00fcgbar unter: <a href=\"https:\/\/hub.hslu.ch\/sustainable\/\">https:\/\/hub.hslu.ch\/sustainable\/<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachhaltige Fonds gewinnen auf dem Schweizer Fondsmarkt im Vergleich zu konventionellen Fonds die deutliche Mehrheit aller neu allozierten Gelder. Innerhalb der verschiedenen Kategorien nachhaltiger Fonds zeigen sich allerdings grosse Unterschiede: Passive Nachhaltigkeitsfonds liegen weiterhin vorne in der Gunst der Investoren, die Nachfrage nach nachhaltige Themenfonds hingegen verl\u00e4uft uneinheitlich und eher moderat.<\/p>\n","protected":false},"author":137,"featured_media":1711,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"100,113,1428,99,97,1439","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[8],"tags":[17,15,14,16],"class_list":["post-1701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sustainable-investments","tag-esg","tag-nachhaltigkeit","tag-sustainability","tag-trends-in-sustainability"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog\" \/>\n<meta property=\"og:description\" content=\"Nachhaltige Fonds gewinnen auf dem Schweizer Fondsmarkt im Vergleich zu konventionellen Fonds die deutliche Mehrheit aller neu allozierten Gelder. Innerhalb der verschiedenen Kategorien nachhaltiger Fonds zeigen sich allerdings grosse Unterschiede: Passive Nachhaltigkeitsfonds liegen weiterhin vorne in der Gunst der Investoren, die Nachfrage nach nachhaltige Themenfonds hingegen verl\u00e4uft uneinheitlich und eher moderat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/\" \/>\n<meta property=\"og:site_name\" content=\"IFZ Sustainable Investments Blog\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-03T17:14:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T13:54:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"983\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"brianmattmann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschrieben von\" \/>\n\t<meta name=\"twitter:data1\" content=\"brianmattmann\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/\"},\"author\":{\"name\":\"brianmattmann\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/#\\\/schema\\\/person\\\/230c6f78cf431e36a2ab2c7db475cca0\"},\"headline\":\"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren?\",\"datePublished\":\"2024-01-03T17:14:37+00:00\",\"dateModified\":\"2026-02-11T13:54:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/\"},\"wordCount\":1021,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg\",\"keywords\":[\"ESG\",\"Nachhaltigkeit\",\"Sustainability\",\"Trends in Sustainability\"],\"articleSection\":[\"Sustainable Investments\"],\"inLanguage\":\"de-CH\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/\",\"name\":\"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg\",\"datePublished\":\"2024-01-03T17:14:37+00:00\",\"dateModified\":\"2026-02-11T13:54:13+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/#\\\/schema\\\/person\\\/230c6f78cf431e36a2ab2c7db475cca0\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#breadcrumb\"},\"inLanguage\":\"de-CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-CH\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/wp-content\\\/uploads\\\/sites\\\/25\\\/2024\\\/01\\\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg\",\"width\":1365,\"height\":983},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/\",\"name\":\"IFZ Sustainable Investments Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-CH\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/sustainable\\\/#\\\/schema\\\/person\\\/230c6f78cf431e36a2ab2c7db475cca0\",\"name\":\"brianmattmann\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/","og_locale":"de_DE","og_type":"article","og_title":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog","og_description":"Nachhaltige Fonds gewinnen auf dem Schweizer Fondsmarkt im Vergleich zu konventionellen Fonds die deutliche Mehrheit aller neu allozierten Gelder. Innerhalb der verschiedenen Kategorien nachhaltiger Fonds zeigen sich allerdings grosse Unterschiede: Passive Nachhaltigkeitsfonds liegen weiterhin vorne in der Gunst der Investoren, die Nachfrage nach nachhaltige Themenfonds hingegen verl\u00e4uft uneinheitlich und eher moderat.","og_url":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/","og_site_name":"IFZ Sustainable Investments Blog","article_published_time":"2024-01-03T17:14:37+00:00","article_modified_time":"2026-02-11T13:54:13+00:00","og_image":[{"width":1365,"height":983,"url":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","type":"image\/jpeg"}],"author":"brianmattmann","twitter_card":"summary_large_image","twitter_misc":{"Geschrieben von":"brianmattmann","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/"},"author":{"name":"brianmattmann","@id":"https:\/\/hub.hslu.ch\/sustainable\/#\/schema\/person\/230c6f78cf431e36a2ab2c7db475cca0"},"headline":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren?","datePublished":"2024-01-03T17:14:37+00:00","dateModified":"2026-02-11T13:54:13+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/"},"wordCount":1021,"image":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","keywords":["ESG","Nachhaltigkeit","Sustainability","Trends in Sustainability"],"articleSection":["Sustainable Investments"],"inLanguage":"de-CH"},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/","url":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/","name":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren? - IFZ Sustainable Investments Blog","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","datePublished":"2024-01-03T17:14:37+00:00","dateModified":"2026-02-11T13:54:13+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/#\/schema\/person\/230c6f78cf431e36a2ab2c7db475cca0"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#breadcrumb"},"inLanguage":"de-CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/"]}]},{"@type":"ImageObject","inLanguage":"de-CH","@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#primaryimage","url":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","contentUrl":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","width":1365,"height":983},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/sustainable\/nachhaltige-fonds-im-schweizer-vertrieb-wer-sind-die-wachstumsmotoren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/sustainable\/"},{"@type":"ListItem","position":2,"name":"Nachhaltige Fonds im Schweizer Vertrieb: Wer sind die Wachstumsmotoren?"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/sustainable\/#website","url":"https:\/\/hub.hslu.ch\/sustainable\/","name":"IFZ Sustainable Investments Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/sustainable\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-CH"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/sustainable\/#\/schema\/person\/230c6f78cf431e36a2ab2c7db475cca0","name":"brianmattmann"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/sustainable\/wp-content\/uploads\/sites\/25\/2024\/01\/casey-horner-4rDCa5hBlCs-unsplash-1-e1704301546913.jpg","author_info":{"display_name":"brianmattmann","author_link":"https:\/\/hub.hslu.ch\/sustainable\/author\/brianmattmann\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/posts\/1701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/users\/137"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/comments?post=1701"}],"version-history":[{"count":11,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/posts\/1701\/revisions"}],"predecessor-version":[{"id":2391,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/posts\/1701\/revisions\/2391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/media\/1711"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/media?parent=1701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/categories?post=1701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/sustainable\/wp-json\/wp\/v2\/tags?post=1701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}