{"id":564,"date":"2025-05-16T16:29:14","date_gmt":"2025-05-16T14:29:14","guid":{"rendered":"https:\/\/hub.hslu.ch\/ta-blog\/?p=564"},"modified":"2026-02-11T16:27:06","modified_gmt":"2026-02-11T15:27:06","slug":"hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/","title":{"rendered":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren"},"content":{"rendered":"\n<p class=\"is-style-lead\">Seit 1861 wird im G\u00fcterverkehr mit Schraubenkupplungen gearbeitet. Diese sind robust und sehr einfach aufgebaut. Ein Vorteil im rauen Umfeld des G\u00fcterverkehrs. Aber die Nachteile \u00fcberwiegen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>M\u00fchsamer und gef\u00e4hrlicher Handbetrieb<\/li>\n\n\n\n<li>Bremsproben erfordern Laufwege entlang des gesamten Zugs<\/li>\n\n\n\n<li>Rangier- und Abfertigungsprozesse sind personalintensiv und teuer<\/li>\n<\/ul>\n\n\n\n<p>Die neu entwickelte Digitale Automatische Kupplung (DAK) k\u00f6nnte hier Abhilfe schaffen. Mit ihr werden die Wagen nicht nur mechanisch miteinander verbunden, es entsteht zugleich eine durchgehende Stromleitung und Datenkommunikation von der Lokomotive zu allen Wagen. Vor allem die Datenkommunikation erm\u00f6glicht ganz neue Prozesse wie etwa das automatische Kuppeln oder die Automatische Bremsprobe (ABP).<\/p>\n\n\n\n<p><strong>Grundlage der DAK ist das von der HSLU entwickelte Kommunikationssystem <a href=\"https:\/\/www.plc-tec.ch\/ptb\/\">PLUS Powerline Train Backbone (PTB)<\/a>. Der Vorteil: PTB nutzt vorhandene Stromleitungen zur Daten\u00fcbertragung. Es sind keine zus\u00e4tzlichen Kabel, Kontakte oder Funkverbindungen n\u00f6tig.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1-1024x770.jpg\" alt=\"Prototyp einer Digital Automatischen Kupplung (DAK)\" class=\"wp-image-566\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1-1024x770.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1-300x226.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1-768x577.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1-928x698.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-1.jpg 1430w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Prototyp einer Digital Automatischen Kupplung (DAK)<\/em>.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Der DAC+-Testzug unterwegs f\u00fcr EU-Rail<\/h2>\n\n\n\n<p>Um ihre neue Technologie zu testen, hat das <a href=\"https:\/\/www.hslu.ch\/de-ch\/technik-architektur\/ueber-uns\/organisation\/kompetenzzentren-und-forschungsgruppen\/technik\/iimsn\/\">Kompetenzzentrum Intelligente Sensoren und Netze (CC ISN)<\/a> der HSLU zusammen mit SBB Cargo den DAC+-Testzug gebaut. Dieser besteht aus sieben Wagen, die jeweils mit einer DAK, einem ABP-System und mit dem Kommunikationssystem \u00abPLUS Powerline Train Backbone\u00bb ausger\u00fcstet sind (der Name \u00abDAC+\u00bb setzt sich aus diesen Komponenten zusammen). Die Tests sind Bestandteil des europ\u00e4ischen Projekts FP5-TRANS4M-R, die Testergebnisse wurden k\u00fcrzlich auf der Website von Europe\u2019s Rail Joint Undertaking (EU-Rail) <a href=\"https:\/\/rail-research.europa.eu\/latest-news\/successful-testing-of-the-dac-with-powerline-train-backbone\/\">publiziert<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3-1024x770.jpg\" alt=\"Testfahrt des DAC+ Testzugs im malerischen Glarus\" class=\"wp-image-568\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3-1024x770.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3-300x226.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3-768x577.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3-928x698.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-3.jpg 1430w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Testfahrt des DAC+ Testzugs im malerischen Glarus.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Erfolgreiche Tests der HSLU-Technologie<\/strong><\/h2>\n\n\n\n<p>Die Technologie hinter \u00abPowerline PLUS Train Backbone\u00bb (PTB) wurde speziell f\u00fcr die Anwendung im Zug entwickelt und in Stand-, Rangier- und Fahrtests ausgiebig auf ihre Leistungsf\u00e4higkeit und Zuverl\u00e4ssigkeit getestet. Die Ergebnisse:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zuverl\u00e4ssige Datenkommunikation<\/li>\n\n\n\n<li>Automatische Detektion der Wagenreihenfolge<\/li>\n\n\n\n<li>Erfolgreiche Tests von Entkupplung und Bremsprobe<\/li>\n\n\n\n<li>Nachweis der Onboard-Zugintegrit\u00e4t (OTI): kontinuierliche Verbindung bis zum letzten Wagen<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Funktionsweise und Vorteile von PLUS Powerline Train Backbone<\/h2>\n\n\n\n<p>Das am CC ISN entwickelte Kommunikationssystem \u00abPLUS Powerline Train Backbone\u00bb \u00fcbertr\u00e4gt Nachrichten zwischen der Lokomotive und den Wagen direkt \u00fcber die Stromleitung. Zu diesem Zweck wurde eine bereits aus dem Heimbereich bekannte Powerline-Kommunikationstechnik weiterentwickelt und an die speziellen Anforderungen des G\u00fcterverkehrs angepasst. Die Vorteile:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mit der Nutzung der Stromleitung zur Daten\u00fcbertragung k\u00f6nnen Kabel gespart werden<\/li>\n\n\n\n<li>Das vermeidet insbesondere auch zus\u00e4tzliche Datenkontakte in der DAK zwischen den Wagen<\/li>\n\n\n\n<li>Damit wird das System zuverl\u00e4ssiger und robuster, was wiederum kostensenkend wirkt. <\/li>\n\n\n\n<li>Gegen\u00fcber den Funkl\u00f6sungen auf dem Markt bietet PTB als leitungsgebundene Technik h\u00f6here Cybersicherheit und funktioniert z.B. auch w\u00e4hrend Tunnelfahrten zuverl\u00e4ssiger.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"770\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2-1024x770.jpg\" alt=\"Live-Demonstration der Automatischen Kupplung in Horw\" class=\"wp-image-569\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2-1024x770.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2-300x226.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2-768x577.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2-928x698.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/Bild-2.jpg 1430w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Live-Demonstration der Automatischen Kupplung in Horw<\/em>.<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Ausblick auf den weiteren Testverlauf<\/h2>\n\n\n\n<p>Damit die DAK erfolgreich im kommerziellen G\u00fcterverkehr eingesetzt werden kann, braucht es noch viele weitere technische L\u00f6sungen. Offene Fragen bestehen etwa bei der Stromversorgung, m\u00fcssen doch viele Rangierbewegungen ohne Bahnstrom funktionieren.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Ein Power Management System soll sicherstellen, dass die Batterien auf den Wagen m\u00f6glichst lange durchhalten. <\/li>\n\n\n\n<li>Ausserdem sollen nicht funktionierende Wagen oder entladene Batterien im Zugverband erkannt werden. <\/li>\n\n\n\n<li>Am Schluss m\u00fcssen dann die L\u00f6sungen f\u00fcr all diese Aufgaben den hohen Sicherheitsstandards der Bahn gen\u00fcgen und sich nahtlos in die komplexen Prozesse der Bahn einbinden lassen. <\/li>\n<\/ul>\n\n\n\n<p>Auch hier wird die HSLU weiterhin mit ihrem Knowhow zur Entwicklung von innovativen L\u00f6sungen beitragen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-1024x682.jpg\" alt=\"Virtual Train Test Lab an der Hochschule Luzern \u2013 Technik &amp; Architektur\" class=\"wp-image-617\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-1024x682.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-300x200.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-768x512.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-600x400.jpg 600w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01-928x618.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_01.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Im Testlabor forscht die HSLU weiter an technischen L\u00f6sungen f\u00fcr den Einsatz der DAK.<\/em><\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">N\u00e4chster Halt: Europas Schienennetz<\/h2>\n\n\n\n<p>Die Entwicklungen und Tests zu DAK laufen EU-weit auf Hochtouren. In Bezug auf die Kupplung selbst werden Crashtests und Klimakammertests durchgef\u00fchrt und Fragen der Interoperabilit\u00e4t gekl\u00e4rt. Andernorts wird betriebsseitig erforscht, wie die Umr\u00fcstung, zu der auch ein Mischbetrieb in einer \u00dcbergangsphase geh\u00f6rt, in die laufenden Prozesse integriert werden kann. Ein wichtiger Meilenstein ist sicherlich der Startschuss f\u00fcr die sogenannten \u00abPioneer Trains\u00bb Mitte 2026. Diese Z\u00fcge, die im Normalbetrieb fahren werden, werden ausger\u00fcstet sein mit Technologien, die einen hohen Reifegrad aufweisen. Der Plan ist, damit Erfahrungen zu sammeln, damit letzte Korrekturen vorgenommen werden k\u00f6nnen, bevor der Umstieg auf die neue Technologie erfolgt.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"blue-box\">\n\t<div class=\"row\">\n\t\t<div class=\"col-md-12\">\n\t\t\t<p><em>The project FP5-TRANS4M-R is supported by the Europe\u2019s Rail Joint Undertaking and its members. Fundedby the European Union. Views and opinions expressed are however those of the author(s) only and do not necessarily reflect those of the European Union or the Europe\u2019s Rail Joint Undertaking. Neither the European Union nor the granting authority can be held responsible for them.<\/em><\/p>\n<p>&nbsp;<\/p>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-image size-medium is-resized is-style-default\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-300x200.jpg\" alt=\"\" class=\"wp-image-579\" style=\"width:auto;height:50px\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-300x200.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-1024x683.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-768x512.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-1536x1025.jpg 1536w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-600x400.jpg 600w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1-928x619.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Logo-1.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"227\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Rail_color-300x227.png\" alt=\"\" class=\"wp-image-578\" style=\"width:auto;height:50px\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Rail_color-300x227.png 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/EU-Rail_color.png 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"71\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-300x71.png\" alt=\"\" class=\"wp-image-576\" style=\"width:auto;height:50px\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-300x71.png 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-1024x242.png 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-768x182.png 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-1536x363.png 1536w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background-928x219.png 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/logo_fp5_full_light_background.png 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der G\u00fcterbahnverkehr ist immer noch stark von manuellen Prozessen gepr\u00e4gt. Mit der Einf\u00fchrung der neu entwickelten Digitalen Automatischen Kupplung DAK k\u00f6nnte Abhilfe geschaffen werden. Forschende der HSLU sind bei der Entwicklung ganz vorne dabei.<\/p>\n","protected":false},"author":189,"featured_media":565,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"157,1,166,467,161,128","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[21,88],"tags":[82,83,78,63],"class_list":["post-564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daten","category-forschung-und-entwicklung","tag-automatisierung","tag-daten","tag-innovation","tag-kuenstliche-intelligenz"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta property=\"og:description\" content=\"Der G\u00fcterbahnverkehr ist immer noch stark von manuellen Prozessen gepr\u00e4gt. Mit der Einf\u00fchrung der neu entwickelten Digitalen Automatischen Kupplung DAK k\u00f6nnte Abhilfe geschaffen werden. Forschende der HSLU sind bei der Entwicklung ganz vorne dabei.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/\" \/>\n<meta property=\"og:site_name\" content=\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-16T14:29:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T15:27:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"nilssager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"nilssager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/\"},\"author\":{\"name\":\"nilssager\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\"},\"headline\":\"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren\",\"datePublished\":\"2025-05-16T14:29:14+00:00\",\"dateModified\":\"2026-02-11T15:27:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/\"},\"wordCount\":678,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/TA_FE_Daten_virtualtraintestlab_03.jpg\",\"keywords\":[\"Automatisierung\",\"Daten\",\"Innovation\",\"K\u00fcnstliche Intelligenz\"],\"articleSection\":[\"Datenbasierte Prozesse und Automatisierung\",\"Forschung und Entwicklung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/\",\"name\":\"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/TA_FE_Daten_virtualtraintestlab_03.jpg\",\"datePublished\":\"2025-05-16T14:29:14+00:00\",\"dateModified\":\"2026-02-11T15:27:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/TA_FE_Daten_virtualtraintestlab_03.jpg\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/05\\\/TA_FE_Daten_virtualtraintestlab_03.jpg\",\"width\":1280,\"height\":853,\"caption\":\"Forscher pr\u00fcft neue Kommunikationstechnologie der HSLU f\u00fcr die Digitale Automatische Kupplung von G\u00fcterz\u00fcgen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\",\"name\":\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"description\":\"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\",\"name\":\"nilssager\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/","og_locale":"de_DE","og_type":"article","og_title":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","og_description":"Der G\u00fcterbahnverkehr ist immer noch stark von manuellen Prozessen gepr\u00e4gt. Mit der Einf\u00fchrung der neu entwickelten Digitalen Automatischen Kupplung DAK k\u00f6nnte Abhilfe geschaffen werden. Forschende der HSLU sind bei der Entwicklung ganz vorne dabei.","og_url":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/","og_site_name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","article_published_time":"2025-05-16T14:29:14+00:00","article_modified_time":"2026-02-11T15:27:06+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","type":"image\/jpeg"}],"author":"nilssager","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"nilssager","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/"},"author":{"name":"nilssager","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850"},"headline":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren","datePublished":"2025-05-16T14:29:14+00:00","dateModified":"2026-02-11T15:27:06+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/"},"wordCount":678,"commentCount":1,"image":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","keywords":["Automatisierung","Daten","Innovation","K\u00fcnstliche Intelligenz"],"articleSection":["Datenbasierte Prozesse und Automatisierung","Forschung und Entwicklung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/","url":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/","name":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","datePublished":"2025-05-16T14:29:14+00:00","dateModified":"2026-02-11T15:27:06+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#primaryimage","url":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","contentUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","width":1280,"height":853,"caption":"Forscher pr\u00fcft neue Kommunikationstechnologie der HSLU f\u00fcr die Digitale Automatische Kupplung von G\u00fcterz\u00fcgen."},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/ta-blog\/hslu-technologie-koennte-europas-schienengueterverkehr-revolutionieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/ta-blog\/"},{"@type":"ListItem","position":2,"name":"HSLU-Technologie k\u00f6nnte Europas Schieneng\u00fcterverkehr revolutionieren"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website","url":"https:\/\/hub.hslu.ch\/ta-blog\/","name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","description":"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/ta-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850","name":"nilssager"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","featured_image_src_square":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/05\/TA_FE_Daten_virtualtraintestlab_03.jpg","author_info":{"display_name":"nilssager","author_link":"https:\/\/hub.hslu.ch\/ta-blog\/author\/nilssager\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/comments?post=564"}],"version-history":[{"count":16,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/564\/revisions"}],"predecessor-version":[{"id":1066,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/564\/revisions\/1066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/media\/565"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/media?parent=564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/categories?post=564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/tags?post=564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}