{"id":621,"date":"2025-07-02T16:53:03","date_gmt":"2025-07-02T14:53:03","guid":{"rendered":"https:\/\/hub.hslu.ch\/ta-blog\/?p=621"},"modified":"2026-02-11T16:27:48","modified_gmt":"2026-02-11T15:27:48","slug":"gridly","status":"publish","type":"post","link":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/","title":{"rendered":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften"},"content":{"rendered":"\n<p class=\"is-style-lead\">\u00abWir arbeiten daran, Energiewissen zu demokratisieren\u00bb, sagt <a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/ueber-uns\/personensuche\/profile\/?pid=5068\">Yousra Sidqi<\/a>, Co-Leiterin des <a href=\"https:\/\/www.hslu.ch\/de-ch\/technik-architektur\/ueber-uns\/organisation\/kompetenzzentren-und-forschungsgruppen\/technik\/digital-energy-and-electric-power\/\">Kompetenzzentrums Digital Energy und Electric Power (DEEP)<\/a>. Darum haben Sidqi und ihre Kolleg:innen ein interaktives Tool f\u00fcr die Simulation Lokaler Energiegemeinschaften (LEG) entwickelt. Das tool heisst Gridly und macht die Vorteile von LEGs f\u00fcr Haushalte sichtbar, zum Beispiel im Hinblick auf Einsparungen bei der Stromrechnung und Unabh\u00e4ngigkeit vom Hauptstromnetz. \u00abUnser Tool zeigt einerseits wie Teilnehmende durch die Beteiligung an einer Energiegemeinschaft finanziell profitieren k\u00f6nnen, aber auch wie fair die Verteilung der Vorteile f\u00fcr alle Teilnehmer:innen ist\u00bb, erkl\u00e4rt Sidqi.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"HSLU developed an interactive tool for exploring local energy markets\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/EAfgG8GPXu4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p>Gridly erm\u00f6glicht es Nutzer:innen, verschiedene Szenarien zu erkunden, indem sie Folgendes ausw\u00e4hlen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Die Jahreszeit.<\/li>\n\n\n\n<li>Die Gr\u00f6\u00dfe der lokalen Energiegemeinschaft (Anzahl der Mitglieder).<\/li>\n\n\n\n<li>Die Verbreitung von Photovoltaik-Systemen unter den Gemeinschaftsmitgliedern.<\/li>\n\n\n\n<li>Das Vorhandensein oder Fehlen von Energiespeichersystemen bei Mitgliedern mit PV-Anlagen.<\/li>\n\n\n\n<li>Der Grad der Verf\u00fcgbarkeit von Lastverschiebung innerhalb der Gemeinschaft durch Demand Side Management (DSM)-Ger\u00e4te.<\/li>\n<\/ul>\n\n\n\n<p>Basierend auf diesen Eingaben berechnet und visualisiert das Tool wichtige Leistungsindikatoren:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Einsparungen bei der Stromrechnung: Nutzer:innen k\u00f6nnen die durchschnittliche Kostenreduktion pro Haushalt beim Mitmachen in einer LEG vergleichen mit dem eigenst\u00e4ndigen Betrieb.<\/li>\n\n\n\n<li>Netzunabh\u00e4ngigkeit: Eine Netzwerkvisualisierung der LEG stellt den internen Handel sowie die Abh\u00e4ngigkeit der Gemeinschaft vom Hauptnetz dar und hebt die importierte und exportierte Strommenge hervor.<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-1024x576.jpg\" alt=\"Screenshot der interaktiven Oberfl\u00e4che des Tools Gridly.\" class=\"wp-image-652\" srcset=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-1024x576.jpg 1024w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-300x169.jpg 300w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-768x432.jpg 768w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-1536x864.jpg 1536w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot-928x522.jpg 928w, https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/07\/TA_FE_Gridly_Screenshot.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Gridly bietet einen intuitiven und datenbasierten Ansatz f\u00fcr das Verst\u00e4ndnis der finanziellen und energiewirtschaftlichen Vorteile von LEGs. \u00abIn einer Energiegemeinschaft sind die Teilnehmenden keine passiven Verbraucher, sondern Eigent\u00fcmer des Systems\u00bb, sagt Sidqi. Das gibt ihnen mehr Entscheidungsfreiheit bei ihrem Energieverbrauch und ihrer Energieerzeugung. Mit Gridly wollen Yousra Sidqi und ihr Team die Menschen dazu inspirieren, an der Energiewende teilzunehmen. Das Tool kann als Entscheidungshilfe f\u00fcr Politik, Wirtschaft, Forschung und im Energiesektor dienen. Denn Gridly erleichtert fundierte Entscheidungen \u00fcber gemeinschaftsbasierte Energiel\u00f6sungen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Strom sparen und unabh\u00e4ngiger vom Netz werden \u2013 das sind Vorteile von Lokalen Energiegemeinschaften (LEG). Um bessere Entscheidungen f\u00fcr solche LEGs treffen zu k\u00f6nnen, hat ein Team der HSLU das Tool Gridly entwickelt.<\/p>\n","protected":false},"author":189,"featured_media":622,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"598,564","_relevanssi_noindex_reason":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[21,16,88],"tags":[],"class_list":["post-621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-daten","category-energie","category-forschung-und-entwicklung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta property=\"og:description\" content=\"Strom sparen und unabh\u00e4ngiger vom Netz werden \u2013 das sind Vorteile von Lokalen Energiegemeinschaften (LEG). Um bessere Entscheidungen f\u00fcr solche LEGs treffen zu k\u00f6nnen, hat ein Team der HSLU das Tool Gridly entwickelt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/\" \/>\n<meta property=\"og:site_name\" content=\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T14:53:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T15:27:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1512\" \/>\n\t<meta property=\"og:image:height\" content=\"854\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"nilssager\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"nilssager\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/\"},\"author\":{\"name\":\"nilssager\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\"},\"headline\":\"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften\",\"datePublished\":\"2025-07-02T14:53:03+00:00\",\"dateModified\":\"2026-02-11T15:27:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/\"},\"wordCount\":320,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/gridly_video_tumbnail.png\",\"articleSection\":[\"Datenbasierte Prozesse und Automatisierung\",\"Energiesysteme und -effizienz\",\"Forschung und Entwicklung\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/\",\"name\":\"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/gridly_video_tumbnail.png\",\"datePublished\":\"2025-07-02T14:53:03+00:00\",\"dateModified\":\"2026-02-11T15:27:48+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/gridly_video_tumbnail.png\",\"contentUrl\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2025\\\/06\\\/gridly_video_tumbnail.png\",\"width\":1512,\"height\":854,\"caption\":\"Yousra Sidqi und Manuel Christen benutzen das interaktive tool Gridly f\u00fcr die Simulation von Energiegemeinschaften.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/gridly\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\",\"name\":\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"description\":\"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#\\\/schema\\\/person\\\/2b17b1f5f0f2e90e7873c536282e0850\",\"name\":\"nilssager\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/","og_locale":"de_DE","og_type":"article","og_title":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","og_description":"Strom sparen und unabh\u00e4ngiger vom Netz werden \u2013 das sind Vorteile von Lokalen Energiegemeinschaften (LEG). Um bessere Entscheidungen f\u00fcr solche LEGs treffen zu k\u00f6nnen, hat ein Team der HSLU das Tool Gridly entwickelt.","og_url":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/","og_site_name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","article_published_time":"2025-07-02T14:53:03+00:00","article_modified_time":"2026-02-11T15:27:48+00:00","og_image":[{"width":1512,"height":854,"url":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","type":"image\/png"}],"author":"nilssager","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"nilssager","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#article","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/"},"author":{"name":"nilssager","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850"},"headline":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften","datePublished":"2025-07-02T14:53:03+00:00","dateModified":"2026-02-11T15:27:48+00:00","mainEntityOfPage":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/"},"wordCount":320,"commentCount":0,"image":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","articleSection":["Datenbasierte Prozesse und Automatisierung","Energiesysteme und -effizienz","Forschung und Entwicklung"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/","url":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/","name":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#primaryimage"},"image":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#primaryimage"},"thumbnailUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","datePublished":"2025-07-02T14:53:03+00:00","dateModified":"2026-02-11T15:27:48+00:00","author":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hub.hslu.ch\/ta-blog\/gridly\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#primaryimage","url":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","contentUrl":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","width":1512,"height":854,"caption":"Yousra Sidqi und Manuel Christen benutzen das interaktive tool Gridly f\u00fcr die Simulation von Energiegemeinschaften."},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/ta-blog\/gridly\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/ta-blog\/"},{"@type":"ListItem","position":2,"name":"Eine interaktive Entscheidungshilfe f\u00fcr mehr Energiegemeinschaften"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website","url":"https:\/\/hub.hslu.ch\/ta-blog\/","name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","description":"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/ta-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#\/schema\/person\/2b17b1f5f0f2e90e7873c536282e0850","name":"nilssager"}]}},"featured_image_src":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","featured_image_src_square":"https:\/\/hub.hslu.ch\/ta-blog\/wp-content\/uploads\/sites\/4\/2025\/06\/gridly_video_tumbnail.png","author_info":{"display_name":"nilssager","author_link":"https:\/\/hub.hslu.ch\/ta-blog\/author\/nilssager\/"},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/users\/189"}],"replies":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/comments?post=621"}],"version-history":[{"count":8,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/621\/revisions"}],"predecessor-version":[{"id":1067,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts\/621\/revisions\/1067"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/media\/622"}],"wp:attachment":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/media?parent=621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/categories?post=621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/tags?post=621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}