{"id":123,"count":1,"description":"","link":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/","name":"Stadtklima","slug":"stadtklima","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/\" \/>\n<meta property=\"og:site_name\" content=\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/tag\\\/stadtklima\\\/\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/tag\\\/stadtklima\\\/\",\"name\":\"Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/tag\\\/stadtklima\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/tag\\\/stadtklima\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stadtklima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/#website\",\"url\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/\",\"name\":\"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung\",\"description\":\"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hub.hslu.ch\\\/ta-blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/","og_locale":"de_DE","og_type":"article","og_title":"Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","og_url":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/","og_site_name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/","url":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/","name":"Stadtklima Archives - Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","isPartOf":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website"},"breadcrumb":{"@id":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/hub.hslu.ch\/ta-blog\/tag\/stadtklima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hub.hslu.ch\/ta-blog\/"},{"@type":"ListItem","position":2,"name":"Stadtklima"}]},{"@type":"WebSite","@id":"https:\/\/hub.hslu.ch\/ta-blog\/#website","url":"https:\/\/hub.hslu.ch\/ta-blog\/","name":"Technik &amp; Architektur f\u00fcr eine nachhaltige Entwicklung","description":"Aktuelle und spannende Insights aus der Hochschule Luzern \u2013 Technik &amp; Architektur","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hub.hslu.ch\/ta-blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/tags\/123","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/hub.hslu.ch\/ta-blog\/wp-json\/wp\/v2\/posts?tags=123"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}